{"id":380222,"date":"2023-05-07T23:04:18","date_gmt":"2023-05-07T21:04:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=380222&#038;preview=true&#038;preview_id=380222"},"modified":"2023-05-07T23:33:07","modified_gmt":"2023-05-07T21:33:07","slug":"top-14-j24-toulouse-domine-union-bordeaux-belges","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/","title":{"rendered":"Top 14 (J24) : Toulouse domine l&rsquo;Union Bordeaux-B\u00e8gles et s&rsquo;assure une place en demies"},"content":{"rendered":"<p align=\"justify\"><em><strong>TOP 14 2022-2023 &#8211; Globalement dominateur, le Stade Toulousain a battu l&rsquo;Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17), en cl\u00f4ture de la 24\u00e8me journ\u00e9e de Top 14.<\/strong><\/em><\/p>\n<p align=\"justify\">\u00c9limin\u00e9 en demi-finales de la Champions Cup le week-end dernier, le <strong>Stade Toulousain<\/strong> se devait de basculer ce dimanche soir avec la r\u00e9ception de l&rsquo;<strong>UBB<\/strong>, dans le cadre de la 24\u00e8me journ\u00e9e de Top 14. Les Toulousains sont assur\u00e9s de disputer la phase finale et pouvaient, en cas de succ\u00e8s, valider une qualification directe dans le dernier carr\u00e9. Pour Bordeaux-B\u00e8gles, un coup \u00e0 Toulouse et le billet pour les barrages serait presque acquis.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Un premier acte de gala<\/h2>\n<p style=\"text-align: justify;\">Toulouse accroch\u00e9, secou\u00e9, mais devant au score \u00e0 la pause. Au terme d&rsquo;une premi\u00e8re p\u00e9riode enlev\u00e9e, les locaux font donc la course en t\u00eate (21-17). Mais les Stadistes sont bouscul\u00e9s par une <strong>Union Bordeaux-B\u00e8gles<\/strong> qui est fid\u00e8le \u00e0 elle-m\u00eame, joueuse et solidaire. Au final, cinq essais sont inscrits lors des quarante premi\u00e8res minutes. Trois pour les <em>Rouge et Noir<\/em>, gr\u00e2ce \u00e0 <strong>Meafou<\/strong> (8&prime;), <strong>Roumat<\/strong> (31&prime;) et <strong>J. Willis<\/strong> (40&prime;). Les deux derniers sont marqu\u00e9s par l&rsquo;omnipr\u00e9sence du d\u00e9tonateur <strong>Antoine Dupont<\/strong>, en feu lors de la premi\u00e8re mi-temps.<\/p>\n<p style=\"text-align: justify;\">En face, les Girondins ne s&rsquo;en sont pas laiss\u00e9s conter. Par deux fois, ils ont r\u00e9ussi \u00e0 aller \u00e0 dame. <strong>Bielle-Biarrey<\/strong> (16&prime;) et <strong>Timu<\/strong> (35&prime;) ont ainsi permis aux leurs de rester au contact \u00e0 la pause, \u00e0 quatre longueurs. Avant de craquer lors du second acte.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Louis Bielle-Biarrey inscrit son 4\u00e8me essai de la saison avec l&rsquo; <a href=\"https:\/\/twitter.com\/UBBrugby?ref_src=twsrc%5Etfw\">@UBBrugby<\/a> ! \ud83d\udd25<\/p>\n<p>Bordeaux prend l&rsquo;avantage au score ! <a href=\"https:\/\/twitter.com\/hashtag\/STUBB?src=hash&amp;ref_src=twsrc%5Etfw\">#STUBB<\/a> <a href=\"https:\/\/t.co\/W7ObTBsTqO\">pic.twitter.com\/W7ObTBsTqO<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/twitter.com\/CanalplusRugby\/status\/1655294777154322435?ref_src=twsrc%5Etfw\">May 7, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Toulouse a le dernier mot<\/h2>\n<p style=\"text-align: justify;\">La premi\u00e8re moiti\u00e9 de cette seconde p\u00e9riode n&rsquo;est pas aussi qualitative que les quarante premi\u00e8res minutes. Le <strong>Stade Toulousain<\/strong> occupe le camp girondin, mais sans parvenir \u00e0 marquer, la faute \u00e0 du d\u00e9chet dans le dernier geste. Il faut attendre l&rsquo;heure de jeu pour voir la rencontre se d\u00e9canter r\u00e9ellement. Sur une combinaison avec <strong>Peato Mauvaka<\/strong>, Antoine Dupont met les cannes aux 30 m\u00e8tres pour aller inscrire le quatri\u00e8me essai stadiste, transform\u00e9 par <strong>Thomas Ramos<\/strong> (28-17, 60&prime;). Cinq minutes plus tard, <strong>Ramos<\/strong> enquille une nouvelle p\u00e9nalit\u00e9 (31-17, 65&prime;). <strong>Toulouse<\/strong> respire, <strong>Bordeaux-B\u00e8gles<\/strong> grimace.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">MAIS QUEL ESSAI DE DUPONT\ud83d\udd25 \ud83d\udd25<\/p>\n<p>Combinaison gagnante pour le <a href=\"https:\/\/twitter.com\/StadeToulousain?ref_src=twsrc%5Etfw\">@StadeToulousain<\/a> qui prend le large dans cette rencontre !<\/p>\n<p>\ud83d\udc40 <a href=\"https:\/\/twitter.com\/Dupont9A?ref_src=twsrc%5Etfw\">@Dupont9A<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/STUBB?src=hash&amp;ref_src=twsrc%5Etfw\">#STUBB<\/a> <a href=\"https:\/\/t.co\/hA3UODUK3y\">pic.twitter.com\/hA3UODUK3y<\/a><\/p>\n<p>\u2014 CANAL+ Rugby (@CanalplusRugby) <a href=\"https:\/\/twitter.com\/CanalplusRugby\/status\/1655311260127223811?ref_src=twsrc%5Etfw\">May 7, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">En qu\u00eate de bonus offensif, les Stadistes continuent alors d&rsquo;attaquer. En vain. Les hommes d&rsquo;<strong>Ugo Mola<\/strong> l&#8217;emportent n\u00e9anmoins assez largement (31-17) et s&rsquo;assurent une place dans le dernier carr\u00e9. L&rsquo;\u00e9limination en demies de Champions Cup est dig\u00e9r\u00e9e. Pour l&rsquo;<strong>UBB<\/strong>, sixi\u00e8me ce dimanche soir, il faudra gagner les deux derniers matchs de la saison r\u00e9guli\u00e8re, \u00e0 Pau et lors de la r\u00e9ception de Toulon, pour \u00e9viter de d\u00e9pendre des r\u00e9sultats des concurrents.<\/p>\n<ul>\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-top-14-2022-2023\/\">Le classement du Top 14<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; Globalement dominateur, le Stade Toulousain a battu l&rsquo;Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17), en cl\u00f4ture de la 24\u00e8me journ\u00e9e de Top 14.<\/p>\n","protected":false},"author":4,"featured_media":380248,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,47050],"tags":[16878,13,110,4008,111,1567,1568],"class_list":["post-380222","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-rugby","tag-rugby-a-xv","tag-stade-toulousain","tag-top-14","tag-ubb","tag-union-bordeaux-begles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Top 14 (J24) : Toulouse domine l&#039;Union Bordeaux-B\u00e8gles et s&#039;assure une place en demies<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - Le Stade Toulousain a battu l&#039;Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Top 14 (J24) : Toulouse domine l&#039;Union Bordeaux-B\u00e8gles et s&#039;assure une place en demies\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - Le Stade Toulousain a battu l&#039;Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-07T21:04:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-07T21:33:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Top 14 (J24) : Toulouse domine l&#039;Union Bordeaux-B\u00e8gles et s&#039;assure une place en demies\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Top 14 (J24) : Toulouse domine l&rsquo;Union Bordeaux-B\u00e8gles et s&rsquo;assure une place en demies\",\"datePublished\":\"2023-05-07T21:04:18+00:00\",\"dateModified\":\"2023-05-07T21:33:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\"},\"wordCount\":525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png\",\"keywords\":[\"br\u00e8ve\",\"Rugby\",\"Rugby \u00e0 XV\",\"Stade Toulousain\",\"Top 14\",\"UBB\",\"Union Bordeaux-B\u00e8gles\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\",\"name\":\"Top 14 (J24) : Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png\",\"datePublished\":\"2023-05-07T21:04:18+00:00\",\"dateModified\":\"2023-05-07T21:33:07+00:00\",\"description\":\"TOP 14 2022-2023 - Le Stade Toulousain a battu l'Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png\",\"width\":800,\"height\":445,\"caption\":\"Top 14 (J24) Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Top 14 (J24) : Toulouse domine l&rsquo;Union Bordeaux-B\u00e8gles et s&rsquo;assure une place en demies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Top 14 (J24) : Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies","description":"TOP 14 2022-2023 - Le Stade Toulousain a battu l'Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/","og_locale":"fr_FR","og_type":"article","og_title":"Top 14 (J24) : Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies","og_description":"TOP 14 2022-2023 - Le Stade Toulousain a battu l'Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).","og_url":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-05-07T21:04:18+00:00","article_modified_time":"2023-05-07T21:33:07+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Top 14 (J24) : Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Top 14 (J24) : Toulouse domine l&rsquo;Union Bordeaux-B\u00e8gles et s&rsquo;assure une place en demies","datePublished":"2023-05-07T21:04:18+00:00","dateModified":"2023-05-07T21:33:07+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png","keywords":["br\u00e8ve","Rugby","Rugby \u00e0 XV","Stade Toulousain","Top 14","UBB","Union Bordeaux-B\u00e8gles"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/","url":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/","name":"Top 14 (J24) : Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png","datePublished":"2023-05-07T21:04:18+00:00","dateModified":"2023-05-07T21:33:07+00:00","description":"TOP 14 2022-2023 - Le Stade Toulousain a battu l'Union Bordeaux-B\u00e8gles ce dimanche soir au Stadium de Toulouse (31-17).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Top-14-J24-Toulouse-domine-lUnion-Bordeaux-Begles-et-sassure-une-place-en-demies.png","width":800,"height":445,"caption":"Top 14 (J24) Toulouse domine l'Union Bordeaux-B\u00e8gles et s'assure une place en demies"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/top-14-j24-toulouse-domine-union-bordeaux-belges\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Top 14 (J24) : Toulouse domine l&rsquo;Union Bordeaux-B\u00e8gles et s&rsquo;assure une place en demies"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/380222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=380222"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/380222\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/380248"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=380222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=380222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=380222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}