{"id":383040,"date":"2023-05-17T19:05:05","date_gmt":"2023-05-17T17:05:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=383040&#038;preview=true&#038;preview_id=383040"},"modified":"2023-05-17T19:40:41","modified_gmt":"2023-05-17T17:40:41","slug":"roland-garros-2023-rafael-nadal-declare-forfait","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/","title":{"rendered":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait"},"content":{"rendered":"<p align=\"justify\"><em><b>ROLAND-GARROS 2023 &#8211; Coup de tonnerre sur la Porte d&rsquo;Auteuil ! Si le doute planait, cela est d\u00e9sormais confirm\u00e9 : Rafael Nadal ne prendra pas part \u00e0 l&rsquo;\u00e9dition de Roland-Garros 2023.<\/b><\/em><\/p>\n<p align=\"justify\">Il s&rsquo;\u00e9tait engag\u00e9 dans une v\u00e9ritable course contre-la-montre depuis janvier dernier, et son dernier match disput\u00e9 \u00e0 l&rsquo;Open d&rsquo;Australie. Depuis sa d\u00e9faite pr\u00e9matur\u00e9e d\u00e8s le 2e tour face \u00e0 Mackenzie McDonald, <strong>Rafael Nadal<\/strong> n&rsquo;a plus disput\u00e9 une seule rencontre sur le circuit. Alors qu&rsquo;il devait reprendre au d\u00e9but de la saison sur terre battue \u00e0 Monte-Carlo, <a href=\"https:\/\/dicodusport.fr\/blog\/atp-madrid-rafael-nadal-forfait\/\">il a successivement d\u00e9clar\u00e9 forfait pour tous les tournois disput\u00e9s ces derni\u00e8res semaines (Madrid, Rome)<\/a>. \u00c0 seulement cinq jours du d\u00e9but du tableau principal de <strong>Roland-Garros<\/strong>, le terrible couperet est tomb\u00e9 : l&rsquo;Espagnol ne prendra pas part \u00e0 la comp\u00e9tition qu&rsquo;<strong>il a remport\u00e9 \u00e0 14 reprises<\/strong> durant son immense carri\u00e8re.<\/p>\n<p align=\"justify\">Le m\u00e9dia espagnol <em>Relevo<\/em> l&rsquo;a confirm\u00e9 en fin d&rsquo;apr\u00e8s-midi. Vainqueur l&rsquo;ann\u00e9e derni\u00e8re, il ne d\u00e9fendra pas son titre. Ainsi, il devrait \u00e9galement conna\u00eetre <strong>une chute vertigineuse au classement ATP<\/strong>, puisqu&rsquo;il perdra une quantit\u00e9 astronomique de points. Actuellement class\u00e9 14e, celui qui f\u00eatera ses 37 ans d\u00e9but juin va devoir se remettre de cette \u00e9norme d\u00e9ception pour retourner sur les courts ensuite. \u00c0 noter que l&rsquo;Espagnol tiendra une conf\u00e9rence de presse demain apr\u00e8s-midi (16h).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\"><a href=\"https:\/\/twitter.com\/hashtag\/%C3%9AltimaHora?src=hash&amp;ref_src=twsrc%5Etfw\">#\u00daltimaHora<\/a> Rafael Nadal se pierde Roland Garros.<\/p>\n<p>\ud83d\udccc El tenista balear no se ha recuperado de su lesi\u00f3n y no podr\u00e1 acudir al torneo que ha ganado 14 veces.<\/p>\n<p>\ud83d\udccc De momento, no tiene fecha de regreso.<\/p>\n<p>\u270d\ufe0f <a href=\"https:\/\/twitter.com\/NachoEncabo?ref_src=twsrc%5Etfw\">@NachoEncabo<\/a><a href=\"https:\/\/t.co\/fHPgt8Oo3r\">https:\/\/t.co\/fHPgt8Oo3r<\/a><\/p>\n<p>\u2014 Relevo (@relevo) <a href=\"https:\/\/twitter.com\/relevo\/status\/1658873251215360000?ref_src=twsrc%5Etfw\">May 17, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROLAND-GARROS 2023 &#8211; Coup de tonnerre sur la Porte d&rsquo;Auteuil ! Si le doute planait, cela est d\u00e9sormais confirm\u00e9 : Rafael Nadal ne prendra pas part \u00e0 l&rsquo;\u00e9dition de Roland-Garros 2023.<\/p>\n","protected":false},"author":55,"featured_media":383041,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47090],"tags":[156,16878,3223,24,136],"class_list":["post-383040","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-roland-garros","tag-atp","tag-breve","tag-rafael-nadal","tag-sport","tag-tennis"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait<\/title>\n<meta name=\"description\" content=\"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l&#039;\u00e9dition \u00e0 venir des Internationaux de France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait\" \/>\n<meta property=\"og:description\" content=\"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l&#039;\u00e9dition \u00e0 venir des Internationaux de France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-17T17:05:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-17T17:40:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait\",\"datePublished\":\"2023-05-17T17:05:05+00:00\",\"dateModified\":\"2023-05-17T17:40:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/\"},\"wordCount\":284,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png\",\"keywords\":[\"ATP\",\"br\u00e8ve\",\"Rafael Nadal\",\"sport\",\"Tennis\"],\"articleSection\":[\"Roland-Garros\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/\",\"name\":\"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png\",\"datePublished\":\"2023-05-17T17:05:05+00:00\",\"dateModified\":\"2023-05-17T17:40:41+00:00\",\"description\":\"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l'\u00e9dition \u00e0 venir des Internationaux de France.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png\",\"width\":800,\"height\":445,\"caption\":\"Roland-Garros 2023 Rafael Nadal d\u00e9clare forfait\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/roland-garros-2023-rafael-nadal-declare-forfait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait","description":"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l'\u00e9dition \u00e0 venir des Internationaux de France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/","og_locale":"fr_FR","og_type":"article","og_title":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait","og_description":"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l'\u00e9dition \u00e0 venir des Internationaux de France.","og_url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-05-17T17:05:05+00:00","article_modified_time":"2023-05-17T17:40:41+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait","datePublished":"2023-05-17T17:05:05+00:00","dateModified":"2023-05-17T17:40:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/"},"wordCount":284,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png","keywords":["ATP","br\u00e8ve","Rafael Nadal","sport","Tennis"],"articleSection":["Roland-Garros"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/","url":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/","name":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png","datePublished":"2023-05-17T17:05:05+00:00","dateModified":"2023-05-17T17:40:41+00:00","description":"ROLAND-GARROS 2023 - Titr\u00e9 \u00e0 14 reprises, Rafael Nadal va d\u00e9clarer forfait pour l'\u00e9dition \u00e0 venir des Internationaux de France.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Roland-Garros-2023-Rafael-Nadal-declare-forfait.png","width":800,"height":445,"caption":"Roland-Garros 2023 Rafael Nadal d\u00e9clare forfait"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/roland-garros-2023-rafael-nadal-declare-forfait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Roland-Garros 2023 : Rafael Nadal d\u00e9clare forfait"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/383040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=383040"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/383040\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/383041"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=383040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=383040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=383040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}