{"id":384540,"date":"2023-05-23T09:19:17","date_gmt":"2023-05-23T07:19:17","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=384540&#038;preview=true&#038;preview_id=384540"},"modified":"2023-05-23T09:33:44","modified_gmt":"2023-05-23T07:33:44","slug":"transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/","title":{"rendered":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>TOP 14 2023-2023 &#8211; Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l&rsquo;ASM Clermont, en plus du RC Toulon, en vue de la saison prochaine.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Combien de joueurs vont quitter <strong>Brive<\/strong> en fin de saison ? Il n&rsquo;y a pas de nombre encore arr\u00eat\u00e9, mais l&rsquo;exode a d\u00e9j\u00e0 commenc\u00e9 et sera massif. Entre les joueurs en fin de contrat et ceux qui avaient une clause pour partir en cas de rel\u00e9gation, l&rsquo;effectif briviste est en train de se vider petit \u00e0 petit. Si peu de mouvements ont encore \u00e9t\u00e9 officialis\u00e9s, ils le seront d\u00e8s que la saison sera termin\u00e9e.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Encore un match Toulon vs Clermont !<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Joris<\/strong> <strong>Jurand<\/strong> fait partie des joueurs qui pourraient changer d&rsquo;air. Bless\u00e9 depuis de longs mois, il \u00e9tait annonc\u00e9 sur les tablettes du <strong>RC<\/strong> <strong>Toulon<\/strong>, qui veut renforcer sa ligne de trois-quarts avec des joueurs JIFF. L&rsquo;<strong>ASM Clermont<\/strong> serait aussi sur le coup pour signer le joueur de 27 ans, apr\u00e8s avoir notamment vu <strong>Auguste<\/strong> <strong>Cadot<\/strong> rejoindre finalement le Montpellier HR.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Clermont<\/strong> et <strong>Toulon<\/strong> vont donc \u00eatre \u00e0 la bagarre sur ce dossier, <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-lasm-clermont-va-aussi-se-faire-doubler-pour-esteban-abadie\/\" target=\"_blank\" rel=\"noopener\">comme sur celui d&rsquo;<strong>Esteban Abadie<\/strong><\/a>. Le troisi\u00e8me ligne de Brive serait n\u00e9anmoins plus proche de rejoindre le club de la Rade que les <strong>Jaunards<\/strong>. <strong>Joris<\/strong> <strong>Jurand<\/strong> a lui jou\u00e9 11 matchs avec le CA Brive cette saison avant de se blesser gravement en janvier. Il ne devrait donc jamais porter \u00e0 nouveau le maillot du club corr\u00e9zien.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Officiellement rel\u00e9gu\u00e9 en Pro D2, Brive voit nombre de ses joueurs quitter le club \ud83d\udc40<a href=\"https:\/\/t.co\/G3DdICD9pH\">https:\/\/t.co\/G3DdICD9pH<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1660892290905243648?ref_src=twsrc%5Etfw\">May 23, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2023 &#8211; Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l&rsquo;ASM Clermont, en plus du RC Toulon, en vue de la saison prochaine.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":384542,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,47050],"tags":[16878,3665,3078,111],"class_list":["post-384540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-ca-brive","tag-rc-toulon","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l&#039;ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l&#039;ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-23T07:19:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-05-23T07:33:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14\",\"datePublished\":\"2023-05-23T07:19:17+00:00\",\"dateModified\":\"2023-05-23T07:33:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\"},\"wordCount\":281,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png\",\"keywords\":[\"br\u00e8ve\",\"ca brive\",\"RC Toulon\",\"Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\",\"name\":\"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png\",\"datePublished\":\"2023-05-23T07:19:17+00:00\",\"dateModified\":\"2023-05-23T07:33:44+00:00\",\"description\":\"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l'ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14","description":"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l'ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14","og_description":"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l'ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-05-23T07:19:17+00:00","article_modified_time":"2023-05-23T07:33:44+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14","datePublished":"2023-05-23T07:19:17+00:00","dateModified":"2023-05-23T07:33:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/"},"wordCount":281,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png","keywords":["br\u00e8ve","ca brive","RC Toulon","Top 14"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/","name":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png","datePublished":"2023-05-23T07:19:17+00:00","dateModified":"2023-05-23T07:33:44+00:00","description":"TOP 14 2023-2023 - Selon Rugbyrama, Joris Jurand serait suivi de pr\u00e8s par l'ASM Clermont en plus du RC Toulon pour la saison prochaine.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/05\/Transferts-Brive-Joris-Jurand-a-une-deuxieme-piste-en-Top-14.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-brive-joris-jurand-a-une-deuxieme-piste-en-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Brive : Joris Jurand a une deuxi\u00e8me piste en Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/384540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=384540"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/384540\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/384542"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=384540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=384540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=384540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}