{"id":387253,"date":"2023-06-01T19:23:27","date_gmt":"2023-06-01T17:23:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=387253&#038;preview=true&#038;preview_id=387253"},"modified":"2023-06-01T19:29:41","modified_gmt":"2023-06-01T17:29:41","slug":"transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/","title":{"rendered":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023"},"content":{"rendered":"<p align=\"justify\"><em><strong>TRANSFERTS RUGBY &#8211; Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, des nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin 2023.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Cowan-Dickie courtis\u00e9 par le Stade Fran\u00e7ais<\/h2>\n<p style=\"text-align: justify;\">Selon le <em>Midi Olympique<\/em>, le talonneur anglais <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-luke-cowan-dickie-a-un-nouveau-pretendant-en-top-14\/\"><strong>Luke Cowan-Dickie<\/strong> (29 ans), a un nouveau pr\u00e9tendant en Top 14<\/a>. Refoul\u00e9 \u00e0 la visite m\u00e9dicale du c\u00f4t\u00e9 de Montpellier, l&rsquo;international anglais est toujours \u00e0 la recherche d&rsquo;un nouveau club. Ainsi, le <strong>Stade Fran\u00e7ais<\/strong> est entr\u00e9 en discussions avec le joueur. Recal\u00e9 dans l&rsquo;H\u00e9rault en raison de probl\u00e8mes persistants aux cervicales, <strong>Cowan-Dickie<\/strong> serait pour l&rsquo;instant trop gourmand sur le plan financier.<\/p>\n<p style=\"text-align: justify;\">Mais la situation pourrait se d\u00e9bloquer. Arriv\u00e9 l&rsquo;\u00e9t\u00e9 dernier en provenance du LOU, <strong>Micka\u00ebl Ivaldi<\/strong> (33 ans) souhaite d\u00e9j\u00e0 quitter la Capitale. L&rsquo;<strong>USAP<\/strong> est int\u00e9ress\u00e9e, mais <strong>Thomas<\/strong>\u00a0<strong>Lombard<\/strong>, directeur g\u00e9n\u00e9ral du <strong>Stade Fran\u00e7ais<\/strong>, avait ferm\u00e9 la porte \u00e0 un d\u00e9part, il y 10 jours. <em>\u00ab Fran\u00e7ois Rivi\u00e8re m\u2019a bien contact\u00e9 pour \u00e9voquer la possible lib\u00e9ration de contrat de Micka\u00ebl Ivaldi. Aujourd\u2019hui, la porte est ferm\u00e9e. Il n\u2019y a pas de discussion \u00bb<\/em>, avait-il alors indiqu\u00e9 dans les colonnes de <em>L&rsquo;\u00c9quipe<\/em>. Affaire \u00e0 suivre.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-luke-cowan-dickie-a-un-nouveau-pretendant-en-top-14\/\" class=\"vlp-link\" title=\"Transferts : Luke Cowan-Dickie a un nouveau pr\u00e9tendant en Top 14\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Luke-Cowan-Dickie-a-un-nouveau-pretendant-en-Top-14.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Luke-Cowan-Dickie-a-un-nouveau-pretendant-en-Top-14.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Luke-Cowan-Dickie-a-un-nouveau-pretendant-en-Top-14-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Luke-Cowan-Dickie-a-un-nouveau-pretendant-en-Top-14-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts : Luke Cowan-Dickie a un nouveau pr\u00e9tendant en Top 14<\/div><div class=\"vlp-block-1 vlp-link-summary\">TOP 14 2023-2024 - Refoul\u00e9 au dernier moment par le MHR, Luke Cowan-Dickie serait en discussions avec le Stade Fran\u00e7ais selon nos confr\u00e8res du Midi Olympique.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2>Dumora prolonge au CO<\/h2>\n<p style=\"text-align: justify;\">Arriv\u00e9 \u00e0 Castres en 2014, <strong>Julien Dumora<\/strong> (35 ans) va poursuivre l&rsquo;aventure dans le Tarn. L&rsquo;arri\u00e8re, qui a disput\u00e9 24 rencontres cette saison pour 24 titularisations et cinq essais inscrits, a rempil\u00e9 pour deux saisons, au sein du club avec lequel il a remport\u00e9 le Top 14, en 2018.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udde0\ud835\uddd8\ud835\udde5\ud835\uddd6\ud835\udddc \ud835\udded\ud835\udde2\ud835\udde8\ud835\udded\ud835\udde2\ud835\udde8 \ud83d\udc99<br \/>\nEt, au fait, on a encore quelque chose \u00e0 vous dire&#8230; \ud83d\udc40\u270d\ufe0f<a href=\"https:\/\/t.co\/FobvRxHKeS\">https:\/\/t.co\/FobvRxHKeS<\/a><a href=\"https:\/\/twitter.com\/hashtag\/TeamCO?src=hash&amp;ref_src=twsrc%5Etfw\">#TeamCO<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/TousEnsemble?src=hash&amp;ref_src=twsrc%5Etfw\">#TousEnsemble<\/a><\/p>\n<p>\u2014 Castres Olympique (@CastresRugby) <a href=\"https:\/\/twitter.com\/CastresRugby\/status\/1663969967769780225?ref_src=twsrc%5Etfw\">May 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Par ailleurs, le CO a aussi annonc\u00e9 la prolongation d&rsquo;<strong>Adrien S\u00e9guret<\/strong> (24 ans). Arriv\u00e9 en provenance de Grenoble l&rsquo;\u00e9t\u00e9 dernier, le centre est d\u00e9sormais li\u00e9 au club tarnais jusqu&rsquo;en 2026.<\/p>\n<h2 style=\"text-align: justify;\">Deux d\u00e9parts en vue \u00e0 Brive<\/h2>\n<p style=\"text-align: justify;\">\u00c0 <strong>Brive<\/strong>, l&rsquo;exode se poursuit. La prolongation de<strong> Sa\u00efd Hireche<\/strong> a \u00e9t\u00e9 un court r\u00e9pit ce mercredi pour le club corr\u00e9zien. Ce jeudi, La Montagne indique que les deux trois-quarts fidjiens, <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-brive-setareki-bituniyata-convoite-par-3-clubs-de-top-14\/\"><strong>Setareki<\/strong>\u00a0<strong>Bituniyata <\/strong>(27 ans) et <strong>Setariki<\/strong>\u00a0<strong>Tuicuvu <\/strong>(27 ans), sont aussi sur le d\u00e9part<\/a>. Le premier cit\u00e9 est pourtant li\u00e9 avec le CAB jusqu&rsquo;en 2026. Mais son envie de rester en Top 14 est plus forte. Un temps en course pour l&rsquo;accueillir, Toulouse a finalement renonc\u00e9. L<strong>&lsquo;ASM Clermont<\/strong> et l&rsquo;<strong>UBB<\/strong> sont d\u00e9sormais dans la course pour accueillir l&rsquo;ailier.<\/p>\n<p style=\"text-align: justify;\">Concernant <strong>Setariki Tuicuvu<\/strong>, l&rsquo;envie est la m\u00eame : \u00e9voluer en Top 14. Sous contrat jusqu&rsquo;en 2025, des clubs de l&rsquo;\u00e9lite du rugby fran\u00e7ais sont int\u00e9ress\u00e9s. Affaire \u00e0 suivre.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-brive-setareki-bituniyata-convoite-par-3-clubs-de-top-14\/\" class=\"vlp-link\" title=\"Transferts Brive : Setareki Bituniyata convoit\u00e9 par 3 clubs de Top 14\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Brive-Setareki-Bituniyata-convoite-par-3-clubs-de-Top-4.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Brive-Setareki-Bituniyata-convoite-par-3-clubs-de-Top-4.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Brive-Setareki-Bituniyata-convoite-par-3-clubs-de-Top-4-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Brive-Setareki-Bituniyata-convoite-par-3-clubs-de-Top-4-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts Brive : Setareki Bituniyata convoit\u00e9 par 3 clubs de Top 14<\/div><div class=\"vlp-block-1 vlp-link-summary\">TOP 14 2023-2024 - Bien que sous contrat, Setareki Bituniyata devrait lui aussi quitter Brive en fin de saison pour rester en Top 14.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Provence Rugby poursuit son mercato XXL<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s <strong> Arthur<\/strong>\u00a0<strong>Coville<\/strong>,\u00a0<strong>Thomas<\/strong>\u00a0<strong>Salles<\/strong>,\u00a0<strong>Atila<\/strong>\u00a0<strong>Septar<\/strong>,\u00a0<strong>Andr\u00e9s<\/strong>\u00a0<strong>Zafra<\/strong>\u00a0et\u00a0<strong>Th\u00e9o<\/strong>\u00a0<strong>Hannoyer<\/strong> mais aussi et surtout le pilier droit gallois, <a href=\"https:\/\/dicodusport.fr\/blog\/transfers-tomas-francis-va-finalement-signer-en-pro-d2\/\"><strong>Tomas Francis<\/strong><\/a>, <strong>Provence Rugby<\/strong> continue d&rsquo;enregistrer les signatures de renom. Selon <em>L&rsquo;\u00c9quipe<\/em>, <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jimmy-gopperth-signe-en-pro-d2\/\">l&rsquo;ouvreur n\u00e9o-z\u00e9landais <strong>Jimmy<\/strong>\u00a0<strong>Gopperth<\/strong>, a donn\u00e9 son accord pour rejoindre le club de <strong>Pro D2<\/strong><\/a>. Le joueur de 39 ans, qui n&rsquo;a jamais jou\u00e9 le moindre match avec les <strong>All<\/strong>\u00a0<strong>Blacks<\/strong>, est arriv\u00e9 sur le continent europ\u00e9en en 2009. \u00c0 l&rsquo;\u00e9poque, il avait rejoint les Falcons de Newcastle, en Angleterre. Il a ensuite \u00e9volu\u00e9 sous les couleurs du Leinster (Irlande), avant de revenir en Angleterre, chez les Wasps puis \u00e0 Leicester. Un renfort de poids donc, avec un joueur exp\u00e9riment\u00e9.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-neo-zelandais-jimmy-gopperth-signe-en-pro-d2\/\" class=\"vlp-link\" title=\"Transferts : Le N\u00e9o-Z\u00e9landais Jimmy Gopperth signe en Pro D2\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Le-Neo-Zelandais-Jimmy-Gopperth-signe-en-Pro-D2.png\" class=\"attachment-800x445 size-800x445\" alt=\"\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Le-Neo-Zelandais-Jimmy-Gopperth-signe-en-Pro-D2.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Le-Neo-Zelandais-Jimmy-Gopperth-signe-en-Pro-D2-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Le-Neo-Zelandais-Jimmy-Gopperth-signe-en-Pro-D2-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Transferts : Le N\u00e9o-Z\u00e9landais Jimmy Gopperth signe en Pro D2<\/div><div class=\"vlp-block-1 vlp-link-summary\">RUGBY \u00c0 XV - Provence Rugby poursuit son march\u00e9 XXL avec le recrutement de l'ouvreur n\u00e9o-z\u00e9landais, Jimmy Gopperth.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, des nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin 2023.<\/p>\n","protected":false},"author":4,"featured_media":387263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129],"tags":[16878,28226,13,110,29105],"class_list":["post-387253","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-01T17:23:27+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-01T17:29:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\",\"datePublished\":\"2023-06-01T17:23:27+00:00\",\"dateModified\":\"2023-06-01T17:29:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\"},\"wordCount\":814,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png\",\"keywords\":[\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\",\"name\":\"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png\",\"datePublished\":\"2023-06-01T17:23:27+00:00\",\"dateModified\":\"2023-06-01T17:29:41+00:00\",\"description\":\"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png\",\"width\":800,\"height\":445,\"caption\":\"Transferts Rugby Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023","description":"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023","og_description":"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-06-01T17:23:27+00:00","article_modified_time":"2023-06-01T17:29:41+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023","datePublished":"2023-06-01T17:23:27+00:00","dateModified":"2023-06-01T17:29:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/"},"wordCount":814,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png","keywords":["br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/","name":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png","datePublished":"2023-06-01T17:23:27+00:00","dateModified":"2023-06-01T17:29:41+00:00","description":"TRANSFERTS RUGBY - Le Stade Fran\u00e7ais discute avec Luke Cowan-Dickie, de nouveaux d\u00e9parts \u00e0 Brive : les infos transferts de ce jeudi 1er juin.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Transferts-Rugby-Stade-Francais-Castres-Brive-les-infos-de-ce-jeudi-1er-juin-2023.png","width":800,"height":445,"caption":"Transferts Rugby Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-stade-francais-castres-brive-les-infos-de-ce-jeudi-1er-juin-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Stade Fran\u00e7ais, Castres, Brive, les infos de ce jeudi 1er juin 2023"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/387253","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=387253"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/387253\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/387263"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=387253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=387253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=387253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}