{"id":387780,"date":"2023-06-03T17:09:18","date_gmt":"2023-06-03T15:09:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=387780&#038;preview=true&#038;preview_id=387780"},"modified":"2023-06-03T17:24:35","modified_gmt":"2023-06-03T15:24:35","slug":"playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/","title":{"rendered":"Playoffs Betclic \u00c9lite : L&rsquo;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><a href=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-tableau-complet-calendrier-et-resultats\/\"><i><b>PLAYOFFS BETCLIC \u00c9LITE 2022-2023<\/b><\/i><\/a><i><b> <\/b><\/i><i><b>\u2013 L&rsquo;AS Monaco est la premi\u00e8re \u00e9quipe officiellement qualifi\u00e9e en finale. La Roca Team a d\u00e9croch\u00e9 la victoire (871-85) qui lui manquait \u00e0 Ekinox pour balayer la s\u00e9rie en trois manches s\u00e8ches. Pour la premi\u00e8re demi-finale de son histoire, la JL Bourg n&rsquo;a pas \u00e0 rougir. Les Bressans ont tout donn\u00e9, mais n&rsquo;ont rien pu faire face \u00e0 la force de frappe l\u00e9tale du 3e de la derni\u00e8re EuroLigue.<\/b><\/i><\/p>\n<p align=\"justify\">La veille, <a href=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-lasvel-demolit-les-metropolitans-a-lastroballe-pour-semparer-du-match-3\/\">l&rsquo;ASVEL a indiqu\u00e9 la marche \u00e0 suivre en l&#8217;emportant face aux Metropolitans<\/a> en \u00e9tant dos au mur. La<strong> JL Bourg<\/strong> vivait le m\u00eame cas de figure en retrouvant l&rsquo;<strong>AS Monaco<\/strong> avec l&rsquo;obligation de l&#8217;emporter. Avec l&rsquo;avantage de jouer \u00e0 <strong>Ekinox<\/strong>, les hommes de <strong>Fr\u00e9d\u00e9ric Fauthoux<\/strong> savaient ce qu&rsquo;ils avaient \u00e0 faire, face \u00e0 une ASM qui comptait sur le retour de <strong>Jordan Loyd<\/strong>, absent lors du match 2.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Le phare Amida Brimah maintient une JLB sur la corde raide dans le match<\/h2>\n<p align=\"justify\">Pour l&rsquo;occasion, la JLB s&rsquo;est appuy\u00e9e en d\u00e9but de rencontre sur un cinq tr\u00e8s physique. Mais l&rsquo;ASM ne se laisse pas enfoncer et s&rsquo;appuie sur la traction <strong>Mike James<\/strong> &#8211; <strong>Donatas Motiejunas<\/strong> pour alimenter le scoring, tout en ne laissant rien de simple aux locaux. Les Bressans sont en panne totale derri\u00e8re l&rsquo;arc (1\/7 dans le QT1) et comptent exclusivement encore une fois sur l&rsquo;impact d&rsquo;<strong>Amida Brimah<\/strong> \u00e0 l&rsquo;int\u00e9rieur pour ne pas sombrer. Brouillons, ils subissent la domination d&rsquo;une Roca Team appliqu\u00e9e et concentr\u00e9e sur l&rsquo;effort d\u00e9fensif (10-16). Le banc mon\u00e9gasque se met alors au diapason sur les premi\u00e8res rotations, \u00e0 l&rsquo;instar de <strong>Matthew Strazel<\/strong> et <strong>Elie Okobo<\/strong> en chefs d&rsquo;orchestre. <strong>James Floyd<\/strong> lib\u00e8re lui enfin Ekinox \u00e0 trois points en fin de premier quart, mais la JLB est d\u00e9j\u00e0 dans les cordes (17-24).<\/p>\n<p align=\"justify\">Agress\u00e9s au rebond, et en difficult\u00e9 pour d\u00e9rouler leur jeu d&rsquo;attaque, les Bressans souffrent. En dehors de l&rsquo;association Julien-Brimah sur pick and roll, la JLB est en s\u00e9cheresse totale. <strong>Le trio am\u00e9ricain Floyd &#8211; Mike &#8211; Palmer Jr est totalement en faillite<\/strong>. Sans donner l&rsquo;impression de forcer, la Roca Team appuie l\u00e0 o\u00f9 il faut en profitant des secondes chances pour s&rsquo;\u00e9chapper (22-32). Mais la machine s&rsquo;enraye progressivement au fil du deuxi\u00e8me quart. Boost\u00e9e, la JLB en profite pour poursuivre lentement sa remont\u00e9e avec son phare <strong>Amida Brimah<\/strong> (15 points, 4 rebonds) pour la guider, et une belle moisson aux lancers francs (16\/19 \u00e0 la pause). \u00c0 la pause, l&rsquo;ASM garde l&rsquo;avantage gr\u00e2ce \u00e0 sa capacit\u00e9 \u00e0 r\u00e9agir derri\u00e8re l&rsquo;arc lorsque le souffle bressan se fait sentir. <strong>Yoan Makoundou <\/strong>\u00e0 deux reprises et <strong>Jaron Blossomgame<\/strong> maintiennent l&rsquo;ASM devant \u00e0 la pause avec seulement deux unit\u00e9s d&rsquo;avance (41-43).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La sp\u00e9ciale <a href=\"https:\/\/twitter.com\/ElieOkobo_0?ref_src=twsrc%5Etfw\">@ElieOkobo_0<\/a> \ud83d\udc4c<a href=\"https:\/\/twitter.com\/ASMonaco_Basket?ref_src=twsrc%5Etfw\">@ASMonaco_Basket<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/PlayoffsBetclicELITE?src=hash&amp;ref_src=twsrc%5Etfw\">#PlayoffsBetclicELITE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LNBextra?src=hash&amp;ref_src=twsrc%5Etfw\">#LNBextra<\/a> <a href=\"https:\/\/t.co\/BFbnOJm9pA\">pic.twitter.com\/BFbnOJm9pA<\/a><\/p>\n<p>\u2014 LNB (@LNBofficiel) <a href=\"https:\/\/twitter.com\/LNBofficiel\/status\/1664989702250983430?ref_src=twsrc%5Etfw\">June 3, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Motiejunas se gave, la JLB si proche, mais si loin<\/h2>\n<p style=\"text-align: justify;\">Le retour sur le parquet va en revanche \u00eatre difficile pour les locaux. L&rsquo;ASM s&rsquo;est remise les id\u00e9es en place, et passe un 10-2 rapide en gobant un nombre incalculable de rebonds (43-53). Les Bressans retombent eux dans leurs travers offensifs et voient la confiance s&rsquo;envoler. En face, <strong>Donatas Motiejunas<\/strong> (18 points, 7 rebonds) continue \u00e0 r\u00e9aliser un \u00e9norme chantier en disposant d&rsquo;un nombre illimit\u00e9 de ticket shoots qu&rsquo;il met \u00e0 profit pour sanctionner (45-56). Des gros shoots de <strong>Pierre Pelos<\/strong> et <strong>Hugo Benitez<\/strong> vont alors permettre aux Bressans de rester en vie dans le troisi\u00e8me quart alors que James Palmer Jr fait lui banquette. Toujours focus, l&rsquo;ASM vacille en fin de p\u00e9riode, mais conserve ais\u00e9ment deux possessions d&rsquo;avance (60-67).<\/p>\n<p style=\"text-align: justify;\">La <strong>JL Bourg<\/strong> ne l\u00e2che pas prise, mais g\u00e2che de pr\u00e9cieuses minutions pour revenir \u00e0 hauteur des Mon\u00e9gasques. Tr\u00e8s agressifs en d\u00e9fense, ils se mettent rapidement dans la p\u00e9nalit\u00e9, et offrent des premiers lancers \u00e0 sept minutes du buzzer. Comme ce fut le cas \u00e0 Gaston-M\u00e9decin deux jours plus t\u00f4t, les Bressans sont proches, mais tellement loin \u00e0 la fois. Les opportunit\u00e9s laiss\u00e9es en route sont pay\u00e9es au centuple par une ASM toujours aussi froide lorsque l&rsquo;occasion se pr\u00e9sente, \u00e0 l&rsquo;instar de <strong>Jordan Loyd<\/strong>. \u00c0 l&rsquo;arriv\u00e9e dans le money time, le capot fume, et l&rsquo;\u00e9cart reste cons\u00e9quent. <strong>Mike James<\/strong> siffle la fin de la r\u00e9cr\u00e9ation derri\u00e8re l&rsquo;arc pour passer \u00e0 +13 \u00e0 trois minutes du buzzer, mettant d\u00e9finitivement \u00e0 terre des Burgiens coriaces, mais trop justes.<\/p>\n<p style=\"text-align: justify;\">Une nouvelle fois, l&rsquo;AS Monaco a fait la course en t\u00eate dans cette rencontre, sans jamais laisser le soin \u00e0 la JLB de repasser devant. Constamment rel\u00e9gu\u00e9s aux alentours des dix points, les Bressans prennent la porte en subissant un sweep dans la s\u00e9rie (0-3) apr\u00e8s cette d\u00e9faite \u00e0 <strong>Ekinox<\/strong>, 71-85. Mais l&rsquo;important est ailleurs puisque le club a r\u00e9alis\u00e9 <strong>la meilleure saison de son histoire<\/strong> en se hissant pour la premi\u00e8re fois en demi-finale. De son c\u00f4t\u00e9, l&rsquo;ASM attend de pied ferme les Metropolitans ou l&rsquo;ASVEL qu&rsquo;elle retrouvera en finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u26a1\ufe0f <a href=\"https:\/\/twitter.com\/TheNatural_05?ref_src=twsrc%5Etfw\">@TheNatural_05<\/a> trop rapide !<a href=\"https:\/\/twitter.com\/ASMonaco_Basket?ref_src=twsrc%5Etfw\">@ASMonaco_Basket<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/PlayoffsBetclicELITE?src=hash&amp;ref_src=twsrc%5Etfw\">#PlayoffsBetclicELITE<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LNBextra?src=hash&amp;ref_src=twsrc%5Etfw\">#LNBextra<\/a> <a href=\"https:\/\/t.co\/F42dDMY3Qd\">pic.twitter.com\/F42dDMY3Qd<\/a><\/p>\n<p>\u2014 LNB (@LNBofficiel) <a href=\"https:\/\/twitter.com\/LNBofficiel\/status\/1664998333260382208?ref_src=twsrc%5Etfw\">June 3, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PLAYOFFS BETCLIC \u00c9LITE 2022-2023 \u2013 L&rsquo;AS Monaco est la premi\u00e8re \u00e9quipe officiellement qualifi\u00e9e en finale. La Roca Team a d\u00e9croch\u00e9 la victoire (871-85) qui lui manquait \u00e0 Ekinox pour balayer la s\u00e9rie en trois manches s\u00e8ches. Pour la premi\u00e8re demi-finale de son histoire, la JL Bourg n&rsquo;a pas \u00e0 rougir. Les Bressans ont tout donn\u00e9, mais n&rsquo;ont rien pu faire face \u00e0 la force de frappe l\u00e9tale du 3e de la derni\u00e8re EuroLigue.<\/p>\n","protected":false},"author":55,"featured_media":387853,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[46998],"tags":[1691,17909,16878,18658,7809,24114,24],"class_list":["post-387780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-betclic-elite","tag-as-monaco","tag-betclic-elite","tag-breve","tag-donatas-motiejunas","tag-jl-bourg","tag-playoffs-betclic-elite","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Playoffs Betclic \u00c9lite : L&#039;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale<\/title>\n<meta name=\"description\" content=\"PLAYOFFS BETCLIC \u00c9LITE - L&#039;AS Monaco s&#039;est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playoffs Betclic \u00c9lite : L&#039;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\" \/>\n<meta property=\"og:description\" content=\"PLAYOFFS BETCLIC \u00c9LITE - L&#039;AS Monaco s&#039;est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-03T15:09:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-03T15:24:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Playoffs Betclic \u00c9lite : L&#039;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Playoffs Betclic \u00c9lite : L&rsquo;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\",\"datePublished\":\"2023-06-03T15:09:18+00:00\",\"dateModified\":\"2023-06-03T15:24:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/\"},\"wordCount\":913,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png\",\"keywords\":[\"AS Monaco\",\"Betclic Elite\",\"br\u00e8ve\",\"Donatas Motiejunas\",\"jl bourg\",\"Playoffs Betclic \u00c9lite\",\"sport\"],\"articleSection\":[\"Betclic \u00c9lite\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/\",\"name\":\"Playoffs Betclic \u00c9lite : L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png\",\"datePublished\":\"2023-06-03T15:09:18+00:00\",\"dateModified\":\"2023-06-03T15:24:35+00:00\",\"description\":\"PLAYOFFS BETCLIC \u00c9LITE - L'AS Monaco s'est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png\",\"width\":800,\"height\":445,\"caption\":\"Playoffs Betclic \u00c9lite L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playoffs Betclic \u00c9lite : L&rsquo;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Playoffs Betclic \u00c9lite : L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale","description":"PLAYOFFS BETCLIC \u00c9LITE - L'AS Monaco s'est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Playoffs Betclic \u00c9lite : L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale","og_description":"PLAYOFFS BETCLIC \u00c9LITE - L'AS Monaco s'est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.","og_url":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-06-03T15:09:18+00:00","article_modified_time":"2023-06-03T15:24:35+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Playoffs Betclic \u00c9lite : L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Playoffs Betclic \u00c9lite : L&rsquo;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale","datePublished":"2023-06-03T15:09:18+00:00","dateModified":"2023-06-03T15:24:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/"},"wordCount":913,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png","keywords":["AS Monaco","Betclic Elite","br\u00e8ve","Donatas Motiejunas","jl bourg","Playoffs Betclic \u00c9lite","sport"],"articleSection":["Betclic \u00c9lite"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/","url":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/","name":"Playoffs Betclic \u00c9lite : L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png","datePublished":"2023-06-03T15:09:18+00:00","dateModified":"2023-06-03T15:24:35+00:00","description":"PLAYOFFS BETCLIC \u00c9LITE - L'AS Monaco s'est qualifi\u00e9e en finale suite \u00e0 sa victoire \u00e0 Bourg-en-Bresse sans laisser un seul match en route.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Playoffs-Betclic-Elite-LAS-Monaco-balaie-la-JL-Bourg-en-trois-manches-et-se-qualifie-en-finale.png","width":800,"height":445,"caption":"Playoffs Betclic \u00c9lite L'AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-betclic-elite-las-monaco-balaie-la-jl-bourg-en-trois-manches-et-se-qualifie-en-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Playoffs Betclic \u00c9lite : L&rsquo;AS Monaco balaie la JL Bourg en trois manches et se qualifie en finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/387780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=387780"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/387780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/387853"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=387780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=387780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=387780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}