{"id":390623,"date":"2023-06-12T11:50:32","date_gmt":"2023-06-12T09:50:32","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=390623&#038;preview=true&#038;preview_id=390623"},"modified":"2023-06-12T12:00:14","modified_gmt":"2023-06-12T10:00:14","slug":"betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/","title":{"rendered":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&rsquo;EuroLigue"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/?s=betclic+%C3%89lite\">BETCLIC \u00c9LITE<\/a> &#8211; Avant de rejoindre la NBA et les Nuggets, Isma\u00ebl Kamagate franchira un nouveau cap sur la sc\u00e8ne europ\u00e9enne la saison prochaine. Le jeune pivot fran\u00e7ais va en effet quitter Paris pour s&rsquo;engager avec l&rsquo;Olimpia Milan.<\/strong><\/em><\/p>\n<p align=\"justify\"><strong>Isma\u00ebl Kamagate<\/strong> ne d\u00e9couvrira pas encore imm\u00e9diatement la NBA. Si cela avait \u00e9t\u00e9 dans les tuyaux ces derni\u00e8res semaines, le jeune pivot tricolore va poursuivre sa progression en Europe avant d&rsquo;esp\u00e9rer int\u00e9grer l&rsquo;effectif des <strong>Nuggets<\/strong>. Il faut dire que ces derniers sont sur le point de remporter leur premier titre NBA, et n&rsquo;auront pas forc\u00e9ment une place \u00e0 accorder dans leur roster \u00e0 un joueur encore \u00ab\u00a0tendre\u00a0\u00bb.<\/p>\n<p align=\"justify\">Au lieu de \u00e7a, l&rsquo;international tricolore va franchir un nouveau palier suppl\u00e9mentaire. \u00c0 22 ans, il s&rsquo;appr\u00eate \u00e0 quitter son cocon parisien pour rejoindre <strong>Milan<\/strong>, de l&rsquo;autre c\u00f4t\u00e9 des Alpes. Avec <strong>l&rsquo;Olimpia<\/strong>, Kamagate aura l&rsquo;opportunit\u00e9 de disputer l&rsquo;<strong>EuroLigue<\/strong> apr\u00e8s avoir d\u00e9couvert l&rsquo;EuroCoupe cette saison sous le maillot du Paris Basketball, le tout avec une certaine r\u00e9ussite (9,3 points, 8,5 rebonds). En Italie, il rejoint un club historique aux grandes ambitions, sur le point de remporter un nouveau titre national (Ils m\u00e8nent les finales 2-0 face \u00e0 la Virtus Bologne), mais qui poss\u00e8de \u00e9galement l&rsquo;un des meilleurs coachs du continent, en la personne de <strong>Ettore Messina<\/strong>. Toutes les conditions sont r\u00e9unies pour qu&rsquo;il s&rsquo;affirme d\u00e9finitivement au plus haut niveau europ\u00e9en avant de traverser l&rsquo;Atlantique, bourr\u00e9e de certitudes.<\/p>\n<p align=\"justify\">D\u00e9barqu\u00e9 dans la capitale en provenance du P\u00f4le France en 2019, le jeune pivot aura tout connu avec le <strong>Paris BasketBall<\/strong>, disputant deux saisons en Pro B, avant ses deux premi\u00e8res campagnes r\u00e9ussies en Betclic \u00c9lite. Avec <a href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-juhann-begarin-quitte-le-paris-basketball-pour-nanterre\/\">le d\u00e9part de <strong>Juhann Begarin<\/strong><\/a>, une v\u00e9ritable page se tourne dans la jeune histoire du club puisque les deux bonhommes ont \u00e9t\u00e9 les deux pi\u00e8ces majeures du nouveau projet entam\u00e9 \u00e0 la fin de la derni\u00e8re d\u00e9cennie.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">The Denver Nuggets&rsquo; stash Ismael Kamagate is finalizing an agreement with EA7 Emporio Armani Milan, sources confirmed.<\/p>\n<p>\u2014 Donatas Urbonas (@Urbodo) <a href=\"https:\/\/twitter.com\/Urbodo\/status\/1668172700475437057?ref_src=twsrc%5Etfw\">June 12, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>BETCLIC \u00c9LITE &#8211; Avant de rejoindre la NBA et les Nuggets, Isma\u00ebl Kamagate franchira un nouveau cap sur la sc\u00e8ne europ\u00e9enne la saison prochaine. Le jeune pivot fran\u00e7ais va en effet quitter Paris pour s&rsquo;engager avec l&rsquo;Olimpia Milan.<\/p>\n","protected":false},"author":55,"featured_media":390636,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2305],"tags":[16878,181,19801,31971,9895],"class_list":["post-390623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-breve","tag-euroligue","tag-ismael-kamagate","tag-mercato-betclic-elite","tag-milan"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&#039;EuroLigue<\/title>\n<meta name=\"description\" content=\"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l&#039;EuroLigue la saison prochaine avec l&#039;Olimpia Milan.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&#039;EuroLigue\" \/>\n<meta property=\"og:description\" content=\"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l&#039;EuroLigue la saison prochaine avec l&#039;Olimpia Milan.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-12T09:50:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-12T10:00:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&#039;EuroLigue\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&rsquo;EuroLigue\",\"datePublished\":\"2023-06-12T09:50:32+00:00\",\"dateModified\":\"2023-06-12T10:00:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png\",\"keywords\":[\"br\u00e8ve\",\"Euroligue\",\"Isma\u00ebl Kamagate\",\"Mercato Betclic Elite\",\"Milan\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/\",\"name\":\"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png\",\"datePublished\":\"2023-06-12T09:50:32+00:00\",\"dateModified\":\"2023-06-12T10:00:14+00:00\",\"description\":\"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l'EuroLigue la saison prochaine avec l'Olimpia Milan.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png\",\"width\":800,\"height\":445,\"caption\":\"Betclic \u00c9lite Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&rsquo;EuroLigue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue","description":"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l'EuroLigue la saison prochaine avec l'Olimpia Milan.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/","og_locale":"fr_FR","og_type":"article","og_title":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue","og_description":"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l'EuroLigue la saison prochaine avec l'Olimpia Milan.","og_url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-06-12T09:50:32+00:00","article_modified_time":"2023-06-12T10:00:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&rsquo;EuroLigue","datePublished":"2023-06-12T09:50:32+00:00","dateModified":"2023-06-12T10:00:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png","keywords":["br\u00e8ve","Euroligue","Isma\u00ebl Kamagate","Mercato Betclic Elite","Milan"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/","url":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/","name":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png","datePublished":"2023-06-12T09:50:32+00:00","dateModified":"2023-06-12T10:00:14+00:00","description":"BETCLIC \u00c9LITE - Isma\u00ebl Kamagate va poursuivre sa progression en d\u00e9couvrant l'EuroLigue la saison prochaine avec l'Olimpia Milan.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Betclic-Elite-Ismael-Kamagate-va-rejoindre-Milan-et-decouvrir-lEuroLigue.png","width":800,"height":445,"caption":"Betclic \u00c9lite Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l'EuroLigue"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/betclic-elite-ismael-kamagate-va-rejoindre-milan-et-decouvrir-leuroligue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Betclic \u00c9lite : Isma\u00ebl Kamagate va rejoindre Milan et d\u00e9couvrir l&rsquo;EuroLigue"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/390623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=390623"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/390623\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/390636"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=390623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=390623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=390623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}