{"id":394139,"date":"2023-06-24T15:31:04","date_gmt":"2023-06-24T13:31:04","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=394139&#038;preview=true&#038;preview_id=394139"},"modified":"2023-06-24T16:04:35","modified_gmt":"2023-06-24T14:04:35","slug":"motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/","title":{"rendered":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&rsquo;impose"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>MOTOGP PAYS-BAS 2023 &#8211; Parti en pole position, l&rsquo;Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi. Il devance Pecco Bagnaia (Ducati) et Fabio Quartararo (Yamaha), qui profite des trois secondes de p\u00e9nalit\u00e9 inflig\u00e9es \u00e0 Brad Binder (KTM).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><strong>Bezzecchi<\/strong> injouable ce week-end \u00e0 Assen. L&rsquo;Italien, vainqueur des Grands Prix d&rsquo;Argentine et de France, le pilote Mooney VR46 a remport\u00e9 ce samedi la course sprint du <strong>Grand Prix des Pays-Bas<\/strong>. Devant <strong>Pecco Bagnaia<\/strong> (Ducati) et <strong>Fabio Quartararo<\/strong> (Yamaha). Le Fran\u00e7ais, parti 4\u00e8me sur la grille, profite de la p\u00e9nalit\u00e9 de trois secondes inflig\u00e9e \u00e0 <strong>Brad Binder<\/strong> (KTM), coupable d&rsquo;avoir d\u00e9pass\u00e9 trop souvent les limites de la piste, pour grimper sur son deuxi\u00e8me podium de la saison, apr\u00e8s celui d\u00e9croch\u00e9 sur le GP des Am\u00e9riques. En difficult\u00e9, <strong>Johann Zarco<\/strong> (Pramac) termine 13\u00e8me.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\udf99\ufe0f \u00ab\u00a0C&rsquo;\u00e9tait une course tr\u00e8s int\u00e9ressante, mais tr\u00e8s dure.\u00a0\u00bb<\/p>\n<p>Podium inattendu pour Fabio Quartararo apr\u00e8s une course sprint solide \ud83d\udcaa <a href=\"https:\/\/twitter.com\/hashtag\/DutchGP?src=hash&amp;ref_src=twsrc%5Etfw\">#DutchGP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MotoGP?src=hash&amp;ref_src=twsrc%5Etfw\">#MotoGP<\/a> <a href=\"https:\/\/t.co\/4wu6zfivPY\">pic.twitter.com\/4wu6zfivPY<\/a><\/p>\n<p>\u2014 CANAL+ MotoGP\u2122 (@CanalplusMotoGP) <a href=\"https:\/\/twitter.com\/CanalplusMotoGP\/status\/1672603998296178688?ref_src=twsrc%5Etfw\">June 24, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-classement-course-sprint\/\"><strong>Classement de la course sprint du Grand Prix des Pays-Bas<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-grille-de-depart-grand-prix-des-pays-bas-2023\/\"><strong>Grille de d\u00e9part du Grand Prix des Pays-Bas<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-2023-calendrier-et-resultats\/\"><strong>MotoGP 2023 &#8211; Calendrier et r\u00e9sultats<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/motogp-2023-classement-du-championnat-du-monde-des-pilotes\/\"><strong>Le classement du championnat du monde des pilotes<\/strong><\/a><\/li>\n<\/ul>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/salaires-motogp-2023-qui-sont-les-pilotes-les-mieux-payes\/\" class=\"vlp-link\" title=\"Salaires MotoGP 2023 : Qui sont les pilotes les mieux pay\u00e9s ?\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Salaires-MotoGP-2023-Qui-sont-les-pilotes-les-mieux-payes-.png\" class=\"attachment-800x445 size-800x445\" alt=\"Salaires MotoGP 2023 Qui sont les pilotes les mieux pay\u00e9s\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Salaires-MotoGP-2023-Qui-sont-les-pilotes-les-mieux-payes-.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Salaires-MotoGP-2023-Qui-sont-les-pilotes-les-mieux-payes--300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Salaires-MotoGP-2023-Qui-sont-les-pilotes-les-mieux-payes--768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Salaires MotoGP 2023 : Qui sont les pilotes les mieux pay\u00e9s ?<\/div><div class=\"vlp-block-1 vlp-link-summary\">SALAIRES MOTOGP 2023 - Sports Data ID, sur les informations, entre autres, de la Gazzetta dello Sport, a d\u00e9voil\u00e9 les salaires des 22 pilotes MotoGP pour la saison 2023.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>MOTOGP PAYS-BAS 2023 &#8211; Parti en pole position, l&rsquo;Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi. Il devance Pecco Bagnaia (Ducati) et Fabio Quartararo (Yamaha), qui profite des trois secondes de p\u00e9nalit\u00e9 inflig\u00e9es \u00e0 Brad Binder (KTM).<\/p>\n","protected":false},"author":4,"featured_media":394147,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47087],"tags":[16878,17578,17577],"class_list":["post-394139","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-motogp","tag-breve","tag-grand-prix-des-pays-bas","tag-grand-prix-des-pays-bas-motogp"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&#039;impose<\/title>\n<meta name=\"description\" content=\"MOTOGP PAYS-BAS 2023 - Parti en pole position, l&#039;Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&#039;impose\" \/>\n<meta property=\"og:description\" content=\"MOTOGP PAYS-BAS 2023 - Parti en pole position, l&#039;Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-24T13:31:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-24T14:04:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&#039;impose\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&rsquo;impose\",\"datePublished\":\"2023-06-24T13:31:04+00:00\",\"dateModified\":\"2023-06-24T14:04:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\"},\"wordCount\":305,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png\",\"keywords\":[\"br\u00e8ve\",\"Grand Prix des Pays-Bas\",\"Grand Prix des Pays-Bas MotoGP\"],\"articleSection\":[\"MotoGP\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\",\"name\":\"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s'impose\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png\",\"datePublished\":\"2023-06-24T13:31:04+00:00\",\"dateModified\":\"2023-06-24T14:04:35+00:00\",\"description\":\"MOTOGP PAYS-BAS 2023 - Parti en pole position, l'Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png\",\"width\":800,\"height\":445,\"caption\":\"MotoGP Pays-Bas 2023 Podium pour Quartararo sur la course sprint, Bezzecchi s'impose\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&rsquo;impose\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s'impose","description":"MOTOGP PAYS-BAS 2023 - Parti en pole position, l'Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/","og_locale":"fr_FR","og_type":"article","og_title":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s'impose","og_description":"MOTOGP PAYS-BAS 2023 - Parti en pole position, l'Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.","og_url":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-06-24T13:31:04+00:00","article_modified_time":"2023-06-24T14:04:35+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s'impose","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&rsquo;impose","datePublished":"2023-06-24T13:31:04+00:00","dateModified":"2023-06-24T14:04:35+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/"},"wordCount":305,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png","keywords":["br\u00e8ve","Grand Prix des Pays-Bas","Grand Prix des Pays-Bas MotoGP"],"articleSection":["MotoGP"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/","url":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/","name":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s'impose","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png","datePublished":"2023-06-24T13:31:04+00:00","dateModified":"2023-06-24T14:04:35+00:00","description":"MOTOGP PAYS-BAS 2023 - Parti en pole position, l'Italien Marco Bezzecchi (Mooney VR46) a remport\u00e9 la course sprint aux Pays-Bas, ce samedi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/MotoGP-Pays-Bas-2023-Podium-pour-Quartararo-sur-la-course-sprint-Bezzecchi-simpose.png","width":800,"height":445,"caption":"MotoGP Pays-Bas 2023 Podium pour Quartararo sur la course sprint, Bezzecchi s'impose"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/motogp-pays-bas-2023-podium-pour-quartararo-sur-la-course-sprint-bezzecchi-simpose\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"MotoGP Pays-Bas 2023 : Podium pour Quartararo sur la course sprint, Bezzecchi s&rsquo;impose"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/394139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=394139"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/394139\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/394147"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=394139"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=394139"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=394139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}