{"id":395525,"date":"2023-06-30T08:37:44","date_gmt":"2023-06-30T06:37:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=395525&#038;preview=true&#038;preview_id=395525"},"modified":"2023-06-30T10:32:58","modified_gmt":"2023-06-30T08:32:58","slug":"diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/","title":{"rendered":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima"},"content":{"rendered":"<p align=\"justify\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-programme-et-resultats\/\">DIAMOND LEAGUE LAUSANNE 2023<\/a> &#8211; Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne se d\u00e9roulant jeudi 29 et vendredi 30 juin. Ingebrigtsen, Cheptegei, Crouser, Moon, Hodgkinson, Mahuchikh, les listes de d\u00e9part annoncent du grand spectacle sur les bords du lac L\u00e9man.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La Diamond League pose ses valises au bord du lac L\u00e9man en cette fin du mois de juin. L&rsquo;\u00e9lite de l&rsquo;athl\u00e9tisme mondial se donne rendez-vous \u00e0 Lausanne pour deux jours, entre le centre-ville et le Stade de la Pontaise. Jeudi, \u00e0 l&rsquo;heure de l&rsquo;ap\u00e9ritif, les sauteuses en hauteur anticipent le meeting et participeront \u00e0 un concours lors du City Event. La cr\u00e8me de la cr\u00e8me est invit\u00e9e ainsi que la rel\u00e8ve de la discipline.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Jeudi, lors du City Event, <a href=\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-nicola-olyslagers-remporte-le-city-event\/\"><b>Nicola Olyslagers <\/b>s&rsquo;est impos\u00e9e (2,02 m)<\/a>, meilleure marque mondiale de l&rsquo;ann\u00e9e<span style=\"font-weight: 400;\">. Elle a devanc\u00e9 les Ukrainiennes <b>Irina Geraschenko <\/b>et <b>Yaroslava Mahuchikh.<\/b> <\/span><\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-nicola-olyslagers-remporte-le-city-event\/\" class=\"vlp-link\" title=\"Diamond League Lausanne 2023 : Nicola Olyslagers remporte le City Event\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Nicola-Olyslagers-remporte-le-City-Event.png\" class=\"attachment-800x445 size-800x445\" alt=\"Diamond League Lausanne 2023 Nicola Olyslagers remporte le City Event\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Nicola-Olyslagers-remporte-le-City-Event.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Nicola-Olyslagers-remporte-le-City-Event-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Nicola-Olyslagers-remporte-le-City-Event-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Diamond League Lausanne 2023 : Nicola Olyslagers remporte le City Event<\/div><div class=\"vlp-block-1 vlp-link-summary\">DIAMOND LEAGUE LAUSANNE 2023 - Le concours de la hauteur, disput\u00e9 en ville, a sacr\u00e9 Nicola Olyslagers. La vice-championne du monde s'est montr\u00e9e \u00e0 son avantage en battant la meilleure performance mondiale de l'ann\u00e9e (2,02 m).<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Jakob Ingebrigtsen et Keely Hodgkinson en roi et reine du demi-fond<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Il est sans doute la t\u00eate d&rsquo;affiche de ce meeting, tous les yeux seront tourn\u00e9s vers lui, vendredi, \u00e0 21h39. <\/span><b>Jakob Ingebrigtsen <\/b><span style=\"font-weight: 400;\">vient de battre, \u00e0 Oslo, le record d&rsquo;Europe du 1 500m. Le Norv\u00e9gien s&rsquo;aligne de nouveau sur cette distance \u00e0 Lausanne et voudra faire mieux. Il aura notamment le m\u00eame li\u00e8vre fran\u00e7ais &#8211; <\/span><b>Mounir Akbache <\/b><span style=\"font-weight: 400;\">&#8211; qu&rsquo;au Bislett Stadion o\u00f9 la course avait \u00e9t\u00e9 supersonique. 3:27.95 pour le jeune viking, 8 hommes sous les 3:30, trois records continentaux battus. Simplement du jamais vu.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">L&rsquo;un des autres moments forts de cette 6\u1d49 \u00e9tape de la Diamond League 2023 sera en d\u00e9but de programme. Juste apr\u00e8s 20 heures, <\/span><b>Keely Hodgkinson <\/b><span style=\"font-weight: 400;\">va courir son second 800m de la saison. Sa rentr\u00e9e sur le tartan du stade Charl\u00e9ty \u00e9tait d&rsquo;un tr\u00e8s haut niveau. 1:55.97, c&rsquo;est finalement \u00e0 moins de trois secondes du meilleur chrono all-time de <\/span><b>Kratochvilova<\/b><span style=\"font-weight: 400;\"> (1:53.28). Dans ce double tour de piste, la Britannique sera en confrontation avec sa compatriote <\/span><b>Jemma Reekie <\/b><span style=\"font-weight: 400;\">mais aussi <\/span><b>Mary Moraa<\/b><span style=\"font-weight: 400;\"> et <\/span><b>Natoya Goule<\/b><span style=\"font-weight: 400;\">. Aucune tricolore ne fait le d\u00e9placement.<\/span><\/p>\n<h2 style=\"text-align: justify;\">Une liste de d\u00e9part excitante sur les haies<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La liste de d\u00e9part du 100m haies est assez extraordinaire. Les deux femmes les plus rapides du monde sur la distance, <\/span><b>Tobi Amusan <\/b><span style=\"font-weight: 400;\">et <\/span><b>Jasmine Camacho-Quinn<\/b><span style=\"font-weight: 400;\">, se feront face, quelques jours apr\u00e8s leur affrontement \u00e0 Ostrava qui a tourn\u00e9 \u00e0 l\u2019avantage de la Portoricaine. Les Am\u00e9ricaines <\/span><b>Ali, Jones <\/b><span style=\"font-weight: 400;\">et <\/span><b>Johnson<\/b> <span style=\"font-weight: 400;\">arbitreront ce duel avec les meilleures europ\u00e9ennes du moment : <\/span><b>Nadine Visser, Pia Skrzyszowska <\/b><span style=\"font-weight: 400;\">et la locale <\/span><b>Ditaji Kambundji<\/b><span style=\"font-weight: 400;\">, petite s\u0153ur de <\/span><b>Mujinga<\/b><span style=\"font-weight: 400;\">. Bien malin celui qui aura le bon pronostic sur cette course.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Plus t\u00f4t dans la soir\u00e9e, les hommes auront aussi le droit de courir une ligne droite et de passer des haies. Un plateau \u00e0 l\u2019accent europ\u00e9en avec notamment le local <\/span><b>Jason Joseph<\/b><span style=\"font-weight: 400;\">, champion d\u2019Europe du 60m haies en salle cet hiver. Il sera oppos\u00e9 aux deux Fran\u00e7ais en forme du moment : <\/span><b>Wilhem Belocian <\/b><span style=\"font-weight: 400;\">et <\/span><b>Just Kwaou-Mathey<\/b><span style=\"font-weight: 400;\">. Ce dernier n\u2019est autre que le meilleur performeur europ\u00e9en de l\u2019ann\u00e9e avec ses 13.09 r\u00e9alis\u00e9s \u00e0 Paris. Il faudra se m\u00e9fier d\u2019<\/span><b>Enrique Llopis <\/b><span style=\"font-weight: 400;\">(22 ans), r\u00e9cent 3\u1d49 des Jeux Europ\u00e9ens derri\u00e8re le duo de l\u2019\u00c9quipe de France. Meilleur temps des engag\u00e9s, le Japonais <\/span><b>Shunsuke Izumiya <\/b><span style=\"font-weight: 400;\">s\u2019est montr\u00e9 r\u00e9gulier lors de comp\u00e9titions en Asie. Une confirmation sur le Vieux Continent serait la bienvenue, \u00e0 l\u2019approche des championnats du monde en Hongrie.<\/span><\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/athletisme-mondiaux-2023-les-francais-qui-ont-realise-les-minima\/\" class=\"vlp-link\" title=\"Athl\u00e9tisme Mondiaux 2023 - Les Fran\u00e7ais qui ont r\u00e9alis\u00e9 les minima\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Athletisme-Les-Francais-qui-ont-realise-les-minima-pour-les-championnats-du-monde-2023.png\" class=\"attachment-800x445 size-800x445\" alt=\"Athl\u00e9tisme - Les Fran\u00e7ais qui ont r\u00e9alis\u00e9 les minima pour les championnats du monde 2023\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Athletisme-Les-Francais-qui-ont-realise-les-minima-pour-les-championnats-du-monde-2023.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Athletisme-Les-Francais-qui-ont-realise-les-minima-pour-les-championnats-du-monde-2023-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Athletisme-Les-Francais-qui-ont-realise-les-minima-pour-les-championnats-du-monde-2023-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Athl\u00e9tisme Mondiaux 2023 - Les Fran\u00e7ais qui ont r\u00e9alis\u00e9 les minima<\/div><div class=\"vlp-block-1 vlp-link-summary\">CHAMPIONNATS DU MONDE ATHL\u00c9TISME 2023 - D\u00e9couvrez la liste des Fran\u00e7ais qui ont fait les minima pour Budapest. Une liste mise \u00e0 jour jusqu'\u00e0 la s\u00e9lection finale tricolore.<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Match Ouganda &#8211; Ethiopie sur le 5 000 m\u00e8tres<\/h2>\n<p style=\"text-align: justify;\"><b>Femke Bol <\/b><span style=\"font-weight: 400;\">continue d&rsquo;engranger des kilom\u00e8tres en se pr\u00e9sentant dans le canton de Vaud. La N\u00e9erlandaise ne devrait pas \u00eatre challeng\u00e9e, aucune de ses adversaires n&rsquo;a couru en dessous des 54 secondes cette saison. En 2023, <\/span><b>Bol<\/b><span style=\"font-weight: 400;\"> s&rsquo;est approch\u00e9e de son record avec un temps de 52.30 et sera donc, une nouvelle fois, la seule et unique favorite. Le 200m hommes s&rsquo;annonce ouvert. <\/span><b>Letsile Tebogo <\/b><span style=\"font-weight: 400;\">poss\u00e8de le meilleur chrono des engag\u00e9s avec 19.87. Sa victoire en Suisse n&rsquo;est pas d&rsquo;une totale \u00e9vidence. <\/span><b>Andr\u00e9 de Grasse <\/b><span style=\"font-weight: 400;\">et <\/span><b>Aaron Brown <\/b><span style=\"font-weight: 400;\">sont pr\u00e9sents, tout comme <\/span><b>Joseph Fahnbulleh <\/b><span style=\"font-weight: 400;\">et le Cubain <\/span><b>Reynier Mena<\/b><span style=\"font-weight: 400;\">, seul autre sprinteur sous les 20 secondes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les \u00c9thiopiens seront en grand nombre sur le 5 000m mais deux Ougandais voleront peut-\u00eatre la vedette. Tous les deux m\u00e9daill\u00e9s \u00e0 la fin du 10 000m des derniers Mondiaux \u00e0 Eugene, <\/span><b>Joshua Cheptegei <\/b><span style=\"font-weight: 400;\">et <\/span><b>Jacob Kiplimo <\/b><span style=\"font-weight: 400;\">seront un s\u00e9rieux danger pour la meute des hauts plateaux men\u00e9e par <\/span><b>Selemon Barega <\/b><span style=\"font-weight: 400;\">et <\/span><b>Haile Bekele<\/b><span style=\"font-weight: 400;\">. Soyez pr\u00eats, le dernier tour est attendu \u00e0 21h02.<\/span><\/p>\n<h2 style=\"text-align: justify;\">Des concours de haute vol\u00e9e en Suisse<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Concernant les autres concours de la soir\u00e9e, le saut en longueur verra le prodige italien <\/span><b>Mattia Furlani<\/b><span style=\"font-weight: 400;\"> affronter <\/span><b>Simon Ehammer<\/b>,<b> Thobias Montler <\/b><span style=\"font-weight: 400;\">et <\/span><b>Miltiadis Tentoglou<\/b>. <span style=\"font-weight: 400;\">La sensation du d\u00e9but de saison estival <\/span><b>Murali Sreeshankar <\/b><span style=\"font-weight: 400;\">sera aussi de la partie. Il y a 10 jours, l&rsquo;Indien s&rsquo;est empar\u00e9 de la meilleure performance mondiale de l&rsquo;ann\u00e9e avec 8,41 m. Au lancer du poids, Lausanne accueille le recordman du monde. <\/span><b>Ryan Crouser<\/b><span style=\"font-weight: 400;\"> a am\u00e9lior\u00e9 celui-ci cette ann\u00e9e en lan\u00e7ant \u00e0 23,56 m. L&rsquo;Am\u00e9ricain a r\u00e9volutionn\u00e9 son sport et se retrouve face \u00e0 ses deux adversaires de toujours, <\/span><b>Joe Kovacs<\/b><span style=\"font-weight: 400;\"> et <\/span><b>Tom Walsh<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La perche f\u00e9minine s&rsquo;annonce \u00e9lectrique. Nord-am\u00e9ricaines, Europ\u00e9ennes, repr\u00e9sentantes de l&rsquo;h\u00e9misph\u00e8re sud, elles seront toutes l\u00e0. Si <\/span><b>Katie Moon<\/b><span style=\"font-weight: 400;\"> est toujours impressionnante, sortie apr\u00e8s sortie, la native de l&rsquo;Ohio aura fort \u00e0 faire face \u00e0 <\/span><b>Nina Kennedy<\/b><span style=\"font-weight: 400;\">, <\/span><b>Wilma Murto <\/b><span style=\"font-weight: 400;\">ou encore <\/span><b>Tina Sutej<\/b><span style=\"font-weight: 400;\">. La Ni\u00e7oise <\/span><b>Margot Chevrier <\/b><span style=\"font-weight: 400;\">participera aussi \u00e0 ce concours, elle qui a \u00e9lev\u00e9 son record \u00e0 4,71 m cette saison. Notons le retour de la N\u00e9o-Z\u00e9landaise <\/span><b>Eliza McCartney<\/b><span style=\"font-weight: 400;\">. Elle n&rsquo;a plus particip\u00e9 \u00e0 une \u00e9tape de la ligue mondiale depuis Z\u00fcrich en 2019. Apr\u00e8s deux saisons blanches, la vice-championne olympique de Rio a pass\u00e9 4,75 m en 2023, soit 19 centim\u00e8tres en dessous de sa meilleure barre en carri\u00e8re.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIAMOND LEAGUE LAUSANNE 2023 &#8211; Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne se d\u00e9roulant jeudi 29 et vendredi 30 juin. Ingebrigtsen, Cheptegei, Crouser, Moon, Hodgkinson, Mahuchikh, les listes de d\u00e9part annoncent du grand spectacle sur les bords du lac L\u00e9man.<\/p>\n","protected":false},"author":61,"featured_media":395759,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308],"tags":[143,16878],"class_list":["post-395525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-athletisme","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima<\/title>\n<meta name=\"description\" content=\"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima\" \/>\n<meta property=\"og:description\" content=\"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-06-30T06:37:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-30T08:32:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima\",\"datePublished\":\"2023-06-30T06:37:44+00:00\",\"dateModified\":\"2023-06-30T08:32:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\"},\"wordCount\":1193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png\",\"keywords\":[\"Athl\u00e9tisme\",\"br\u00e8ve\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\",\"name\":\"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png\",\"datePublished\":\"2023-06-30T06:37:44+00:00\",\"dateModified\":\"2023-06-30T08:32:58+00:00\",\"description\":\"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png\",\"width\":800,\"height\":445,\"caption\":\"Diamond League Lausanne 2023 Un plateau hors-norme pour Athletissima\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima","description":"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/","og_locale":"fr_FR","og_type":"article","og_title":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima","og_description":"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.","og_url":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-06-30T06:37:44+00:00","article_modified_time":"2023-06-30T08:32:58+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima","datePublished":"2023-06-30T06:37:44+00:00","dateModified":"2023-06-30T08:32:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/"},"wordCount":1193,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png","keywords":["Athl\u00e9tisme","br\u00e8ve"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/","url":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/","name":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png","datePublished":"2023-06-30T06:37:44+00:00","dateModified":"2023-06-30T08:32:58+00:00","description":"DIAMOND LEAGUE LAUSANNE 2023 - Dicodusport vous propose une pr\u00e9sentation du meeting Diamond League de Lausanne.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/06\/Diamond-League-Lausanne-2023-Un-plateau-hors-norme-pour-Athletissima.png","width":800,"height":445,"caption":"Diamond League Lausanne 2023 Un plateau hors-norme pour Athletissima"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/diamond-league-lausanne-2023-un-plateau-hors-norme-pour-athletissima\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Diamond League Lausanne 2023 : Un plateau hors norme pour Athletissima"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/395525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=395525"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/395525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/395759"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=395525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=395525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=395525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}