{"id":396597,"date":"2023-07-02T10:19:52","date_gmt":"2023-07-02T08:19:52","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=396597&#038;preview=true&#038;preview_id=396597"},"modified":"2023-07-02T15:50:52","modified_gmt":"2023-07-02T13:50:52","slug":"video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/","title":{"rendered":"[Vid\u00e9o] Le but exceptionnel d&rsquo;Anthony Baron avec la Guadeloupe"},"content":{"rendered":"<p align=\"justify\"><em><b><a href=\"https:\/\/dicodusport.fr\/definition-sport\/football\/\" target=\"_blank\" rel=\"noopener\">FOOTBALL<\/a> &#8211; Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit de samedi \u00e0 dimanche.\u00a0<\/b><\/em><\/p>\n<p align=\"justify\">Il y a des buts qui marquent une carri\u00e8re et celui d&rsquo;<strong>Anthony Baron<\/strong> la nuit derni\u00e8re en fait partie. Lors de la <a href=\"https:\/\/dicodusport.fr\/blog\/football-gold-cup-la-guadeloupe-etrille-cuba\/\" target=\"_blank\" rel=\"noopener\">large victoire de la Guadeloupe face \u00e0 Cuba<\/a>, le d\u00e9fenseur a marqu\u00e9 un but exceptionnel apr\u00e8s une roulette dans la surface de r\u00e9paration adverse. R\u00e9ussir le geste pr\u00e9f\u00e9r\u00e9 de <strong>Zin\u00e9dine<\/strong> <strong>Zidane<\/strong> est une chose, mais le faire dans les 16 m\u00e8tres 50 adverses en est une autre.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le \ud835\uddef\ud835\ude02\ud835\ude01 \ud835\uddfa\ud835\uddee\ud835\uddf4\ud835\uddfb\ud835\uddf6\ud835\uddf3\ud835\uddf6\ud835\uddfe\ud835\ude02\ud835\uddf2 marqu\u00e9 cette nuit par Anthony Baron avec la Guadeloupe contre Cuba ! \ud83d\ude31\ud83c\udde7\ud83c\uddf7<\/p>\n<p>Les Gwada Boyz l\u2019ont emport\u00e9 4-1 et sont \ud835\udde3\ud835\udde5\ud835\uddd8\ud835\udde0\ud835\udddc\ud835\uddd8\ud835\udde5\ud835\udde6 \ud835\uddd7\ud835\uddd8 \ud835\udddf\ud835\uddd8\ud835\udde8\ud835\udde5 \ud835\uddda\ud835\udde5\ud835\udde2\ud835\udde8\ud835\udde3\ud835\uddd8 de qualif \u00e0 la Gold Cup ! \ud83d\udd25\ud83d\udd25<\/p>\n<p>Le classement lors de la deuxi\u00e8me journ\u00e9e :<\/p>\n<p>1-\u2026 <a href=\"https:\/\/t.co\/ZGjEDJoPgV\">pic.twitter.com\/ZGjEDJoPgV<\/a><\/p>\n<p>\u2014 Instant Foot \u26bd\ufe0f (@lnstantFoot) <a href=\"https:\/\/twitter.com\/lnstantFoot\/status\/1675354837704384512?ref_src=twsrc%5Etfw\">July 2, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOOTBALL &#8211; Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":396600,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[16878,75,11885,1102,4605],"class_list":["post-396597","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-football","tag-gold-cup","tag-guadeloupe","tag-video"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Vid\u00e9o] Le but exceptionnel d&#039;Anthony Baron avec la Guadeloupe<\/title>\n<meta name=\"description\" content=\"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] Le but exceptionnel d&#039;Anthony Baron avec la Guadeloupe\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-02T08:19:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-02T13:50:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] Le but exceptionnel d&#039;Anthony Baron avec la Guadeloupe\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"[Vid\u00e9o] Le but exceptionnel d&rsquo;Anthony Baron avec la Guadeloupe\",\"datePublished\":\"2023-07-02T08:19:52+00:00\",\"dateModified\":\"2023-07-02T13:50:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\"},\"wordCount\":152,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Gold Cup\",\"guadeloupe\",\"vid\u00e9o\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\",\"name\":\"[Vid\u00e9o] Le but exceptionnel d'Anthony Baron avec la Guadeloupe\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png\",\"datePublished\":\"2023-07-02T08:19:52+00:00\",\"dateModified\":\"2023-07-02T13:50:52+00:00\",\"description\":\"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] Le but exceptionnel d&rsquo;Anthony Baron avec la Guadeloupe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] Le but exceptionnel d'Anthony Baron avec la Guadeloupe","description":"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] Le but exceptionnel d'Anthony Baron avec la Guadeloupe","og_description":"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-07-02T08:19:52+00:00","article_modified_time":"2023-07-02T13:50:52+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] Le but exceptionnel d'Anthony Baron avec la Guadeloupe","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"[Vid\u00e9o] Le but exceptionnel d&rsquo;Anthony Baron avec la Guadeloupe","datePublished":"2023-07-02T08:19:52+00:00","dateModified":"2023-07-02T13:50:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/"},"wordCount":152,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png","keywords":["br\u00e8ve","Football","Gold Cup","guadeloupe","vid\u00e9o"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/","url":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/","name":"[Vid\u00e9o] Le but exceptionnel d'Anthony Baron avec la Guadeloupe","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png","datePublished":"2023-07-02T08:19:52+00:00","dateModified":"2023-07-02T13:50:52+00:00","description":"FOOTBALL - Anthony Baron a marqu\u00e9 un but exceptionnel avec la Guadeloupe face \u00e0 Cuba dans la nuit samedi \u00e0 dimanche.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Video-Le-but-exceptionnel-dAnthony-Baron-avec-la-Guadeloupe.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/video-le-but-exceptionnel-danthony-baron-avec-la-guadeloupe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] Le but exceptionnel d&rsquo;Anthony Baron avec la Guadeloupe"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/396597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=396597"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/396597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/396600"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=396597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=396597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=396597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}