{"id":397673,"date":"2023-07-08T08:15:21","date_gmt":"2023-07-08T06:15:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=397673&#038;preview=true&#038;preview_id=397673"},"modified":"2023-07-08T23:56:27","modified_gmt":"2023-07-08T21:56:27","slug":"wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/","title":{"rendered":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>WNBA 2023 &#8211; Le contingent fran\u00e7ais en WNBA va s&rsquo;agrandir dans les prochains jours. Gabby Williams et Iliana Rupert viennent de rejoindre leur \u00e9quipe (respectivement le Seattle Storm et l&rsquo;Atlanta Dream) et sont sur le point de disputer leurs premi\u00e8res minutes cette saison. \u00c0 cause d&rsquo;un calendrier trop charg\u00e9, elles ne vont donc disputer que la deuxi\u00e8me moiti\u00e9 de saison.<br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Les annonces ont eu lieu \u00e0 un jour d&rsquo;\u00e9cart. Ce lundi 3 juillet, le Seattle Storm communiquait <strong>le retour de la Fran\u00e7aise Gabby Williams<\/strong>, apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/wnba-gabby-williams-piece-majeure-du-seattle-storm\/\">une saison 2022 fructueuse individuellement et collectivement<\/a>. Le lendemain, Atlanta annon\u00e7ait qu&rsquo;<strong>Iliana Rupert rejoignait officiellement le groupe du Dream<\/strong> pour la saison. Ce alors que les \u00e9quipes ont d\u00e9j\u00e0 disput\u00e9 quasiment la moiti\u00e9 de la saison (16 matchs sur 40 pour Atlanta, 5\u00e8me au classement, 17 matchs sur 40 pour Seattle, 11\u00e8me).<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Calendrier charg\u00e9<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\">Pour l&rsquo;une comme pour l&rsquo;autre, plusieurs jours d&rsquo;acclimatation ont \u00e9t\u00e9 n\u00e9cessaires. <strong>Rupert<\/strong> et <strong>Williams<\/strong> ont d&rsquo;abord d\u00fb signer leurs contrats, passer les tests m\u00e9dicaux, et participer \u00e0 plusieurs entra\u00eenements avec leurs co\u00e9quipi\u00e8res. Toute une mise en route n\u00e9cessaire avant de disputer leurs premi\u00e8res minutes de la saison. <strong>Elles devraient toutes les deux jouer leur premier match en d\u00e9but de semaine prochaine<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Et, si les deux Tricolores sont arriv\u00e9es un mois et demi apr\u00e8s le d\u00e9but officiel de la saison, c&rsquo;est qu&rsquo;<strong>elles ont subi un calendrier particuli\u00e8rement serr\u00e9<\/strong>. Apr\u00e8s avoir termin\u00e9 sa saison avec la Virtus Bologne d\u00e9but mai, <strong>Rupert<\/strong> a rejoint l&rsquo;\u00c9quipe de France. De fin mai \u00e0 fin juin, elle a pris part \u00e0 l&rsquo;EuroBasket et \u00e0 ses semaines de pr\u00e9paration. Moins de deux semaines apr\u00e8s<a href=\"https:\/\/dicodusport.fr\/blog\/eurobasket-feminin-les-bleues-terminent-a-la-troisieme-place\/\"> la fin de la comp\u00e9tition<\/a>, la voil\u00e0 d\u00e9j\u00e0 en WNBA.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Williams a, elle, connu une situation un peu diff\u00e9rente. La Franco-Am\u00e9ricaine de 26 ans a subi<strong> une commotion c\u00e9r\u00e9brale<\/strong> pendant les demi-finales LFB avec l&rsquo;ASVEL d\u00e9but mai. Les m\u00e9decins l&rsquo;ont forc\u00e9e \u00e0 rester \u00e9loign\u00e9e des parquets pendant trois semaines, l&#8217;emp\u00eachant donc de participer \u00e0 l&rsquo;EuroBasket. <strong>Une fois r\u00e9tablie et apr\u00e8s avoir <a href=\"https:\/\/twitter.com\/Tom_Cprt\/status\/1674823440644153345\">r\u00e9gl\u00e9 des soucis contractuels<\/a>, elle a enfin pu rejoindre Seattle.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">3 semaines d&rsquo;arr\u00eat pour Gabby Williams pour commotion et r\u00e9\u00e9ducation c\u00e9r\u00e9brale donc convalescence et pas d&rsquo; euro basket pour elle avec l&rsquo;\u00e9quipe de France \ud83d\ude22<a href=\"https:\/\/twitter.com\/hashtag\/EDFBasket?src=hash&amp;ref_src=twsrc%5Etfw\">#EDFBasket<\/a><a href=\"https:\/\/twitter.com\/hashtag\/EuroBasketWomen?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroBasketWomen<\/a> <a href=\"https:\/\/t.co\/DKzQzcqQXC\">https:\/\/t.co\/DKzQzcqQXC<\/a> <a href=\"https:\/\/t.co\/PIokqnKDme\">pic.twitter.com\/PIokqnKDme<\/a><\/p>\n<p>\u2014 jean-Fran\u00e7ois.T \ud83d\udc0d\ud83c\udfc0 (@mynameiskb24) <a href=\"https:\/\/twitter.com\/mynameiskb24\/status\/1661111691906523166?ref_src=twsrc%5Etfw\">May 23, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Les troisi\u00e8me et quatri\u00e8me Fran\u00e7aises \u00e0 fouler les parquets<\/h2>\n<p style=\"text-align: justify;\">\u00c0 l&rsquo;heure actuelle, seulement deux tricolores ont du temps de jeu en NBA. D&rsquo;une part, <strong>Marine Johann\u00e8s,<\/strong> qui est remarquablement productive avec le <strong>New York Liberty<\/strong>. Au sein d&rsquo;un effectif taill\u00e9 pour le titre, la Normande parvient \u00e0 se faire une place en tant que 6\u00e8me femme. Elle joue 20 minutes par match, pour des moyennes de <strong>8.5 points, 1.4 rebond, 2.0 passes et 0.9 interception \u00e0 44% au tir et 38% \u00e0 trois points<\/strong>. Plusieurs de ses passes g\u00e9niales et paniers acrobatiques ont d\u00e9j\u00e0 fait le tour des r\u00e9seaux sociaux. <a href=\"https:\/\/twitter.com\/MylesEhrlich\/status\/1667351274784714753\">Sa coach Sandy Brandello a expliqu\u00e9<\/a> \u00e0 quel point c&rsquo;\u00e9tait <em>\u00ab un luxe d&rsquo;avoir une joueuse de ce calibre en sortie de banc. \u00bb<\/em><\/p>\n<p style=\"text-align: justify;\">D&rsquo;autre part,<strong> Kadi Cissoko<\/strong>, qui est une rookie draft\u00e9e en avril dernier \u00e0 la 29\u00e8me position par le <strong>Phoenix Mercury<\/strong>. D\u00e9j\u00e0 pr\u00eate physiquement apr\u00e8s quatre ann\u00e9es d&rsquo;universit\u00e9 aux \u00c9tats-Unis, l&rsquo;int\u00e9rieure tricolore de 24 ans a d\u00e9j\u00e0 jou\u00e9 16 matchs avec la franchise de l&rsquo;Arizona. Son r\u00f4le est principalement d&rsquo;apporter en sortie de banc sa pr\u00e9sence et sa taille dans la raquette. C&rsquo;est pourquoi elle ne compile que <strong>1.1 point et 1.2 rebond de moyenne en 7 minutes de jeu.<\/strong><\/p>\n<p style=\"text-align: justify;\">A contrario, <strong>Lou Lopez S\u00e9n\u00e9chal<\/strong>, la deuxi\u00e8me plus haute draft\u00e9e fran\u00e7aise de l&rsquo;histoire (5\u00e8me position), <strong>n&rsquo;a toujours pas jou\u00e9 cette saison<\/strong>. La rookie est bless\u00e9e au genou depuis la fin de saison derni\u00e8re. Elle devra attendre la deuxi\u00e8me partie de saison pour disputer ses premi\u00e8res minutes avec Dallas. La 12\u00e8me de la Draft <strong>Ma\u00efa Hirsch,<\/strong> qui s&rsquo;est fait op\u00e9rer du pied le mois dernier, <strong>ne va pas jouer en WNBA cette saison<\/strong>. Le plan des Minnesota Lynx qui l&rsquo;ont draft\u00e9e est de l&rsquo;accueillir dans leur effectif en 2024.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Working on the next Elite is Elite release and clipped a ton of Marine Johannes jumpers, because man <a href=\"https:\/\/t.co\/PZS3ckdqLa\">pic.twitter.com\/PZS3ckdqLa<\/a><\/p>\n<p>\u2014 Mark Schindler (@MG_Schindler) <a href=\"https:\/\/twitter.com\/MG_Schindler\/status\/1674128282688667648?ref_src=twsrc%5Etfw\">June 28, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>WNBA 2023 &#8211; Le contingent fran\u00e7ais en WNBA va s&rsquo;agrandir dans les prochains jours. Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes (respectivement le Seattle Storm et l&rsquo;Atlanta Dream) et sont sur le point de disputer leurs premi\u00e8res minutes cette saison. \u00c0 cause d&rsquo;un calendrier trop charg\u00e9, elles ne vont donc disputer que la deuxi\u00e8me moiti\u00e9 de saison.<\/p>\n","protected":false},"author":13,"featured_media":398227,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[16878,22868,22831,2605,8306],"class_list":["post-397673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-breve","tag-gabby-williams","tag-iliana-rupert","tag-marine-johannes","tag-wnba"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison<\/title>\n<meta name=\"description\" content=\"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison\" \/>\n<meta property=\"og:description\" content=\"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-08T06:15:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-08T21:56:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tom Compayrot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Tom_Cprt\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\"},\"author\":{\"name\":\"Tom Compayrot\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7\"},\"headline\":\"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison\",\"datePublished\":\"2023-07-08T06:15:21+00:00\",\"dateModified\":\"2023-07-08T21:56:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\"},\"wordCount\":774,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png\",\"keywords\":[\"br\u00e8ve\",\"Gabby Williams\",\"Iliana Rupert\",\"Marine Johann\u00e8s\",\"WNBA\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\",\"name\":\"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png\",\"datePublished\":\"2023-07-08T06:15:21+00:00\",\"dateModified\":\"2023-07-08T21:56:27+00:00\",\"description\":\"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7\",\"name\":\"Tom Compayrot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg\",\"caption\":\"Tom Compayrot\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Tom_Cprt\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/tom\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison","description":"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/","og_locale":"fr_FR","og_type":"article","og_title":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison","og_description":"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.","og_url":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-07-08T06:15:21+00:00","article_modified_time":"2023-07-08T21:56:27+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png","type":"image\/png"}],"author":"Tom Compayrot","twitter_card":"summary_large_image","twitter_title":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison","twitter_creator":"@https:\/\/twitter.com\/Tom_Cprt","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/"},"author":{"name":"Tom Compayrot","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7"},"headline":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison","datePublished":"2023-07-08T06:15:21+00:00","dateModified":"2023-07-08T21:56:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/"},"wordCount":774,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png","keywords":["br\u00e8ve","Gabby Williams","Iliana Rupert","Marine Johann\u00e8s","WNBA"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/","url":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/","name":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png","datePublished":"2023-07-08T06:15:21+00:00","dateModified":"2023-07-08T21:56:27+00:00","description":"Gabby Williams et Iliana Rupert viennent de rejoindre leurs \u00e9quipes WNBA (Seattle et Atlanta) et vont donc enfin pouvoir d\u00e9buter leur saison.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/wnba-iliana-rupert-et-gabby-williams-sur-le-point-de-debuter-leur-saison\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"WNBA : Iliana Rupert et Gabby Williams sur le point de d\u00e9buter leur saison"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7","name":"Tom Compayrot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","caption":"Tom Compayrot"},"description":"Journaliste\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Tom_Cprt"],"url":"https:\/\/dicodusport.fr\/blog\/author\/tom\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/397673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=397673"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/397673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/398227"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=397673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=397673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=397673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}