{"id":399201,"date":"2023-07-11T19:50:14","date_gmt":"2023-07-11T17:50:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=399201&#038;preview=true&#038;preview_id=399201"},"modified":"2023-07-11T19:50:14","modified_gmt":"2023-07-11T17:50:14","slug":"transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/","title":{"rendered":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><b>TRANSFERTS RUGBY &#8211; Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan accueille un talonneur du Stade Rochelais : les infos transferts de ce mardi 11 juillet 2023.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Toulouse : Nepo Laulala officialis\u00e9<\/h2>\n<p align=\"justify\">C&rsquo;est fait. <strong>Nepo Laulala<\/strong> sera un joueur du <strong>Stade Toulousain<\/strong> la saison prochaine. Le pilier droit n\u00e9o-z\u00e9landais (32 ans, 45 s\u00e9lections avec les All Blacks), a sign\u00e9 un contrat de trois saisons en Haute-Garonne, soit jusqu&rsquo;en 2026. Num\u00e9riquement, l&rsquo;ancien joueur des Blues remplacera son compatriote <strong>Charlie Faumuina<\/strong>, 36 ans, fra\u00eechement retrait\u00e9 des terrains. Ce dernier, 50 s\u00e9lections avec la <strong>Nouvelle-Z\u00e9lande<\/strong>, \u00e9tait arriv\u00e9 dans la ville rose en 2017, ann\u00e9e de sa retraite internationale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u2115\ud835\udd56\ud835\udd61\ud835\udd60 \ud835\udd43\ud835\udd52\ud835\udd66\ud835\udd5d\ud835\udd52\ud835\udd5d\ud835\udd52, nouveau Stadiste \ud83d\udd25<\/p>\n<p>L&rsquo;ancien joueur des Blues d&rsquo;Auckland s&rsquo;engage \u00e0 nos c\u00f4t\u00e9s jusqu&rsquo;en 2026 \ud83e\udd1d<\/p>\n<p>Axe 2\ufe0f\u20e3 : \ud835\udc11\ud835\udc1e\ud835\udc27\ud835\udc1f\ud835\udc28\ud835\udc2b\ud835\udc1c\ud835\udc1e\ud835\udc2b \ud835\udc2c\ud835\udc28\ud835\udc27 \ud835\udc1e\ud835\udc1f\ud835\udc1f\ud835\udc1e\ud835\udc1c\ud835\udc2d\ud835\udc22\ud835\udc1f <a href=\"https:\/\/twitter.com\/hashtag\/Trajectoire2027?src=hash&amp;ref_src=twsrc%5Etfw\">#Trajectoire2027<\/a> \ud83d\udd34\u26ab <a href=\"https:\/\/t.co\/FT75jsfDJB\">pic.twitter.com\/FT75jsfDJB<\/a><\/p>\n<p>\u2014 Stade Toulousain (@StadeToulousain) <a href=\"https:\/\/twitter.com\/StadeToulousain\/status\/1678793958711779328?ref_src=twsrc%5Etfw\">July 11, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Oyonnax : Premier contrat pro pour L\u00e9o Treilles<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Oyonnax<\/strong> poursuit la consolidation de son effectif pour son retour en Top 14. Les <em>Oyomen<\/em> ont annonc\u00e9 ce mardi que <strong>L\u00e9o Treilles<\/strong> (23 ans), avait sign\u00e9 son premier contrat professionnel au sein du club de l&rsquo;Ain. Le trois-quarts centre, \u00e9galement capable d&rsquo;\u00e9voluer \u00e0 l&rsquo;ouverture, a sign\u00e9 un contrat de deux saisons avec le promu. Le joueur qui a fait ses classes \u00e0 Clermont est arriv\u00e9 \u00e0 <strong>Oyonnax<\/strong> en 2021, dans les rangs espoirs du club. La saison pass\u00e9e, il s&rsquo;est illustr\u00e9e avec l&rsquo;\u00e9quipe premi\u00e8re en <strong>Pro D2<\/strong>, avec neuf matchs disput\u00e9s pour quatre titularisations.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u270d\ufe0f \ud835\udde3\ud835\udde5\ud835\udde2\ud835\udddf\ud835\udde2\ud835\udde1\ud835\uddda\ud835\uddd4\ud835\udde7\ud835\udddc\ud835\udde2\ud835\udde1 I Avec \u0299\u1d05\u1d0f \u1d00\u1d20\u1d0f\u1d04\u1d00\u1d1bs, nous avons le plaisir de vous annoncer la signature d&rsquo;un premier contrat professionnel d&rsquo;une dur\u00e9e de 2 ans pour notre trois-quarts centre \ud835\udddf\ud835\uddd8\ud835\udde2 \ud835\udde7\ud835\udde5\ud835\uddd8\ud835\udddc\ud835\udddf\ud835\udddf\ud835\uddd8\ud835\udde6, soit jusqu&rsquo;en \ud835\udfee\ud835\udfec\ud835\udfee\ud835\udff1.<a href=\"https:\/\/twitter.com\/hashtag\/TOUSOYOMEN?src=hash&amp;ref_src=twsrc%5Etfw\">#TOUSOYOMEN<\/a> <a href=\"https:\/\/t.co\/s6Pg3NfDyZ\">pic.twitter.com\/s6Pg3NfDyZ<\/a><\/p>\n<p>\u2014 Oyonnax Rugby (@OyonnaxRugby) <a href=\"https:\/\/twitter.com\/OyonnaxRugby\/status\/1678706511642542082?ref_src=twsrc%5Etfw\">July 11, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p align=\"justify\">Dans le sens des d\u00e9parts, le trois-quarts polyvalent <strong>Gabiriele Lovobalavu<\/strong> (38 ans) a trouv\u00e9 un nouveau point de chute. Arriv\u00e9 dans l&rsquo;Ain en 2019, le Fidjien, qui a fait les belles heures de <strong>Toulon<\/strong> et <strong>Bayonne<\/strong> par le pass\u00e9, s&rsquo;est engag\u00e9 avec <strong>Hy\u00e8res<\/strong>, club de Nationale.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Mont-de-Marsan : Samuel Lagrange (La Rochelle) officialis\u00e9<\/h2>\n<p class=\"article-full__chapo\" style=\"text-align: justify;\">C&rsquo;\u00e9tait pressenti depuis plusieurs semaines, c&rsquo;est d\u00e9sormais act\u00e9. Le talonneur de 26 ans, <strong>Samuel Lagrange<\/strong>, s&rsquo;est officiellement engag\u00e9 avec <strong>Mont-de-Marsan<\/strong>. En fin de contrat avec le <strong>Stade Rochelais<\/strong>, club dans lequel il a \u00e9t\u00e9 form\u00e9, celui qui a commenc\u00e9 le rugby dans le club de La Tremblade, pr\u00e8s de <strong>La Rochelle<\/strong>, va donc se lancer un nouveau d\u00e9fi avec le club montois. Une recrue de choix pour les Landais, puisque <strong>Lagrange<\/strong> dispose d&rsquo;une solide exp\u00e9rience du haut-niveau, avec 50 matchs de Top 14 au compteur.<\/p>\n<p class=\"article-full__chapo\"><iframe loading=\"lazy\" style=\"border: none; overflow: hidden;\" src=\"https:\/\/www.facebook.com\/plugins\/video.php?height=314&amp;href=https%3A%2F%2Fwww.facebook.com%2FSM.Rugby.Pro%2Fvideos%2F1277803482871672%2F&amp;show_text=false&amp;width=560&amp;t=0\" width=\"560\" height=\"314\" frameborder=\"0\" scrolling=\"no\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan accueille un talonneur du Stade Rochelais : les infos transferts de ce mardi 11 juillet 2023.<\/p>\n","protected":false},"author":4,"featured_media":399211,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129],"tags":[16878,28226,13,110,29105],"class_list":["post-399201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-11T17:50:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\",\"datePublished\":\"2023-07-11T17:50:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\"},\"wordCount\":436,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png\",\"keywords\":[\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\",\"name\":\"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png\",\"datePublished\":\"2023-07-11T17:50:14+00:00\",\"description\":\"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png\",\"width\":800,\"height\":445,\"caption\":\"Transferts Rugby Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet","description":"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet","og_description":"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-07-11T17:50:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet","datePublished":"2023-07-11T17:50:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/"},"wordCount":436,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png","keywords":["br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/","name":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png","datePublished":"2023-07-11T17:50:14+00:00","description":"TRANSFERTS RUGBY - Une officialisation \u00e0 Toulouse, Oyonnax signe un trois-quarts, Mont-de-Marsan : les infos transferts de ce mardi 11 juillet 2023.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Rugby-Toulouse-Oyonnax-Mont-de-Marsan-les-infos-transferts-du-mardi-11-juillet.png","width":800,"height":445,"caption":"Transferts Rugby Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-toulouse-oyonnax-mont-de-marsan-les-infos-transferts-du-mardi-11-juillet\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Toulouse, Oyonnax, Mont-de-Marsan, les infos transferts du mardi 11 juillet"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/399201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=399201"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/399201\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/399211"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=399201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=399201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=399201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}