{"id":403122,"date":"2023-07-25T19:23:41","date_gmt":"2023-07-25T17:23:41","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=403122&#038;preview=true&#038;preview_id=403122"},"modified":"2023-07-25T19:36:14","modified_gmt":"2023-07-25T17:36:14","slug":"transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/","title":{"rendered":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>TOP 14 2023-2024 &#8211; Mauvaise nouvelle pour le RC Toulon, puisque l&rsquo;international Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d&rsquo;une s\u00e9v\u00e8re commotion.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Le <strong>RC<\/strong> <strong>Toulon<\/strong> avait r\u00e9alis\u00e9 un gros coup <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-le-wallaby-jake-gordon-arrive-en-top-14\/\">en recrutant <strong>Jake<\/strong> <strong>Gordon<\/strong><\/a> comme joker Coupe du monde de <strong>Ben<\/strong> <strong>White<\/strong> (\u00c9cosse) et <strong>Baptiste<\/strong> <strong>Serin<\/strong> (France). L&rsquo;international australien n&rsquo;\u00e9tait pas dans les plans d&rsquo;<strong>Eddie Jones<\/strong> pour la <strong>Coupe du monde<\/strong> et le club varois en a profit\u00e9 pour le recruter. Mais le demi de m\u00eal\u00e9e a \u00e9t\u00e9 touch\u00e9 lors d&rsquo;un match de l&rsquo;Australie A il y a une dizaine de jours.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">S\u00e9v\u00e8re commotion pour Gordon<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\">Titulaire avec la deuxi\u00e8me \u00e9quipe australienne, <strong>Jake<\/strong> <strong>Gordon<\/strong> a subi une s\u00e9v\u00e8re commotion c\u00e9r\u00e9brale et va \u00eatre absent plusieurs semaines. <strong>Pierre<\/strong> <strong>Mignoni<\/strong>, manager du <strong>RC<\/strong> <strong>Toulon<\/strong>, a expliqu\u00e9 qu&rsquo;il ne pouvait donc pas tenir sa place de joker <strong>Coupe du monde<\/strong>.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\" align=\"justify\">Il est arriv\u00e9 d\u2019Australie la semaine derni\u00e8re. Il vient d\u2019effectuer un match contre les Tonga, vendredi dernier. Il a eu une grosse commotion c\u00e9r\u00e9brale. Il ne peut pas assurer ce r\u00f4le de joker coupe du Monde. Il en a pour 4 et 8 semaines en dehors des terrains.<\/p>\n<\/blockquote>\n<p align=\"justify\">Le <strong>RC<\/strong> <strong>Toulon<\/strong>, qui ne sait toujours pas si <strong>Baptiste<\/strong> <strong>Serin<\/strong> sera dans le groupe final du <strong>XV de France<\/strong> pour la Coupe du monde, doit se remettre en qu\u00eate d&rsquo;un joker Coupe du monde au poste de num\u00e9ro neuf. Pour le moment, aucune piste n&rsquo;a filtr\u00e9, mais les dirigeants toulonnais prospectent d\u00e9j\u00e0.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Arriv\u00e9 comme joker coupe du Monde, le demi de m\u00eal\u00e9e australien Jake Gordon, victime d&rsquo;une commotion, est contraint de d\u00e9clarer forfait pour plusieurs semaines.<a href=\"https:\/\/t.co\/d6YRFdVm5g\">https:\/\/t.co\/d6YRFdVm5g<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1683871438770515968?ref_src=twsrc%5Etfw\">July 25, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Mauvaise nouvelle pour le RC Toulon, puisque l&rsquo;international Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d&rsquo;une s\u00e9v\u00e8re commotion.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":403123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,47050],"tags":[16878,3078],"class_list":["post-403122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-rc-toulon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d&#039;une s\u00e9v\u00e8re commotion.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d&#039;une s\u00e9v\u00e8re commotion.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-25T17:23:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-25T17:36:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9\",\"datePublished\":\"2023-07-25T17:23:41+00:00\",\"dateModified\":\"2023-07-25T17:36:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png\",\"keywords\":[\"br\u00e8ve\",\"RC Toulon\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\",\"name\":\"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png\",\"datePublished\":\"2023-07-25T17:23:41+00:00\",\"dateModified\":\"2023-07-25T17:36:14+00:00\",\"description\":\"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d'une s\u00e9v\u00e8re commotion.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9","description":"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d'une s\u00e9v\u00e8re commotion.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9","og_description":"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d'une s\u00e9v\u00e8re commotion.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-07-25T17:23:41+00:00","article_modified_time":"2023-07-25T17:36:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9","datePublished":"2023-07-25T17:23:41+00:00","dateModified":"2023-07-25T17:36:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png","keywords":["br\u00e8ve","RC Toulon"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/","name":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png","datePublished":"2023-07-25T17:23:41+00:00","dateModified":"2023-07-25T17:36:14+00:00","description":"TOP 14 2023-2024 - Mauvaise nouvelle pour le RC Toulon puisque Jake Gordon doit d\u00e9j\u00e0 quitter le club \u00e0 cause d'une s\u00e9v\u00e8re commotion.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/07\/Transferts-Jake-Gordon-quitte-deja-Toulon-un-numero-9-recherche.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-jake-gordon-quitte-deja-toulon-un-numero-9-recherche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Jake Gordon quitte d\u00e9j\u00e0 Toulon, un num\u00e9ro 9 recherch\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/403122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=403122"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/403122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/403123"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=403122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=403122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=403122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}