{"id":405289,"date":"2023-08-02T21:16:18","date_gmt":"2023-08-02T19:16:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=405289&#038;preview=true&#038;preview_id=405289"},"modified":"2023-08-02T21:16:18","modified_gmt":"2023-08-02T19:16:18","slug":"eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/","title":{"rendered":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-eurobasket-u20-feminin-2023\/\">EUROBASKET U20 F\u00c9MININ<\/a> &#8211; Pas de suspense pour les Bleuettes, qui ont tranquillement rempli leur contrat face aux Tch\u00e8ques, et qui seront au rendez-vous des quarts de finale.\u00a0<\/strong><\/em><\/p>\n<p align=\"justify\">Phase de poules parfaite pour les Bleuettes. Trois matchs, trois victoires, et des certitudes avant d&rsquo;aborder les matchs \u00e0 \u00e9limination directe. La R\u00e9publique Tch\u00e8que ne devait pas repr\u00e9senter un obstacle majeur, mais ayant battu la Serbie pour son unique succ\u00e8s en poules, le s\u00e9rieux \u00e9tait demand\u00e9.<\/p>\n<p align=\"justify\">Message re\u00e7u par des Bleuettes qui n&rsquo;auront tout simplement jamais \u00e9t\u00e9 men\u00e9es au score. Comment ? Gr\u00e2ce \u00e0 la d\u00e9fense, bien \u00e9videmment, et un total hallucinant de 8 interceptions dans un premier quart qui aura permis de cr\u00e9er un vrai \u00e9cart pour se rendre la partie facile (<strong>25-15<\/strong>). Histoire de tuer d\u00e9finitivement le suspense, elles ont plac\u00e9 un coup d&rsquo;acc\u00e9l\u00e9rateur impressionnant en d\u00e9but de deuxi\u00e8me quart, toujours men\u00e9es par un duo <strong>Carla Leite &#8211; Sara Roumy<\/strong> euphorique, pour arriver \u00e0 la pause tout en s\u00e9r\u00e9nit\u00e9 (<strong>58-29<\/strong>).<\/p>\n<p align=\"justify\">Fatalement, la deuxi\u00e8me moiti\u00e9 du match n&rsquo;\u00e9tait pas passionnante. Mais encore fallait il que les Bleuettes restent s\u00e9rieuses du d\u00e9but \u00e0 la fin d&rsquo;une rencontre \u00e0 enjeu, ce qui serait b\u00e9n\u00e9fique plus tard dans la comp\u00e9tition. Bien s\u00fbr, le rythme a baiss\u00e9, les effectifs ont tourn\u00e9, mais malgr\u00e9 une certaine forme de rel\u00e2chement, le travail a \u00e9t\u00e9 fait par les filles d&rsquo;<strong>\u00c9lise Prodhomme<\/strong>. Victoire <strong>100-69<\/strong>, et direction les quarts vendredi (12h00) contre les Italiennes, o\u00f9 il faudra encore monter d&rsquo;un cran.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/--6Xt05jmNI\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROBASKET U20 F\u00c9MININ &#8211; Pas de suspense pour les Bleuettes, qui ont tranquillement rempli leur contrat face aux Tch\u00e8ques, et qui seront au rendez-vous des quarts de finale.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":405295,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[174,16878],"class_list":["post-405289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basket","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale<\/title>\n<meta name=\"description\" content=\"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\" \/>\n<meta property=\"og:description\" content=\"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-02T19:16:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\",\"datePublished\":\"2023-08-02T19:16:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png\",\"keywords\":[\"basket\",\"br\u00e8ve\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\",\"name\":\"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png\",\"datePublished\":\"2023-08-02T19:16:18+00:00\",\"description\":\"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png\",\"width\":800,\"height\":445,\"caption\":\"EuroBasket U20 f\u00e9minin En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale","description":"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale","og_description":"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-08-02T19:16:18+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale","datePublished":"2023-08-02T19:16:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png","keywords":["basket","br\u00e8ve"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/","url":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/","name":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png","datePublished":"2023-08-02T19:16:18+00:00","description":"EUROBASKET U20 F\u00c9MININ - Pas de suspense pour les Bleuettes, qui seront au rendez-vous des quarts de finale.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/EuroBasket-U20-feminin-En-demonstration-face-aux-Tcheques-les-Bleuettes-filent-en-quarts-de-finale.png","width":800,"height":445,"caption":"EuroBasket U20 f\u00e9minin En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/eurobasket-u20-feminin-en-demonstration-face-aux-tcheques-les-bleuettes-filent-en-quarts-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroBasket U20 f\u00e9minin : En d\u00e9monstration face aux Tch\u00e8ques, les Bleuettes filent en quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/405289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=405289"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/405289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/405295"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=405289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=405289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=405289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}