{"id":406610,"date":"2023-08-07T16:44:08","date_gmt":"2023-08-07T14:44:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=406610&#038;preview=true&#038;preview_id=406610"},"modified":"2023-08-07T18:19:11","modified_gmt":"2023-08-07T16:19:11","slug":"coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/","title":{"rendered":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire"},"content":{"rendered":"<p align=\"justify\"><em><b>XV DE FRANCE &#8211; Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0<\/b><\/em><\/p>\n<p align=\"justify\">Alors que le Mondial arrive \u00e0 grands pas, les primes en cas de victoire n&rsquo;avait pas \u00e9t\u00e9 valid\u00e9es entre la <strong>F\u00e9d\u00e9ration Fran\u00e7aise de Rugby<\/strong> et les joueurs du <strong>XV<\/strong> <strong>de<\/strong> <strong>France<\/strong>. <strong>Serge Simon<\/strong> avait bien \u00e9voqu\u00e9 des montants mais rien n&rsquo;avait \u00e9t\u00e9 act\u00e9. Selon certains joueurs, l&rsquo;ancien vice-pr\u00e9sident de la FFR avait parl\u00e9 d&rsquo;une enveloppe comprise entre 10 et 11 millions d&rsquo;euros mais qui n&rsquo;\u00e9tait pas financ\u00e9e.<\/p>\n<p align=\"justify\">Lors du premier stage de pr\u00e9paration \u00e0 la Coupe du monde \u00e0 <strong>Monaco<\/strong>, <strong>Jean-Marc Lhermet<\/strong> a men\u00e9 les n\u00e9gociations avec les repr\u00e9sentants des joueurs. Les partenaires de la <strong>F\u00e9d\u00e9ration Fran\u00e7aise de Rugby<\/strong> verseront un peu plus de 6 millions en cas de succ\u00e8s au d\u00e9but du mois de novembre et c&rsquo;est sur ce montant que les primes des joueurs en cas de victoire ont \u00e9t\u00e9 index\u00e9es.<\/p>\n<p align=\"justify\">La semaine pass\u00e9e \u00e0 <strong>Marcourssis<\/strong> les deux parties ont ent\u00e9rin\u00e9 un accord pour une prime l\u00e9g\u00e8rement inf\u00e9rieure \u00e0 <strong>200 000 euros<\/strong> par joueur en cas de triomphe. C&rsquo;est 100 000 de moins que ce qu&rsquo;avait pr\u00e9vu le duo <strong>Bernard<\/strong> <strong>Laporte<\/strong> &#8211; <strong>Serge<\/strong> <strong>Simon<\/strong> mais cela r\u00e9pond \u00e0 la r\u00e9alit\u00e9 \u00e9conomique de la F\u00e9d\u00e9ration qui a r\u00e9cemment annonc\u00e9 des pertes d&rsquo;exploitation de 13 millions d&rsquo;euros.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le montant des primes pour la Coupe du monde a \u00e9t\u00e9 fix\u00e9 de mani\u00e8re d\u00e9finitive la semaine pass\u00e9e. Et il est inf\u00e9rieur \u00e0 ce qui avait \u00e9t\u00e9 initialement pr\u00e9vu par l\u2019ancienne gouvernance. Explications.<a href=\"https:\/\/t.co\/dWlSZWYU0A\">https:\/\/t.co\/dWlSZWYU0A<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1688461305106026496?ref_src=twsrc%5Etfw\">August 7, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":406623,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,19951],"tags":[16878,1530,30,1638],"class_list":["post-406610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-breve","tag-coupe-du-monde","tag-france","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-07T14:44:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-07T16:19:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire\",\"datePublished\":\"2023-08-07T14:44:08+00:00\",\"dateModified\":\"2023-08-07T16:19:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\"},\"wordCount\":310,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png\",\"keywords\":[\"br\u00e8ve\",\"Coupe du monde\",\"France\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\",\"name\":\"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png\",\"datePublished\":\"2023-08-07T14:44:08+00:00\",\"dateModified\":\"2023-08-07T16:19:11+00:00\",\"description\":\"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire","description":"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire","og_description":"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-08-07T14:44:08+00:00","article_modified_time":"2023-08-07T16:19:11+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire","datePublished":"2023-08-07T14:44:08+00:00","dateModified":"2023-08-07T16:19:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/"},"wordCount":310,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png","keywords":["br\u00e8ve","Coupe du monde","France","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/","name":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png","datePublished":"2023-08-07T14:44:08+00:00","dateModified":"2023-08-07T16:19:11+00:00","description":"XV DE FRANCE - Selon le Midi Olympique, les Bleus toucheront un peu moins de 200 000 euros en cas de victoire lors de la prochaine Coup du monde.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Coupe-du-monde-de-rugby-La-prime-des-joueurs-du-XV-de-France-en-cas-de-victoire.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-rugby-la-prime-des-joueurs-du-xv-de-france-en-cas-de-victoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde de rugby : La prime des joueurs du XV de France en cas de victoire"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/406610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=406610"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/406610\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/406623"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=406610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=406610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=406610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}