{"id":407313,"date":"2023-08-12T08:15:39","date_gmt":"2023-08-12T06:15:39","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=407313&#038;preview=true&#038;preview_id=407313"},"modified":"2023-08-12T09:06:52","modified_gmt":"2023-08-12T07:06:52","slug":"australie-france-a-quelle-heure-et-sur-quelle-chaine-tv","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/","title":{"rendered":"Australie &#8211; France : \u00c0 quelle heure et sur quelle cha\u00eene"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-coupe-du-monde-feminine-de-football-2023\/\" target=\"_blank\" rel=\"noopener\">COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023<\/a> &#8211; Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale de la Coupe du monde 2023. Heure et cha\u00eene TV du match.<\/b><\/em><\/p>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9quipe de <strong>France<\/strong> s&rsquo;est qualifi\u00e9e en quarts de finale de la Coupe du monde avec la mani\u00e8re. Les joueuses de <strong>Herv\u00e9<\/strong> <strong>Renard<\/strong> <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-monde-feminine-2023-bleues-font-une-bouchee-maroc-pour-acceder-quarts\/\">ont largement domin\u00e9 le <strong>Maroc<\/strong> sur le score de quatre \u00e0 z\u00e9ro<\/a>. Le milieu du premier acte a \u00e9t\u00e9 d\u00e9cisif avec trois buts en moins de 10 minutes qui ont scell\u00e9 l&rsquo;issue de ce huiti\u00e8me de finale. La <strong>France<\/strong> s&rsquo;est rendue le match facile et peut regarder plus loin.<\/p>\n<p style=\"text-align: justify;\">Un quart de finale c&rsquo;est le m\u00eame r\u00e9sultat que lors de la derni\u00e8re \u00e9dition, mais les <strong>Bleues<\/strong> veulent regarder bien plus loin. Si toutes les filles ont r\u00e9pondu pr\u00e9sent lors de ce match face au <strong>Maroc<\/strong>, la grande satisfaction est le duo <strong>Eug\u00e9nie<\/strong> <strong>Le Sommer<\/strong> &#8211; <strong>Kadidiatou<\/strong> <strong>Diani<\/strong>. Les deux filles se trouvent facilement sur le terrain et leur entente est meilleure \u00e0 chaque sortie.<\/p>\n<h2 style=\"text-align: justify;\">La France favorite face \u00e0 l&rsquo;Australie<\/h2>\n<p style=\"text-align: justify;\">On oublierait presque que deux des meilleures attaquantes fran\u00e7aises sont absentes : <strong>Delphine<\/strong> <strong>Cascarino<\/strong> et <strong>Marie-Antoinette Katoto<\/strong>. Dans le couloir gauche, le duo <strong>Selma Bacha<\/strong> &#8211; <strong>Sakina<\/strong> <strong>Karchaoui<\/strong> fait aussi des merveilles et sera une des cl\u00e9s du quart de finale face \u00e0 l&rsquo;Australie. La France devra affronter onze joueuses et un stade acquis \u00e0 la cause des adversaires qui jouent \u00e0 la maison.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Australie<\/strong> a remport\u00e9 deux de ses trois matchs de poules, face \u00e0 l&rsquo;<strong>Irlande<\/strong> et le <strong>Canada<\/strong> mais s&rsquo;est inclin\u00e9e face au <strong>Nig\u00e9ria<\/strong>. En huiti\u00e8me de finale, les Australiennes ont domin\u00e9 le <strong>Danemark<\/strong> 2 \u00e0 0. Les deux nations se sont affront\u00e9es il y a quelques jours en amical avec <a href=\"https:\/\/dicodusport.fr\/blog\/preparation-coupe-du-monde-les-bleues-battues-par-laustralie\/\">une victoire de l&rsquo;<strong>Australie<\/strong> face \u00e0 la <strong>France<\/strong><\/a>. Malgr\u00e9 \u00e7a, les Bleues sont favorites pour ce quart de finale.<\/p>\n<h2 style=\"text-align: justify;\">Heure et cha\u00eene TV du match Australie &#8211; France<\/h2>\n<h3 style=\"text-align: justify;\">Samedi 12 ao\u00fbt 2023<\/h3>\n<p style=\"text-align: justify;\"><strong>France 2<\/strong><\/p>\n<p style=\"text-align: justify;\">8h50 : Avant-match<br \/>\n9h00 : Coup d&rsquo;envoi<\/p>\n<h2 style=\"text-align: justify;\">Les cotes de Australie &#8211; France<\/h2>\n<table style=\"width: 800px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\" colspan=\"3\"><span style=\"font-size: 12px; color: #ffffff;\">Samedi 12 ao\u00fbt, 9h00<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 14px;\"><b>Australie<br \/>\n<\/b><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/36887581?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#143cdb;border-color:#1030b0;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5b77e6;border-radius:5px;text-shadow:none\"> 3.50<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/36887581?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#143cdb;border-color:#1030b0;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5b77e6;border-radius:5px;text-shadow:none\"> 3.30<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 14px;\"><b>France<br \/>\n<\/b><\/span><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/36887581?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#fff;background-color:#143cdb;border-color:#1030b0;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#fff;padding:0px 20px;font-size:16px;line-height:32px;border-color:#5b77e6;border-radius:5px;text-shadow:none\"> 2.15<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 &#8211; Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale de la Coupe du monde 2023. Heure et cha\u00eene TV du match.<\/p>\n","protected":false},"author":1,"featured_media":407314,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47043,2301],"tags":[1534,16878,17213,75,30,21872,21768,8799],"class_list":["post-407313","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","category-football","tag-australie","tag-breve","tag-chaine","tag-football","tag-france","tag-heure","tag-horaire","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-12T06:15:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-12T07:06:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Australie &#8211; France : \u00c0 quelle heure et sur quelle cha\u00eene\",\"datePublished\":\"2023-08-12T06:15:39+00:00\",\"dateModified\":\"2023-08-12T07:06:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"keywords\":[\"Australie\",\"br\u00e8ve\",\"Cha\u00eene\",\"Football\",\"France\",\"Heure\",\"Horaire\",\"Programme TV\"],\"articleSection\":[\"Coupe du monde de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\",\"name\":\"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"datePublished\":\"2023-08-12T06:15:39+00:00\",\"dateModified\":\"2023-08-12T07:06:52+00:00\",\"description\":\"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Australie &#8211; France : \u00c0 quelle heure et sur quelle cha\u00eene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene","description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_locale":"fr_FR","og_type":"article","og_title":"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene","og_description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.","og_url":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-08-12T06:15:39+00:00","article_modified_time":"2023-08-12T07:06:52+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Australie &#8211; France : \u00c0 quelle heure et sur quelle cha\u00eene","datePublished":"2023-08-12T06:15:39+00:00","dateModified":"2023-08-12T07:06:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png","keywords":["Australie","br\u00e8ve","Cha\u00eene","Football","France","Heure","Horaire","Programme TV"],"articleSection":["Coupe du monde de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/","url":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/","name":"Australie - France : \u00c0 quelle heure et sur quelle cha\u00eene","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png","datePublished":"2023-08-12T06:15:39+00:00","dateModified":"2023-08-12T07:06:52+00:00","description":"COUPE DU MONDE F\u00c9MININE DE FOOTBALL 2023 - Ce samedi, la France affronte le Maroc en huiti\u00e8me de finale. Heure et cha\u00eene TV du match.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Australie-France-A-quelle-heure-et-sur-quelle-chaine-TV.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/australie-france-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Australie &#8211; France : \u00c0 quelle heure et sur quelle cha\u00eene"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/407313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=407313"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/407313\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/407314"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=407313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=407313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=407313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}