{"id":40798,"date":"2019-06-05T16:53:29","date_gmt":"2019-06-05T14:53:29","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=40798"},"modified":"2019-06-05T21:30:47","modified_gmt":"2019-06-05T19:30:47","slug":"paris-en-ligne-des-courtsiders-expulses-a-roland-garros","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/","title":{"rendered":"Paris en ligne : des \u00ab\u00a0courtsiders\u00a0\u00bb expuls\u00e9s \u00e0 Roland-Garros"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Si les matches sont aujourd&rsquo;hui retard\u00e9s \u00e0 cause des conditions m\u00e9t\u00e9orologiques, une affaire est cependant venue secouer la terre battue de la Porte d&rsquo;Auteuil en d\u00e9but d&rsquo;apr\u00e8s-midi. On apprend par le biais des organisateurs que des \u00ab\u00a0courtsiders\u00a0\u00bb auraient \u00e9t\u00e9 expuls\u00e9s de l&rsquo;enceinte du tournoi. Questions et r\u00e9ponses sur l&rsquo;affaire du jour \u00e0 <a href=\"https:\/\/dicodusport.fr\/blog\/?s=roland-garros\" target=\"_blank\" rel=\"noopener\">Roland-Garros<\/a>.<\/strong><\/em><\/p>\n<h1 style=\"text-align: justify;\">Des \u00ab\u00a0courtsiders\u00a0\u00bb, mais qu&rsquo;est-ce donc ?<\/h1>\n<p style=\"text-align: justify;\">De plus en plus discrets, ces hommes et femmes sont la hantise des organisateurs d&rsquo;\u00e9v\u00e8nements sportifs.\u00a0Litt\u00e9ralement, un \u00ab\u00a0<strong>courtsider<\/strong>\u00a0\u00bb est une personne \u00ab <strong>qui est \u00e0 c\u00f4t\u00e9 du court<\/strong> \u00bb. En pratique,<strong> il s&rsquo;agit d&rsquo;un parieur-fraudeur ou d&rsquo;une personne complice d&rsquo;un parieur-fraudeur, qui tente de transmettre sous une forme ou sous une autre les informations qu&rsquo;il a sous les yeux<\/strong>. Ces informations, en direct, doivent \u00eatre transmises plus rapidement \u00e0 leurs comparses avant que ne les re\u00e7oivent les sites de paris en ligne. Ils profitent ainsi du temps de latence de la transmission entre l&rsquo;action elle-m\u00eame et la cl\u00f4ture d\u00e9finitive du pari sur la plateforme de \u00ab\u00a0<strong>live-betting<\/strong>\u00a0\u00bb pour gagner \u00e0 tous les coups.<\/p>\n<h1 style=\"text-align: justify;\">Mais que vient faire Roland-Garros dans cette histoire ?<\/h1>\n<p style=\"text-align: justify;\">C&rsquo;est un jeu du chat et de la souris qui a lieu quotidiennement \u00e0 Roland-Garros. Depuis le d\u00e9but des qualifications, <strong>la s\u00e9curit\u00e9 du tournoi a expuls\u00e9 pas moins de huit personnes qui contrevenaient aux r\u00e8gles sur les paris sportifs et la transmission de donn\u00e9es sur les matches<\/strong>. Chaque ann\u00e9e, ils sont entre 5 et 20 \u00e0 \u00eatre rep\u00e9r\u00e9s puis expuls\u00e9s des tribunes.<\/p>\n<p style=\"text-align: justify;\">Pour tenter de contenir, et pourquoi pas de contrer tous\u00a0ces informateurs ill\u00e9gaux, Roland-Garros a form\u00e9 et d\u00e9velopp\u00e9 son personnel. Des \u00e9quipes, compos\u00e9es de sp\u00e9cialistes du service juridique et des membres de la s\u00e9curit\u00e9 sont charg\u00e9es de rep\u00e9rer en permanence des personnes \u00ab\u00a0suspectes\u00a0\u00bb.<\/p>\n<p><strong><em>Maxime Giralt<br \/>\n<a href=\"https:\/\/www.facebook.com\/Max11me\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png\" alt=\"\" width=\"38\" height=\"38\" \/><\/a><\/em><\/strong><a href=\"https:\/\/l.facebook.com\/l.php?u=https%3A%2F%2Fwww.linkedin.com%2Fin%2Fmaxime-giralt-1461a917b%2F%3Ffbclid%3DIwAR2o5nEQF1MbwOxhcZA53vciCrvhvHic9QZkhVnMl6B-BY_Hnj32ZE--uew&amp;h=AT0LoCNeRcbrBR7e8K1V93ja3oJ6Y-mNjmtrSMMYYjgplVOS3HK2KUlvJOSwWegSKG3Oe3hzQbAIm94g7G6qYCFYQQWPI1BS9WhzZoe-sPpYMw4rBaFo2prjau_nWQ-RyZQ\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3711\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-linkedin.png\" alt=\"\" width=\"38\" height=\"38\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-linkedin.png 295w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/08\/signature-linkedin-150x150.png 150w\" sizes=\"auto, (max-width: 38px) 100vw, 38px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On apprend par le biais des organisateurs que des \u00ab\u00a0courtsiders\u00a0\u00bb auraient \u00e9t\u00e9 expuls\u00e9s de l&rsquo;enceinte du tournoi. Questions et r\u00e9ponses sur l&rsquo;affaire du jour \u00e0 Roland-Garros.<\/p>\n","protected":false},"author":38,"featured_media":40807,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2,2365,2302],"tags":[159],"class_list":["post-40798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-sports-de-raquette","category-tennis","tag-roland-garros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paris en ligne : des &quot;courtsiders&quot; expuls\u00e9s \u00e0 Roland-Garros<\/title>\n<meta name=\"description\" content=\"Roland-Garros - On apprend par le biais des organisateurs que des &quot;courtsiders&quot; auraient \u00e9t\u00e9 expuls\u00e9s de l&#039;enceinte du tournoi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paris en ligne : des &quot;courtsiders&quot; expuls\u00e9s \u00e0 Roland-Garros\" \/>\n<meta property=\"og:description\" content=\"Roland-Garros - On apprend par le biais des organisateurs que des &quot;courtsiders&quot; auraient \u00e9t\u00e9 expuls\u00e9s de l&#039;enceinte du tournoi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2019-06-05T14:53:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-05T19:30:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Giralt\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Paris en ligne : des &quot;courtsiders&quot; expuls\u00e9s \u00e0 Roland-Garros\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\"},\"author\":{\"name\":\"Maxime Giralt\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/48bad9bec547f458f90c709b91a41248\"},\"headline\":\"Paris en ligne : des \u00ab\u00a0courtsiders\u00a0\u00bb expuls\u00e9s \u00e0 Roland-Garros\",\"datePublished\":\"2019-06-05T14:53:29+00:00\",\"dateModified\":\"2019-06-05T19:30:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\"},\"wordCount\":326,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png\",\"keywords\":[\"Roland-Garros\"],\"articleSection\":[\"Actualit\u00e9s\",\"Sports de raquette\",\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\",\"name\":\"Paris en ligne : des \\\"courtsiders\\\" expuls\u00e9s \u00e0 Roland-Garros\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png\",\"datePublished\":\"2019-06-05T14:53:29+00:00\",\"dateModified\":\"2019-06-05T19:30:47+00:00\",\"description\":\"Roland-Garros - On apprend par le biais des organisateurs que des \\\"courtsiders\\\" auraient \u00e9t\u00e9 expuls\u00e9s de l'enceinte du tournoi.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paris en ligne : des \u00ab\u00a0courtsiders\u00a0\u00bb expuls\u00e9s \u00e0 Roland-Garros\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/48bad9bec547f458f90c709b91a41248\",\"name\":\"Maxime Giralt\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/01\/logo-dicodusport-sans-fond-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/01\/logo-dicodusport-sans-fond-150x150.png\",\"caption\":\"Maxime Giralt\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maxime\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paris en ligne : des \"courtsiders\" expuls\u00e9s \u00e0 Roland-Garros","description":"Roland-Garros - On apprend par le biais des organisateurs que des \"courtsiders\" auraient \u00e9t\u00e9 expuls\u00e9s de l'enceinte du tournoi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/","og_locale":"fr_FR","og_type":"article","og_title":"Paris en ligne : des \"courtsiders\" expuls\u00e9s \u00e0 Roland-Garros","og_description":"Roland-Garros - On apprend par le biais des organisateurs que des \"courtsiders\" auraient \u00e9t\u00e9 expuls\u00e9s de l'enceinte du tournoi.","og_url":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2019-06-05T14:53:29+00:00","article_modified_time":"2019-06-05T19:30:47+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png","type":"image\/png"}],"author":"Maxime Giralt","twitter_card":"summary_large_image","twitter_title":"Paris en ligne : des \"courtsiders\" expuls\u00e9s \u00e0 Roland-Garros","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/"},"author":{"name":"Maxime Giralt","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/48bad9bec547f458f90c709b91a41248"},"headline":"Paris en ligne : des \u00ab\u00a0courtsiders\u00a0\u00bb expuls\u00e9s \u00e0 Roland-Garros","datePublished":"2019-06-05T14:53:29+00:00","dateModified":"2019-06-05T19:30:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/"},"wordCount":326,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png","keywords":["Roland-Garros"],"articleSection":["Actualit\u00e9s","Sports de raquette","Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/","url":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/","name":"Paris en ligne : des \"courtsiders\" expuls\u00e9s \u00e0 Roland-Garros","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png","datePublished":"2019-06-05T14:53:29+00:00","dateModified":"2019-06-05T19:30:47+00:00","description":"Roland-Garros - On apprend par le biais des organisateurs que des \"courtsiders\" auraient \u00e9t\u00e9 expuls\u00e9s de l'enceinte du tournoi.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/06\/Courtsiders-Roland-Garros.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/paris-en-ligne-des-courtsiders-expulses-a-roland-garros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Paris en ligne : des \u00ab\u00a0courtsiders\u00a0\u00bb expuls\u00e9s \u00e0 Roland-Garros"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/48bad9bec547f458f90c709b91a41248","name":"Maxime Giralt","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/01\/logo-dicodusport-sans-fond-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/01\/logo-dicodusport-sans-fond-150x150.png","caption":"Maxime Giralt"},"url":"https:\/\/dicodusport.fr\/blog\/author\/maxime\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/40798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=40798"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/40798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/40807"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=40798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=40798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=40798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}