{"id":414194,"date":"2023-08-31T22:52:56","date_gmt":"2023-08-31T20:52:56","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=414194&#038;preview=true&#038;preview_id=414194"},"modified":"2023-08-31T23:07:44","modified_gmt":"2023-08-31T21:07:44","slug":"pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/","title":{"rendered":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou"},"content":{"rendered":"<p align=\"justify\"><em><strong>PRO D2 2023-2024 &#8211; Au terme d&rsquo;une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34). Compl\u00e8tement domin\u00e9s apr\u00e8s une demi-heure de jeu (6-24), les locaux ont fait preuve d&rsquo;abn\u00e9gation pour remporter son 3e succ\u00e8s de rang, malgr\u00e9 une fin de match totalement folle. Ils font leur meilleur d\u00e9but de saison de leur histoire et gardent la t\u00eate de Pro D2.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Trois essais en dix minutes pour Nevers<\/h2>\n<p style=\"text-align: justify;\">Le d\u00e9but de match voit un duel entre les deux buteurs de la partie. C&rsquo;est l&rsquo;arri\u00e8re <strong>Thomas Salles<\/strong> qui donne le tempo, avec deux coups de pied r\u00e9ussi contre un pour<strong> Shaun Reynolds<\/strong> (6-3, 10\u1d49). Globalement, les Proven\u00e7aux dominent ce d\u00e9but de partie. Avec une belle tenue du ballon, mais aussi une occupation du terrain. Mais sans parvenir \u00e0 trouver la faille dans une solide d\u00e9fense de Nevers.<\/p>\n<p style=\"text-align: justify;\">Et en moins de dix minutes, les <em>Jaune et Bleu<\/em> vont compl\u00e8tement enfoncer une \u00e9quipe de Provence. Cela commence par un super ballon port\u00e9, apr\u00e8s une touche, conclu par leur talonneur <strong>Jonathan Maiau<\/strong> (6-10, 22\u1d49). Les Nivernais vont ensuite profiter de l&rsquo;immense na\u00efvet\u00e9 d&rsquo;une \u00e9quipe locale. <strong>Hugues Bastide<\/strong> h\u00e9rite du ballon en interceptant celui-ci \u00e0 la suite d&rsquo;une attaque au milieu de terrain des Proven\u00e7aux. Le 3\u1d49 ligne d\u00e9ploie les cannes jusqu&rsquo;\u00e0 la terre promise (6-17, 25\u1d49). C&rsquo;est sur une nouvelle interception que l&rsquo;ouvreur <strong>Shaun Reynolds<\/strong> est propuls\u00e9 \u00e0 l&rsquo;essai, le troisi\u00e8me des <em>Jaune et Bleu<\/em> en dix minutes. L&rsquo;ouvreur a tout de m\u00eame r\u00e9alis\u00e9 un gros num\u00e9ro avec un coup de pied par-dessus, pour lui-m\u00eame. Provence a pris un coup terrible sur la t\u00eate (6-24, 30\u1d49). Si on leur avait \u00e9crit le sc\u00e9nario du reste de la partie, eux-m\u00eames ne l&rsquo;auraient peut-\u00eatre pas cru.<\/p>\n<p style=\"text-align: justify;\">Touch\u00e9s, mais pas coul\u00e9s, les Proven\u00e7aux vont se ruer \u00e0 l&rsquo;attaque. Pendant de longues minutes, ils vont faire le si\u00e8ge des 22 m\u00e8tres adverses. Puis des cinq m\u00e8tres. Nevers se met \u00e0 la faute, mais les locaux continuent de jouer. <strong>Jimmy Gobberth<\/strong> profite pour jouer l&rsquo;alternance, avec un jeu au pied pour son ailier <strong>Nadir Bouhedjeur<\/strong>, qui est d\u00e9marqu\u00e9 et qui r\u00e9duit la marque (11-24, 40+2).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/PROD2?src=hash&amp;ref_src=twsrc%5Etfw\">#PROD2<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/PRUSON?src=hash&amp;ref_src=twsrc%5Etfw\">#PRUSON<\/a> &#8211; J3<br \/>\nDans un match o\u00f9 les deux \u00e9quipes envoient du jeu, c&rsquo;est l&rsquo;<a href=\"https:\/\/twitter.com\/usonneversrugby?ref_src=twsrc%5Etfw\">@usonneversrugby<\/a> qui vient jouer les mauvais tours aux Proven\u00e7aux \ud83d\udca5 <a href=\"https:\/\/t.co\/babxgYByu3\">pic.twitter.com\/babxgYByu3<\/a><\/p>\n<p>\u2014 Rugby PRO D2 (@rugbyprod2) <a href=\"https:\/\/twitter.com\/rugbyprod2\/status\/1697336458640494773?ref_src=twsrc%5Etfw\">August 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Provence s&rsquo;est jet\u00e9 corps et \u00e2me dans le second acte<\/h2>\n<p style=\"text-align: justify;\"><strong>Provence Rugby<\/strong> reprend ce second acte comme il a termin\u00e9 le premier. \u00c0 savoir pilonner une d\u00e9fense de Nevers, dont les joueurs ont fait preuve de trop de maladresses en d\u00e9but de cette deuxi\u00e8me mi-temps. \u00c0 force de plier, Nevers craque et, en force, <strong>Guillaume Piazzoli<\/strong> trouve la faille, pour le second essai des siens. Revoil\u00e0 Provence totalement relanc\u00e9 dans une partie pourtant mal embarqu\u00e9e \u00e0 la demi-heure de jeu (18-24, 47\u1d49). Il n&rsquo;y a plus qu&rsquo;une seule \u00e9quipe sur le terrain. Nevers est compl\u00e8tement d\u00e9vor\u00e9 par des locaux qui ont retrouv\u00e9 un suppl\u00e9ment d&rsquo;\u00e2me.<strong> Adrien Lapegue<\/strong> profite d&rsquo;une touche bien n\u00e9goci\u00e9e de son \u00e9quipe. <strong>Arthur Coville<\/strong> a tout lu et, d&rsquo;un petit coup de pied, propulse son ailier vers le 3\u1d49 essai. La transformation de <strong>Thomas Salles<\/strong> propulse Aix devant, pour la premi\u00e8re fois depuis la 22\u1d49 minute (24-23, 50\u1d49).<\/p>\n<p style=\"text-align: justify;\"><strong>Shaun Reynolds<\/strong> redonne l&rsquo;avantage aux visiteurs, avec une p\u00e9nalit\u00e9 de pr\u00e8s de 50 m\u00e8tres (25-27, 54\u1d49). Une toute petite \u00e9claircie dans l&rsquo;orage qu&rsquo;est en train d&rsquo;essuyer Nevers. Provence continue de faire le si\u00e8ge de la d\u00e9fense adverse. <strong>Arthur Coville<\/strong> d\u00e9livre une merveille de passe saut\u00e9e pour <strong>Nadir Bouhedjeur,<\/strong> qui s&rsquo;offre un doubl\u00e9. Mais <strong>Thomas Salles<\/strong> conna\u00eet un \u00e9chec au pied (30-27, 61\u1d49). Mais Nevers ne se rend pas comme cela et malgr\u00e9 une inf\u00e9riorit\u00e9 num\u00e9rique, les Nivernais repartent \u00e0 l&rsquo;attaque. Et campent dans les cinq m\u00e8tres adverses. Et<strong> Arthurs Barbier<\/strong> r\u00e9compense le sursaut d&rsquo;orgueil de son \u00e9quipe. Ce match est exceptionnel et ce sont les visiteurs qui en reprennent les commandes (30-34, 68\u1d49).<\/p>\n<p style=\"text-align: justify;\">Avantage de courte dur\u00e9e. \u00c0 la suite d&rsquo;un excellent coup d&rsquo;envoi, les Proven\u00e7aux s&rsquo;installent dans le camp de Nevers. Apr\u00e8s une monstrueuse s\u00e9ance de picks &amp; go, <strong>Arthur Coville<\/strong> a encore eu un coup de g\u00e9nie, pour trouver <strong>Inga Finau<\/strong>, entr\u00e9 en jeu et qui inscrit le 5\u1d49 essais des siens. Essai transform\u00e9 (37-34, 70\u1d49). Cette fin de match est totalement d\u00e9cousue, \u00e0 la fois monumentale et proche du <em>hourra rugby<\/em>, avec de la rupture entre les deux formations. Chaque \u00e9quipe met en difficult\u00e9 l&rsquo;autre. Nevers aura eu une \u00e9norme balle de match, mais cafouille son ultime ballon \u00e0 30 secondes du terme. Provence Rugby s&rsquo;impose et reste invaincu apr\u00e8s trois journ\u00e9es de Pro D2.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udd34 SCORE FINAL | C&rsquo;\u00e9tait un match de dingo et les Noirs l&rsquo;ont emport\u00e9 ! Yesss ! <a href=\"https:\/\/t.co\/QX1Muytm80\">pic.twitter.com\/QX1Muytm80<\/a><\/p>\n<p>\u2014 Provence Rugby \u26ab\ufe0f\ud83c\udfc9 (@ProvenceRugby) <a href=\"https:\/\/twitter.com\/ProvenceRugby\/status\/1697351292459376899?ref_src=twsrc%5Etfw\">August 31, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2023-2024\/\">Classement de la Pro D2<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2023-2024 &#8211; Au terme d&rsquo;une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34). Compl\u00e8tement domin\u00e9s apr\u00e8s une demi-heure de jeu (6-24), les locaux ont fait preuve d&rsquo;abn\u00e9gation pour remporter son 3e succ\u00e8s de rang, malgr\u00e9 une fin de match totalement folle. Ils font leur meilleur d\u00e9but de saison de leur histoire et gardent la t\u00eate de Pro D2.<\/p>\n","protected":false},"author":83,"featured_media":414224,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[16878,1839,10237,13,110],"class_list":["post-414194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-pro-d2","tag-provence-rugby","tag-rugby","tag-rugby-a-xv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou<\/title>\n<meta name=\"description\" content=\"PRO D2 2023-2024 - Au terme d&#039;une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2023-2024 - Au terme d&#039;une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-08-31T20:52:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-31T21:07:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou\",\"datePublished\":\"2023-08-31T20:52:56+00:00\",\"dateModified\":\"2023-08-31T21:07:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/\"},\"wordCount\":876,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\",\"Provence Rugby\",\"Rugby\",\"Rugby \u00e0 XV\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/\",\"name\":\"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png\",\"datePublished\":\"2023-08-31T20:52:56+00:00\",\"dateModified\":\"2023-08-31T21:07:44+00:00\",\"description\":\"PRO D2 2023-2024 - Au terme d'une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/etienne-goursaud\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou","description":"PRO D2 2023-2024 - Au terme d'une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou","og_description":"PRO D2 2023-2024 - Au terme d'une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).","og_url":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-08-31T20:52:56+00:00","article_modified_time":"2023-08-31T21:07:44+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou","datePublished":"2023-08-31T20:52:56+00:00","dateModified":"2023-08-31T21:07:44+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/"},"wordCount":876,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png","keywords":["br\u00e8ve","Pro D2","Provence Rugby","Rugby","Rugby \u00e0 XV"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/","url":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/","name":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png","datePublished":"2023-08-31T20:52:56+00:00","dateModified":"2023-08-31T21:07:44+00:00","description":"PRO D2 2023-2024 - Au terme d'une fantastique partie, Provence Rugby, pourtant mal embarqu\u00e9, a renvers\u00e9 Nevers (37-34).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Pro-D2-J2-Provence-Rugby-domine-Nevers-apres-un-match-fou.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-j3-provence-rugby-domine-nevers-apres-un-match-fou\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pro D2 (J3) : Provence Rugby domine Nevers apr\u00e8s un match fou"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/414194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=414194"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/414194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/414224"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=414194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=414194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=414194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}