{"id":414497,"date":"2023-09-01T21:57:51","date_gmt":"2023-09-01T19:57:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=414497&#038;preview=true&#038;preview_id=414497"},"modified":"2023-09-02T23:34:17","modified_gmt":"2023-09-02T21:34:17","slug":"coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/","title":{"rendered":"Coupe du monde f\u00e9minine de basket 3&#215;3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a title=\"Calendrier et r\u00e9sultats Coupe du monde f\u00e9minine de basket 3\u00d73 U18 2023\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-coupe-du-monde-feminine-de-basket-3x3-u18-2023\/\" target=\"_blank\" rel=\"noopener\">CDM BASKET 3&#215;3 U18<\/a> &#8211; Trois victoires et une d\u00e9faite pour l&rsquo;\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale de la comp\u00e9tition.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Pour d\u00e9buter la soir\u00e9e, les Fran\u00e7aises affrontaient l&rsquo;<strong>Allemagne<\/strong>. Elles ont rapidement pris les devants. Si l&rsquo;adresse \u00e0 2 points \u00e9tait moins importante que lors de leur dernier match, elles \u00e9taient bien pr\u00e9sentes au rebond. Pour rapidement mener 6-1. Encore une fois, la <strong>d\u00e9fense<\/strong> est en place. Le temps mort t\u00e9l\u00e9vis\u00e9 a fait du bien \u00e0 l&rsquo;Allemagne qui a pu recoller. Les Bleuettes ont tout de m\u00eame r\u00e9ussi \u00e0 conserver une petite avance. Mais \u00e0 force de jouer avec le feu, les Allemandes reviennent \u00e0 \u00e9galit\u00e9 dans la derni\u00e8re minute (18-18). D\u00e9fendue mais parvenue \u00e0 se d\u00e9faire du marquage de 9, <strong>Lilou Th\u00e9venet<\/strong> donne la victoire \u00e0 la France d&rsquo;un shoot \u00e0 2 points alors qu&rsquo;il restait 20 secondes \u00e0 jouer (21-19) ! Explosion de joie pour les Fran\u00e7aises, larmes pour les Allemandes. Car ce r\u00e9sultat envoie la France en quarts et met fin aux espoirs de qualification l&rsquo;Allemagne.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LILOU THEVENET ! QUELLE FIN DE MATCH ! \ud83e\udd2f<\/p>\n<p>L&rsquo;\u00c9quipe de France U18 est qualifi\u00e9e pour les quarts de finale de la Coupe du Monde sur ce tir incroyable \ud83c\udde8\ud83c\uddf5<a href=\"https:\/\/twitter.com\/hashtag\/3x3U18?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3U18<\/a> | <a href=\"https:\/\/twitter.com\/FIBA3x3?ref_src=twsrc%5Etfw\">@FIBA3x3<\/a><br \/>\n<a href=\"https:\/\/t.co\/fJeAT6Sq8N\">pic.twitter.com\/fJeAT6Sq8N<\/a><\/p>\n<p>\u2014 3&#215;3 FFBB (@3x3ffbb) <a href=\"https:\/\/twitter.com\/3x3ffbb\/status\/1697659832155648276?ref_src=twsrc%5Etfw\">September 1, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Avant m\u00eame de d\u00e9buter son choc face aux <strong>\u00c9tats-Unis<\/strong>, la France \u00e9tait donc assur\u00e9e d&rsquo;\u00eatre de retour sur les terrains dimanche. Et heureusement qu&rsquo;elles avaient fait le travail avant car la marche am\u00e9ricaine \u00e9tait trop haute pour les Bleuettes ce soir. D\u00e9fendues comme elles ne l&rsquo;ont jamais \u00e9t\u00e9 depuis le d\u00e9but de la comp\u00e9tition, elles ont eu du mal \u00e0 atteindre le panier. Et quand c&rsquo;\u00e9tait le cas, elles n&rsquo;\u00e9taient pas en bonne position pour r\u00e9ussir leur panier. R\u00e9sultat, d\u00e9faite 12-21.<\/p>\n<p style=\"text-align: justify;\">En quart de finale, la <strong>France<\/strong> affrontera la <strong>Pologne<\/strong>, invaincue. Match \u00e0 10h25 dimanche 3 septembre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CDM BASKET 3&#215;3 U18 &#8211; Trois victoires et une d\u00e9faite pour l&rsquo;\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale de la comp\u00e9tition.<\/p>\n","protected":false},"author":12,"featured_media":414563,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27116],"tags":[9140,33418,16878,33987],"class_list":["post-414497","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-basket-3x3","tag-basket-3x3-u18","tag-breve","tag-france-u18-3x3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale<\/title>\n<meta name=\"description\" content=\"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l&#039;\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale\" \/>\n<meta property=\"og:description\" content=\"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l&#039;\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-01T19:57:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-02T21:34:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Coupe du monde f\u00e9minine de basket 3&#215;3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale\",\"datePublished\":\"2023-09-01T19:57:51+00:00\",\"dateModified\":\"2023-09-02T21:34:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/\"},\"wordCount\":356,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png\",\"keywords\":[\"Basket 3x3\",\"Basket 3x3 U18\",\"br\u00e8ve\",\"France U18 3x3\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/\",\"name\":\"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png\",\"datePublished\":\"2023-09-01T19:57:51+00:00\",\"dateModified\":\"2023-09-02T21:34:17+00:00\",\"description\":\"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l'\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 La France qualifi\u00e9e pour les quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde f\u00e9minine de basket 3&#215;3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Shiclette94\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/arlette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale","description":"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l'\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale","og_description":"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l'\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-09-01T19:57:51+00:00","article_modified_time":"2023-09-02T21:34:17+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Coupe du monde f\u00e9minine de basket 3&#215;3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale","datePublished":"2023-09-01T19:57:51+00:00","dateModified":"2023-09-02T21:34:17+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/"},"wordCount":356,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png","keywords":["Basket 3x3","Basket 3x3 U18","br\u00e8ve","France U18 3x3"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/","name":"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png","datePublished":"2023-09-01T19:57:51+00:00","dateModified":"2023-09-02T21:34:17+00:00","description":"CDM BASKET 3x3 U18 - Trois victoires et une d\u00e9faite pour l'\u00e9quipe de France f\u00e9minine qui se qualifie ainsi pour les quarts de finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-feminine-de-basket-3x3-U18-2023-La-France-qualifiee-pour-les-quarts-de-finale.png","width":800,"height":445,"caption":"Coupe du monde f\u00e9minine de basket 3x3 U18 2023 La France qualifi\u00e9e pour les quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-feminine-de-basket-3x3-u18-2023-la-france-qualifiee-pour-les-quarts-de-finale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde f\u00e9minine de basket 3&#215;3 U18 2023 : La France qualifi\u00e9e pour les quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/414497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=414497"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/414497\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/414563"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=414497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=414497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=414497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}