{"id":416481,"date":"2023-09-07T19:46:44","date_gmt":"2023-09-07T17:46:44","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=416481&#038;preview=true&#038;preview_id=416481"},"modified":"2023-09-07T22:51:12","modified_gmt":"2023-09-07T20:51:12","slug":"coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/","title":{"rendered":"Coupe d&rsquo;Europe de basket 3&#215;3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me"},"content":{"rendered":"<p align=\"justify\"><em><strong><a title=\"Calendrier et r\u00e9sultats Coupe d\u2019Europe masculine de basket 3\u00d73 2023\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-coupe-deurope-masculine-de-basket-3x3-2023\/\" target=\"_blank\" rel=\"noopener\">COUPE D&rsquo;EUROPE DE BASKET 3&#215;3<\/a> &#8211; Comme ses homologues f\u00e9minines, l&rsquo;\u00c9quipe de France masculine repart sans m\u00e9daille. Les Bleus se sont inclin\u00e9s 22-19 en petite finale contre la Lettonie, sur un panier au buzzer adverse. Alors qu&rsquo;ils avaient le match en main apr\u00e8s une entame parfaite, ils ont compl\u00e8tement craqu\u00e9 mentalement et physiquement.<\/strong><\/em><\/p>\n<p align=\"justify\"><strong>L&rsquo;\u00c9quipe de France termine tr\u00e8s mal sa Coupe d&rsquo;Europe<\/strong>. Alors qu&rsquo;ils \u00e9taient invaincus en phase de poules et qu&rsquo;ils avaient <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-lequipe-de-france-masculine-va-jouer-le-dernier-carre\/\">facilement domin\u00e9 l&rsquo;Autriche en quarts de finale<\/a>, <strong>les Bleus ont encha\u00een\u00e9 deux d\u00e9sillusions<\/strong>. En demi-finale d&rsquo;abord, ils ont <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze\/\">rev\u00e9cu le cauchemar du dernier Mondial face \u00e0 la Lituanie<\/a>, en \u00e9tant domin\u00e9s physiquement. Moins d&rsquo;une heure plus tard, ils ont d\u00fb encha\u00eener avec la petite finale contre la Lettonie. Malgr\u00e9 la fatigue, les Fran\u00e7ais ont parfaitement entam\u00e9 leur rencontre avec un 6-0 inflig\u00e9 d&rsquo;entr\u00e9e, qui s&rsquo;est transform\u00e9 en 11-2.<\/p>\n<h2 align=\"justify\">Inversion de la dynamique<\/h2>\n<p align=\"justify\">\u00c0 ce moment-l\u00e0, on pensait les co\u00e9quipiers d&rsquo;un <strong>L\u00e9opold Cavali\u00e8re dominant<\/strong> (5 points, 4 rebonds) \u00e0 l&rsquo;abri. Mais petit \u00e0 petit,<strong> les signes ont tourn\u00e9 en leur d\u00e9faveur<\/strong>. D&rsquo;abord, les Bleus ont rat\u00e9 trois lancers francs d&rsquo;affil\u00e9e, laissant les Lettons revenir \u00e0 13-9. Ensuite, ils ont commenc\u00e9 \u00e0 souffrir physiquement de l&rsquo;encha\u00eenement des matchs. Ils ont <strong>manqu\u00e9 d&rsquo;\u00e9nergie et de lucidit\u00e9 en d\u00e9fense<\/strong> et se sont fait syst\u00e9matiquement d\u00e9passer par leurs vis-\u00e0-vis. Le score est pass\u00e9 \u00e0 15-15. Enfin, un sursaut d&rsquo;orgueil leur a permis de se mettre en bonne position pour l&#8217;emporter (18-15). Mais leurs adversaires ont encha\u00een\u00e9 les tirs <em>clutchs<\/em>, jusqu&rsquo;au tir \u00e0 2 points victorieux au buzzer du MVP <strong>Karlis Lasmanis<\/strong>, qui termine meilleur marqueur avec 16 points.<\/p>\n<p align=\"justify\">Le bilan de cette Coupe d&rsquo;Europe est donc peu glorieux pour les \u00e9quipes fran\u00e7aises. <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-deurope-feminine-de-basket-3x3-2023-les-bleues-eliminees-des-les-quarts-de-finale\/\">Les f\u00e9minines ont \u00e9t\u00e9 \u00e9limin\u00e9es par surprise en quarts par le Portuga<\/a>l, et n&rsquo;ont donc m\u00eame pas pu jouer pour une m\u00e9daille. Les masculins eux en sont pass\u00e9s tout proches, mais terminent finalement \u00e0 la quatri\u00e8me place. <strong>La d\u00e9l\u00e9gation tricolore repart donc de J\u00e9rusalem sans la moindre m\u00e9daille<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">C&rsquo;est cruel ! Les Bleus terminent leur campagne europ\u00e9enne au pied du podium \ud83d\udc94<a href=\"https:\/\/twitter.com\/hashtag\/3x3Europe?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3Europe<\/a> | <a href=\"https:\/\/twitter.com\/ffbasketball?ref_src=twsrc%5Etfw\">@ffbasketball<\/a> \ud83c\udde8\ud83c\uddf5 <a href=\"https:\/\/t.co\/dV84vXhvyC\">pic.twitter.com\/dV84vXhvyC<\/a><\/p>\n<p>\u2014 3&#215;3 FFBB (@3x3ffbb) <a href=\"https:\/\/twitter.com\/3x3ffbb\/status\/1699843974490415511?ref_src=twsrc%5Etfw\">September 7, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE D&rsquo;EUROPE DE BASKET 3&#215;3 &#8211; Comme ses homologues f\u00e9minines, l&rsquo;\u00c9quipe de France masculine repart sans m\u00e9daille. Les Bleus se sont inclin\u00e9s 22-19 en petite finale contre la Lettonie, sur un panier au buzzer adverse. Alors qu&rsquo;ils avaient le match en main apr\u00e8s une entame parfaite, ils ont compl\u00e8tement craqu\u00e9 mentalement et physiquement. L&rsquo;\u00c9quipe de [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":416494,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27116],"tags":[16878,16919],"class_list":["post-416481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-breve","tag-equipe-de-france-de-basket-3x3"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coupe d&#039;Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me<\/title>\n<meta name=\"description\" content=\"Alors qu&#039;ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe d&#039;Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me\" \/>\n<meta property=\"og:description\" content=\"Alors qu&#039;ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-07T17:46:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-07T20:51:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tom Compayrot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe d&#039;Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Tom_Cprt\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/\"},\"author\":{\"name\":\"Tom Compayrot\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/bf1e4f404e108bd2be5b447b16bde9a7\"},\"headline\":\"Coupe d&rsquo;Europe de basket 3&#215;3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me\",\"datePublished\":\"2023-09-07T17:46:44+00:00\",\"dateModified\":\"2023-09-07T20:51:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/\"},\"wordCount\":416,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png\",\"keywords\":[\"br\u00e8ve\",\"\u00c9quipe de France de basket 3X3\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/\",\"name\":\"Coupe d'Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png\",\"datePublished\":\"2023-09-07T17:46:44+00:00\",\"dateModified\":\"2023-09-07T20:51:12+00:00\",\"description\":\"Alors qu'ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe d&rsquo;Europe de basket 3&#215;3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/bf1e4f404e108bd2be5b447b16bde9a7\",\"name\":\"Tom Compayrot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Tom-Compayrot-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Tom-Compayrot-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Tom-Compayrot-150x150.jpg\",\"caption\":\"Tom Compayrot\"},\"description\":\"Journaliste\\\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Tom_Cprt\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/tom\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe d'Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me","description":"Alors qu'ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe d'Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me","og_description":"Alors qu'ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-09-07T17:46:44+00:00","article_modified_time":"2023-09-07T20:51:12+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png","type":"image\/png"}],"author":"Tom Compayrot","twitter_card":"summary_large_image","twitter_title":"Coupe d'Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me","twitter_creator":"@https:\/\/twitter.com\/Tom_Cprt","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/"},"author":{"name":"Tom Compayrot","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7"},"headline":"Coupe d&rsquo;Europe de basket 3&#215;3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me","datePublished":"2023-09-07T17:46:44+00:00","dateModified":"2023-09-07T20:51:12+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/"},"wordCount":416,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png","keywords":["br\u00e8ve","\u00c9quipe de France de basket 3X3"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/","name":"Coupe d'Europe de basket 3x3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png","datePublished":"2023-09-07T17:46:44+00:00","dateModified":"2023-09-07T20:51:12+00:00","description":"Alors qu'ils avaient la petite finale en main apr\u00e8s une entame parfaite, les Bleus ont compl\u00e8tement craqu\u00e9 et repartent sans m\u00e9daille.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/coupe-deurope-de-basket-3x3-les-bleus-perdent-encore-contre-la-lituanie-et-joueront-le-bronze-1.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-deurope-de-basket-3x3-crucifiee-par-la-lettonie-la-france-termine-quatrieme\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe d&rsquo;Europe de basket 3&#215;3 : Crucifi\u00e9e par la Lettonie, la France termine quatri\u00e8me"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7","name":"Tom Compayrot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","caption":"Tom Compayrot"},"description":"Journaliste\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Tom_Cprt"],"url":"https:\/\/dicodusport.fr\/blog\/author\/tom\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/416481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=416481"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/416481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/416494"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=416481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=416481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=416481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}