{"id":418644,"date":"2023-09-14T14:21:05","date_gmt":"2023-09-14T12:21:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=418644&#038;preview=true&#038;preview_id=418644"},"modified":"2023-09-14T15:43:30","modified_gmt":"2023-09-14T13:43:30","slug":"finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/","title":{"rendered":"Finale Nations League U23 3&#215;3 2023 : Direction les quarts pour l&rsquo;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-finale-nations-league-u23-3x3-2023\/\" target=\"_blank\" rel=\"noopener\">FINALE NATIONS LEAGUE 3X3<\/a> &#8211; C&rsquo;est un 4\/4 pour la France puisque les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Sans-faute pour l&rsquo;\u00e9quipe de France f\u00e9minine U21<\/h2>\n<p style=\"text-align: justify;\">Les Bleuettes ont bien d\u00e9but\u00e9 leur comp\u00e9tition. Elles ont ouvert le bal de cette deuxi\u00e8me journ\u00e9e face \u00e0 l&rsquo;\u00e9quipe <strong>U21 de l&rsquo;\u00c9gypte<\/strong>. Et les Bleuettes n&rsquo;ont pas trembl\u00e9 dans cette rencontre prenant rapidement les devants. <strong>Clarisse Vergiat<\/strong> s&rsquo;est montr\u00e9e adroite \u00e0 2 points avec 3 paniers dont 1 sur le gong. Solides d\u00e9fensivement, les Bleuettes ont profit\u00e9 de la maladresse des \u00c9gyptiennes aux lancers et dans le jeu. Il aura fallu attendre<strong> 5 minutes<\/strong> pour qu&rsquo;elles inscrivent leur premier point (9-1) ! Les \u00c9gyptiennes ont fini par trouver leur rythme en fin de match, mais c&rsquo;\u00e9tait trop tard. Victoire 18-8 de la F<strong>rance<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Avant m\u00eame de jouer leur match face \u00e0 l&rsquo;<strong>Allemagne<\/strong>, les Fran\u00e7aises \u00e9taient assur\u00e9es de disputer les quarts, l&rsquo;\u00c9gypte ayant perdu son 2e match. Mais pour terminer en t\u00eate de son groupe et esp\u00e9rer retrouver l&rsquo;\u00e9quipe de France U23 le plus tard possible (en finale), cette premi\u00e8re place \u00e9tait importante !<\/p>\n<p style=\"text-align: justify;\">Ce sont les <strong>Allemandes<\/strong> qui prennent les devants en d\u00e9but de rencontre. Les Fran\u00e7aises se retrouvent men\u00e9es 1-4. L&rsquo;\u00e9cart est mont\u00e9 \u00e0 -4. Mais la vitesse de <strong>Vaciana Gomis<\/strong> fait la diff\u00e9rence et elles recollent \u00e0 7-8. Les Allemandes ne s&rsquo;affolent pas et continuent de percer la d\u00e9fense fran\u00e7aise \u00e0 l&rsquo;int\u00e9rieur. Gomis \u00e9galise (9-9) et apr\u00e8s une bonne d\u00e9fense fran\u00e7aise, les Bleuettes passent devant pour la premi\u00e8re fois. <strong>Clarisse Vergiat<\/strong> inscrit un lay-up et la faute obtenue avec (11-9). Les Fran\u00e7aises continuent leur marche en avant mais leurs adversaires \u00e9galisent avec un panier \u00e0 2 points. Finalement, elles n&rsquo;ont pas l\u00e2ch\u00e9 leur avantage. Challeng\u00e9es par les Allemandes revenues \u00e0 20-19, elles s&rsquo;imposent finalement 21-19 et terminent \u00e0 la premi\u00e8re place de leur poule !<\/p>\n<p style=\"text-align: justify;\">En <strong>quarts<\/strong>, elles affronteront le 2e de la poule D : les\u00a0<strong>\u00c9tats-Unis\u00a0<\/strong>qui s&rsquo;en sortent avec une victoire face \u00e0 l&rsquo;Allemagne U21 et des d\u00e9faites face \u00e0 la Pologne et la Mongolie.<\/p>\n<h2>Les U23 fran\u00e7ais s&rsquo;en sortent in extremis !<\/h2>\n<p style=\"text-align: justify;\">Juste apr\u00e8s leurs homologues U21, les <strong>Bleuets U23<\/strong> faisaient \u00e9galement leurs d\u00e9buts dans la comp\u00e9tition. Eux aussi face \u00e0 l&rsquo;<strong>\u00c9gypte<\/strong>. <strong>Arthur Dalambaye Bouba<\/strong> a directement donn\u00e9 le ton en inscrivant un panier avec la faute. Mais il a rat\u00e9 son lancer franc. Cependant, la France a rapidement men\u00e9 6-2 tandis que les \u00c9gyptiens accumulaient les fautes (5). Petit \u00e0 petit, ceux-ci ont recoll\u00e9. Mais les Fran\u00e7ais sont parvenus \u00e0 garder leurs distances et se sont impos\u00e9s 18-12. Table de marque bien r\u00e9partie avec 5 points pour <strong>Paul Billong<\/strong>, <strong>Arthur Bouba<\/strong> et <strong>Florian Fortas<\/strong>. <strong>Sya Plaucoste<\/strong> en a lui inscrit 3.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Plaucoste dunks so effortlessly he could do it while \ud83d\ude34\ud83e\udd71<a href=\"https:\/\/twitter.com\/hashtag\/3x3NL?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3NL<\/a> <a href=\"https:\/\/t.co\/GOSs9De5Xz\">pic.twitter.com\/GOSs9De5Xz<\/a><\/p>\n<p>\u2014 FIBA3x3 (@FIBA3x3) <a href=\"https:\/\/twitter.com\/FIBA3x3\/status\/1702214848720085118?ref_src=twsrc%5Etfw\">September 14, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pour leur deuxi\u00e8me match face \u00e0 la <strong>Pologne U21<\/strong>, il fallait \u00eatre vigilant. L&rsquo;\u00c9gypte l&rsquo;ayant battue, la France n&rsquo;avait pas le droit \u00e0 l&rsquo;erreur. Elle devait s&rsquo;imposer ou s&rsquo;incliner en inscrivant plus de 15 points.<\/p>\n<p style=\"text-align: justify;\">En d\u00e9but de match, les deux \u00e9quipes se rendent coup pour coup. <strong>Sya Plaucoste<\/strong> inscrit un panier \u00e0 2 points ? La r\u00e9ponse polonaise est imm\u00e9diate. Celui de <strong>Florian Fortas<\/strong> permet \u00e0 la France de prendre 2 points d&rsquo;avance (5-3). Le jeu s&rsquo;acc\u00e9l\u00e8re et les Fran\u00e7ais continuent de garder leur avance. Mais ils laissent filer des points sur lancer franc (0\/3 pour Bouba dans l&rsquo;exercice). Et la Pologne \u00e9galise (10-10). Mais <strong>Sya Plaucoste<\/strong> redonne tout de suite l&rsquo;avantage aux siens (12-10). Les deux \u00e9quipes jouent au chat et \u00e0 la souris. Les Polonais ne font que tirer \u00e0 2 points pour rester au contact puis passer devant (13-14).<\/p>\n<p style=\"text-align: justify;\">Les Fran\u00e7ais accumulent les marchers tandis que la Pologne continue son festival \u00e0<strong> 2 points<\/strong> (15-20). Et une faute offensive est siffl\u00e9e au m\u00eame moment contre les Fran\u00e7ais qui ne doivent absolument pas prendre de panier. Mais ils font faute et <strong>B\u0142a\u017cej Czerniewicz<\/strong> est envoy\u00e9 sur la ligne des lancers francs. Il inscrit le premier, la Pologne s&rsquo;impose 21-15 et prend la t\u00eate de la poule ! La France est \u00e0 \u00e9galit\u00e9 avec l&rsquo;\u00c9gypte, avec le m\u00eame nombre de points marqu\u00e9s. Mais les Bleuets \u00e9tant mieux class\u00e9s (2 contre 8), ce sont eux qui se qualifient en quarts de finale.<\/p>\n<p style=\"text-align: justify;\">Demain, ils affronteront le premier du groupe D : l&rsquo;<strong>Espagne<\/strong>, qui est invaincue. Et ils pourraient retrouver les U21 fran\u00e7ais en demies en cas de victoire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FINALE NATIONS LEAGUE 3X3 &#8211; C&rsquo;est un 4\/4 pour la France puisque les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.<\/p>\n","protected":false},"author":12,"featured_media":418795,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27116],"tags":[9140,16878,34378,34372,26637,34208],"class_list":["post-418644","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-basket-3x3","tag-breve","tag-equipe-de-france-u23-3x3","tag-france-nations-league-3x3","tag-nations-league-3x3","tag-nations-league-3x3-u23"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Finale Nations League U23 3x3 2023 : Direction les quarts pour l&#039;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23<\/title>\n<meta name=\"description\" content=\"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Finale Nations League U23 3x3 2023 : Direction les quarts pour l&#039;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\" \/>\n<meta property=\"og:description\" content=\"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-14T12:21:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-14T13:43:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Finale Nations League U23 3x3 2023 : Direction les quarts pour l&#039;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Finale Nations League U23 3&#215;3 2023 : Direction les quarts pour l&rsquo;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\",\"datePublished\":\"2023-09-14T12:21:05+00:00\",\"dateModified\":\"2023-09-14T13:43:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/\"},\"wordCount\":804,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png\",\"keywords\":[\"Basket 3x3\",\"br\u00e8ve\",\"\u00e9quipe de France U23 3x3\",\"France Nations league 3x3\",\"Nations League 3X3\",\"Nations League 3x3 U23\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/\",\"name\":\"Finale Nations League U23 3x3 2023 : Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png\",\"datePublished\":\"2023-09-14T12:21:05+00:00\",\"dateModified\":\"2023-09-14T13:43:30+00:00\",\"description\":\"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png\",\"width\":800,\"height\":445,\"caption\":\"Finale Nations League U23 3x3 2023 Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Finale Nations League U23 3&#215;3 2023 : Direction les quarts pour l&rsquo;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Shiclette94\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/arlette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Finale Nations League U23 3x3 2023 : Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23","description":"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/","og_locale":"fr_FR","og_type":"article","og_title":"Finale Nations League U23 3x3 2023 : Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23","og_description":"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.","og_url":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-09-14T12:21:05+00:00","article_modified_time":"2023-09-14T13:43:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Finale Nations League U23 3x3 2023 : Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Finale Nations League U23 3&#215;3 2023 : Direction les quarts pour l&rsquo;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23","datePublished":"2023-09-14T12:21:05+00:00","dateModified":"2023-09-14T13:43:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/"},"wordCount":804,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png","keywords":["Basket 3x3","br\u00e8ve","\u00e9quipe de France U23 3x3","France Nations league 3x3","Nations League 3X3","Nations League 3x3 U23"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/","url":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/","name":"Finale Nations League U23 3x3 2023 : Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png","datePublished":"2023-09-14T12:21:05+00:00","dateModified":"2023-09-14T13:43:30+00:00","description":"FINALE NATIONS LEAGUE 3X3 - Les \u00e9quipes de France f\u00e9minine U21 et masculine U23 rejoignent \u00e9galement les quarts de finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Finale-Nations-League-U23-3x3-2023-Direction-les-quarts-pour-lequipe-de-France-feminine-U21-et-les-Bleuets-U23.png","width":800,"height":445,"caption":"Finale Nations League U23 3x3 2023 Direction les quarts pour l'\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/finale-nations-league-u23-3x3-2023-direction-les-quarts-pour-lequipe-de-france-feminine-u21-et-les-bleuets-u23\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Finale Nations League U23 3&#215;3 2023 : Direction les quarts pour l&rsquo;\u00e9quipe de France f\u00e9minine U21 et les Bleuets U23"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/418644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=418644"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/418644\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/418795"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=418644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=418644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=418644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}