{"id":419,"date":"2016-06-08T08:19:06","date_gmt":"2016-06-08T07:19:06","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=419"},"modified":"2025-08-24T13:26:58","modified_gmt":"2025-08-24T11:26:58","slug":"euro-2016-limpact-economique","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/","title":{"rendered":"Euro 2016 : L&rsquo;impact \u00e9conomique"},"content":{"rendered":"<p class=\"p1\" style=\"text-align: justify;\"><strong><span style=\"color: #000000;\"><em><span style=\"font-size: 12pt;\"><span class=\"s1\">Les meilleurs\u00a0joueurs du continent se disputeront d\u00e8s vendredi pour essayer de d\u00e9crocher la coupe europ\u00e9enne. La comp\u00e9tition devrait rapporter plus de 1 milliard d\u2019euros \u00e0 l\u2019\u00e9conomie fran\u00e7aise.<\/span><\/span><\/em><\/span><\/strong><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s1\" style=\"color: #000000;\">Le Centre de Droit et d\u2019\u00c9conomie du Sport (CDES) a d\u00e9voil\u00e9 les chiffres, sur toute la dur\u00e9e du tournoi c\u2019est 1,26 milliard apport\u00e9 au pays. Ce chiffre est le r\u00e9sultat estim\u00e9 des d\u00e9penses au niveau des acteurs \u00e9trangers.<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span class=\"s1\" style=\"color: #000000;\">Ils totalisent \u00e0 eux seuls 62% de l\u2019impact \u00e9conomique global. En\u00a0ajoutant les spectateurs fran\u00e7ais, les revenus des spectateurs stades g\u00e9n\u00e8reront 842 millions de b\u00e9n\u00e9fices sur la totalit\u00e9 de l\u2019\u00e9v\u00e8nement. Le panier\u00a0moyen des d\u00e9penses est estim\u00e9 en moyenne \u00e0 environ 353\u20ac\u00a0<\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span style=\"color: #000000;\">Pour lire la suite de l&rsquo;article rendez-vous sur <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/blog.playeur.co\/euro-2016-impact-economique\/\" target=\"_blank\" rel=\"noopener\">playeur.co<\/a><\/span><\/span><\/p>\n<p class=\"p1\" style=\"text-align: justify;\"><span style=\"color: #000000;\"><span style=\"color: #0000ff;\"><em><em><em><a style=\"color: #000000; text-decoration: underline;\" href=\"http:\/\/www.dicodusport.fr\" target=\"_blank\" rel=\"noopener\"><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4 aligncenter\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/04\/logo-150x150.png\" alt=\"logo\" width=\"106\" height=\"106\" \/><\/a><\/em><\/em><\/em><\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les meilleurs\u00a0joueurs du continent se disputeront d\u00e8s vendredi pour essayer de d\u00e9crocher la coupe europ\u00e9enne. La comp\u00e9tition devrait rapporter plus de 1 milliard d\u2019euros \u00e0 l\u2019\u00e9conomie fran\u00e7aise. Le Centre de Droit et d\u2019\u00c9conomie du Sport (CDES) a d\u00e9voil\u00e9 les chiffres, sur toute la dur\u00e9e du tournoi c\u2019est 1,26 milliard apport\u00e9 au pays. Ce chiffre est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":150798,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[38,75,30],"class_list":["post-419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-dicodusport-fr","tag-football","tag-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Euro 2016 : L&#039;impact \u00e9conomique<\/title>\n<meta name=\"description\" content=\"Quel sera l&#039;impact de l&#039;euro 2016 sur l&#039;\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro 2016 : L&#039;impact \u00e9conomique\" \/>\n<meta property=\"og:description\" content=\"Quel sera l&#039;impact de l&#039;euro 2016 sur l&#039;\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-08T07:19:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-24T11:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Euro 2016 : L&rsquo;impact \u00e9conomique\",\"datePublished\":\"2016-06-08T07:19:06+00:00\",\"dateModified\":\"2025-08-24T11:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\"},\"wordCount\":137,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png\",\"keywords\":[\"dicodusport.fr\",\"Football\",\"France\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#respond\"]}],\"copyrightYear\":\"2016\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\",\"name\":\"Euro 2016 : L'impact \u00e9conomique\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png\",\"datePublished\":\"2016-06-08T07:19:06+00:00\",\"dateModified\":\"2025-08-24T11:26:58+00:00\",\"description\":\"Quel sera l'impact de l'euro 2016 sur l'\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro 2016 : L&rsquo;impact \u00e9conomique\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro 2016 : L'impact \u00e9conomique","description":"Quel sera l'impact de l'euro 2016 sur l'\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro 2016 : L'impact \u00e9conomique","og_description":"Quel sera l'impact de l'euro 2016 sur l'\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.","og_url":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2016-06-08T07:19:06+00:00","article_modified_time":"2025-08-24T11:26:58+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Euro 2016 : L&rsquo;impact \u00e9conomique","datePublished":"2016-06-08T07:19:06+00:00","dateModified":"2025-08-24T11:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/"},"wordCount":137,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png","keywords":["dicodusport.fr","Football","France"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#respond"]}],"copyrightYear":"2016","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/","url":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/","name":"Euro 2016 : L'impact \u00e9conomique","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png","datePublished":"2016-06-08T07:19:06+00:00","dateModified":"2025-08-24T11:26:58+00:00","description":"Quel sera l'impact de l'euro 2016 sur l'\u00e9conomie fran\u00e7aise ? El\u00e9ments de r\u00e9ponses a quelques jours du d\u00e9but de la comp\u00e9tition.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2016\/06\/Euro-2016-Limpact-e\u0301conomique.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-2016-limpact-economique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro 2016 : L&rsquo;impact \u00e9conomique"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=419"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/419\/revisions"}],"predecessor-version":[{"id":605090,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/419\/revisions\/605090"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/150798"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}