{"id":421588,"date":"2023-09-22T13:03:16","date_gmt":"2023-09-22T11:03:16","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=421588&#038;preview=true&#038;preview_id=421588"},"modified":"2023-09-22T16:18:00","modified_gmt":"2023-09-22T14:18:00","slug":"psg-marseille-chaine-tv-et-heure-du-match","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/","title":{"rendered":"PSG &#8211; Marseille : Cha\u00eene TV et Heure du match"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2023-2024\/\" target=\"_blank\" rel=\"noopener\">LIGUE 1 2023-2024<\/a><b> &#8211; Ce dimanche, le Paris Saint-Germain re\u00e7oit l&rsquo;OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.<\/b><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/sondage-pablo-longoria-doit-il-rester-president-de-lom\/\" target=\"_blank\" rel=\"noopener\">Pablo Longoria doit-il rester pr\u00e9sident de l\u2019OM ?<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Comme chaque saison, le <strong>Classico<\/strong> est un des plus grands rendez-vous de la saison de Ligue 1. Les deux clubs ont tous les deux fait leur d\u00e9but en Coupe d&rsquo;Europe cette semaine avec de diverses fortunes. Le <strong>PSG<\/strong> s&rsquo;est impos\u00e9 deux \u00e0 z\u00e9ro face \u00e0 <strong>Dortmund<\/strong> en rendant une copie tr\u00e8s propre gr\u00e2ce notamment \u00e0 un milieu de terrain tr\u00e8s inspir\u00e9 et une grosse prestation d&rsquo;<strong>Achraf Hakimi<\/strong>.<\/p>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Olympique de Marseille<\/strong> s&rsquo;est d\u00e9plac\u00e9 \u00e0 Amsterdam dans une ambiance pesante suite \u00e0 la crise que traverse le club depuis quelques jours. Alors que <strong>Marcelino<\/strong> a quitt\u00e9 le club, <strong>Jacques<\/strong> <strong>Abardonado<\/strong> a dirig\u00e9 sa premi\u00e8re rencontre en <strong>Ligue<\/strong> <strong>Europa<\/strong>. <strong>Marseille<\/strong> a fait preuve de beaucoup de caract\u00e8re <a title=\"Ligue Europa (J1) : L\u2019OM accroche l\u2019Ajax Amsterdam\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-j1-om-accroche-ajax-amsterdam\/\" rel=\"\">pour obtenir un nul trois partout<\/a> face \u00e0 l&rsquo;<strong>Ajax<\/strong> apr\u00e8s avoir \u00e9t\u00e9 men\u00e9 au score presque tout le match.<\/p>\n<ul style=\"text-align: justify;\">\n<li><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2023-2024-6eme-journee-programme-tv-et-resultats\/\">Le programme de la 6\u00e8me journ\u00e9e de Ligue 1<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">En championnat, aucune des deux \u00e9quipes n&rsquo;est dans le top 3 au classement apr\u00e8s cinq journ\u00e9es. L&rsquo;<strong>Olympique de Marseille<\/strong> pointe au cinqui\u00e8me rang avec neuf points en \u00e9tant toujours invaincu alors que le <strong>Paris Saint-Germain<\/strong> est cinqui\u00e8me avec neuf points. Les Parisiens ont d\u00e9j\u00e0 perdu une fois cette saison, face \u00e0 Nice la semaine pass\u00e9e au Parc des Princes.<\/p>\n<p style=\"text-align: justify;\">La saison pass\u00e9e, le <strong>PSG<\/strong> a gagn\u00e9 les deux matchs de championnat, mais l&rsquo;<strong>OM<\/strong> s&rsquo;est impos\u00e9 en <strong>Coupe de France<\/strong>. Chez les bookmakers, le <strong>Paris Saint-Germain<\/strong> est largement favori pour cette rencontre de la 6\u00e8me journ\u00e9e de Ligue 1.<\/p>\n<h2 style=\"text-align: justify;\">Ligue 1 : Le Programme TV du match PSG &#8211; Marseille<\/h2>\n<h3 style=\"text-align: justify;\">Dimanche 24 septembre 2023<\/h3>\n<p style=\"text-align: justify;\"><b>Match diffus\u00e9 sur Amazon Prime Video<\/b><b>\u00a0: <\/b>D\u00e9but du match \u00e0<strong> 20h45.<\/strong><\/p>\n<h2 style=\"text-align: justify;\">Les cotes de PSG &#8211; Marseille<\/h2>\n<table style=\"width: 800px;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"background-color: #404040; text-align: left; border-color: #ededed; width: 500px;\" colspan=\"3\"><span style=\"font-size: 12px; color: #ffffff;\">Dimanche 24 septembre, 20h45<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>PSG<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/42004611?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#091C3E;background-color:#CDFB0A;border-color:#a4c908;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#091C3E;padding:0px 20px;font-size:16px;line-height:32px;border-color:#dcfd54;border-radius:5px;text-shadow:none\"> 1.66<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Match nul<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/42004611?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#091C3E;background-color:#CDFB0A;border-color:#a4c908;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#091C3E;padding:0px 20px;font-size:16px;line-height:32px;border-color:#dcfd54;border-radius:5px;text-shadow:none\"> 4.40<\/span><\/a><\/span><\/td>\n<td style=\"background-color: #ffffff; border-color: #ededed; vertical-align: middle; text-align: center; width: 266px;\"><span style=\"font-size: 10px;\"><span style=\"font-size: 14px;\"><strong>Marseille<\/strong><\/span><br \/>\n<a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/42004611?banid=33423\" class=\"su-button su-button-style-flat su-button-wide\" style=\"color:#091C3E;background-color:#CDFB0A;border-color:#a4c908;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:#091C3E;padding:0px 20px;font-size:16px;line-height:32px;border-color:#dcfd54;border-radius:5px;text-shadow:none\"> 4.80<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en profitant de votre <a href=\"https:\/\/www.winamax.fr\/registration\/landing\/affiliation_Bonus100?banid=33423\">1er d\u00e9p\u00f4t doubl\u00e9 jusqu&rsquo;\u00e0 100 \u20ac<\/a> direct en paris gratuits sur Winamax !<\/p>\n<hr \/>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-complet-ligue-1-2022-2023\/\"><strong>Le classement de la Ligue 1<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-meilleurs-buteurs-ligue-1-2023-2024\/\"><strong>Le classement des meilleurs buteurs de la Ligue 1<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2023-2024 &#8211; Ce dimanche, le Paris Saint-Germain re\u00e7oit l&rsquo;OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.<\/p>\n","protected":false},"author":1,"featured_media":421611,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301,47045],"tags":[5460,17213,75,21872,21768,1554,449,8799],"class_list":["post-421588","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-brest","tag-chaine","tag-football","tag-heure","tag-horaire","tag-ligue-1","tag-lyon","tag-programme-tv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PSG - Marseille : Cha\u00eene TV et Heure du match<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l&#039;OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PSG - Marseille : Cha\u00eene TV et Heure du match\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l&#039;OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-22T11:03:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-22T14:18:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"PSG - Marseille : Cha\u00eene TV et Heure du match\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"PSG &#8211; Marseille : Cha\u00eene TV et Heure du match\",\"datePublished\":\"2023-09-22T11:03:16+00:00\",\"dateModified\":\"2023-09-22T14:18:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png\",\"keywords\":[\"Brest\",\"Cha\u00eene\",\"Football\",\"Heure\",\"Horaire\",\"Ligue 1\",\"Lyon\",\"Programme TV\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\",\"name\":\"PSG - Marseille : Cha\u00eene TV et Heure du match\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png\",\"datePublished\":\"2023-09-22T11:03:16+00:00\",\"dateModified\":\"2023-09-22T14:18:00+00:00\",\"description\":\"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l'OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png\",\"width\":800,\"height\":445,\"caption\":\"Randal Kolo Muani - PSG\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PSG &#8211; Marseille : Cha\u00eene TV et Heure du match\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"PSG - Marseille : Cha\u00eene TV et Heure du match","description":"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l'OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/","og_locale":"fr_FR","og_type":"article","og_title":"PSG - Marseille : Cha\u00eene TV et Heure du match","og_description":"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l'OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","og_url":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-09-22T11:03:16+00:00","article_modified_time":"2023-09-22T14:18:00+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"PSG - Marseille : Cha\u00eene TV et Heure du match","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"PSG &#8211; Marseille : Cha\u00eene TV et Heure du match","datePublished":"2023-09-22T11:03:16+00:00","dateModified":"2023-09-22T14:18:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png","keywords":["Brest","Cha\u00eene","Football","Heure","Horaire","Ligue 1","Lyon","Programme TV"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/","url":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/","name":"PSG - Marseille : Cha\u00eene TV et Heure du match","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png","datePublished":"2023-09-22T11:03:16+00:00","dateModified":"2023-09-22T14:18:00+00:00","description":"LIGUE 1 2023-2024 - Ce dimanche, le Paris Saint-Germain re\u00e7oit l'OM dans le cadre de la 6\u00e8me journ\u00e9e de Ligue 1. D\u00e9couvrez le programme TV.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/PSG-Marseille-Chaine-TV-Heure-du-match.png","width":800,"height":445,"caption":"Randal Kolo Muani - PSG"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/psg-marseille-chaine-tv-et-heure-du-match\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"PSG &#8211; Marseille : Cha\u00eene TV et Heure du match"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/421588","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=421588"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/421588\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/421611"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=421588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=421588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=421588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}