{"id":423406,"date":"2023-09-28T16:01:31","date_gmt":"2023-09-28T14:01:31","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=423406&#038;preview=true&#038;preview_id=423406"},"modified":"2023-09-28T19:00:03","modified_gmt":"2023-09-28T17:00:03","slug":"baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/","title":{"rendered":"Baseball : Les Bleus battus au bout du suspense en quarts de l&rsquo;Euro"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><b>CHAMPIONNAT D&rsquo;EUROPE MASCULIN DE BASEBALL &#8211; La victoire \u00e9tait \u00e0 port\u00e9e de main, mais les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l&rsquo;Allemagne, et ne verront pas le dernier carr\u00e9 de l&rsquo;Euro.\u00a0<\/b><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Apr\u00e8s une phase de poule ma\u00eetris\u00e9e (2 victoires &#8211; 1 d\u00e9faite), l&rsquo;\u00e9quipe de France masculine de baseball abordait les quarts de finale avec la volont\u00e9 de faire un coup. L&rsquo;affaire s&rsquo;annon\u00e7ait toutefois compliqu\u00e9e pour les Bleus, puisqu&rsquo;ils affrontaient une \u00e9quipe d&rsquo;Allemagne sortie invaincue de son groupe, avec notamment une victoire sur les redoutables Isra\u00e9liens. Mais les Fran\u00e7ais n&rsquo;avaient clairement rien \u00e0 perdre.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Si pr\u00e8s du grand bonheur<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\">Et l&rsquo;ont prouv\u00e9 en r\u00e9pondant rapidement \u00e0 l&rsquo;ouverture du score adverse, \u00e9galisant d\u00e8s la deuxi\u00e8me manche, avant de voir les Allemands marquer de nouveau dans la cinqui\u00e8me. Cette fois, les Bleus semblaient ne pas avoir la solution, mais ont totalement renvers\u00e9 le match dans l&rsquo;avant-derni\u00e8re manche, gr\u00e2ce \u00e0 <strong>Ma\u00ebl Zan<\/strong> et <strong>Ernesto Martinez<\/strong>, avant de porter l&rsquo;estocade dans la derni\u00e8re pour mener 5-2 et plier le match. Du moins, c&rsquo;est ce qu&rsquo;on croyait.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Car les Bleus vont craquer au pire moment, et les derniers jeux allemands vont rapporter in extremis les trois points n\u00e9cessaires pour aller forcer une manche suppl\u00e9mentaire. Et comme on pouvait le craindre \u00e0 ce moment-l\u00e0, elle sera fatale aux Bleus, qui s&rsquo;inclinent 6-5 et ratent une belle opportunit\u00e9 de rejoindre le dernier carr\u00e9 de l&rsquo;Euro pour la premi\u00e8re fois depuis 2001. Rageant.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La France s&rsquo;incline 6-5 en manche suppl\u00e9mentaire face \u00e0 l&rsquo;Allemagne en 1\/4 de finale de l&rsquo;Euro Baseball 2023. <a href=\"https:\/\/t.co\/EEbK5rNjgi\">https:\/\/t.co\/EEbK5rNjgi<\/a> <a href=\"https:\/\/t.co\/x9bgGeSoOZ\">pic.twitter.com\/x9bgGeSoOZ<\/a><\/p>\n<p>\u2014 France Baseball Softball \u26be\ufe0f \ud83e\udd4e\ud83d\udd90 (@ffbs_baseball) <a href=\"https:\/\/twitter.com\/ffbs_baseball\/status\/1707396860099334171?ref_src=twsrc%5Etfw\">September 28, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNAT D&rsquo;EUROPE MASCULIN DE BASEBALL &#8211; La victoire \u00e9tait \u00e0 port\u00e9e de main, mais les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l&rsquo;Allemagne, et ne verront pas le dernier carr\u00e9 de l&rsquo;Euro.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":422886,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[10077],"tags":[16878],"class_list":["post-423406","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baseball","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Baseball : Les Bleus battus au bout du suspense en quarts de l&#039;Euro<\/title>\n<meta name=\"description\" content=\"CHAMPIONNAT D&#039;EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l&#039;Allemagne.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baseball : Les Bleus battus au bout du suspense en quarts de l&#039;Euro\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNAT D&#039;EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l&#039;Allemagne.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-28T14:01:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-28T17:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Baseball : Les Bleus battus au bout du suspense en quarts de l&#039;Euro\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Baseball : Les Bleus battus au bout du suspense en quarts de l&rsquo;Euro\",\"datePublished\":\"2023-09-28T14:01:31+00:00\",\"dateModified\":\"2023-09-28T17:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\"},\"wordCount\":317,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Baseball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\",\"name\":\"Baseball : Les Bleus battus au bout du suspense en quarts de l'Euro\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png\",\"datePublished\":\"2023-09-28T14:01:31+00:00\",\"dateModified\":\"2023-09-28T17:00:03+00:00\",\"description\":\"CHAMPIONNAT D'EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l'Allemagne.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png\",\"width\":800,\"height\":445,\"caption\":\"Baseball Les Bleus battus au bout du suspense en quarts de l'Euro\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baseball : Les Bleus battus au bout du suspense en quarts de l&rsquo;Euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baseball : Les Bleus battus au bout du suspense en quarts de l'Euro","description":"CHAMPIONNAT D'EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l'Allemagne.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/","og_locale":"fr_FR","og_type":"article","og_title":"Baseball : Les Bleus battus au bout du suspense en quarts de l'Euro","og_description":"CHAMPIONNAT D'EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l'Allemagne.","og_url":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-09-28T14:01:31+00:00","article_modified_time":"2023-09-28T17:00:03+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Baseball : Les Bleus battus au bout du suspense en quarts de l'Euro","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Baseball : Les Bleus battus au bout du suspense en quarts de l&rsquo;Euro","datePublished":"2023-09-28T14:01:31+00:00","dateModified":"2023-09-28T17:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/"},"wordCount":317,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png","keywords":["br\u00e8ve"],"articleSection":["Baseball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/","url":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/","name":"Baseball : Les Bleus battus au bout du suspense en quarts de l'Euro","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png","datePublished":"2023-09-28T14:01:31+00:00","dateModified":"2023-09-28T17:00:03+00:00","description":"CHAMPIONNAT D'EUROPE MASCULIN DE BASEBALL - les Bleus ont fini par c\u00e9der en manche suppl\u00e9mentaire contre l'Allemagne.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Baseball-Les-Bleus-en-route-vers-les-quarts-de-finale-de-lEuro.png","width":800,"height":445,"caption":"Baseball Les Bleus battus au bout du suspense en quarts de l'Euro"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/baseball-les-bleus-battus-au-bout-du-suspense-en-quarts-de-leuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Baseball : Les Bleus battus au bout du suspense en quarts de l&rsquo;Euro"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/423406","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=423406"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/423406\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/422886"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=423406"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=423406"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=423406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}