{"id":423920,"date":"2023-09-29T18:56:00","date_gmt":"2023-09-29T16:56:00","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=423920&#038;preview=true&#038;preview_id=423920"},"modified":"2023-09-29T19:27:25","modified_gmt":"2023-09-29T17:27:25","slug":"coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/","title":{"rendered":"Coupe du monde masculine de basket 3&#215;3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a title=\"Calendrier et r\u00e9sultats Coupe du monde masculine de basket 3\u00d73 U23 2023\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-coupe-du-monde-masculine-de-basket-3x3-u23-2023\/\" target=\"_blank\" rel=\"noopener\">COUPE DU MONDE MASCULINE U23 3&#215;3<\/a> &#8211; Deux nouvelles victoires pour les Fran\u00e7ais qui se qualifient pour les quarts de finale o\u00f9 ils affronteront la Lituanie.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Mercredi, les Fran\u00e7ais ont parfaitement d\u00e9but\u00e9 avec <strong>deux victoires<\/strong>. D&rsquo;abord, une inesp\u00e9r\u00e9e en prolongations sur un <a href=\"https:\/\/twitter.com\/3x3ffbb\/status\/1707054707842105720\" target=\"_blank\" rel=\"noopener\">shoot improbable de Baptiste Oger<\/a> pour battre la <strong>Roumanie<\/strong> (17-15). Puis en battant avec autorit\u00e9 la <strong>Pologne<\/strong>, tenante du titre et h\u00f4te de la comp\u00e9tition (21-13).<\/p>\n<p style=\"text-align: justify;\">Et ils ont continu\u00e9 aujourd&rsquo;hui. Le match face \u00e0 l&rsquo;<strong>Autriche<\/strong> est parti sur les chapeaux de roue. Moins de 30 secondes de jeu et d\u00e9j\u00e0 4 shoots (3-3). Avec <strong>Math\u00e9o Cauwet<\/strong> qui r\u00e9pond au panier \u00e0 2 points de <strong>Nico Kaltenbrunner<\/strong>. Les Fran\u00e7ais monopolisent le ballon et imposent une grosse d\u00e9fense \u00e0 leurs adversaires. Qui sont pouss\u00e9s \u00e0 prendre des tirs ext\u00e9rieurs. Les Bleus font la course en t\u00eate mais un bon passage des Autrichiens leur permet de revenir \u00e0 \u00e9galit\u00e9 (12-12). Mais \u00e0 5 minutes de la fin, ceux-ci se retrouvent d\u00e9j\u00e0 dans la p\u00e9nalit\u00e9 (7 fautes). Les Fran\u00e7ais continuent leur course en t\u00eate mais l&rsquo;Autriche reste au contact. Sur la ligne des lancers, Oger donne finalement la victoire aux siens (21-17).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/3x3U23?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3U23<\/a> | Les Bleus restent en t\u00eate de la poule grace \u00e0 la win 21-17 contre l\u2019Autriche \ud83d\ude4c<\/p>\n<p>\u23ef\ufe0f Dernier match de poule contre le B\u00e9nin \u00e0 18h35 en direct sur <a href=\"https:\/\/t.co\/prCOZ8bFvu\">https:\/\/t.co\/prCOZ8bFvu<\/a> et YouTube <a href=\"https:\/\/twitter.com\/FIBA3x3?ref_src=twsrc%5Etfw\">@fiba3x3<\/a> \ud83c\uddeb\ud83c\uddf7\u26a1\ufe0f\ud83c\udde7\ud83c\uddef <a href=\"https:\/\/t.co\/sjHON4PceD\">pic.twitter.com\/sjHON4PceD<\/a><\/p>\n<p>\u2014 3&#215;3 FFBB (@3x3ffbb) <a href=\"https:\/\/twitter.com\/3x3ffbb\/status\/1707773023829320148?ref_src=twsrc%5Etfw\">September 29, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pour leur dernier match, les Fran\u00e7ais affrontaient le <strong>B\u00e9nin<\/strong>. En mode diesel, ils ont pris les commandes du match. <strong>Herv\u00e9 Jean-Pierre <\/strong>a encha\u00een\u00e9 les paniers \u00e0 2 points. Avec s\u00e9rieux, les Fran\u00e7ais ont poursuivi leur domination. <strong>Math\u00e9o Cauwet<\/strong>\u00a0prenant le relais de Jean-Pierre avec l&rsquo;encha\u00eenement de 3 paniers \u00e0 2 points.\u00a0 La France s&rsquo;impose finalement 21-9 et termine premi\u00e8re de son groupe. Les Bleuets sont qualifi\u00e9s pour les quarts, o\u00f9 ils affronteront un gros morceau : la <strong>Lituanie<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/3x3U23?src=hash&amp;ref_src=twsrc%5Etfw\">#3x3U23<\/a> | Les Bleus se qualifient en quarts, suppl\u00e9ment premiers de la poule apr\u00e8s la victoire 21-9 contre le B\u00e9nin \ud83d\udd25<\/p>\n<p>\u23ef\ufe0f Quarts de finale : 13h50 dimanche 1er octobre face \u00e0 la Lituanie \ud83c\uddeb\ud83c\uddf7\u26a1\ufe0f\ud83c\uddf1\ud83c\uddf9 <a href=\"https:\/\/t.co\/XiXBYWuYG6\">pic.twitter.com\/XiXBYWuYG6<\/a><\/p>\n<p>\u2014 3&#215;3 FFBB (@3x3ffbb) <a href=\"https:\/\/twitter.com\/3x3ffbb\/status\/1707805067473043617?ref_src=twsrc%5Etfw\">September 29, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE MASCULINE U23 3&#215;3 &#8211; Deux nouvelles victoires pour les Fran\u00e7ais qui se qualifient pour les quarts de finale o\u00f9 ils affronteront la Lituanie.<\/p>\n","protected":false},"author":12,"featured_media":423956,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[27116],"tags":[9140,16878],"class_list":["post-423920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball-3x3","tag-basket-3x3","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-09-29T16:56:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-29T17:27:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Coupe du monde masculine de basket 3&#215;3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\",\"datePublished\":\"2023-09-29T16:56:00+00:00\",\"dateModified\":\"2023-09-29T17:27:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png\",\"keywords\":[\"Basket 3x3\",\"br\u00e8ve\"],\"articleSection\":[\"Basket-ball 3x3\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/\",\"name\":\"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png\",\"datePublished\":\"2023-09-29T16:56:00+00:00\",\"dateModified\":\"2023-09-29T17:27:25+00:00\",\"description\":\"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde masculine de basket 3x3 U23 2023 Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde masculine de basket 3&#215;3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Shiclette94\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/arlette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale","description":"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale","og_description":"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-09-29T16:56:00+00:00","article_modified_time":"2023-09-29T17:27:25+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Coupe du monde masculine de basket 3&#215;3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale","datePublished":"2023-09-29T16:56:00+00:00","dateModified":"2023-09-29T17:27:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png","keywords":["Basket 3x3","br\u00e8ve"],"articleSection":["Basket-ball 3x3"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/","name":"Coupe du monde masculine de basket 3x3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png","datePublished":"2023-09-29T16:56:00+00:00","dateModified":"2023-09-29T17:27:25+00:00","description":"COUPE DU MONDE MASCULINE U23 3x3 - Deux nouvelles victoires pour les Fran\u00e7ais qui affronteront la Lituanie en quarts de finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/09\/Coupe-du-monde-masculine-de-basket-3x3-U23-2023-Sans-faute-pour-les-Francais-qualifies.png","width":800,"height":445,"caption":"Coupe du monde masculine de basket 3x3 U23 2023 Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-masculine-de-basket-3x3-u23-2023-sans-faute-pour-les-francais-qualifies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde masculine de basket 3&#215;3 U23 2023 : Sans-faute pour les Fran\u00e7ais qualifi\u00e9s pour les quarts de finale"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/423920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=423920"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/423920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/423956"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=423920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=423920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=423920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}