{"id":426502,"date":"2023-10-05T20:40:54","date_gmt":"2023-10-05T18:40:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=426502&#038;preview=true&#038;preview_id=426502"},"modified":"2023-10-06T07:10:36","modified_gmt":"2023-10-06T05:10:36","slug":"ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/","title":{"rendered":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>LIGUE EUROPA CONF\u00c9RENCE &#8211; Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0). Du haut de ses 800 000 \u20ac de budget, le club des Iles F\u00e9ro\u00e9 a tenu t\u00eate aux Lillois tout au long de la partie, pour prendre un point historique en coupe d&rsquo;Europe.<\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Budget 120 fois sup\u00e9rieur pour un score nul<\/h2>\n<p align=\"justify\">C&rsquo;\u00e9tait un vrai choc des mondes ce jeudi soir entre<strong> Klaksvik<\/strong> et <strong>Lille.<\/strong> Le club des Iles F\u00e9ro\u00e9 ne poss\u00e8de qu&rsquo;un tr\u00e8s modeste budget, inf\u00e9rieur au million d&rsquo;euros (800 000 \u20ac). Pour donner un point de comparaison, le budget moyen d&rsquo;un club de National 2 (quatri\u00e8me division) est quasiment deux fois sup\u00e9rieur &#8211; on parle de 1,3 million d&rsquo;euros, d\u00e9j\u00e0 une vraie diff\u00e9rence. Un autre monde par rapport aux 100 millions d&rsquo;euros du LOSC, install\u00e9 dans le haut du panier en Ligue 1.<\/p>\n<p align=\"justify\">Souvent, les clubs fran\u00e7ais ont avanc\u00e9 la diff\u00e9rence de budget pour expliquer les mauvais r\u00e9sultats en Coupe d&rsquo;Europe, par rapport \u00e0 la riche Premier League. Argument qui pourrait s&rsquo;entendre, si des clubs ayant moins de budget que des clubs de Ligue 1, avaient gagn\u00e9 des Coupes d&rsquo;Europe au 21\u1d49 si\u00e8cle. Et face \u00e0<strong> Klaksvik<\/strong>, qui a franchi des tours de qualification en Ligue des Champions, le LOSC n&rsquo;a clairement pas su trouver la cl\u00e9 de la victoire.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Domination st\u00e9rile des Lillois<\/h2>\n<p align=\"justify\">Une fois qu&rsquo;on a parl\u00e9 de la diff\u00e9rence de budget, il convient de dire que Lille aurait pu gagner ce match. Voire aurait d\u00fb, tant le diff\u00e9rentiel entre les \u00e9quipes, en termes d&rsquo;occasions, a \u00e9t\u00e9 flagrant ce soir.<\/p>\n<p align=\"justify\">Treize tirs \u00e0 deux, 70 % possession de balle pour les Lillois. Le premier \u00e9clair de ce match vient de<strong> Yusuf Yazici<\/strong>, le joueur le plus incisif du LOSC ce jeudi soir. Sa frappe, apr\u00e8s un encha\u00eenement tr\u00e8s rapide, meurt \u00e0 quelques centim\u00e8tres de la lucarne adverse (19\u1d49). <strong>Hakon Haraldsson<\/strong>, bien lanc\u00e9 en profondeur, voit sa frappe flirter avec le montant (29\u1d49). Pas plus de r\u00e9ussite pour <strong>Gabriel Gudmundsson<\/strong> (43\u1d49). La deuxi\u00e8me mi-temps confirmera la tendance.<strong> Yusuf Yazici<\/strong> (49\u1d49, 70\u1d49) va se casser les dents sur ses tentatives. Comme<strong> Alan Virginius<\/strong>, qui voit sa magnifique frappe, dans la surface, fracasser la barre (56\u1d49). Pire encore, le LOSC a sembl\u00e9 \u00e0 la fois impuissant et fatigu\u00e9 dans le dernier quart d&rsquo;heure. Comme s&rsquo;il s&rsquo;\u00e9tait content\u00e9 de ce bien triste 0-0.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">C&rsquo;est termin\u00e9, match nul face au K\u00cd Klaksv\u00edk.<\/p>\n<p>Dans un match verrouill\u00e9 contre une \u00e9quipe f\u00e9ro\u00efenne bien organis\u00e9e, les Dogues n\u2019ont pas su trouver l\u2019inspiration n\u00e9cessaire pour percer le coffre-fort adverse (0-0).<a href=\"https:\/\/twitter.com\/hashtag\/KILOSC?src=hash&amp;ref_src=twsrc%5Etfw\">#KILOSC<\/a> 0-0 | 90&prime;<\/p>\n<p>\u2014 LOSC (@losclive) <a href=\"https:\/\/twitter.com\/losclive\/status\/1710001052806795453?ref_src=twsrc%5Etfw\">October 5, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p align=\"justify\">On se souviendra que c&rsquo;est un club fran\u00e7ais qui offre le premier point de l&rsquo;histoire en Coupe d&rsquo;Europe \u00e0 un club des Iles F\u00e9ro\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE EUROPA CONF\u00c9RENCE &#8211; Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0). Du haut de ses 800 000 \u20ac de budget, le club des Iles F\u00e9ro\u00e9 a tenu t\u00eate aux Lillois tout au long de la partie, pour prendre un point historique en coupe d&rsquo;Europe.<\/p>\n","protected":false},"author":83,"featured_media":426528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[16878,75,451,19345,2391],"class_list":["post-426502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-football","tag-lille","tag-lille-osc","tag-losc"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik<\/title>\n<meta name=\"description\" content=\"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik\" \/>\n<meta property=\"og:description\" content=\"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-05T18:40:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-06T05:10:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik\",\"datePublished\":\"2023-10-05T18:40:54+00:00\",\"dateModified\":\"2023-10-06T05:10:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\"},\"wordCount\":499,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Lille\",\"Lille OSC\",\"LOSC\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\",\"name\":\"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png\",\"datePublished\":\"2023-10-05T18:40:54+00:00\",\"dateModified\":\"2023-10-06T05:10:36+00:00\",\"description\":\"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue Europa Conf\u00e9rence Match nul bien nul pour le LOSC \u00e0 Klaksvik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik","description":"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik","og_description":"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-10-05T18:40:54+00:00","article_modified_time":"2023-10-06T05:10:36+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik","datePublished":"2023-10-05T18:40:54+00:00","dateModified":"2023-10-06T05:10:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/"},"wordCount":499,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png","keywords":["br\u00e8ve","Football","Lille","Lille OSC","LOSC"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/","name":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png","datePublished":"2023-10-05T18:40:54+00:00","dateModified":"2023-10-06T05:10:36+00:00","description":"LIGUE EUROPA CONF\u00c9RENCE - Le LOSC a conc\u00e9d\u00e9 un bien triste match nul sur la pelouse de Klaksvik, le petit poucet de la poule (0-0).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Ligue-Europa-Conference-Match-nul-bien-nul-pour-le-LOSC-a-Klaksvik.png","width":800,"height":445,"caption":"Ligue Europa Conf\u00e9rence Match nul bien nul pour le LOSC \u00e0 Klaksvik"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-conference-j2-match-nul-bien-nul-pour-le-losc-a-klaksvik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue Europa Conf\u00e9rence (J2) : Match nul, bien nul, pour le LOSC \u00e0 Klaksvik"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/426502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=426502"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/426502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/426528"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=426502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=426502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=426502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}