{"id":426994,"date":"2023-10-07T15:51:51","date_gmt":"2023-10-07T13:51:51","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=426994&#038;preview=true&#038;preview_id=426994"},"modified":"2023-10-07T16:21:32","modified_gmt":"2023-10-07T14:21:32","slug":"mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/","title":{"rendered":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&rsquo;offre Simone Biles au saut, Coline Devillard derni\u00e8re"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a title=\"Programme et r\u00e9sultats Gymnastique artistique Championnats du monde 2023\" href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-gymnastique-artistique-championnats-du-monde-2023\/\" target=\"_blank\" rel=\"noopener\">MONDIAUX GYMNASTIQUE ARTISTIQUE 2023<\/a> \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devan\u00e7ant Simone Biles et Seojeong Yeo.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Simone Biles<\/strong> a ouvert la finale du saut. Sur le nouveau nomm\u00e9 \u00ab\u00a0<strong>Biles II<\/strong>\u00ab\u00a0, l&rsquo;Am\u00e9ricaine a r\u00e9alis\u00e9 un Yurchenko double carp\u00e9 o\u00f9 elle est all\u00e9e tr\u00e8s haut et est retomb\u00e9e sur le dos. Malgr\u00e9 la p\u00e9nalit\u00e9 car son entraineur \u00e9tait sur le tapis, elle obtient 14.433. C&rsquo;est la seule \u00e0 pr\u00e9senter un saut de cette difficult\u00e9 (6.400). Avec 14.666 pour son <a href=\"https:\/\/twitter.com\/SportNMedia\/status\/1710641146924347443\">deuxi\u00e8me saut<\/a>, elle obtient une moyenne de 14.549.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"zxx\"><a href=\"https:\/\/t.co\/Xh1nk6LcBa\">pic.twitter.com\/Xh1nk6LcBa<\/a><\/p>\n<p>\u2014 SportMedia (@SportNMedia) <a href=\"https:\/\/twitter.com\/SportNMedia\/status\/1710641423568023573?ref_src=twsrc%5Etfw\">October 7, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Coline Devillard trop juste<\/h2>\n<p style=\"text-align: justify;\"><strong>Coline Devillard<\/strong> passait juste apr\u00e8s Simone Biles, en deuxi\u00e8me position. Sur son premier saut en lune vrille et demie, sa main touche le tapis \u00e0 la fin. Elle obtient 13.200. Elle devait ensuite effectuer un Yurchenko double vrille mais une seule vrille. Elle obtient une moyenne de 13.183.<\/p>\n<p style=\"text-align: justify;\">Suite \u00e0 une d\u00e9chirure au niveau de la fesse 3 jours avant le d\u00e9part pour les Mondiaux, la Fran\u00e7aise n&rsquo;a pas d\u00e9but\u00e9 la comp\u00e9tition de la mani\u00e8re la plus sereine. Ce qui ne l&rsquo;a pas emp\u00each\u00e9 d&rsquo;assurer pour l&rsquo;\u00e9quipe lors des qualifications et de la finale et de s&rsquo;offrir \u00e9galement une finale en individuel.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">Apr\u00e8s ce qu&rsquo;on a fait en \u00e9quipe, j&rsquo;avais dit que c&rsquo;\u00e9tait que du plus. J&rsquo;ai r\u00e9ussi \u00e0 me qualifier en finale avec une vrille. Au premier saut j&rsquo;\u00e9tais bien, j&rsquo;\u00e9tais en jambes. Il y a eu un petit truc qui a fait que \u00e7a n&rsquo;a pas fonctionn\u00e9. Au vu du premier saut, j&rsquo;ai d\u00e9cid\u00e9 de faire seulement une vrille aussi au deuxi\u00e8me. Je me lan\u00e7ais en double vrille seulement si mon premier saut \u00e9tait bien parce que je n&rsquo;\u00e9tais pas forc\u00e9ment pr\u00eate pour la double vrille. J&rsquo;ai fait une ann\u00e9e avec pas mal de r\u00e9ussite sur le premier saut sur le tour. Et le plus important c&rsquo;est de repartir avec de l&rsquo;exp\u00e9rience, un ticket pour les Jeux et une m\u00e9daille en \u00e9quipes.<\/p>\n<\/blockquote>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"zxx\"><a href=\"https:\/\/t.co\/88T9IEgOfD\">pic.twitter.com\/88T9IEgOfD<\/a><\/p>\n<p>\u2014 SportMedia (@SportNMedia) <a href=\"https:\/\/twitter.com\/SportNMedia\/status\/1710643721950105805?ref_src=twsrc%5Etfw\">October 7, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Troisi\u00e8me m\u00e9daille pour Rebeca Andrade \u00e0 Anvers<\/h2>\n<p style=\"text-align: justify;\"><strong>Rebeca Andrade<\/strong> cl\u00f4turait cette finale. Et elle a parfaitement d\u00e9but\u00e9 avec un Cheng magnifiquement ex\u00e9cut\u00e9 : 15.000. Yurchenko double twist pour son deuxi\u00e8me saut et elle obtient une moyenne de 14.750. Elle passe ainsi devant l&rsquo;Am\u00e9ricaine et devient championne du monde pour la deuxi\u00e8me fois apr\u00e8s 2021 ! La championne olympique en titre remporte ainsi sa 3e m\u00e9daille de la comp\u00e9tition apr\u00e8s l&rsquo;argent par \u00e9quipes et lors du concours g\u00e9n\u00e9ral. Le podium est compl\u00e9t\u00e9 par la Sud-Cor\u00e9enne <strong>Seojeong Yeo<\/strong> (14.416). L&rsquo;ann\u00e9e derni\u00e8re, elle avait termin\u00e9 7e.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"zxx\"><a href=\"https:\/\/t.co\/e2c8iJTvT5\">pic.twitter.com\/e2c8iJTvT5<\/a><\/p>\n<p>\u2014 SportMedia (@SportNMedia) <a href=\"https:\/\/twitter.com\/SportNMedia\/status\/1710650924551553278?ref_src=twsrc%5Etfw\">October 7, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Coline Devillard : \u00ab\u00a0C&rsquo;\u00e9tait une finale stratosph\u00e9rique\u00a0\u00bb<\/h2>\n<blockquote>\n<p style=\"text-align: justify;\">C&rsquo;\u00e9tait une finale stratosph\u00e9rique. En vrai c&rsquo;\u00e9tait fou ! 1, 2 c&rsquo;\u00e9tait s\u00fbr. 3e, trop contente pour la Cor\u00e9enne parce qu&rsquo;elle fait 2 sauts magnifiques. Le reste c&rsquo;\u00e9tait bien, c&rsquo;\u00e9tait une finale presque sans chute. Simone tombe sur double carp\u00e9 et sort quand m\u00eame 14.4. J&rsquo;\u00e9tais hyper contente de pouvoir faire une finale avec Simone et Rebeca. C&rsquo;est quand m\u00eame deux grosses t\u00eates d&rsquo;affiche. Je me construis pour Paris.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">En faisant \u00ab\u00a02 beaux sauts\u00a0\u00bb, la Fran\u00e7aise estimait pouvoir finir \u00e0 la 4e place. Quant \u00e0 l&rsquo;\u00e9volution \u00e0 apporter \u00e0 ses sauts pour aller chercher une 3e place, elle estime que le travail se situe sur son 2e saut. Et qu&rsquo;\u00e0 l&rsquo;heure actuelle, c&rsquo;est peut-\u00eatre plus mental que physique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.<\/p>\n","protected":false},"author":12,"featured_media":427050,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10429],"tags":[16878,1595,6587],"class_list":["post-426994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gymnastique","tag-breve","tag-coline-devillard","tag-simone-biles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&#039;offre Simone Biles au saut, Coline Devillard derni\u00e8re<\/title>\n<meta name=\"description\" content=\"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&#039;offre Simone Biles au saut, Coline Devillard derni\u00e8re\" \/>\n<meta property=\"og:description\" content=\"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-07T13:51:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-07T14:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&#039;offre Simone Biles au saut, Coline Devillard derni\u00e8re\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&rsquo;offre Simone Biles au saut, Coline Devillard derni\u00e8re\",\"datePublished\":\"2023-10-07T13:51:51+00:00\",\"dateModified\":\"2023-10-07T14:21:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\"},\"wordCount\":638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png\",\"keywords\":[\"br\u00e8ve\",\"Coline Devillard\",\"Simone Biles\"],\"articleSection\":[\"Gymnastique\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\",\"name\":\"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png\",\"datePublished\":\"2023-10-07T13:51:51+00:00\",\"dateModified\":\"2023-10-07T14:21:32+00:00\",\"description\":\"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png\",\"width\":800,\"height\":445,\"caption\":\"Mondiaux Gymnastique artistique 2023 Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&rsquo;offre Simone Biles au saut, Coline Devillard derni\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re","description":"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/","og_locale":"fr_FR","og_type":"article","og_title":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re","og_description":"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.","og_url":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-10-07T13:51:51+00:00","article_modified_time":"2023-10-07T14:21:32+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&rsquo;offre Simone Biles au saut, Coline Devillard derni\u00e8re","datePublished":"2023-10-07T13:51:51+00:00","dateModified":"2023-10-07T14:21:32+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/"},"wordCount":638,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png","keywords":["br\u00e8ve","Coline Devillard","Simone Biles"],"articleSection":["Gymnastique"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/","url":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/","name":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png","datePublished":"2023-10-07T13:51:51+00:00","dateModified":"2023-10-07T14:21:32+00:00","description":"MONDIAUX GYMNASTIQUE ARTISTIQUE 2023 \u2013 Belle finale du saut o\u00f9 Rebeca Andrade remporte un second titre, devant Simone Biles et Seojeong Yeo.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Mondiaux-Gymnastique-artistique-2023-Rebeca-Andrade-soffre-Simone-Biles-au-saut-Coline-Devillard-derniere.png","width":800,"height":445,"caption":"Mondiaux Gymnastique artistique 2023 Rebeca Andrade s'offre Simone Biles au saut, Coline Devillard derni\u00e8re"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-gymnastique-artistique-2023-rebeca-andrade-soffre-simone-biles-au-saut-coline-devillard-derniere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mondiaux Gymnastique artistique 2023 : Rebeca Andrade s&rsquo;offre Simone Biles au saut, Coline Devillard derni\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/426994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=426994"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/426994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/427050"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=426994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=426994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=426994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}