{"id":430989,"date":"2023-10-21T11:38:21","date_gmt":"2023-10-21T09:38:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=430989&#038;preview=true&#038;preview_id=430989"},"modified":"2023-10-21T12:41:33","modified_gmt":"2023-10-21T10:41:33","slug":"nice-marseille-les-compositions-probables","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/","title":{"rendered":"Nice &#8211; Marseille : Les compositions probables"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/classement-ligue-1-2023-2024\/\" target=\"_blank\" rel=\"noopener\">LIGUE 1 2023-2024<\/a><b>\u00a0\u2013<\/b> Selon L&rsquo;\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0<\/strong><\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/nice-marseille-chaine-tv-et-heure-du-match\/\" target=\"_blank\" rel=\"noopener\">Nice \u2013 Marseille : Cha\u00eene TV et Heure du match<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Choc en Ligue 1 entre deux pr\u00e9tendants aux comp\u00e9titions europ\u00e9ennes alors que Nice a quatre points d&rsquo;avance sur Marseille avant ce match. <strong>Francesco<\/strong> <strong>Farioli<\/strong> devrait aligner une \u00e9quipe tr\u00e8s similaire \u00e0 celle qui a battu <strong>Metz<\/strong> avant la tr\u00eave internationale. <strong>Kh\u00e9phren Thuram<\/strong> est suspendu et devrait donc \u00eatre le seul changement dans le onze de d\u00e9part. <strong>Morgan<\/strong> <strong>Sanson<\/strong> devrait donc d\u00e9buter.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi \u2013\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-2023-2024-9eme-journee-programme-tv-et-resultats\/\">Le programme de la 9\u00e8me journ\u00e9e de Ligue 1<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">C\u00f4t\u00e9 OM, <strong>Gennaro<\/strong> <strong>Gattuso<\/strong> veut encha\u00eener apr\u00e8s avoir obtenu sa premi\u00e8re victoire depuis sa prise de fonction lors de la r\u00e9ception du Havre. <strong>Samuel<\/strong> <strong>Gigot<\/strong> est forfait et devrait \u00eatre remplac\u00e9 par <strong>Leonardo<\/strong> <strong>Balerdi<\/strong> en d\u00e9fense centrale. Devant la d\u00e9fense, pas de surprise puisque <strong>Valentin<\/strong> <strong>Rongier<\/strong> et <strong>Jordan<\/strong> <strong>Veretout<\/strong> seront probablement align\u00e9s.<\/p>\n<p style=\"text-align: justify;\"><strong>Amine<\/strong> <strong>Harit<\/strong> devrait \u00eatre pr\u00e9f\u00e9r\u00e9 \u00e0 <strong>Azzedine<\/strong> <strong>Ounahi<\/strong> au poste de num\u00e9ro 10 alors qu&rsquo;<strong>Iliman Ndiaye<\/strong> et <strong>Isma\u00efla<\/strong> <strong>Sarr<\/strong> sont attendus dans les couloirs. Enfin, pour le poste d&rsquo;avant-centre, l&rsquo;entra\u00eeneur italien devrait maintenir sa confiance \u00e0 <strong>Pierre-Emerick Aubameyang<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">La composition probable de Nice face \u00e0 Marseille<\/h2>\n<p style=\"text-align: justify;\">Bulka \u2013 Lotomba, Todibo, Dant\u00e9, Bard \u2013 Sanson, Ndayishimiye, Boudaoui \u2013 Laborde, Boga, Moffi.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">La composition probable de Marseille face \u00e0 Nice<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\">Pau Lopez &#8211; Clauss, Mbemba, Balerdi, Lodi &#8211; Veretout, Rongier (cap.) &#8211; Ndiaye, Harit, Sarr &#8211; Aubameyang.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/classement-complet-ligue-1-2022-2023\/\"><strong>Le classement de la Ligue 1<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2023-2024\u00a0\u2013 Selon L&rsquo;\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":413783,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301,47045],"tags":[16878,75,446,460,1889],"class_list":["post-430989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-breve","tag-football","tag-marseille","tag-nice","tag-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Nice - Marseille : Les compositions probables<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2023-2024\u00a0\u2013 Selon L&#039;\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nice - Marseille : Les compositions probables\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2023-2024\u00a0\u2013 Selon L&#039;\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-21T09:38:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-21T10:41:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Nice - Marseille : Les compositions probables\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Nice &#8211; Marseille : Les compositions probables\",\"datePublished\":\"2023-10-21T09:38:21+00:00\",\"dateModified\":\"2023-10-21T10:41:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/\"},\"wordCount\":269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Marseille\",\"Nice\",\"OM\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/\",\"name\":\"Nice - Marseille : Les compositions probables\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"datePublished\":\"2023-10-21T09:38:21+00:00\",\"dateModified\":\"2023-10-21T10:41:33+00:00\",\"description\":\"LIGUE 1 2023-2024\u00a0\u2013 Selon L'\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/nice-marseille-les-compositions-probables\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nice &#8211; Marseille : Les compositions probables\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nice - Marseille : Les compositions probables","description":"LIGUE 1 2023-2024\u00a0\u2013 Selon L'\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/","og_locale":"fr_FR","og_type":"article","og_title":"Nice - Marseille : Les compositions probables","og_description":"LIGUE 1 2023-2024\u00a0\u2013 Selon L'\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-10-21T09:38:21+00:00","article_modified_time":"2023-10-21T10:41:33+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Nice - Marseille : Les compositions probables","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Nice &#8211; Marseille : Les compositions probables","datePublished":"2023-10-21T09:38:21+00:00","dateModified":"2023-10-21T10:41:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/"},"wordCount":269,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png","keywords":["br\u00e8ve","Football","Marseille","Nice","OM"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/","url":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/","name":"Nice - Marseille : Les compositions probables","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png","datePublished":"2023-10-21T09:38:21+00:00","dateModified":"2023-10-21T10:41:33+00:00","description":"LIGUE 1 2023-2024\u00a0\u2013 Selon L'\u00c9quipe, voici les compositions probables du choc entre Nice et Marseille pr\u00e9vu ce samedi.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/08\/Nantes-Marseille-A-quelle-heure-et-sur-quelle-chaine-TV.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nice-marseille-les-compositions-probables\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Nice &#8211; Marseille : Les compositions probables"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/430989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=430989"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/430989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/413783"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=430989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=430989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=430989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}