{"id":432359,"date":"2024-08-10T09:21:21","date_gmt":"2024-08-10T07:21:21","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=432359&#038;preview=true&#038;preview_id=432359"},"modified":"2024-08-10T09:21:21","modified_gmt":"2024-08-10T07:21:21","slug":"tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/","title":{"rendered":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2024\/tour-de-france-femmes-2024\/\">TOUR DE FRANCE FEMMES 2024<\/a> &#8211; La 3e \u00e9dition du Tour de France Femmes d\u00e9butera pour la premi\u00e8re fois depuis l&rsquo;\u00e9tranger. En effet, ce lundi 12 ao\u00fbt, la premi\u00e8re \u00e9tape se d\u00e9roulera entre Rotterdam et La Haye sur 123 kilom\u00e8tres tout plats.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-ce-quil-faut-retenir-du-parcours-de-la-3e-edition\/\">Tour de France Femmes 2024 : Ce qu\u2019il faut retenir du parcours de la 3e \u00e9dition<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Parcours et profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024<\/h2>\n<p style=\"text-align: justify;\">D&rsquo;abord, les coureuses s&rsquo;\u00e9lanceront \u00e0 12h15 depuis <strong>Rotterdam<\/strong> dans la province de Hollande-M\u00e9ridionale, la deuxi\u00e8me ville des Pays-Bas en nombre d&rsquo;habitants apr\u00e8s la capitale, Amsterdam. Puis, elles iront vers l&rsquo;est par <strong>Vlaardingen<\/strong> avant d&rsquo;effectuer une boucle au sud par <strong>Hellevoetsluis, Oudenhoorn<\/strong> et le <strong>Maasdeltatunnel<\/strong>, le <span class=\"mw-page-title-main\">Tunnel du delta de la Meuse, long de 945 m\u00e8tres, avec une mont\u00e9e de 1 km \u00e0 3,1 % qui sera class\u00e9e en 4e cat\u00e9gorie.\u00a0<\/span><\/p>\n<p style=\"text-align: justify;\">Ensuite, les concurrentes iront vers l&rsquo;ouest pour traverser, sur des lignes droites, les localit\u00e9s de <strong>Maasluis, Westland, Groeneweg<\/strong>, pour le sprint interm\u00e9diaire de la journ\u00e9e, et <strong>Monster,<\/strong> avec des routes plus sinueuses. Une fois arriv\u00e9es \u00e0 <strong>La Haye<\/strong>, les coureuses auront une boucle de 21,5 kilom\u00e8tres avec des routes rectilignes. Ces routes seront expos\u00e9es au vent.<\/p>\n<p style=\"text-align: justify;\">Finalement, l&rsquo;arriv\u00e9e sera jug\u00e9e \u00e0 <strong>La Haye <\/strong>entre 15h35 et 15h45 pour un sprint massif. Les derni\u00e8res centaines de m\u00e8tres, trac\u00e9es \u00e0 c\u00f4t\u00e9 de la plage de Kijkduin, monteront l\u00e9g\u00e8rement. Cette ville accueille le gouvernement des Pays-Bas, mais aussi plusieurs institutions internationales telles que la Cour internationale de Justice, la Cour p\u00e9nale internationale, la Cour permanente d&rsquo;arbitrage, Europol, Eurojust, la Commission internationale pour les personnes disparues, l&rsquo;Organisation pour l&rsquo;interdiction des armes chimiques et le M\u00e9canisme pour les Tribunaux p\u00e9naux internationaux.<\/p>\n<div id=\"attachment_511116\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-511116\" class=\"wp-image-511116 size-full\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024.jpg\" alt=\"Profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024\" width=\"960\" height=\"576\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024-300x180.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024-768x461.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024-590x354.jpg 590w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Profil-de-la-1ere-etape-du-Tour-de-France-Femmes-2024-400x240.jpg 400w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-511116\" class=\"wp-caption-text\">Profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024 &#8211; Via ASO<\/p><\/div>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2024\/\">L&rsquo;actualit\u00e9 du cyclisme sur route<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Parcours et profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024.<\/p>\n","protected":false},"author":48,"featured_media":511124,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[46995],"tags":[32415,16878,2875,19848],"class_list":["post-432359","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-de-france","tag-actu","tag-breve","tag-cyclisme-feminin","tag-tour-de-france-femmes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape<\/title>\n<meta name=\"description\" content=\"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-10T07:21:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\",\"datePublished\":\"2024-08-10T07:21:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\"},\"wordCount\":346,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"cyclisme f\u00e9minin\",\"Tour de France Femmes\"],\"articleSection\":[\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\",\"name\":\"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"datePublished\":\"2024-08-10T07:21:21+00:00\",\"description\":\"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png\",\"width\":1200,\"height\":674,\"caption\":\"Tour de France Femmes 2024 Parcours et profil de la 1\u00e8re \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","description":"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","og_description":"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2024-08-10T07:21:21+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","datePublished":"2024-08-10T07:21:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/"},"wordCount":346,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png","keywords":["actu","br\u00e8ve","cyclisme f\u00e9minin","Tour de France Femmes"],"articleSection":["Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/","name":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png","datePublished":"2024-08-10T07:21:21+00:00","description":"Retrouvez le parcours et le profil de la 1\u00e8re \u00e9tape du Tour de France Femmes 2024, qui se d\u00e9roule ce lundi 12 ao\u00fbt entre Rotterdam et La Haye.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/08\/Tour-de-France-Femmes-2024-Parcours-et-profil-de-la-1ere-etape.png","width":1200,"height":674,"caption":"Tour de France Femmes 2024 Parcours et profil de la 1\u00e8re \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-femmes-2024-parcours-et-profil-de-la-1ere-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France Femmes 2024 : Parcours et profil de la 1\u00e8re \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/432359","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=432359"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/432359\/revisions"}],"predecessor-version":[{"id":511125,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/432359\/revisions\/511125"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/511124"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=432359"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=432359"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=432359"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}