{"id":434098,"date":"2023-11-01T13:57:31","date_gmt":"2023-11-01T12:57:31","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=434098&#038;preview=true&#038;preview_id=434098"},"modified":"2023-11-01T15:32:04","modified_gmt":"2023-11-01T14:32:04","slug":"le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/","title":{"rendered":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>FOOTBALL &#8211; La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l&rsquo;entr\u00e9e en lice des clubs de Ligue 2.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00c0 noter que le tirage au sort a \u00e9t\u00e9 fait par groupes regroupant des \u00e9quipes d&rsquo;un point de vue g\u00e9ographique. Parmi les clubs de <strong>Ligue<\/strong> <strong>2<\/strong>, seulement deux vont devoir se frotter \u00e0 une \u00e9quipe de Nationale alors que les autres affrontent toute une \u00e9quipe d&rsquo;un niveau inf\u00e9rieur. <strong>Villefranche-Beaujolais<\/strong> (N) recevra <strong>Grenoble<\/strong> (L2) alors qu&rsquo;<strong>\u00c9pinal<\/strong> (N) sera oppos\u00e9 \u00e0 <strong>Troyes<\/strong> (L2).<\/p>\n<p style=\"text-align: justify;\"><strong>Saint-Etienne<\/strong> (L2) se d\u00e9placera \u00e0\u00a0<strong>Bourg-P\u00e9ronnas<\/strong> (N2) alors que les <strong>Girondins<\/strong> <strong>de Bordeaux<\/strong> (L2) iront d\u00e9fier le <strong>Canet<\/strong> <strong>RFC<\/strong> (N3). <strong>Quevilly-Rouen<\/strong> (L2) aura l&rsquo;adversaire le plus faible sur le papier, <strong>Montdidier<\/strong> (R3).<\/p>\n<h2 style=\"text-align: justify;\">Le tirage au sort complet du 7\u00e8me tour de la Coupe de France 2023\/2024<\/h2>\n<p style=\"text-align: justify;\">Plabennec (N3) &#8211; Challans (N3)<br \/>\nStade Paimpolais (R2) &#8211; Flers (N3)<br \/>\nSaint-Brieuc (N2) &#8211; Concarneau (L2)<br \/>\nLes Herbiers (N2) &#8211; US Avranches (N1)<br \/>\nDinan-L\u00e9hon (N2) &#8211; Rennes TA (N3)<br \/>\nCh\u00e2teaugiron (R3) &#8211; Vitr\u00e9 (N3)<br \/>\nDives-Cabourg (N3) &#8211; Dieppe (N3)<br \/>\nErgu\u00e9 Gab\u00e9ric (N3) &#8211; Saint-Renan (R1)<br \/>\nGSI Pontivy (N3) &#8211; Plougastel (R1)<br \/>\nStade Pontivyen (N3) &#8211; Rouen (N1)<br \/>\nSaint-Malo (N2) &#8211; Guingamp (L2)<br \/>\nAG Caen (N3) &#8211; Foug\u00e8res (N3)<br \/>\nProvins (R1) &#8211; Laval (L2)<br \/>\nSaint-Philbert-Grand-Lieu (N3) &#8211; Vend\u00e9e Poir\u00e9 (N3)<br \/>\nTorcy (R1) &#8211; Fleury (N2)<br \/>\nNoeuxoise (R1) &#8211; Avoine-Chinon (N2)<br \/>\nCh\u00e2teauroux (N1) &#8211; Red Star (N1)<br \/>\nDouvres D\u00e9livrand (R2) &#8211; Choisy-au-Bac (R1)<br \/>\nPlessis-Robinsson (R1) &#8211; Brissac (R2)<br \/>\nHouilles (R1) &#8211; Angers (L2)<br \/>\nVillers-Houlgate (N3) &#8211; Equeurd Hainnev (R1)<br \/>\nLaon (R1) &#8211; Racing CFF (N2)<br \/>\nSaint-Michel (D1) &#8211; Entente SSG (N3)<br \/>\nNoisy-le-Sec (R2) &#8211; Furiani (N2)<br \/>\nM\u00e2con (N2) &#8211; Louhans-Cuiseaux (N3)<br \/>\nCosne (N3) &#8211; Chantilly (N3)<br \/>\nPays-du-Valois (N3) &#8211; Auxerre (L2)<br \/>\nSaint-M\u00e9zi\u00e9ry (R1) &#8211; Pirae (Tahiti)<br \/>\nSaint-Omer (R1) &#8211; Saint-Denis (R1)<br \/>\n\u00c9pinal (N1) &#8211; Troyes (L2)<br \/>\nQuesnoy (R3) &#8211; M\u00e9tropole Troyenne (N3)<br \/>\nVillejuif (R1) &#8211; Paris FC (L2)<br \/>\nMontdidier (R3) &#8211; QRM (L2)<br \/>\nDoullens (D1) &#8211; Dijon FCO (N1)<br \/>\nBondues (R1) &#8211; Feignies-Aulnoye (N2)<br \/>\nItancourt (R1) &#8211; Croix (N3)<br \/>\nBl\u00e9riot-Plage (R3) &#8211; ASPTT Dijon (N3)<br \/>\nCorbie (R2) ou Camon (D1) &#8211; Chambly (N2)<br \/>\nLoon-Plage (R1) &#8211; Caen (L2)<br \/>\nCalais (R1) &#8211; Longueau (R1)<br \/>\nReims-Sainte-Anne (N3) &#8211; Boulogne\/Mer (N2)<br \/>\nChaumont (R1) &#8211; Dunkerque (L2)<br \/>\nJarville (R1) &#8211; Sarreguemines (R1)<br \/>\nVillerupt (R1) &#8211; Biesheim (N2)<br \/>\nForbach (R1) &#8211; Geispolsheim (R1)<br \/>\nSochaux (N1) &#8211; Jura Sud (N2)<br \/>\nThaon (N3) &#8211; Schweighouse\/Moder (R2)<br \/>\nHombourg-Haut (R1) &#8211; Amiens (L2)<br \/>\nSarre-Union (N3) &#8211; APM Metz (R1)<br \/>\nColmar (N2) &#8211; Pontarlier (N3)<br \/>\nHaguenau (N2) &#8211; Valenciennes (L2)<br \/>\nMulhouse (R1) &#8211; Jura Dolois (N3)<br \/>\nGu\u00e9rande St-Aubin (R3) &#8211; Revel (R1)<br \/>\nBlagnac (N3) &#8211; Bayonne (N3)<br \/>\nVillenavaise (R1) &#8211; Isle (R2)<br \/>\nFrance Aizenay (R2) &#8211; Libourne (N2)<br \/>\nChauray (N3) &#8211; Pau (L2)<br \/>\nCoulaines (R1) &#8211; Cholet (N1)<br \/>\nStade Mayennais (R1) &#8211; St-Paul (N3) ou Avenir Aunis (R3)<br \/>\nLiffr\u00e9 (R1) &#8211; Rodez (L2)<br \/>\nqualifi\u00e9 Nouvelle-Aquitaine (R1) &#8211; Saumur (N2)<br \/>\n\u00c9toile Maritime (R1) ou Rochefort (R1) &#8211; Tr\u00e9lissac (N2)<br \/>\nToulouse M\u00e9tropole (R1) &#8211; Ajaccio (L2)<br \/>\nLavernose Lherm Mauzac (R3) Saint-Sulpice (R2) ou Uchaud (D3) &#8211; Orl\u00e9ans (N1)<br \/>\nMontlouis (N3) &#8211; Bergerac (N2)<br \/>\nMorlaas Est B\u00e9arn (R2) &#8211; Panazol (N3)<br \/>\nCanet (N3) &#8211; Bordeaux (L2)<br \/>\nVierzon (N3) &#8211; Angoul\u00eame (N2)<br \/>\nPoitiers (N3) &#8211; Castanet (N3)<br \/>\nAuch (R1) &#8211; Romorantin (N2)<br \/>\nSaint-Roche (R2) &#8211; Saint-Priest (N3)<br \/>\nLimonest (N3) &#8211; Dom\u00e9rat (R1)<br \/>\nVelay (R1) &#8211; Martigues (N1)<br \/>\nRosador (R1) &#8211; Al\u00e8s (N2)<br \/>\nLyon-Duch\u00e8re (N3) &#8211; Bastia (L2)<br \/>\nThonon \u00c9vian (N2) &#8211; Aubagne (N2)<br \/>\nNeuvillois (R1) &#8211; Hauts-Lyonnais (N3)<br \/>\nFeurs (N3) &#8211; Espaly (N3)<br \/>\nVillefranche (N1) &#8211; Grenoble (L2)<br \/>\nVolvic (R1) &#8211; Chamb\u00e9ry (N3)<br \/>\nChaponnay-Marennes (R2) &#8211; Hy\u00e8res (N2)<br \/>\nSeyssins (D1) &#8211; Le Puy (N2)<br \/>\nBourg-P\u00e9ronnas (N2) &#8211; Saint-\u00c9tienne (L2)<br \/>\nRoanne (R2) &#8211; N\u00eemes (N1)<br \/>\nFabr\u00e8gues (N3) ou Muret (R1) &#8211; Squadra Valincu (R1)<br \/>\nCannes (N2) &#8211; Bourgoin-Jallieu (N2)<br \/>\nFos-sur-Mer (N3) &#8211; Annecy (L2)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>FOOTBALL &#8211; La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l&rsquo;entr\u00e9e en lice des clubs de Ligue 2.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":434102,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[2301],"tags":[16878,2870,75,231],"class_list":["post-434098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-breve","tag-coupe-de-france","tag-football","tag-ligue-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024<\/title>\n<meta name=\"description\" content=\"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l&#039;entr\u00e9e en lice des clubs de Ligue 2.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024\" \/>\n<meta property=\"og:description\" content=\"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l&#039;entr\u00e9e en lice des clubs de Ligue 2.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T12:57:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-01T14:32:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024\",\"datePublished\":\"2023-11-01T12:57:31+00:00\",\"dateModified\":\"2023-11-01T14:32:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png\",\"keywords\":[\"br\u00e8ve\",\"Coupe de France\",\"Football\",\"ligue 2\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\",\"name\":\"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png\",\"datePublished\":\"2023-11-01T12:57:31+00:00\",\"dateModified\":\"2023-11-01T14:32:04+00:00\",\"description\":\"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l'entr\u00e9e en lice des clubs de Ligue 2.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024","description":"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l'entr\u00e9e en lice des clubs de Ligue 2.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/","og_locale":"fr_FR","og_type":"article","og_title":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024","og_description":"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l'entr\u00e9e en lice des clubs de Ligue 2.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-11-01T12:57:31+00:00","article_modified_time":"2023-11-01T14:32:04+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024","datePublished":"2023-11-01T12:57:31+00:00","dateModified":"2023-11-01T14:32:04+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png","keywords":["br\u00e8ve","Coupe de France","Football","ligue 2"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/","url":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/","name":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png","datePublished":"2023-11-01T12:57:31+00:00","dateModified":"2023-11-01T14:32:04+00:00","description":"FOOTBALL - La FFF a effectu\u00e9 le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024 avec l'entr\u00e9e en lice des clubs de Ligue 2.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Le-tirage-au-sort-du-7eme-tour-de-la-Coupe-de-France-20232024.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/le-tirage-au-sort-du-7eme-tour-de-la-coupe-de-france-2023-2024\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Le tirage au sort du 7\u00e8me tour de la Coupe de France 2023\/2024"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/434098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=434098"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/434098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/434102"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=434098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=434098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=434098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}