{"id":434920,"date":"2023-11-04T22:58:34","date_gmt":"2023-11-04T21:58:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=434920&#038;preview=true&#038;preview_id=434920"},"modified":"2023-11-05T10:31:10","modified_gmt":"2023-11-05T09:31:10","slug":"ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/","title":{"rendered":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&rsquo;un match d\u00e9cevant"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE 1 2023-2024 &#8211;<\/em><\/strong><strong><em> L\u2019OM et le LOSC se quittent sur un triste 0-0 dans le cadre de la 11e journ\u00e9e. Les deux formations ont manqu\u00e9 cruellement de r\u00e9alisme dans la surface.\u00a0 <\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Possession st\u00e9rile du LOSC<\/h2>\n<p style=\"text-align: justify;\">Les 45 premi\u00e8res minutes ont plut\u00f4t tourn\u00e9 \u00e0 l\u2019avantage des Lillois. Les joueurs de <strong>Fonseca<\/strong> ont \u00e9t\u00e9 techniquement tr\u00e8s propres dans le jeu. Toutefois, ils n\u2019ont jamais mis <strong>Pau Lopez<\/strong> \u00e0 contribution. Difficile de marquer lorsqu\u2019on ne cadre pas, comme dit le dicton. <strong>Yazici<\/strong> n\u2019est pourtant pas pass\u00e9 loin d&rsquo;ouvrir le score au quart d\u2019heure de jeu sur un lob de 40 m\u00e8tres, alors que Pau Lopez avait totalement d\u00e9sert\u00e9 ses cages. Heureusement pour ce dernier, le Turc n\u2019a pu trouver que la barre transversale.<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, l\u2019OM a surtout jou\u00e9 des coups. L\u2019occasion majeure des Olympiens dans cette premi\u00e8re p\u00e9riode reste la reprise de vol\u00e9e rat\u00e9e de <strong>Harit<\/strong> sur un centre parfait de <strong>Jonathan Clauss<\/strong>, juste avant le retour aux vestiaires. L\u2019\u00e9quipe de <strong>Gattuso<\/strong> a \u00e9t\u00e9 d\u00e9cevante dans le match du milieu de terrain, comme en t\u00e9moigne la mi-temps de <strong>Jordan Veretout<\/strong> : seulement 10 ballons touch\u00e9s et la moiti\u00e9 de perdus. Offensivement, la triplette n\u2019a pas \u00e9t\u00e9 en r\u00e9ussite non plus.<\/p>\n<h2 style=\"text-align: justify;\">L\u2019OM d\u00e9cevant offensivement<\/h2>\n<p style=\"text-align: justify;\">Le second acte a \u00e9t\u00e9 une sorte de copier-coller du premier, \u00e0 la seule exception que l\u2019OM a port\u00e9 un peu plus le ballon. Marseille pourra remercier <strong>Gigot<\/strong> pour son beau travail en d\u00e9but de mi-temps (et sur l\u2019ensemble de la partie), notamment sur la frappe de <strong>Gomes<\/strong> (55e). <strong>Lopez <\/strong>a fait son premier arr\u00eat \u00e0 la 80e minute sur une nouvelle occasion du milieu offensif anglais. Peu de choses \u00e0 dire sur l\u2019OM, qui a certainement eu ses meilleures situations sur des coups de pied arr\u00eat\u00e9s.\u00a0<strong>Lucas Chevalier<\/strong> a su \u00eatre vigilant pour ne pas se faire surprendre. <strong>Aubameyang<\/strong> est sorti sous les sifflets du V\u00e9lodrome, preuve de la pauvret\u00e9 offensive des Phoc\u00e9ens. Lille pourra regretter son manque de r\u00e9alisme\u00a0: 10 tirs et 1 seul cadr\u00e9 sur l\u2019ensemble de la partie. Un probl\u00e8me r\u00e9current du c\u00f4t\u00e9 des <em>Dogues<\/em>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Les chiffres du match \ud83d\udccc<a href=\"https:\/\/twitter.com\/hashtag\/OMLOSC?src=hash&amp;ref_src=twsrc%5Etfw\">#OMLOSC<\/a> <a href=\"https:\/\/t.co\/kjXfVoN40S\">pic.twitter.com\/kjXfVoN40S<\/a><\/p>\n<p>\u2014 Ligue 1 Uber Eats (@Ligue1UberEats) <a href=\"https:\/\/twitter.com\/Ligue1UberEats\/status\/1720922288114041011?ref_src=twsrc%5Etfw\">November 4, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2023-2024 &#8211; L\u2019OM et le LOSC se sont quitt\u00e9s sur un triste 0-0. Les deux formations ont manqu\u00e9 cruellement de r\u00e9alisme dans la surface.\u00a0<\/p>\n","protected":false},"author":86,"featured_media":434930,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47045],"tags":[16878,1554,2391,2924],"class_list":["post-434920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-1","tag-breve","tag-ligue-1","tag-losc","tag-olympique-de-marseille"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&#039;un match d\u00e9cevant<\/title>\n<meta name=\"description\" content=\"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l&#039;OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&#039;un match d\u00e9cevant\" \/>\n<meta property=\"og:description\" content=\"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l&#039;OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-04T21:58:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-05T09:31:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Parant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&#039;un match d\u00e9cevant\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\"},\"author\":{\"name\":\"Nicolas Parant\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/816f1c1bae6e11b6ef5b39687639be63\"},\"headline\":\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&rsquo;un match d\u00e9cevant\",\"datePublished\":\"2023-11-04T21:58:34+00:00\",\"dateModified\":\"2023-11-05T09:31:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\"},\"wordCount\":405,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png\",\"keywords\":[\"br\u00e8ve\",\"Ligue 1\",\"LOSC\",\"Olympique de Marseille\"],\"articleSection\":[\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\",\"name\":\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png\",\"datePublished\":\"2023-11-04T21:58:34+00:00\",\"dateModified\":\"2023-11-05T09:31:10+00:00\",\"description\":\"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l'OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&rsquo;un match d\u00e9cevant\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/816f1c1bae6e11b6ef5b39687639be63\",\"name\":\"Nicolas Parant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/1B6E3319-7CA3-49A2-A3FB-D53C46115743-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/1B6E3319-7CA3-49A2-A3FB-D53C46115743-150x150.jpeg\",\"caption\":\"Nicolas Parant\"},\"description\":\"Passionn\u00e9 de sport et d\u2019\u00e9criture, r\u00e9diger des articles a \u00e9t\u00e9 une v\u00e9ritable r\u00e9v\u00e9lation quand j\u2019ai pris la plume num\u00e9rique pour la premi\u00e8re fois en 2021. Admiratif des exploits de Nadal \u00e0 Roland Garros et du charisme de Zlatan Ibrahimovi\u0107 \u00e0 son arriv\u00e9e dans la capitale, je m\u2019efforce de transmettre au mieux les \u00e9motions des athl\u00e8tes de la nouvelle g\u00e9n\u00e9ration. \u00c0 Dicodusport depuis 2023, je commente principalement les batailles qui se d\u00e9roulent dans l\u2019octogone de l\u2019UFC ou sur les pelouses de football et de rugby.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/nicolas-parant\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant","description":"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l'OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant","og_description":"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l'OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-11-04T21:58:34+00:00","article_modified_time":"2023-11-05T09:31:10+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png","type":"image\/png"}],"author":"Nicolas Parant","twitter_card":"summary_large_image","twitter_title":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/"},"author":{"name":"Nicolas Parant","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/816f1c1bae6e11b6ef5b39687639be63"},"headline":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&rsquo;un match d\u00e9cevant","datePublished":"2023-11-04T21:58:34+00:00","dateModified":"2023-11-05T09:31:10+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/"},"wordCount":405,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png","keywords":["br\u00e8ve","Ligue 1","LOSC","Olympique de Marseille"],"articleSection":["Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/","name":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png","datePublished":"2023-11-04T21:58:34+00:00","dateModified":"2023-11-05T09:31:10+00:00","description":"Ligue 1 - Match tr\u00e8s d\u00e9cevant entre l'OM et le LOSC au Stade V\u00e9lodrome. Les deux \u00e9quipes se quittent sur un triste 0-0.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Ligue-1-J11.png","width":800,"height":445,"caption":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d'un match d\u00e9cevant"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-1-j11-marseille-et-lille-se-neutralisent-au-terme-dun-match-decevant\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 1 (J11) : Marseille et Lille se neutralisent au terme d&rsquo;un match d\u00e9cevant"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/816f1c1bae6e11b6ef5b39687639be63","name":"Nicolas Parant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/1B6E3319-7CA3-49A2-A3FB-D53C46115743-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/1B6E3319-7CA3-49A2-A3FB-D53C46115743-150x150.jpeg","caption":"Nicolas Parant"},"description":"Passionn\u00e9 de sport et d\u2019\u00e9criture, r\u00e9diger des articles a \u00e9t\u00e9 une v\u00e9ritable r\u00e9v\u00e9lation quand j\u2019ai pris la plume num\u00e9rique pour la premi\u00e8re fois en 2021. Admiratif des exploits de Nadal \u00e0 Roland Garros et du charisme de Zlatan Ibrahimovi\u0107 \u00e0 son arriv\u00e9e dans la capitale, je m\u2019efforce de transmettre au mieux les \u00e9motions des athl\u00e8tes de la nouvelle g\u00e9n\u00e9ration. \u00c0 Dicodusport depuis 2023, je commente principalement les batailles qui se d\u00e9roulent dans l\u2019octogone de l\u2019UFC ou sur les pelouses de football et de rugby.","url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-parant\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/434920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/86"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=434920"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/434920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/434930"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=434920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=434920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=434920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}