{"id":435520,"date":"2023-11-07T17:59:30","date_gmt":"2023-11-07T16:59:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=435520&#038;preview=true&#038;preview_id=435520"},"modified":"2023-11-07T18:54:59","modified_gmt":"2023-11-07T17:54:59","slug":"transferts-agen-annonce-les-prolongations-de-4-jeunes-avants","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/","title":{"rendered":"Transferts : Agen annonce les prolongations de 4 jeunes avants"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>RUGBY \u00c0 XV &#8211; Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Onzi\u00e8me au <a href=\"https:\/\/dicodusport.fr\/blog\/classement-pro-d2-2023-2024\/\">classement de <strong>Pro D2<\/strong><\/a> apr\u00e8s neuf journ\u00e9es, <strong>Agen<\/strong> sait que cette saison ne sera pas aussi bonne que la pr\u00e9c\u00e9dente. Le club n&rsquo;a pas pu recruter cet \u00e9t\u00e9 \u00e0 cause d&rsquo;un projet de vente de la structure professionnelle qui a finalement \u00e9chou\u00e9.<\/p>\n<p style=\"text-align: justify;\">En attendant, le <strong>SUA<\/strong> verrouille ses jeunes.<strong> Hans Lombard-Buret<\/strong> et <strong>Alex Burin<\/strong> sont tous les deux internationaux avec l&rsquo;<strong>\u00e9quipe de<\/strong> <strong>France U20<\/strong>. Ils arrivaient en fin de contrat l&rsquo;\u00e9t\u00e9 prochain. Ils ont prolong\u00e9 jusqu&rsquo;en 2027 pour le premier et 2026 pour le second.<\/p>\n<p style=\"text-align: justify;\">Le troisi\u00e8me ligne <strong>Julien Lebian<\/strong> prolonge lui jusqu&rsquo;en 2027. Arriv\u00e9 en 2020 \u00e0 <strong>Agen<\/strong>, le joueur de 22 ans compte 10 matchs de <strong>Pro D2<\/strong>. Toujours en 3\u00e8me ligne, <strong>Matthieu Bonnet<\/strong> prolonge lui l&rsquo;aventure pour deux saisons, soit jusqu&rsquo;en juin 2026. Il compte d\u00e9j\u00e0 25 matchs de <strong>Pro D2<\/strong> dont 10 titularisations.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\ude4b\ud835\ude67\ud835\ude64\ud835\ude61\ud835\ude64\ud835\ude63\ud835\ude5c\ud835\ude56\ud835\ude69\ud835\ude5e\ud835\ude64\ud835\ude63 \u270d\ufe0f<\/p>\n<p>Notre pilier Alex BURIN prolonge \ud835\uddf7\ud835\ude02\ud835\ude00\ud835\uddfe\ud835\ude02&rsquo;\ud835\uddf2\ud835\uddfb \ud835\udfee\ud835\udfec\ud835\udfee\ud835\udff2 \ud83d\udfe6\u2b1c\ufe0f<\/p>\n<p>\ud83d\udc49 <a href=\"https:\/\/t.co\/1TUNykWvvr\">https:\/\/t.co\/1TUNykWvvr<\/a> <a href=\"https:\/\/t.co\/WLMYMUQdz7\">pic.twitter.com\/WLMYMUQdz7<\/a><\/p>\n<p>\u2014 Agen Rugby &#8211; SUA LG (@agen_rugby) <a href=\"https:\/\/twitter.com\/agen_rugby\/status\/1721866804425863196?ref_src=twsrc%5Etfw\">November 7, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY \u00c0 XV &#8211; Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.<\/p>\n","protected":false},"author":1,"featured_media":435521,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[2339,16878,1839],"class_list":["post-435520","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-agen","tag-breve","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts : Agen annonce les prolongations de 4 jeunes avants<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Agen annonce les prolongations de 4 jeunes avants\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-07T16:59:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-07T17:54:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Agen annonce les prolongations de 4 jeunes avants\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Agen annonce les prolongations de 4 jeunes avants\",\"datePublished\":\"2023-11-07T16:59:30+00:00\",\"dateModified\":\"2023-11-07T17:54:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png\",\"keywords\":[\"Agen\",\"br\u00e8ve\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/\",\"name\":\"Transferts : Agen annonce les prolongations de 4 jeunes avants\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png\",\"datePublished\":\"2023-11-07T16:59:30+00:00\",\"dateModified\":\"2023-11-07T17:54:59+00:00\",\"description\":\"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Agen annonce les prolongations de 4 jeunes avants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Agen annonce les prolongations de 4 jeunes avants","description":"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Agen annonce les prolongations de 4 jeunes avants","og_description":"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-11-07T16:59:30+00:00","article_modified_time":"2023-11-07T17:54:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Agen annonce les prolongations de 4 jeunes avants","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Agen annonce les prolongations de 4 jeunes avants","datePublished":"2023-11-07T16:59:30+00:00","dateModified":"2023-11-07T17:54:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png","keywords":["Agen","br\u00e8ve","Pro D2"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/","name":"Transferts : Agen annonce les prolongations de 4 jeunes avants","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png","datePublished":"2023-11-07T16:59:30+00:00","dateModified":"2023-11-07T17:54:59+00:00","description":"TOP 14 2023-2024 - Le SU Agen a annonc\u00e9 la prolongation de quatre jeunes joueurs de son effectif pour les saisons \u00e0 venir.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Transferts-Agen-annonce-4-prolongations-de-jeunes-talents.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-agen-annonce-les-prolongations-de-4-jeunes-avants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Agen annonce les prolongations de 4 jeunes avants"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/435520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=435520"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/435520\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/435521"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=435520"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=435520"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=435520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}