{"id":435942,"date":"2023-11-09T17:43:52","date_gmt":"2023-11-09T16:43:52","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=435942&#038;preview=true&#038;preview_id=435942"},"modified":"2023-11-09T17:46:30","modified_gmt":"2023-11-09T16:46:30","slug":"baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/","title":{"rendered":"Baseball 5 : L&rsquo;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&rsquo;Euro"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>CHAMPIONNAT D&rsquo;EUROPE DE BASEBALL 5 &#8211; Tenante du titre, l&rsquo;\u00e9quipe de France a conclu aujourd&rsquo;hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est en Lituanie qu&rsquo;a lieu la deuxi\u00e8me \u00e9dition du Championnat d&rsquo;Europe de baseball 5. Discipline r\u00e9cente, elle est une variante plus rapide et se jouant en salle. Pour la premi\u00e8re \u00e9dition en 2020, c&rsquo;est l&rsquo;\u00e9quipe de France qui avait rafl\u00e9 la mise. Et visiblement, les Bleus sont pr\u00eats pour la d\u00e9fense de leur titre, puisqu&rsquo;ils viennent de boucler une phase de poule parfaite.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Les bleus terminent le premier tour de l&rsquo;Euro Baseball5 invaincus avec un succ\u00e8s 2-0 face \u00e0 la Finlande. Direction le 2\u00e8me tour ! <a href=\"https:\/\/t.co\/BJjGfCOsXy\">pic.twitter.com\/BJjGfCOsXy<\/a><\/p>\n<p>\u2014 France Baseball Softball \u26be\ufe0f \ud83e\udd4e\ud83d\udd90 (@ffbs_baseball) <a href=\"https:\/\/twitter.com\/ffbs_baseball\/status\/1722649153333838298?ref_src=twsrc%5Etfw\">November 9, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n6 matchs, six victoires <strong>2-0<\/strong> contre la Lettonie, l&rsquo;Espagne, les Pays-Bas, la Bulgarie, la Roumanie et la Finlande. Un bilan de qualit\u00e9 qui affirme clairement les ambitions tricolores dans cette comp\u00e9tition. Mais qui permet surtout d&rsquo;aborder la deuxi\u00e8me phase en confiance, en conservant le b\u00e9n\u00e9fice de deux de ces victoires. Reste donc trois matchs face \u00e0 la Lituanie, la Belgique puis l&rsquo;Italie, et si tout va bien, la finale samedi (14h15) pour le doubl\u00e9. Une perspective r\u00e9jouissante pour une \u00e9quipe qui semble s\u00fbre de sa force.<\/p>\n<h2 style=\"text-align: justify;\">Composition de l&rsquo;\u00e9quipe de France<\/h2>\n<p style=\"text-align: justify;\">Ang\u00e9lique Andr\u00e9 &#8211; Ambre Brouard &#8211; Nathan Cregut &#8211; Marcel Cremel-Baker &#8211; Chiara Enrione-Thorrand &#8211; Omar Diodene-Pacheco &#8211; Flavien Hasslauer &#8211; Amina Taleb. Manager : Lahcene Benhamida.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNAT D&rsquo;EUROPE DE BASEBALL 5 &#8211; Tenante du titre, l&rsquo;\u00e9quipe de France a conclu aujourd&rsquo;hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":435946,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10077],"tags":[16878],"class_list":["post-435942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-baseball","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Baseball 5 : L&#039;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&#039;Euro<\/title>\n<meta name=\"description\" content=\"CHAMPIONNAT D&#039;EUROPE DE BASEBALL 5 - Tenante du titre, l&#039;\u00e9quipe de France a conclu aujourd&#039;hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Baseball 5 : L&#039;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&#039;Euro\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNAT D&#039;EUROPE DE BASEBALL 5 - Tenante du titre, l&#039;\u00e9quipe de France a conclu aujourd&#039;hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-09T16:43:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-09T16:46:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Baseball 5 : L&#039;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&#039;Euro\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Baseball 5 : L&rsquo;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&rsquo;Euro\",\"datePublished\":\"2023-11-09T16:43:52+00:00\",\"dateModified\":\"2023-11-09T16:46:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\"},\"wordCount\":272,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png\",\"keywords\":[\"br\u00e8ve\"],\"articleSection\":[\"Baseball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\",\"name\":\"Baseball 5 : L'\u00e9quipe de France franchit ais\u00e9ment le premier tour de l'Euro\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png\",\"datePublished\":\"2023-11-09T16:43:52+00:00\",\"dateModified\":\"2023-11-09T16:46:30+00:00\",\"description\":\"CHAMPIONNAT D'EUROPE DE BASEBALL 5 - Tenante du titre, l'\u00e9quipe de France a conclu aujourd'hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png\",\"width\":800,\"height\":445,\"caption\":\"Baseball 5 La France \u00e9choue en finale de l'Euro contre la Lituanie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Baseball 5 : L&rsquo;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&rsquo;Euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Baseball 5 : L'\u00e9quipe de France franchit ais\u00e9ment le premier tour de l'Euro","description":"CHAMPIONNAT D'EUROPE DE BASEBALL 5 - Tenante du titre, l'\u00e9quipe de France a conclu aujourd'hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/","og_locale":"fr_FR","og_type":"article","og_title":"Baseball 5 : L'\u00e9quipe de France franchit ais\u00e9ment le premier tour de l'Euro","og_description":"CHAMPIONNAT D'EUROPE DE BASEBALL 5 - Tenante du titre, l'\u00e9quipe de France a conclu aujourd'hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-11-09T16:43:52+00:00","article_modified_time":"2023-11-09T16:46:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Baseball 5 : L'\u00e9quipe de France franchit ais\u00e9ment le premier tour de l'Euro","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Baseball 5 : L&rsquo;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&rsquo;Euro","datePublished":"2023-11-09T16:43:52+00:00","dateModified":"2023-11-09T16:46:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/"},"wordCount":272,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png","keywords":["br\u00e8ve"],"articleSection":["Baseball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/","url":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/","name":"Baseball 5 : L'\u00e9quipe de France franchit ais\u00e9ment le premier tour de l'Euro","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png","datePublished":"2023-11-09T16:43:52+00:00","dateModified":"2023-11-09T16:46:30+00:00","description":"CHAMPIONNAT D'EUROPE DE BASEBALL 5 - Tenante du titre, l'\u00e9quipe de France a conclu aujourd'hui une premi\u00e8re phase parfaite avec une sixi\u00e8me victoire.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/Baseball-5-Lequipe-de-France-franchit-aisement-le-premier-tour-de-lEuro.png","width":800,"height":445,"caption":"Baseball 5 La France \u00e9choue en finale de l'Euro contre la Lituanie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/baseball-5-lequipe-de-france-franchit-aisement-le-premier-tour-de-leuro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Baseball 5 : L&rsquo;\u00e9quipe de France franchit ais\u00e9ment le premier tour de l&rsquo;Euro"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/435942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=435942"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/435942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/435946"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=435942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=435942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=435942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}