{"id":438347,"date":"2023-11-19T08:38:19","date_gmt":"2023-11-19T07:38:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=438347&#038;preview=true&#038;preview_id=438347"},"modified":"2023-11-19T10:24:51","modified_gmt":"2023-11-19T09:24:51","slug":"f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/","title":{"rendered":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/f1-grand-prix-de-las-vegas-programme-chaine-tv-et-resultats\/\">F1 &#8211; GRAND PRIX DE LAS VEGAS 2023<\/a><b> &#8211; \u00c0 l\u2019issue d&rsquo;une course rythm\u00e9e sur le circuit de Las Vegas, Max Verstappen (Red Bull) s&rsquo;est impos\u00e9. Le podium est compl\u00e9t\u00e9 par Charles Leclerc (Ferrari) et Sergio Perez (Red Bull). Le Fran\u00e7ais Esteban Ocon (Alpine) termine 4\u00e8me tandis que son co\u00e9quipier et compatriote Pierre Gasly a termin\u00e9 11\u00e8me.<\/b><\/em><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/f1-classement-grand-prix-de-las-vegas-2023\/\"><strong>F1 Las Vegas 2023 &#8211; Classement du Grand Prix<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\u00c0 l\u2019occasion de la vingt-et-uni\u00e8me manche de la saison,\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/f1-grille-de-depart-du-grand-prix-de-las-vegas-2023\/\">la grille de d\u00e9part<\/a>\u00a0s\u2019est mise en place sur le circuit de Las Vegas.<strong>\u00a0Charles Leclerc <\/strong>(Ferrari) partait en pole position. Il \u00e9tait accompagn\u00e9 sur la m\u00eame ligne par le triple champion du monde en titre <strong>Max Verstappen<\/strong> (Red Bull). Le Britannique <strong>George Russell<\/strong> (Mercedes) partait depuis la 3\u00e8me place.\u00a0Les Fran\u00e7ais d\u2019Alpine <strong>Pierre Gasly <\/strong>et <strong>Esteban Ocon<\/strong> s\u2019\u00e9lan\u00e7aient des 4<sup>\u00e8me<\/sup>\u00a0et 16<sup>\u00e8me<\/sup> places.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Un d\u00e9part controvers\u00e9<\/strong><\/h2>\n<p style=\"text-align: justify;\">C\u2019est \u00e0 un d\u00e9part mouvement\u00e9 auquel nous avons assist\u00e9, puisque <strong>Max Verstappen<\/strong> a d\u00e9pass\u00e9 <strong>Charles Leclerc<\/strong> dans le premier virage. N\u00e9anmoins, la man\u0153uvre a \u00e9t\u00e9 jug\u00e9e litigieuse, car les deux monoplaces se trouvaient en dehors des limites de piste au moment de l\u2019action de d\u00e9passement. C\u2019est pourquoi <strong>Max Verstappen <\/strong>a subi une p\u00e9nalit\u00e9 de cinq secondes de p\u00e9nalit\u00e9 qu\u2019il a purg\u00e9e au stand apr\u00e8s s\u2019\u00eatre fait reprendre la t\u00eate par le Mon\u00e9gasque au tour 8. Dans les premiers tours, <strong>Lando Norris<\/strong> (McLaren) s\u2019est crash\u00e9 et a provoqu\u00e9 une voiture de s\u00e9curit\u00e9.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le d\u00e9part du Grand Prix de Las Vegas \ud83c\udf89\u26a1\ufe0f<\/p>\n<p>Le 1er virage est sous enqu\u00eate \u26a0\ufe0f<a href=\"https:\/\/twitter.com\/hashtag\/LasVegasGP?src=hash&amp;ref_src=twsrc%5Etfw\">#LasVegasGP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/F1?src=hash&amp;ref_src=twsrc%5Etfw\">#F1<\/a> <a href=\"https:\/\/t.co\/OJXl6aGg6p\">pic.twitter.com\/OJXl6aGg6p<\/a><\/p>\n<p>\u2014 CANAL+ F1\u00ae (@CanalplusF1) <a href=\"https:\/\/twitter.com\/CanalplusF1\/status\/1726121291504128067?ref_src=twsrc%5Etfw\">November 19, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\"><strong>Entre strat\u00e9gies et batailles<\/strong><\/h2>\n<p style=\"text-align: justify;\">De nombreuses batailles ont lieu en piste et lors du 27<sup>\u00e8me<\/sup> tour de course, une touchette entre <strong>Lewis Hamilton<\/strong> (Mercedes) et <strong>Oscar Piastri <\/strong>(McLaren) a d\u00e9bouch\u00e9 sur une crevaison sur les deux monoplaces, provoquant une nouvelle voiture de s\u00e9curit\u00e9. Gr\u00e2ce \u00e0 celle-ci, <strong>Sergio Perez<\/strong> (Red Bull) a pu s\u2019arr\u00eater au stand sans que cela lui co\u00fbte beaucoup. Il ressort en deuxi\u00e8me position derri\u00e8re <strong>Charles Leclerc<\/strong>, qu\u2019il va d\u00e9passer ensuite. Une bataille se dessine alors pour la premi\u00e8re place entre les deux hommes, mais aussi avec <strong>Max Verstappen<\/strong>, qui revient alors en force. Le N\u00e9erlandais a d\u2019ailleurs pris les commandes \u00e0 15 tours de la fin de course.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Max Verstappen \u00e0 nouveau vainqueur<\/strong><\/h2>\n<p style=\"text-align: justify;\">Le N\u00e9erlandais <strong>Max Verstappen <\/strong>a su prendre assez d\u2019avance pour conserver la t\u00eate et d\u00e9crocher une nouvelle victoire. C\u2019est sa 53<sup>\u00e8me<\/sup> en carri\u00e8re et sa dix-huiti\u00e8me de la saison. Derri\u00e8re, <strong>Charles Leclerc<\/strong> (Ferrari) a d\u00e9pass\u00e9 <strong>Sergio Perez <\/strong>(Red Bull) dans le dernier tour pour la deuxi\u00e8me position.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">LA BATAILLE POUR LA DEUXI\u00c8ME PLACE !! IL Y VA CHARLES LECLERC \ud83e\udd29\ud83d\udca5<a href=\"https:\/\/twitter.com\/hashtag\/LasVegasGP?src=hash&amp;ref_src=twsrc%5Etfw\">#LasVegasGP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/F1?src=hash&amp;ref_src=twsrc%5Etfw\">#F1<\/a> <a href=\"https:\/\/t.co\/avN1KLc1Mf\">pic.twitter.com\/avN1KLc1Mf<\/a><\/p>\n<p>\u2014 CANAL+ F1\u00ae (@CanalplusF1) <a href=\"https:\/\/twitter.com\/CanalplusF1\/status\/1726142618227085701?ref_src=twsrc%5Etfw\">November 19, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Le Fran\u00e7ais <strong>Esteban Ocon<\/strong> (Alpine) a pris la 4<sup>\u00e8me<\/sup> place devant <strong>Lance Stroll <\/strong>(Aston Martin), <strong>Carlos Sainz<\/strong> (Ferrari) et <strong>Lewis Hamilton<\/strong> (Mercedes) qui se tiennent tous en quatre secondes. <strong>George Russell<\/strong> (Mercedes) a franchi la ligne en 4<sup>\u00e8me<\/sup> position, mais a pris la 8<sup>\u00e8me<\/sup> place de la course apr\u00e8s application de sa p\u00e9nalit\u00e9 de cinq secondes. <strong>Fernando Alonso<\/strong> (Aston Martin) et <strong>Oscar Piastri<\/strong> (McLaren) compl\u00e8tent le Top 10.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/f1-classement-championnat-du-monde-des-pilotes-2023\/\"><strong>Classement championnat du monde des pilotes<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/f1-classement-championnat-du-monde-des-constructeurs-2023\/\"><strong>Classement Championnat du monde des constructeurs<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/f1-2023-calendrier-et-resultats\/\"><strong>F1 2023 &#8211; Calendrier et r\u00e9sultats<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>F1 &#8211; GRAND PRIX DE LAS VEGAS 2023 &#8211; \u00c0 l\u2019issue d&rsquo;une course rythm\u00e9e sur le circuit de Las Vegas, Max Verstappen (Red Bull) s&rsquo;est impos\u00e9. Le podium est compl\u00e9t\u00e9 par Charles Leclerc (Ferrari) et Sergio Perez (Red Bull). Le Fran\u00e7ais Esteban Ocon (Alpine) termine 4\u00e8me tandis que son co\u00e9quipier et compatriote Pierre Gasly a termin\u00e9 11\u00e8me.<\/p>\n","protected":false},"author":54,"featured_media":438387,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[8653],"tags":[16878,3166,2065,35920,24],"class_list":["post-438347","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-formule-1","tag-breve","tag-f1","tag-formule-1","tag-grand-prix-de-las-vegas-f1","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen<\/title>\n<meta name=\"description\" content=\"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen\" \/>\n<meta property=\"og:description\" content=\"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/roxane.lecacher\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-19T07:38:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-19T09:24:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Roxane Lecacher\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\"},\"author\":{\"name\":\"Roxane Lecacher\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\"},\"headline\":\"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen\",\"datePublished\":\"2023-11-19T07:38:19+00:00\",\"dateModified\":\"2023-11-19T09:24:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png\",\"keywords\":[\"br\u00e8ve\",\"F1\",\"Formule 1\",\"Grand Prix de Las Vegas F1\",\"sport\"],\"articleSection\":[\"Formule 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\",\"name\":\"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png\",\"datePublished\":\"2023-11-19T07:38:19+00:00\",\"dateModified\":\"2023-11-19T09:24:51+00:00\",\"description\":\"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png\",\"width\":800,\"height\":445,\"caption\":\"https:\/\/www.cyclismactu.net\/news-cyclisme-route-patrick-lefevere-tient-son-successeur-j-ai-trouve-quelqu-un-78446.html\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a\",\"name\":\"Roxane Lecacher\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg\",\"caption\":\"Roxane Lecacher\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.\",\"sameAs\":[\"https:\/\/www.facebook.com\/roxane.lecacher\",\"https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen","description":"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/","og_locale":"fr_FR","og_type":"article","og_title":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen","og_description":"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.","og_url":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/roxane.lecacher","article_published_time":"2023-11-19T07:38:19+00:00","article_modified_time":"2023-11-19T09:24:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png","type":"image\/png"}],"author":"Roxane Lecacher","twitter_card":"summary_large_image","twitter_title":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/"},"author":{"name":"Roxane Lecacher","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a"},"headline":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen","datePublished":"2023-11-19T07:38:19+00:00","dateModified":"2023-11-19T09:24:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png","keywords":["br\u00e8ve","F1","Formule 1","Grand Prix de Las Vegas F1","sport"],"articleSection":["Formule 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/","url":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/","name":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png","datePublished":"2023-11-19T07:38:19+00:00","dateModified":"2023-11-19T09:24:51+00:00","description":"F1 - GRAND PRIX DE LAS VEGAS 2023 - Le N\u00e9erlandais Max Verstappen (Red Bull) remporte le premier Grand Prix de Las Vegas.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/11\/F1-Las-Vegas-2023-18eme-succes-de-la-saison-pour-Max-Verstappen-1.png","width":800,"height":445,"caption":"https:\/\/www.cyclismactu.net\/news-cyclisme-route-patrick-lefevere-tient-son-successeur-j-ai-trouve-quelqu-un-78446.html"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/f1-las-vegas-2023-18eme-succes-de-la-saison-pour-max-verstappen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"F1 Las Vegas 2023 : 18\u00e8me succ\u00e8s de la saison pour Max Verstappen"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/819fb2545dd2715bd7c0580d6d4b411a","name":"Roxane Lecacher","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Roxane-Lecacher-150x150.jpg","caption":"Roxane Lecacher"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2021 - N\u00e9e quelques jours avant la premi\u00e8re \u00e9toile des Bleus, je baigne dans une famille tr\u00e8s sportive. Je n\u2019ai eu d\u2019autres choix que de me passionner pour le sujet. Pratiquante de l\u2019athl\u00e9tisme depuis toute petite, j\u2019ai aussi un attrait tout particulier pour la Formule 1, le biathlon et le foot. Pendant les grands \u00e9v\u00e9nements, il est impossible de d\u00e9crocher de ma t\u00e9l\u00e9. C\u2019est \u00e0 travers Dicodusport que j\u2019aime d\u00e9sormais vous transmettre mes \u00e9motions et ma passion.","sameAs":["https:\/\/www.facebook.com\/roxane.lecacher","https:\/\/fr.linkedin.com\/in\/roxane-lecacher-23368313b"],"url":"https:\/\/dicodusport.fr\/blog\/author\/roxanel\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/438347","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/54"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=438347"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/438347\/revisions"}],"predecessor-version":[{"id":438380,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/438347\/revisions\/438380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/438387"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=438347"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=438347"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=438347"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}