{"id":441982,"date":"2023-12-02T16:40:40","date_gmt":"2023-12-02T15:40:40","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=441982&#038;preview=true&#038;preview_id=441982"},"modified":"2023-12-02T16:56:50","modified_gmt":"2023-12-02T15:56:50","slug":"coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/","title":{"rendered":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE DE SNOWBOARDCROSS &#8211; Lors de l&rsquo;ouverture de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo ont pris une belle deuxi\u00e8me place lors de l&rsquo;\u00e9preuve par \u00e9quipes, derri\u00e8re d&rsquo;intouchables britanniques.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Belle entr\u00e9e en mati\u00e8re pour nos Fran\u00e7ais pour l&rsquo;ouverture de la <strong>Coupe du monde de Snowboard<\/strong>. Solides en qualifications, en quarts de finale et en demi-finales, <strong>Chlo\u00e9 Trespeuch<\/strong> et <strong>Loan Bozzolo<\/strong> ont r\u00e9pondu \u00e9galement aux attentes en finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddeb\ud83c\uddf7 Podium \u00e0 la maison ! \ud83d\udd25<br \/>\nDans la station des 2 Alpes, \u00e0 la maison, Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la 2\u20e3e place du snowboard cross par \u00e9quipe. \ud83c\uddeb\ud83c\uddf7 \ud83d\udcaa\ud83d\udd25<\/p>\n<p>\ud83d\udcf8 FIS <a href=\"https:\/\/t.co\/pfybApJDMx\">pic.twitter.com\/pfybApJDMx<\/a><\/p>\n<p>\u2014 FFS &#8211; F\u00e9d\u00e9ration Fran\u00e7aise de Ski (@FedFranceSki) <a href=\"https:\/\/twitter.com\/FedFranceSki\/status\/1730962656759079234?ref_src=twsrc%5Etfw\">December 2, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Charlotte Bankes \u00e9tait trop forte<\/h2>\n<p style=\"text-align: justify;\">Se montrant r\u00e9guliers et performants, ils prennent une tr\u00e8s belle deuxi\u00e8me place derri\u00e8re les Britanniques. Il faut dire que <strong>Charlotte Bankes<\/strong> a tenu son rang de patronne. La derni\u00e8re vainqueure du <strong>Gros Globe de Cristal<\/strong> a tout le temps r\u00e9cup\u00e9r\u00e9 le temps perdu par son \u00e9quipier <strong>Huw Nightingale<\/strong>, sur toutes les manches. Elle permet \u00e0 la Grande-Bretagne de remporter cette manche avec une belle marge. Les Am\u00e9ricains <strong>Lindsey Jacobellis<\/strong> et <strong>Jake Vedder<\/strong> compl\u00e8tent le podium.<\/p>\n<p style=\"text-align: justify;\"><strong>Aidan Chollet<\/strong> et <strong>Manon Petit-Lenoir<\/strong> ont d\u00fb rendre les armes en quarts de finale, la faute \u00e0 une chute de la Fran\u00e7aise dans le dernier virage. Quant \u00e0 la paire <strong>Merlin Surget<\/strong> \/ <strong>L\u00e9a Casta<\/strong>, ils ont subi exactement le m\u00eame sort.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE SNOWBOARDCROSS &#8211; Lors de l&rsquo;ouverture de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo ont pris une belle deuxi\u00e8me place lors de l&rsquo;\u00e9preuve par \u00e9quipes, derri\u00e8re d&rsquo;intouchables britanniques.<\/p>\n","protected":false},"author":92,"featured_media":442007,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10126],"tags":[16878,3021,28526],"class_list":["post-441982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-snowboard","tag-breve","tag-chloe-trespeuch","tag-loan-bozzolo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes<\/title>\n<meta name=\"description\" content=\"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\" \/>\n<meta property=\"og:description\" content=\"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-02T15:40:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-02T15:56:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Olivier Dobiezynski\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/Olivier_Matros\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\"},\"author\":{\"name\":\"Olivier Dobiezynski\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc\"},\"headline\":\"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\",\"datePublished\":\"2023-12-02T15:40:40+00:00\",\"dateModified\":\"2023-12-02T15:56:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\"},\"wordCount\":270,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png\",\"keywords\":[\"br\u00e8ve\",\"Chlo\u00e9 Trespeuch\",\"Loan Bozzolo\"],\"articleSection\":[\"Snowboard\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\",\"name\":\"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png\",\"datePublished\":\"2023-12-02T15:40:40+00:00\",\"dateModified\":\"2023-12-02T15:56:50+00:00\",\"description\":\"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png\",\"width\":1200,\"height\":674,\"caption\":\"Coupe du monde Snowboardcross Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc\",\"name\":\"Olivier Dobiezynski\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg\",\"caption\":\"Olivier Dobiezynski\"},\"description\":\"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/x.com\/Olivier_Matros\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/olivier-gh\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes","description":"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes","og_description":"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-12-02T15:40:40+00:00","article_modified_time":"2023-12-02T15:56:50+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png","type":"image\/png"}],"author":"Olivier Dobiezynski","twitter_card":"summary_large_image","twitter_title":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes","twitter_creator":"@https:\/\/x.com\/Olivier_Matros","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/"},"author":{"name":"Olivier Dobiezynski","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc"},"headline":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes","datePublished":"2023-12-02T15:40:40+00:00","dateModified":"2023-12-02T15:56:50+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/"},"wordCount":270,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png","keywords":["br\u00e8ve","Chlo\u00e9 Trespeuch","Loan Bozzolo"],"articleSection":["Snowboard"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/","name":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png","datePublished":"2023-12-02T15:40:40+00:00","dateModified":"2023-12-02T15:56:50+00:00","description":"Lors de la Coupe du monde de Snowboardcross aux Deux Alpes, les Fran\u00e7ais Chlo\u00e9 Trespeuch et Loan Bozzolo prennent la seconde place.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Coupe-du-monde-Snowboardcross-Trespeuch-et-Bozzolo-deuxiemes-aux-Deux-Alpes.png","width":1200,"height":674,"caption":"Coupe du monde Snowboardcross Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-trespeuch-et-bozzolo-deuxiemes-aux-deux-alpes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde Snowboardcross : Trespeuch et Bozzolo deuxi\u00e8mes aux Deux-Alpes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fe500246414ca17ddf0c0312d7a792cc","name":"Olivier Dobiezynski","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/09\/5be8fe8d-9962-4f1e-ad06-d6f9dee30e6d-150x150.jpg","caption":"Olivier Dobiezynski"},"description":"Depuis le milieu des ann\u00e9es 90, la passion du cyclisme m'anime. Mes h\u00e9ros s'appellent Luc Leblanc, Piotr Ugrumov, Paolo Savoldelli, Peter Sagan et bien \u00e9videmment Romain Bardet. R\u00e9dacteur depuis 2023, je suis ici pour partager cet amour de la Petite Reine. Vous pourrez me lire \u00e9galement sur du trail, du ski de fond et tout autre sujet susceptible d'\u00e9veiller ma curiosit\u00e9 sportive.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/Olivier_Matros"],"url":"https:\/\/dicodusport.fr\/blog\/author\/olivier-gh\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/441982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/92"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=441982"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/441982\/revisions"}],"predecessor-version":[{"id":442013,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/441982\/revisions\/442013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/442007"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=441982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=441982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=441982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}