{"id":442794,"date":"2023-12-05T21:28:45","date_gmt":"2023-12-05T20:28:45","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=442794&#038;preview=true&#038;preview_id=442794"},"modified":"2023-12-06T07:47:57","modified_gmt":"2023-12-06T06:47:57","slug":"volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/","title":{"rendered":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL &#8211; Dans sa salle, le Vol\u00e9ro Le Cannet n&rsquo;a pas fait le poids contre les Roumaines d&rsquo;Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Trois matchs, trois victoires : pour l&rsquo;instant, soit \u00e0 mi-parcours de la phase de poule, tout se passe pour le mieux pour le <strong>Vol\u00e9ro Le Cannet<\/strong>. Les doubles championnes de France avaient l&rsquo;occasion de frapper ce soir un grand coup, et de se rapprocher d&rsquo;une qualification directe en quarts de finale de la Ligue des Champions. Pour cela, il fallait vaincre Alba Blaj \u00e0 La Palestre, <a href=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-arrache-la-victoire-sur-le-parquet-dalba-blaj\/\">apr\u00e8s avoir domin\u00e9 ce m\u00eame adversaire au tie-break \u00e0 l&rsquo;aller en Roumanie<\/a>.<\/p>\n<p style=\"text-align: justify;\">Sauf que la rencontre n&rsquo;a pas suivi le sc\u00e9nario escompt\u00e9. Certes, la lutte a \u00e9t\u00e9 f\u00e9roce, mais la premi\u00e8re manche est tomb\u00e9e dans l&rsquo;escarcelle roumaine, puis la deuxi\u00e8me alors que Le Cannet menait <strong>24-23<\/strong> avant d&rsquo;encaisser trois points d&rsquo;affil\u00e9e. On attendait une r\u00e9action, on a eu une noyade. Les Cannetanes vont totalement perdre pied dans le troisi\u00e8me set pour finalement subir une lourde d\u00e9faite<strong> 3-0<\/strong> devant leur public (<strong>25-23, 26-24, 25-15<\/strong>), leur premi\u00e8re en Ligue des Champions cette saison. N\u00e9anmoins, rien n&rsquo;est encore fait dans cette poule ultra dense, et il reste deux matchs aux Azur\u00e9ennes pour prouver qu&rsquo;elles ont leur place en quarts de finale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL &#8211; Dans sa salle, le Vol\u00e9ro Le Cannet n&rsquo;a pas fait le poids contre les Roumaines d&rsquo;Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":442837,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[16878,28388,27409,24931],"class_list":["post-442794","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-breve","tag-ligue-des-champions-feminine-de-volleyball","tag-volero-le-cannet","tag-volleyball-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n&#039;a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n&#039;a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-05T20:28:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-06T06:47:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\",\"datePublished\":\"2023-12-05T20:28:45+00:00\",\"dateModified\":\"2023-12-06T06:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/\"},\"wordCount\":258,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png\",\"keywords\":[\"br\u00e8ve\",\"Ligue des Champions f\u00e9minine de volleyball\",\"Vol\u00e9ro Le Cannet\",\"volleyball fran\u00e7ais\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/\",\"name\":\"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png\",\"datePublished\":\"2023-12-05T20:28:45+00:00\",\"dateModified\":\"2023-12-06T06:47:57+00:00\",\"description\":\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n'a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png\",\"width\":1200,\"height\":674,\"caption\":\"Volley Ligue des Champions f\u00e9minine Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj","description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n'a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/","og_locale":"fr_FR","og_type":"article","og_title":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj","og_description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n'a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-12-05T20:28:45+00:00","article_modified_time":"2023-12-06T06:47:57+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj","datePublished":"2023-12-05T20:28:45+00:00","dateModified":"2023-12-06T06:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/"},"wordCount":258,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png","keywords":["br\u00e8ve","Ligue des Champions f\u00e9minine de volleyball","Vol\u00e9ro Le Cannet","volleyball fran\u00e7ais"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/","url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/","name":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png","datePublished":"2023-12-05T20:28:45+00:00","dateModified":"2023-12-06T06:47:57+00:00","description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Le Cannet n'a pas fait le poids contre Alba Blaj, et conc\u00e8de une d\u00e9faite s\u00e8che en trois manches.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Volley-Ligue-des-Champions-feminine-Le-Cannet-chute-lourdement-a-domicile-contre-Alba-Blaj.png","width":1200,"height":674,"caption":"Volley Ligue des Champions f\u00e9minine Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-le-cannet-chute-lourdement-a-domicile-contre-alba-blaj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volley Ligue des Champions f\u00e9minine : Le Cannet chute lourdement \u00e0 domicile contre Alba Blaj"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442794","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=442794"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442794\/revisions"}],"predecessor-version":[{"id":442865,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442794\/revisions\/442865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/442837"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=442794"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=442794"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=442794"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}