{"id":442976,"date":"2023-12-06T16:48:54","date_gmt":"2023-12-06T15:48:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=442976&#038;preview=true&#038;preview_id=442976"},"modified":"2023-12-07T05:08:29","modified_gmt":"2023-12-07T04:08:29","slug":"transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/","title":{"rendered":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2023-2024 &#8211; Selon L&rsquo;\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Lyon<\/strong> a mal d\u00e9marr\u00e9 son mercato pour la saison prochaine en perdant deux internationaux, \u00e0 quelques semaines d&rsquo;intervalle. <strong>Demba<\/strong> <strong>Bamba<\/strong> puis <strong>Romain<\/strong> <strong>Taofifenua<\/strong> ont en effet accept\u00e9 de rejoindre le <strong>Racing<\/strong> <strong>92<\/strong> \u00e0 compter de l&rsquo;\u00e9t\u00e9 2024. Mais le <strong>LOU<\/strong> a depuis redress\u00e9 la barre en r\u00e9ussissant \u00e0 prolonger plusieurs cadres pourtant tr\u00e8s courtis\u00e9s, comme <strong>L\u00e9o Berdeu<\/strong> et <strong>Killian Geraci<\/strong>.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-top-14-2024-2025-tableau-du-mercato\/\" target=\"_blank\" rel=\"noopener\">Transferts Top 14 2024-2025 \u2013 Tableau du mercato<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Paddy Jackson et Thibaut Regard vont rester au LOU<\/h2>\n<p style=\"text-align: justify;\">Arriv\u00e9 cette saison au <strong>LOU<\/strong>, <strong>Paddy<\/strong> <strong>Jackson<\/strong> a r\u00e9alis\u00e9 de belles prestations et a pleinement convaincu en interne. Alors que son premier passage en France \u00e0 <strong>Perpignan<\/strong> n&rsquo;avait pas \u00e9t\u00e9 un succ\u00e8s, l&rsquo;ouvreur irlandais semble avoir franchi un cap. En fin de contrat en juin, il serait proche de signer un nouveau bail pour deux saisons suppl\u00e9mentaires.<\/p>\n<p style=\"text-align: justify;\"><strong>Thibaut<\/strong> <strong>Regard<\/strong>, qui a fait toute sa carri\u00e8re au <strong>LOU<\/strong>, qu&rsquo;il a rejoint en 2008 \u00e0 tout juste 15 ans, arrive aussi au terme de son engagement en juin prochain. L&rsquo;homme aux 241 matchs avec le club rhodanien est toujours \u00e0 son meilleur niveau et va poursuivre l&rsquo;aventure avec les Lyonnais. Il est tomb\u00e9 d&rsquo;accord avec ses dirigeants pour une prolongation de trois ans, soit jusqu&rsquo;\u00e0 l&rsquo;\u00e9t\u00e9 2027. Il a disput\u00e9 sept rencontres cette saison dont six comme titulaire.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Thibaut Regard s&rsquo;engage pour trois ans de plus au LOU <a href=\"https:\/\/t.co\/G4PJA3VMiK\">https:\/\/t.co\/G4PJA3VMiK<\/a> via <a href=\"https:\/\/twitter.com\/lequipe?ref_src=twsrc%5Etfw\">@lequipe<\/a><\/p>\n<p>\u2014 JF Paturaud (@JFPaturaud) <a href=\"https:\/\/twitter.com\/JFPaturaud\/status\/1732415086302814667?ref_src=twsrc%5Etfw\">December 6, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon L&rsquo;\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.<\/p>\n","protected":false},"author":1,"featured_media":442978,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[16878,2812],"class_list":["post-442976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-lou"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon L&#039;\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon L&#039;\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-06T15:48:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-07T04:08:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir\",\"datePublished\":\"2023-12-06T15:48:54+00:00\",\"dateModified\":\"2023-12-07T04:08:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\"},\"wordCount\":273,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png\",\"keywords\":[\"br\u00e8ve\",\"LOU\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\",\"name\":\"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png\",\"datePublished\":\"2023-12-06T15:48:54+00:00\",\"dateModified\":\"2023-12-07T04:08:29+00:00\",\"description\":\"TOP 14 2023-2024 - Selon L'\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby : Paddy Jackson, Bayonne, les infos du mercredi 24 janvier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir","description":"TOP 14 2023-2024 - Selon L'\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir","og_description":"TOP 14 2023-2024 - Selon L'\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-12-06T15:48:54+00:00","article_modified_time":"2023-12-07T04:08:29+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir","datePublished":"2023-12-06T15:48:54+00:00","dateModified":"2023-12-07T04:08:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/"},"wordCount":273,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png","keywords":["br\u00e8ve","LOU"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/","name":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png","datePublished":"2023-12-06T15:48:54+00:00","dateModified":"2023-12-07T04:08:29+00:00","description":"TOP 14 2023-2024 - Selon L'\u00c9quipe, Paddy Jackson et Thibaut Regard vont prolonger leur contrat avec le LOU.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-LOU-Paddy-Jackson-et-Thibaut-Regard-ont-tranche-pour-leur-avenir.png","width":1200,"height":674,"caption":"Transferts Rugby : Paddy Jackson, Bayonne, les infos du mercredi 24 janvier"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-lou-paddy-jackson-et-thibaut-regard-ont-tranche-pour-leur-avenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts LOU : Paddy Jackson et Thibaut Regard ont tranch\u00e9 pour leur avenir"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=442976"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442976\/revisions"}],"predecessor-version":[{"id":443089,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/442976\/revisions\/443089"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/442978"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=442976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=442976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=442976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}