{"id":446762,"date":"2023-12-21T08:08:15","date_gmt":"2023-12-21T07:08:15","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=446762&#038;preview=true&#038;preview_id=446762"},"modified":"2023-12-21T08:08:15","modified_gmt":"2023-12-21T07:08:15","slug":"la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/","title":{"rendered":"La perf&rsquo; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/basket-ball\/nba\/nba-2023-2024\/\">SAISON NBA 2023\/2024<\/a> &#8211; Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n&rsquo;ont rien pu faire contre Joel Embiid, parfaitement second\u00e9 par Tyrese Maxey, et qui bat son record de la saison.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">La saison des Minnesota Timberwolves d\u00e9passe pour l&rsquo;instant toutes les esp\u00e9rances. Meilleur<strong> defensive rating<\/strong> de la NBA, les Loups ont b\u00e9n\u00e9fici\u00e9 de l&rsquo;apport d&rsquo;un certain <strong>Rudy Gobert<\/strong> dans ce secteur, alors qu&rsquo;<strong>Anthony Edwards<\/strong> et <strong>Karl-Anthony Towns<\/strong> rayonnent au centre du projet. Ce qui donnait un bilan de 20v \/ 5d sur les 25 premiers matchs de la saison, le meilleur de toute la ligue. Mais hier soir, les Wolves se sont fracass\u00e9s sur un rocher appel\u00e9 <strong>Joel Embiid<\/strong>.<\/p>\n<p style=\"text-align: justify;\">MVP en titre, le Camerouno-Am\u00e9ricano-Fran\u00e7ais vise le doubl\u00e9, et ce match pourrait compter en fin de saison. Contre la meilleur d\u00e9fense actuelle, il a envoy\u00e9<strong> 51 points<\/strong> (17\/25 au tir) assortis de 12 rebonds. Inarr\u00eatable, il a grandement contribu\u00e9 \u00e0 la victoire<strong> 127-113<\/strong> des 76ers, solides 3e \u00e0 l&rsquo;Est. On n&rsquo;oublie pas <strong>Tyrese Maxey<\/strong>, son lieutenant officiel, qui a envoy\u00e9 35 unit\u00e9s cette nuit, dans la lign\u00e9e de sa belle saison qui pourrait le conduire \u00e0 une premi\u00e8re \u00e9toile de <em>All-Star<\/em>. Mais c&rsquo;est bien <strong>Joel Embiid<\/strong> qui a pes\u00e9 le plus lourd, battant son record de points cette saison, et envoyant un message \u00e0 tous ceux qui l&rsquo;accusaient de ne coller des cartons qu&rsquo;aux \u00ab\u00a0petites\u00a0\u00bb \u00e9quipes. De quoi envisager une nouvelle statuette.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">JOEL. EMBIID. \ud83d\ude24<\/p>\n<p>51 POINTS<br \/>\n12 REBONDS<br \/>\n17-25 FG<br \/>\n17-18 FT<\/p>\n<p>Le tout, face \u00e0 la meilleure d\u00e9fense de la ligue&#8230; \ud83d\udea7 <a href=\"https:\/\/t.co\/8VbZthlBrO\">pic.twitter.com\/8VbZthlBrO<\/a><\/p>\n<p>\u2014 NBA France (@NBAFRANCE) <a href=\"https:\/\/twitter.com\/NBAFRANCE\/status\/1737728711787520289?ref_src=twsrc%5Etfw\">December 21, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAISON NBA 2023\/2024 &#8211; Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n&rsquo;ont rien pu faire contre Joel Embiid, parfaitement second\u00e9 par Tyrese Maxey, et qui bat son record de la saison.<\/p>\n","protected":false},"author":59,"featured_media":446765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10533],"tags":[16878,2524,13273],"class_list":["post-446762","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-breve","tag-joel-embiid","tag-philadelphia-76ers"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La perf&#039; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves<\/title>\n<meta name=\"description\" content=\"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n&#039;ont rien pu faire contre Joel Embiid.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La perf&#039; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves\" \/>\n<meta property=\"og:description\" content=\"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n&#039;ont rien pu faire contre Joel Embiid.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-21T07:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La perf&#039; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"La perf&rsquo; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves\",\"datePublished\":\"2023-12-21T07:08:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\"},\"wordCount\":285,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png\",\"keywords\":[\"br\u00e8ve\",\"Joel Embiid\",\"Philadelphia 76ers\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\",\"name\":\"La perf' de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png\",\"datePublished\":\"2023-12-21T07:08:15+00:00\",\"description\":\"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n'ont rien pu faire contre Joel Embiid.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png\",\"width\":1200,\"height\":674,\"caption\":\"La perf' de la nuit en NBA Joel Embiid en colle 51 aux Timberwolves\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La perf&rsquo; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La perf' de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves","description":"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n'ont rien pu faire contre Joel Embiid.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/","og_locale":"fr_FR","og_type":"article","og_title":"La perf' de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves","og_description":"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n'ont rien pu faire contre Joel Embiid.","og_url":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-12-21T07:08:15+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"La perf' de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"La perf&rsquo; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves","datePublished":"2023-12-21T07:08:15+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/"},"wordCount":285,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png","keywords":["br\u00e8ve","Joel Embiid","Philadelphia 76ers"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/","url":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/","name":"La perf' de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png","datePublished":"2023-12-21T07:08:15+00:00","description":"SAISON NBA 2023\/2024 - Meilleur bilan et meilleure d\u00e9fense de la NBA, les Timberwolves n'ont rien pu faire contre Joel Embiid.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/La-perf-de-la-nuit-en-NBA-Joel-Embiid-en-colle-51-aux-Timberwolves.png","width":1200,"height":674,"caption":"La perf' de la nuit en NBA Joel Embiid en colle 51 aux Timberwolves"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/la-perf-de-la-nuit-en-nba-joel-embiid-en-colle-51-aux-timberwolves\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"La perf&rsquo; de la nuit en NBA : Joel Embiid en colle 51 aux Timberwolves"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/446762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=446762"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/446762\/revisions"}],"predecessor-version":[{"id":446766,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/446762\/revisions\/446766"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/446765"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=446762"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=446762"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=446762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}