{"id":44774,"date":"2019-08-06T16:11:28","date_gmt":"2019-08-06T14:11:28","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=44774"},"modified":"2019-08-06T16:31:00","modified_gmt":"2019-08-06T14:31:00","slug":"l-italie-absente-des-jo-2020-a-tokyo","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/","title":{"rendered":"L&rsquo;Italie absente des JO 2020 \u00e0 Tokyo ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Verra-t-on l&rsquo;Italie \u00e0 Tokyo ? Rien n&rsquo;est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au CONI, le Comit\u00e9 Olympique National Italien. Ce dernier est en effet menac\u00e9 par le parlement transalpin.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Selon les informations du <strong>Corriere della Sera<\/strong>, le <a href=\"https:\/\/www.olympic.org\/fr\" target=\"_blank\" rel=\"noopener\"><strong>CIO<\/strong><\/a> aurait envoy\u00e9 une lettre ce mardi au <strong>Comit\u00e9 Olympique National Italien<\/strong>. En cause, les lois discut\u00e9es au Parlement transalpin, qui menaceraient l&rsquo;ind\u00e9pendance du <strong>CONI<\/strong>. Si cette derni\u00e8re devait \u00eatre remise en cause, cela serait alors <em>\u00ab non-conforme aux principes de la Charte olympique. \u00bb <\/em>Dans sa lettre, le <strong>CIO<\/strong> met en garde le comit\u00e9 italien, expliquant que <em>\u00ab l&rsquo;autonomie du sport est formellement \u00e9tablie dans une r\u00e9solution de l&rsquo;Assembl\u00e9e g\u00e9n\u00e9rale des Nations Unies adopt\u00e9e \u00e0 New-York en octobre 2014. \u00bb <\/em><\/p>\n<p style=\"text-align: justify;\">Deuxi\u00e8me cons\u00e9quence possible, et pas des moindres, l&rsquo;Italie serait \u00e9galement priv\u00e9e de l&rsquo;organisation des JO d&rsquo;hiver 2026, pr\u00e9vus \u00e0 Milan. Le <strong>CIO<\/strong> a ainsi pr\u00e9cis\u00e9 que <em>\u00ab Le CONI ne devrait pas \u00eatre r\u00e9organis\u00e9 par des d\u00e9cisions unilat\u00e9rales du gouvernement. \u00bb <\/em>Avant ces hypoth\u00e9tiques (lourdes) cons\u00e9quences, le <strong>Comit\u00e9 International Olympique<\/strong> n&rsquo;exclut pas d&rsquo;organiser une r\u00e9union dans les prochains jours \u00e0 Lausanne. Affaire \u00e0 suivre.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Verra-t-on l&rsquo;Italie \u00e0 Tokyo ? Rien n&rsquo;est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au CONI, le Comit\u00e9 Olympique National Italien. Ce dernier est en effet menac\u00e9 par le parlement transalpin.<\/p>\n","protected":false},"author":4,"featured_media":44776,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8433],"tags":[374,396],"class_list":["post-44774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-jo-tokyo-2020","tag-italie","tag-jo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L&#039;Italie absente des JO 2020 \u00e0 Tokyo ?<\/title>\n<meta name=\"description\" content=\"Verra-t-on l&#039;Italie \u00e0 Tokyo ? Rien n&#039;est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Italie absente des JO 2020 \u00e0 Tokyo ?\" \/>\n<meta property=\"og:description\" content=\"Verra-t-on l&#039;Italie \u00e0 Tokyo ? Rien n&#039;est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-06T14:11:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-06T14:31:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;Italie absente des JO 2020 \u00e0 Tokyo ?\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"L&rsquo;Italie absente des JO 2020 \u00e0 Tokyo ?\",\"datePublished\":\"2019-08-06T14:11:28+00:00\",\"dateModified\":\"2019-08-06T14:31:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/\"},\"wordCount\":212,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LItalie-absente-des-JO-2020-_.png\",\"keywords\":[\"Italie\",\"JO\"],\"articleSection\":[\"JO Tokyo 2020\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/\",\"name\":\"L'Italie absente des JO 2020 \u00e0 Tokyo ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LItalie-absente-des-JO-2020-_.png\",\"datePublished\":\"2019-08-06T14:11:28+00:00\",\"dateModified\":\"2019-08-06T14:31:00+00:00\",\"description\":\"Verra-t-on l'Italie \u00e0 Tokyo ? Rien n'est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LItalie-absente-des-JO-2020-_.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/LItalie-absente-des-JO-2020-_.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/l-italie-absente-des-jo-2020-a-tokyo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;Italie absente des JO 2020 \u00e0 Tokyo ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'Italie absente des JO 2020 \u00e0 Tokyo ?","description":"Verra-t-on l'Italie \u00e0 Tokyo ? Rien n'est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/","og_locale":"fr_FR","og_type":"article","og_title":"L'Italie absente des JO 2020 \u00e0 Tokyo ?","og_description":"Verra-t-on l'Italie \u00e0 Tokyo ? Rien n'est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.","og_url":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2019-08-06T14:11:28+00:00","article_modified_time":"2019-08-06T14:31:00+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"L'Italie absente des JO 2020 \u00e0 Tokyo ?","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"L&rsquo;Italie absente des JO 2020 \u00e0 Tokyo ?","datePublished":"2019-08-06T14:11:28+00:00","dateModified":"2019-08-06T14:31:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/"},"wordCount":212,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png","keywords":["Italie","JO"],"articleSection":["JO Tokyo 2020"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/","url":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/","name":"L'Italie absente des JO 2020 \u00e0 Tokyo ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png","datePublished":"2019-08-06T14:11:28+00:00","dateModified":"2019-08-06T14:31:00+00:00","description":"Verra-t-on l'Italie \u00e0 Tokyo ? Rien n'est moins s\u00fbr. Le Comit\u00e9 International Olympique a envoy\u00e9 ce mardi une lettre au Comit\u00e9 Olympique National Italien.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/LItalie-absente-des-JO-2020-_.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/l-italie-absente-des-jo-2020-a-tokyo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;Italie absente des JO 2020 \u00e0 Tokyo ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/44774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=44774"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/44774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/44776"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=44774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=44774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=44774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}