{"id":447816,"date":"2023-12-28T10:08:26","date_gmt":"2023-12-28T09:08:26","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=447816&#038;preview=true&#038;preview_id=447816"},"modified":"2023-12-28T11:59:31","modified_gmt":"2023-12-28T10:59:31","slug":"transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/","title":{"rendered":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Antoine<\/strong> <strong>Dupont<\/strong> va vivre une premi\u00e8re partie d&rsquo;ann\u00e9e 2024 tr\u00e8s particuli\u00e8re, car il sera partag\u00e9 entre le <strong>Stade<\/strong> <strong>Toulousain<\/strong> et France 7. Le capitaine du XV de France ne devrait pas prendre part au Tournoi des 6 Nations 2024 pour se concentrer sur la pr\u00e9paration des <strong>Jeux<\/strong> <strong>Olympiques<\/strong>. Si tout est boucl\u00e9 jusqu&rsquo;\u00e0 l&rsquo;\u00e9v\u00e9nement plan\u00e9taire \u00e0 Paris, la suite de l&rsquo;ann\u00e9e est un peu plus flou.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-toulouse-antoine-dupont-pourrait-signer-au-japon-apres-les-jo-2024\/\" target=\"_blank\" rel=\"noopener\">Transferts Toulouse : Antoine Dupont pourrait signer au Japon apr\u00e8s les JO 2024<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Antoine Dupont va rester au Stade Toulousain<\/h2>\n<p style=\"text-align: justify;\">En d\u00e9but de semaine, nos confr\u00e8res de <em>L&rsquo;\u00c9quipe<\/em> expliquaient qu&rsquo;il y avait une possibilit\u00e9 <strong>qu&rsquo;Antoine<\/strong> <strong>Dupont<\/strong> fasse une pige au Japon apr\u00e8s les JO de Paris 2024, et qu&rsquo;il pourrait en cons\u00e9quent manquer le Tournoi des 6 Nations 2025. Mais selon le <em>Midol<\/em>, le demi de m\u00eal\u00e9e des Bleus devrait bien rester au Stade Toulousain la saison prochaine.<\/p>\n<p style=\"text-align: justify;\">Comme \u00e9voqu\u00e9 par <strong>Didier<\/strong> <strong>Lacroix<\/strong>, il y a bien une possibilit\u00e9 qu&rsquo;il fasse une pause apr\u00e8s le tournoi olympique apr\u00e8s <strong>France<\/strong> <strong>7<\/strong>. Le demi de m\u00eal\u00e9e sera ensuite de retour avec Toulouse en Top 14. <strong>Antoine<\/strong> <strong>Dupont<\/strong> sera donc pr\u00e9sent pour le Tournoi des 6 Nations 2025 avec le XV de France. Il faudra suivre comment <strong>Fabien<\/strong> <strong>Galthi\u00e9<\/strong> g\u00e9rera le capitanat, puisque <strong>Charles Ollivon<\/strong> devrait le r\u00e9cup\u00e9rer pendant l&rsquo;absence de la star fran\u00e7aise.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\uddeb\ud83c\uddf7 S\u2019il ne devrait pas participer au prochain Tournoi des 6 Nations pour se concentrer sur son int\u00e9gration avec France 7, Antoine Dupont ne fera pas de pige au Japon et sera pr\u00e9sent pour l\u2019\u00e9dition 2025.<\/p>\n<p>\u27a1\ufe0f Plus d&rsquo;infos &gt; <a href=\"https:\/\/t.co\/eLSklZkY64\">https:\/\/t.co\/eLSklZkY64<\/a> <a href=\"https:\/\/t.co\/29qYvETgMz\">pic.twitter.com\/29qYvETgMz<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1740295458516603283?ref_src=twsrc%5Etfw\">December 28, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.<\/p>\n","protected":false},"author":1,"featured_media":447817,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[2373,16878,7278,4008],"class_list":["post-447816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-antoine-dupont","tag-breve","tag-dupont","tag-stade-toulousain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-28T09:08:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-28T10:59:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir\",\"datePublished\":\"2023-12-28T09:08:26+00:00\",\"dateModified\":\"2023-12-28T10:59:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png\",\"keywords\":[\"Antoine Dupont\",\"br\u00e8ve\",\"Dupont\",\"Stade Toulousain\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\",\"name\":\"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png\",\"datePublished\":\"2023-12-28T09:08:26+00:00\",\"dateModified\":\"2023-12-28T10:59:31+00:00\",\"description\":\"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir","og_description":"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-12-28T09:08:26+00:00","article_modified_time":"2023-12-28T10:59:31+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir","datePublished":"2023-12-28T09:08:26+00:00","dateModified":"2023-12-28T10:59:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png","keywords":["Antoine Dupont","br\u00e8ve","Dupont","Stade Toulousain"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/","name":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png","datePublished":"2023-12-28T09:08:26+00:00","dateModified":"2023-12-28T10:59:31+00:00","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Antoine Dupont ne devrait pas aller au Japon la saison prochaine et participera au 6 Nations 2025.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/Transferts-Stade-Toulousain-Antoine-Dupont-a-tranche-pour-son-avenir.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-antoine-dupont-a-tranche-pour-son-avenir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Stade Toulousain : Antoine Dupont a tranch\u00e9 pour son avenir"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/447816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=447816"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/447816\/revisions"}],"predecessor-version":[{"id":447838,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/447816\/revisions\/447838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/447817"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=447816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=447816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=447816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}