{"id":448404,"date":"2023-12-30T17:37:05","date_gmt":"2023-12-30T16:37:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=448404&#038;preview=true&#038;preview_id=448404"},"modified":"2024-01-06T10:11:18","modified_gmt":"2024-01-06T09:11:18","slug":"nba-goran-dragic-annonce-sa-retraite","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/","title":{"rendered":"NBA : Goran Dragic annonce sa retraite"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/?s=nba\">NBA 2023\/24<\/a> &#8211; A 37 ans, et sans contrat depuis l&rsquo;\u00e9t\u00e9 dernier, Goran Dragic a annonc\u00e9 ce samedi la fin de sa carri\u00e8re. Une fois All Star et champion d&rsquo;Europe avec la Slov\u00e9nie, le meneur aura marqu\u00e9 le basket mondial durant les quinze derni\u00e8res ann\u00e9es.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Finalement, le retour de <strong>Goran Dragic<\/strong> sur les parquets <strong>NBA<\/strong> n&rsquo;aura pas lieu. Longtemps annonc\u00e9 du c\u00f4t\u00e9 de Miami, le meneur slov\u00e8ne n&rsquo;a pas trouv\u00e9 de contrat l&rsquo;\u00e9t\u00e9 dernier, et il vient d&rsquo;annoncer officiellement la fin de son immense carri\u00e8re. A 37 ans, il disputera une sorte de jubil\u00e9 chez lui \u00e0 <strong>Ljubljana<\/strong> au mois d&rsquo;ao\u00fbt prochain pour mettre un terme d\u00e9finitif \u00e0 une longue histoire.<\/p>\n<h2 style=\"text-align: justify;\">MIP et All Star en NBA, MVP et champion d&rsquo;Europe avec la Slov\u00e9nie<\/h2>\n<p style=\"text-align: justify;\">Lanc\u00e9 en 2004 par le <strong>Slovan<\/strong> en Slov\u00e9nie, Dragic aura connu une belle premi\u00e8re carri\u00e8re en Europe, gravissant une \u00e0 une les \u00e9tapes pour devenir le leader du <strong>Petrol Olimpija<\/strong> en EuroLigue. Suite \u00e0 une excellente campagne, il s&rsquo;\u00e9tait ensuite envol\u00e9 outre-Atlantique en 2008 en rejoignant les <strong>Phoenix Suns<\/strong>. Cantonn\u00e9 \u00e0 un r\u00f4le de rempla\u00e7ant durant trois ans, il a ensuite pris de l&rsquo;\u00e9paisseur lors de ses deux ann\u00e9es suivantes du c\u00f4t\u00e9 de <strong>Houston<\/strong>. Mais c&rsquo;est bien lors de son deuxi\u00e8me passage avec les Suns que le Slov\u00e8ne va franchir un \u00e9norme cap. Il devient un titulaire indiscutable et signe une saison \u00e0 plus de 20 points de moyenne, ce qui lui permet au passage d&rsquo;\u00eatre \u00e9lu <strong>MIP en 2014<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Transf\u00e9r\u00e9 ensuite \u00e0 <strong>Miami<\/strong>, il va y passer plus de six ans en marquant durablement la franchise. R\u00e9compens\u00e9 par une s\u00e9lection au <strong>All Star Game en 2018<\/strong>, il aura \u00e9galement \u00e9t\u00e9 d\u00e9terminant dans la magnifique campagne de play-offs du Heat de 2020 o\u00f9 la franchise s&rsquo;est hiss\u00e9e jusqu&rsquo;en finales NBA. Ensuite pass\u00e9 par Brooklyn, Toronto, Chicago et Milwaukee, il quitte la NBA avec plus de 900 rencontres au compteur.<\/p>\n<p style=\"text-align: justify;\">Par ailleurs, il s&rsquo;est \u00e9galement illustr\u00e9 en s\u00e9lection nationale. En 2017, il a \u00e9t\u00e9 \u00e9lu <strong>MVP de l&rsquo;EuroBasket remport\u00e9 \u00e0 la surprise g\u00e9n\u00e9rale par la Slov\u00e9nie<\/strong>, aux c\u00f4t\u00e9s notamment d&rsquo;un tout jeune Luka Doncic.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">After 15 NBA seasons, Goran Dragic is retiring and will play a farewell game in Slovenia in August. The one-time All-Star and Most Improved Player of the Year played 946 NBA games for the Heat, Suns, Rockets, Raptors, Nets, Bulls and Bucks. <a href=\"https:\/\/t.co\/YaRNqmprn3\">pic.twitter.com\/YaRNqmprn3<\/a><\/p>\n<p>\u2014 Shams Charania (@ShamsCharania) <a href=\"https:\/\/twitter.com\/ShamsCharania\/status\/1741117568486609062?ref_src=twsrc%5Etfw\">December 30, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>NBA 2023\/24 &#8211; A 37 ans, et sans contrat depuis l&rsquo;\u00e9t\u00e9 dernier, Goran Dragic a annonc\u00e9 ce samedi la fin de sa carri\u00e8re. Une fois All Star et champion d&rsquo;Europe avec la Slov\u00e9nie, le meneur aura marqu\u00e9 le basket mondial durant les quinze derni\u00e8res ann\u00e9es.<\/p>\n","protected":false},"author":55,"featured_media":448408,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10533],"tags":[16878,179,1803],"class_list":["post-448404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nba","tag-breve","tag-nba","tag-slovenie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>NBA : Goran Dragic annonce sa retraite<\/title>\n<meta name=\"description\" content=\"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NBA : Goran Dragic annonce sa retraite\" \/>\n<meta property=\"og:description\" content=\"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-30T16:37:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-06T09:11:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"NBA : Goran Dragic annonce sa retraite\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"NBA : Goran Dragic annonce sa retraite\",\"datePublished\":\"2023-12-30T16:37:05+00:00\",\"dateModified\":\"2024-01-06T09:11:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png\",\"keywords\":[\"br\u00e8ve\",\"NBA\",\"slovenie\"],\"articleSection\":[\"NBA\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\",\"name\":\"NBA : Goran Dragic annonce sa retraite\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png\",\"datePublished\":\"2023-12-30T16:37:05+00:00\",\"dateModified\":\"2024-01-06T09:11:18+00:00\",\"description\":\"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png\",\"width\":1200,\"height\":674,\"caption\":\"NBA : Goran Dragic annonce sa retraite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NBA : Goran Dragic annonce sa retraite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"NBA : Goran Dragic annonce sa retraite","description":"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/","og_locale":"fr_FR","og_type":"article","og_title":"NBA : Goran Dragic annonce sa retraite","og_description":"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.","og_url":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-12-30T16:37:05+00:00","article_modified_time":"2024-01-06T09:11:18+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"NBA : Goran Dragic annonce sa retraite","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"NBA : Goran Dragic annonce sa retraite","datePublished":"2023-12-30T16:37:05+00:00","dateModified":"2024-01-06T09:11:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png","keywords":["br\u00e8ve","NBA","slovenie"],"articleSection":["NBA"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/","url":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/","name":"NBA : Goran Dragic annonce sa retraite","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png","datePublished":"2023-12-30T16:37:05+00:00","dateModified":"2024-01-06T09:11:18+00:00","description":"NBA 2023-2024 - Le meneur slov\u00e8ne Goran Dragic, All Star \u00e0 une reprise, a annonc\u00e9 la fin de sa carri\u00e8re \u00e0 37 ans.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/NBA-Gordan-Dragic-annonce-sa-retraite.png","width":1200,"height":674,"caption":"NBA : Goran Dragic annonce sa retraite"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/nba-goran-dragic-annonce-sa-retraite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"NBA : Goran Dragic annonce sa retraite"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/448404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=448404"}],"version-history":[{"count":4,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/448404\/revisions"}],"predecessor-version":[{"id":449673,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/448404\/revisions\/449673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/448408"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=448404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=448404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=448404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}