{"id":449333,"date":"2024-01-05T09:44:43","date_gmt":"2024-01-05T08:44:43","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=449333&#038;preview=true&#038;preview_id=449333"},"modified":"2026-01-03T14:12:38","modified_gmt":"2026-01-03T13:12:38","slug":"dakar-2024-motos-classement-prologue","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/","title":{"rendered":"Dakar 2024 Motos &#8211; Classement prologue"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-mecaniques\/dakar\/\">DAKAR<\/a> 2024 &#8211; Retrouvez le classement du prologue du <a href=\"https:\/\/fr.wikipedia.org\/wiki\/Rallye_Dakar_2024\">Dakar 2024<\/a> dans la cat\u00e9gorie motos, qui s&rsquo;est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024. Vingt-sept kilom\u00e8tres chronom\u00e9tr\u00e9s \u00e9taient au programme autour de AlUla.<\/i><\/b><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/dakar-2024-parcours-et-calendrier-des-etapes\/\">Dakar 2024 : Parcours et calendrier des \u00e9tapes<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Classement Prologue Motos &#8211; Dakar 2024<\/h2>\n<p style=\"text-align: justify;\"><strong><span style=\"font-size: 14px;\"><em>Cette ann\u00e9e, le prologue ne compte pas pour le classement g\u00e9n\u00e9ral.<\/em><\/span><\/strong><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><img decoding=\"async\" class=\"emoji\" role=\"img\" src=\"https:\/\/s.w.org\/images\/core\/emoji\/14.0.0\/svg\/1f3c6.svg\" alt=\"\" \/><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>PILOTES<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS<br \/>\n<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 Tosha SCHAREINA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">17m35s<\/span><\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa Daniel SANDERS<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL GAS GAS FACTORY TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 12s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde7\ud83c\uddfc Ross BRANCH<\/strong><br \/>\n<span style=\"font-size: 0.8em\">HERO MOTOSPORTS TEAM RALLY<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 19s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 Adrien VAN BEVEREN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 24s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddf7 Luciano BENAVIDES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">HUSQVARNA FACTORY RACING<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 26s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 Sam SUNDERLAND<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL GAS GAS FACTORY TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 28s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7<\/span><span style=\"font-size: 0.9em\">.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\uddf1 Pablo QUINTANILLA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MONSTER ENERGY HONDA TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 47s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddfa Toby PRICE<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL KTM FACTORY TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 51s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde6\ud83c\uddf7 Kevin BENAVIDES<\/strong><br \/>\n<span style=\"font-size: 0.8em\">RED BULL KTM FACTORY TEAM<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 56s<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddfa\ud83c\uddf8 Mason KLEIN<\/strong><br \/>\n<span style=\"font-size: 0.8em\">KORR OFFROAD RACING<\/span><br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\u00e0 58s<\/span><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2>\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.dakar.live.worldrallyraidchampionship.com\/fr\/moto\/0\/classements\"><strong>Dakar 2024 &#8211; Motos : le classement complet du prologue<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>DAKAR 2024 &#8211; Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s&rsquo;est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.<\/p>\n","protected":false},"author":4,"featured_media":449337,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9493],"tags":[16878,2736],"class_list":["post-449333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dakar","tag-breve","tag-dakar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dakar 2024 Motos - Classement prologue<\/title>\n<meta name=\"description\" content=\"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s&#039;est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dakar 2024 Motos - Classement prologue\" \/>\n<meta property=\"og:description\" content=\"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s&#039;est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-05T08:44:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-03T13:12:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Dakar 2024 Motos - Classement prologue\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Dakar 2024 Motos &#8211; Classement prologue\",\"datePublished\":\"2024-01-05T08:44:43+00:00\",\"dateModified\":\"2026-01-03T13:12:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\"},\"wordCount\":159,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png\",\"keywords\":[\"br\u00e8ve\",\"dakar\"],\"articleSection\":[\"Dakar\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\",\"name\":\"Dakar 2024 Motos - Classement prologue\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png\",\"datePublished\":\"2024-01-05T08:44:43+00:00\",\"dateModified\":\"2026-01-03T13:12:38+00:00\",\"description\":\"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png\",\"width\":1200,\"height\":674,\"caption\":\"Dakar 2024 Motos - Classement prologue\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dakar 2024 Motos &#8211; Classement prologue\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dakar 2024 Motos - Classement prologue","description":"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/","og_locale":"fr_FR","og_type":"article","og_title":"Dakar 2024 Motos - Classement prologue","og_description":"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.","og_url":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-01-05T08:44:43+00:00","article_modified_time":"2026-01-03T13:12:38+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Dakar 2024 Motos - Classement prologue","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Dakar 2024 Motos &#8211; Classement prologue","datePublished":"2024-01-05T08:44:43+00:00","dateModified":"2026-01-03T13:12:38+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/"},"wordCount":159,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png","keywords":["br\u00e8ve","dakar"],"articleSection":["Dakar"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/","url":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/","name":"Dakar 2024 Motos - Classement prologue","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png","datePublished":"2024-01-05T08:44:43+00:00","dateModified":"2026-01-03T13:12:38+00:00","description":"DAKAR 2024 - Retrouvez le classement du prologue du Dakar 2024 dans la cat\u00e9gorie motos, qui s'est d\u00e9roul\u00e9 ce vendredi 5 janvier 2024.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Dakar-2024-Motos-Classement-prologue.png","width":1200,"height":674,"caption":"Dakar 2024 Motos - Classement prologue"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/dakar-2024-motos-classement-prologue\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Dakar 2024 Motos &#8211; Classement prologue"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/449333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=449333"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/449333\/revisions"}],"predecessor-version":[{"id":635574,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/449333\/revisions\/635574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/449337"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=449333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=449333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=449333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}