{"id":450818,"date":"2024-01-09T20:23:52","date_gmt":"2024-01-09T19:23:52","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=450818&#038;preview=true&#038;preview_id=450818"},"modified":"2024-01-11T14:27:18","modified_gmt":"2024-01-11T13:27:18","slug":"volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/","title":{"rendered":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/?s=ligue+des+champions+feminine+volley\">LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL<\/a> &#8211; Le Volley Mulhouse Alsace s&rsquo;est inclin\u00e9 face au Vakifbank Spor K\u00fcl\u00fcb\u00fc, 3-0, et se retrouve d\u00e9finitivement hors course pour la qualification en 8e de finale.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Les journ\u00e9es s&rsquo;enchainent et les d\u00e9faites \u00e9galement pour <strong>Mulhouse<\/strong>. Dans une poule extr\u00eamement d\u00e9licate, les Alsaciennes souffrent. Pour leur cinqui\u00e8me rencontre, ces derni\u00e8res ont essuy\u00e9 un cinqui\u00e8me revers de rang. \u00c0 domicile, elles ont \u00e9t\u00e9 impuissantes face \u00e0 la puissance des doubles championnes d&rsquo;Europe en titre, les Turques du <strong>Vakifbank Spor K\u00fcb\u00fcl\u00fc<\/strong>. Pourtant, les Tricolores se sont montr\u00e9es accrocheuses en livrant une r\u00e9elle bataille. Mais les Turques ont effectu\u00e9 une gestion parfaite en assurant le coup jusqu&rsquo;\u00e0 mi-manche avant d&rsquo;acc\u00e9l\u00e9rer pour emp\u00eacher les locales d&rsquo;esp\u00e9rer quoi que ce soit. Ainsi, ces derni\u00e8res s&rsquo;envolent en r\u00e9p\u00e9tant ce sc\u00e9nario dans les deux premi\u00e8res, avant de finir le boulot en d\u00e9roulant dans l&rsquo;ultime manche (25-22\/25-20\/25-17).<\/p>\n<p style=\"text-align: justify;\">Battu 3-0 \u00e0 domicile, <strong>Mulhouse est d\u00e9sormais officiellement \u00e9limin\u00e9 de toutes coupes d&rsquo;Europe<\/strong>, et tentera de sauver l&rsquo;honneur lors de la derni\u00e8re journ\u00e9e, o\u00f9 le club affrontera les Serbes de <strong>Jedinstvo<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">End of the third set \u2935\ufe0f<br \/>\nVolley Mulhouse Alsace: 17 &#8211; Vak\u0131fBank: 25<br \/>\nSets: 0-3<a href=\"https:\/\/twitter.com\/hashtag\/ForMore?src=hash&amp;ref_src=twsrc%5Etfw\">#ForMore<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/CLVolleyW?src=hash&amp;ref_src=twsrc%5Etfw\">#CLVolleyW<\/a> <a href=\"https:\/\/t.co\/Dovx7rCeDK\">pic.twitter.com\/Dovx7rCeDK<\/a><\/p>\n<p>\u2014 Vak\u0131fBankSporKul\u00fcb\u00fc (@VakifBankSK) <a href=\"https:\/\/twitter.com\/VakifBankSK\/status\/1744801643952996657?ref_src=twsrc%5Etfw\">January 9, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL &#8211; Le Volley Mulhouse Alsace s&rsquo;est inclin\u00e9 face au Vakifbank Spor K\u00fcl\u00fcb\u00fc, 3-0, et se retrouve hors course pour la qualification en 8e de finale.<\/p>\n","protected":false},"author":55,"featured_media":450839,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8369],"tags":[7721,16878,28388,24931],"class_list":["post-450818","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-volley-ball","tag-asptt-mulhouse-volley","tag-breve","tag-ligue-des-champions-feminine-de-volleyball","tag-volleyball-francais"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s&#039;est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s&#039;est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-09T19:23:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-11T13:27:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre\",\"datePublished\":\"2024-01-09T19:23:52+00:00\",\"dateModified\":\"2024-01-11T13:27:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/\"},\"wordCount\":250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png\",\"keywords\":[\"ASPTT Mulhouse Volley\",\"br\u00e8ve\",\"Ligue des Champions f\u00e9minine de volleyball\",\"volleyball fran\u00e7ais\"],\"articleSection\":[\"Volley-Ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/\",\"name\":\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png\",\"datePublished\":\"2024-01-09T19:23:52+00:00\",\"dateModified\":\"2024-01-11T13:27:18+00:00\",\"description\":\"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s'est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png\",\"width\":1200,\"height\":674,\"caption\":\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tentant en titre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre","description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s'est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/","og_locale":"fr_FR","og_type":"article","og_title":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre","og_description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s'est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.","og_url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-01-09T19:23:52+00:00","article_modified_time":"2024-01-11T13:27:18+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre","datePublished":"2024-01-09T19:23:52+00:00","dateModified":"2024-01-11T13:27:18+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/"},"wordCount":250,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png","keywords":["ASPTT Mulhouse Volley","br\u00e8ve","Ligue des Champions f\u00e9minine de volleyball","volleyball fran\u00e7ais"],"articleSection":["Volley-Ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/","url":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/","name":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png","datePublished":"2024-01-09T19:23:52+00:00","dateModified":"2024-01-11T13:27:18+00:00","description":"LIGUE DES CHAMPIONS F\u00c9MININE DE VOLLEYBALL - Mulhouse s'est lourdement inclin\u00e9 face au Vakifbank Spor K\u00fcb\u00fcl\u00fc, 3-0.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Volley-Ligue-des-Champions-feminine-Mulhouse-domine-par-le-double-tentant-en-titre.png","width":1200,"height":674,"caption":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tentant en titre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/volley-ligue-des-champions-feminine-mulhouse-domine-par-le-double-tentant-en-titre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Volley Ligue des Champions f\u00e9minine : Mulhouse domin\u00e9 par le double tenant en titre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/450818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=450818"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/450818\/revisions"}],"predecessor-version":[{"id":450864,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/450818\/revisions\/450864"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/450839"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=450818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=450818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=450818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}