{"id":45360,"date":"2019-08-13T08:26:55","date_gmt":"2019-08-13T06:26:55","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=45360"},"modified":"2019-08-13T09:51:51","modified_gmt":"2019-08-13T07:51:51","slug":"l-om-et-adil-rami-c-est-definitivement-termine","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/","title":{"rendered":"L&rsquo;OM et Adil Rami, c&rsquo;est d\u00e9finitivement termin\u00e9"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Selon l\u2019\u00c9quipe, Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave. Le d\u00e9fenseur international, champion du monde avec les Bleus, est d\u00e9sormais libre de s&rsquo;engager avec un autre club.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Vis\u00e9 par une proc\u00e9dure disciplinaire, <strong>Adil Rami<\/strong> a re\u00e7u sa lettre de r\u00e9siliation de contrat pour faute grave. C&rsquo;est ce qu&rsquo;avancent <em>l&rsquo;Equipe<\/em> et <em>La Provence<\/em>. Coupable de certains \u00e9carts la saison derni\u00e8re selon le pr\u00e9sident de l&rsquo;<strong>OM<\/strong>, <strong>Jacques-Henri Eyraud<\/strong>, c&rsquo;est le passage du natif de Bastia dans l&rsquo;\u00e9mission de t\u00e9l\u00e9vision <em>Fort Boyard<\/em>, enregistr\u00e9e le 20 mai dernier, qui aurait men\u00e9 \u00e0 cette proc\u00e9dure <strong>L&rsquo;aventure olympienne du joueur de 33 ans se termine deux avant la fin de son contrat, en 2021, apr\u00e8s avoir d\u00e9but\u00e9 durant l&rsquo;hiver 2017<\/strong>. Le d\u00e9fenseur international aura disput\u00e9 une finale d&rsquo;Europe League avec le club phoc\u00e9en, en 2018.<\/p>\n<p style=\"text-align: justify;\">Mais la bataille entre l&rsquo;ancien joueur du <strong>FC S\u00e9ville<\/strong> et la direction de l&rsquo;<strong>OM<\/strong> ne devrait pas en rester l\u00e0. Apr\u00e8s un rendez-vous qui n&rsquo;a rien donn\u00e9 entre les deux parties le 30 juillet dernier devant <strong>la commission juridique de la LFP<\/strong>, c&rsquo;est aux prud&rsquo;hommes que les deux camps devraient se retrouver, l&rsquo;ancien Lillois voulant montrer qu&rsquo;il n&rsquo;a commis aucune faute grave.<\/p>\n<p><strong><em>Dicodusport<br \/>\n<a href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/dicodusport\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Selon l\u2019\u00c9quipe, Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave. Le d\u00e9fenseur international, champion du monde avec les Bleus, est d\u00e9sormais libre de s&rsquo;engager avec un autre club.<\/p>\n","protected":false},"author":4,"featured_media":45365,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[75,1889],"class_list":["post-45360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-football","tag-om"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;OM et Adil Rami, c&#039;est d\u00e9finitivement termin\u00e9<\/title>\n<meta name=\"description\" content=\"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;OM et Adil Rami, c&#039;est d\u00e9finitivement termin\u00e9\" \/>\n<meta property=\"og:description\" content=\"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-13T06:26:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-13T07:51:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;OM et Adil Rami, c&#039;est d\u00e9finitivement termin\u00e9\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"L&rsquo;OM et Adil Rami, c&rsquo;est d\u00e9finitivement termin\u00e9\",\"datePublished\":\"2019-08-13T06:26:55+00:00\",\"dateModified\":\"2019-08-13T07:51:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\"},\"wordCount\":239,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png\",\"keywords\":[\"Football\",\"OM\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\",\"name\":\"L'OM et Adil Rami, c'est d\u00e9finitivement termin\u00e9\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png\",\"datePublished\":\"2019-08-13T06:26:55+00:00\",\"dateModified\":\"2019-08-13T07:51:51+00:00\",\"description\":\"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;OM et Adil Rami, c&rsquo;est d\u00e9finitivement termin\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'OM et Adil Rami, c'est d\u00e9finitivement termin\u00e9","description":"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/","og_locale":"fr_FR","og_type":"article","og_title":"L'OM et Adil Rami, c'est d\u00e9finitivement termin\u00e9","og_description":"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.","og_url":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2019-08-13T06:26:55+00:00","article_modified_time":"2019-08-13T07:51:51+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"L'OM et Adil Rami, c'est d\u00e9finitivement termin\u00e9","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"L&rsquo;OM et Adil Rami, c&rsquo;est d\u00e9finitivement termin\u00e9","datePublished":"2019-08-13T06:26:55+00:00","dateModified":"2019-08-13T07:51:51+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/"},"wordCount":239,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png","keywords":["Football","OM"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/","url":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/","name":"L'OM et Adil Rami, c'est d\u00e9finitivement termin\u00e9","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png","datePublished":"2019-08-13T06:26:55+00:00","dateModified":"2019-08-13T07:51:51+00:00","description":"Selon l\u2019\u00c9quipe, le d\u00e9fenseur international Adil Rami a re\u00e7u une lettre de r\u00e9siliation de contrat pour faute grave.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Adil-Rami-OM.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/l-om-et-adil-rami-c-est-definitivement-termine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;OM et Adil Rami, c&rsquo;est d\u00e9finitivement termin\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/45360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=45360"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/45360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/45365"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=45360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=45360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=45360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}