{"id":454081,"date":"2024-01-18T18:56:58","date_gmt":"2024-01-18T17:56:58","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=454081&#038;preview=true&#038;preview_id=454081"},"modified":"2024-01-18T21:43:00","modified_gmt":"2024-01-18T20:43:00","slug":"transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/","title":{"rendered":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><strong><em>TRANSFERTS RUGBY &#8211; Avenir scell\u00e9 pour Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau <\/em><\/strong><strong><em>: les infos transferts de ce jeudi 18 janvier 2024.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Stade Toulousain : Jack Willis jouera \u00e0 Toulouse la saison prochaine<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est act\u00e9. Le troisi\u00e8me ligne anglais <strong>Jack Willis<\/strong> (27 ans) \u00e9voluera \u00e0 Toulouse la saison prochaine. Rappel des faits. Au printemps dernier,<strong> Willis<\/strong> avait sign\u00e9 une prolongation de trois saisons, avec les deux derni\u00e8res en option. Ainsi, il s&rsquo;\u00e9tait engag\u00e9 par l&rsquo;exercice 2023-2024. Les saisons 2024-2025 et 2025-26 \u00e9taient en option.<\/p>\n<p style=\"text-align: justify;\">Dans les faits, <strong>Jack Willis<\/strong> avait jusqu\u2019au 31 d\u00e9cembre 2023 pour annuler l&rsquo;option de la saison prochaine, mais l&rsquo;Anglais ne l\u2019a pas fait. Par cons\u00e9quent, l&rsquo;ancien joueur des <strong>Wasps<\/strong> est dor\u00e9navant li\u00e9 au <strong>Stade Toulousain<\/strong> jusqu\u2019en juin 2025. Pour l&rsquo;\u00eatre aussi en vue de la saison 2025-2026, il aura de nouveau jusqu\u2019au 31 d\u00e9cembre 2024 pour la valider, ou non. Une excellente nouvelle donc pour <strong>Toulouse<\/strong>, qui pourra compter sur l&rsquo;Anglais durant les doublons du 6 Nations, ce dernier n&rsquo;\u00e9tant plus \u00e9ligible avec le XV de la Rose.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis Dicodusport<\/strong> : Une bonne chose de valid\u00e9e pour le board toulousain, qui est plus que satisfait du rendement de l&rsquo;international anglais. Que ce soit en sortie de banc ou dans le costume de titulaire, ses prestations sont toujours positives. Son exp\u00e9rience et sa science du combat seront pr\u00e9cieuses durant le 6 Nations.<\/em><\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211;\u00a0<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-stade-toulousain-jack-willis-a-tranche-pour-son-avenir\/\">Transferts Stade Toulousain : Jack Willis a tranch\u00e9 pour son avenir<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">USAP : Alivereti Duguivalu rempile<\/h2>\n<p style=\"text-align: justify;\">Nouvelle prolongation \u00e0 <strong>Perpignan<\/strong>. \u00c0 26 ans, <strong>Alivereti Duguivalu<\/strong> va poursuivre sa carri\u00e8re \u00e0 l&rsquo;<strong>USAP<\/strong>. Celui qui \u00e9volue au sein du club catalan depuis ses d\u00e9buts professionnels, en 2017, a prolong\u00e9 pour deux saisons suppl\u00e9mentaires avec les <em>Sang et Or<\/em>. Le Fidjien, qui poss\u00e8de le statut JIFF, est d\u00e9sormais li\u00e9 aux Usapistes jusqu&rsquo;en 2026.<\/p>\n<p style=\"text-align: justify;\">Cette saison, l&rsquo;ailier\/arri\u00e8re fidjien a disput\u00e9 six rencontres, dont cinq dans la peau d&rsquo;un titulaire. Il compte, depuis 2017, 51 feuilles de match avec l&rsquo;<strong>USAP<\/strong>. Il s&rsquo;agit de la neuvi\u00e8me prolongation contrat dans les rangs perpignanais, apr\u00e8s, entre autres, <strong>Posolo Tuilagi<\/strong>, <strong>Joaquin Oviedo<\/strong> ou encore <strong>Jake McIntyre<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis Dicodusport<\/strong> : Dans la continuit\u00e9 de ces derni\u00e8res semaines, l&rsquo;USAP continue de prolonger ses fid\u00e8les parmi les fid\u00e8les. Alivereti Duguivalu en fait partie et est logiquement reconduit pour les deux prochaines saisons.<\/em><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud835\udde3\ud835\uddff\ud835\uddfc\ud835\uddf9\ud835\uddfc\ud835\uddfb\ud835\uddf4\ud835\uddee\ud835\ude01\ud835\uddf6\ud835\uddfc\ud835\uddfb \u270d\ufe0f<\/p>\n<p>Alivereti Duguivalu prolonge avec le club pour deux saisons suppl\u00e9mentaires \u2611\ufe0f<a href=\"https:\/\/twitter.com\/hashtag\/prolongation?src=hash&amp;ref_src=twsrc%5Etfw\">#prolongation<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/avenir?src=hash&amp;ref_src=twsrc%5Etfw\">#avenir<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Usap?src=hash&amp;ref_src=twsrc%5Etfw\">#Usap<\/a> <a href=\"https:\/\/t.co\/0hOrPU3xZY\">pic.twitter.com\/0hOrPU3xZY<\/a><\/p>\n<p>\u2014 USAP (@usap_officiel) <a href=\"https:\/\/twitter.com\/usap_officiel\/status\/1747979923656933399?ref_src=twsrc%5Etfw\">January 18, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Pau : Thomas Carol prolonge sur la dur\u00e9e<\/h2>\n<p style=\"text-align: justify;\">Sixi\u00e8me prolongation dans les rangs de la<strong> Section Paloise<\/strong>. Apr\u00e8s <strong>Siate Tokolahi<\/strong>, <strong>Guram Papidze<\/strong>, <strong>Sacha Zegueur<\/strong>, <strong>Tumua Manu<\/strong> et <strong>Nathan Decron<\/strong>, c&rsquo;est au tour de<strong> Thomas Carol<\/strong> de prolonger. L&rsquo;arri\u00e8re\/ailier de 23 ans est arriv\u00e9 \u00e0 <strong>Pau<\/strong> en 2021, avec un contrat espoir \u00e0 la cl\u00e9. Pass\u00e9 par les centres de formation du <strong>Racing 92<\/strong> et du <strong>Stade Rochelais<\/strong>, <strong>Carol<\/strong>, \u00e9galement membre de l&rsquo;\u00e9quipe de France \u00e0 7, est d\u00e9sormais li\u00e9 au club b\u00e9arnais jusqu&rsquo;en 2026, avec cette fois, un contrat professionnel.<\/p>\n<p style=\"text-align: justify;\">Depuis le d\u00e9but de la saison, <strong>Thomas Carol<\/strong> a pris part \u00e0 six rencontres avec la<strong> Section Paloise<\/strong>, toutes entam\u00e9es dans le costume de titulaire. Depuis 2021, celui qui a fait ses premiers pas rugbystiques \u00e0 <strong>Boulogne-Billancourt<\/strong> a port\u00e9 \u00e0 21 reprises le maillot de la <strong>Section Paloise<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><em><strong>L&rsquo;avis Dicodusport<\/strong> : Ambitieuse, la Section Paloise est active sur le march\u00e9 des transferts. Mais elle compte aussi sur ses jeunes, et le prouve en prolongeant Carol, apr\u00e8s Zegueur et Decron.<\/em><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u270d\ufe0f \ud835\udc7b\ud835\udc89\ud835\udc90\ud835\udc8e\ud835\udc82\ud835\udc94 \ud835\udc6a\ud835\udc82\ud835\udc93\ud835\udc90\ud835\udc8d \ud83e\udd1d 2\ufe0f\u20e30\ufe0f\u20e32\ufe0f\u20e36\ufe0f\u20e3<\/p>\n<p>Au tour de notre ailier-arri\u00e8re \u00e0 XV et international France 7 de prolonger l&rsquo;aventure en B\u00e9arn, il signe son premier contrat professionnel \ud83d\udc49 <a href=\"https:\/\/t.co\/8EeQsk66YK\">https:\/\/t.co\/8EeQsk66YK<\/a><a href=\"https:\/\/twitter.com\/hashtag\/HonhaSection?src=hash&amp;ref_src=twsrc%5Etfw\">#HonhaSection<\/a> <a href=\"https:\/\/t.co\/f3jUQxQcbP\">pic.twitter.com\/f3jUQxQcbP<\/a><\/p>\n<p>\u2014 SectionPaloise (@SectionPaloise) <a href=\"https:\/\/twitter.com\/SectionPaloise\/status\/1747932540189446214?ref_src=twsrc%5Etfw\">January 18, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TRANSFERTS RUGBY &#8211; Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.<\/p>\n","protected":false},"author":4,"featured_media":454089,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[32415,16878,28226,13,110,29105],"class_list":["post-454081","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-actu","tag-breve","tag-mercato-rugby","tag-rugby","tag-rugby-a-xv","tag-transferts-rugby"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier<\/title>\n<meta name=\"description\" content=\"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\" \/>\n<meta property=\"og:description\" content=\"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-18T17:56:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-18T20:43:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\",\"datePublished\":\"2024-01-18T17:56:58+00:00\",\"dateModified\":\"2024-01-18T20:43:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\"},\"wordCount\":637,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png\",\"keywords\":[\"actu\",\"br\u00e8ve\",\"Mercato Rugby\",\"Rugby\",\"Rugby \u00e0 XV\",\"Transferts rugby\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\",\"name\":\"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png\",\"datePublished\":\"2024-01-18T17:56:58+00:00\",\"dateModified\":\"2024-01-18T20:43:00+00:00\",\"description\":\"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png\",\"width\":1200,\"height\":674,\"caption\":\"Transferts Rugby Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier","description":"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier","og_description":"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2024-01-18T17:56:58+00:00","article_modified_time":"2024-01-18T20:43:00+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier","datePublished":"2024-01-18T17:56:58+00:00","dateModified":"2024-01-18T20:43:00+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/"},"wordCount":637,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png","keywords":["actu","br\u00e8ve","Mercato Rugby","Rugby","Rugby \u00e0 XV","Transferts rugby"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/","name":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png","datePublished":"2024-01-18T17:56:58+00:00","dateModified":"2024-01-18T20:43:00+00:00","description":"TRANSFERTS RUGBY - Avenir scell\u00e9 par Jack Willis, \u00e7a prolonge \u00e0 Perpignan et Pau : les infos transferts de ce jeudi 18 janvier 2024.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Rugby-Jack-Willis-USAP-Pau-les-infos-du-jeudi-18-janvier.png","width":1200,"height":674,"caption":"Transferts Rugby Jack Willis, USAP, Pau, les infos du jeudi 18 janvier"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-rugby-jack-willis-usap-pau-les-infos-du-jeudi-18-janvier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Rugby : Jack Willis, USAP, Pau, les infos du jeudi 18 janvier"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/454081","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=454081"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/454081\/revisions"}],"predecessor-version":[{"id":454169,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/454081\/revisions\/454169"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/454089"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=454081"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=454081"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=454081"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}