{"id":45512,"date":"2019-08-15T13:07:22","date_gmt":"2019-08-15T11:07:22","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=45512"},"modified":"2019-08-30T13:49:29","modified_gmt":"2019-08-30T11:49:29","slug":"retrospective-sur-la-coupe-du-monde-de-basket-ball","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/","title":{"rendered":"R\u00e9trospective sur la Coupe du monde de basket-ball"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Avis aux amateurs de basket ! Si vous ma\u00eetrisez l&rsquo;anglais, vous appr\u00e9cierez ce documentaire qui retrace l&rsquo;histoire de la Coupe du monde de basket-ball FIBA.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">A l&rsquo;occasion de la Coupe du monde masculine 2019 de basket (31 ao\u00fbt-15 septembre), la FIBA met en ligne un documentaire en quatre \u00e9pisodes sur l&rsquo;histoire de l&rsquo;ancien Championnat du monde de basket-ball.<\/p>\n<p style=\"text-align: justify;\">\u00c9v\u00e8nement\u00a0qui passionne les fans \u00e0 travers le monde, le premier championnat du monde a eu lieu en 1950. Ce documentaire fait un focus sur les joueurs, les matchs et les \u00e9ditions qui ont fait de cette comp\u00e9tition ce qu&rsquo;elle est aujourd&rsquo;hui. On y retrouve des interviews de stars qui ont marqu\u00e9 la comp\u00e9tition.<\/p>\n<ul style=\"list-style-type: square;\">\n<li style=\"text-align: justify;\"><strong>9 ao\u00fbt<\/strong> \u2013 <a href=\"https:\/\/www.youtube.com\/watch?v=wFYsDkR0d3Y&amp;\" target=\"_blank\" rel=\"noopener\">Episode 1<\/a> :<br \/>\n<em><em>Une r\u00e9trospective de l&rsquo;histoire de la Coupe du monde de basket-ball FIBA en commen\u00e7ant par 1994 et la Dream Team 2<\/em><\/em><\/li>\n<li style=\"text-align: justify;\"><strong>16 ao\u00fbt<\/strong> \u2013 <a href=\"https:\/\/www.youtube.com\/watch?v=t08_YnGC67w\" target=\"_blank\" rel=\"noopener\">Episode 2<\/a> :<br \/>\n<em><em>Les 5 premi\u00e8res \u00e9ditions de la Coupe du monde de basket-ball FIBA qui ont eu lieu en Am\u00e9rique du Sud et la rivalit\u00e9 f\u00e9roce entre l&rsquo;ex-Yougoslavie et l&rsquo;ex-URSS<\/em><\/em><\/li>\n<li style=\"text-align: justify;\"><strong>23 ao\u00fbt<\/strong> \u2013 <a href=\"https:\/\/www.youtube.com\/watch?v=6h4OtY-An2s\" target=\"_blank\" rel=\"noopener\">Episode 3<\/a> :<br \/>\n<em><em>Nouvelle g\u00e9n\u00e9ration de talents dans les ann\u00e9es 80 alors que les \u00c9tats-Unis deviennent des joueurs majeurs sur la sc\u00e8ne internationale<\/em><\/em><\/li>\n<li style=\"text-align: justify;\"><strong>30 ao\u00fbt<\/strong> \u2013 <a href=\"https:\/\/www.youtube.com\/watch?v=Xzx3PqT7Q-c\" target=\"_blank\" rel=\"noopener\">Episode 4<\/a> :<br \/>\n<em>Les Coupes du monde de basket-ball FIBA dans les ann\u00e9es 90-2000 et un coup d&rsquo;oeil sur l&rsquo;\u00e9dition 2019 en Chine<\/em><\/li>\n<\/ul>\n<p><strong><em>Arlette<\/em><\/strong><br \/>\n<a href=\"http:\/\/twitter.com\/Shiclette94\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-e1516110106986.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Avis aux amateurs de basket ! Si vous ma\u00eetrisez l&rsquo;anglais, vous appr\u00e9cierez ce documentaire qui retrace l&rsquo;histoire de la Coupe du monde de basket-ball FIBA.<\/p>\n","protected":false},"author":12,"featured_media":45515,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305,8],"tags":[174,5281],"class_list":["post-45512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","category-histoire","tag-basket","tag-coupe-du-monde-de-basket"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9trospective sur la Coupe du monde de basket-ball<\/title>\n<meta name=\"description\" content=\"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l&#039;anglais, vous appr\u00e9cierez ce documentaire qui retrace l&#039;histoire de la Coupe du monde de basket-ball FIBA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La FIBA propose une r\u00e9trospective sur la Coupe du monde de basket\" \/>\n<meta property=\"og:description\" content=\"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l&#039;anglais, vous appr\u00e9cierez ce documentaire qui retrace l&#039;histoire de la Coupe du monde de basket-ball FIBA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-15T11:07:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-30T11:49:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"La FIBA propose une r\u00e9trospective sur la Coupe du monde de basket\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"R\u00e9trospective sur la Coupe du monde de basket-ball\",\"datePublished\":\"2019-08-15T11:07:22+00:00\",\"dateModified\":\"2019-08-30T11:49:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\"},\"wordCount\":241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png\",\"keywords\":[\"basket\",\"Coupe du monde de basket\"],\"articleSection\":[\"Basket-ball\",\"Histoire\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\",\"name\":\"R\u00e9trospective sur la Coupe du monde de basket-ball\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png\",\"datePublished\":\"2019-08-15T11:07:22+00:00\",\"dateModified\":\"2019-08-30T11:49:29+00:00\",\"description\":\"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l'anglais, vous appr\u00e9cierez ce documentaire qui retrace l'histoire de la Coupe du monde de basket-ball FIBA.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00e9trospective sur la Coupe du monde de basket-ball\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"R\u00e9trospective sur la Coupe du monde de basket-ball","description":"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l'anglais, vous appr\u00e9cierez ce documentaire qui retrace l'histoire de la Coupe du monde de basket-ball FIBA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/","og_locale":"fr_FR","og_type":"article","og_title":"La FIBA propose une r\u00e9trospective sur la Coupe du monde de basket","og_description":"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l'anglais, vous appr\u00e9cierez ce documentaire qui retrace l'histoire de la Coupe du monde de basket-ball FIBA.","og_url":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2019-08-15T11:07:22+00:00","article_modified_time":"2019-08-30T11:49:29+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png","type":"image\/png"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"La FIBA propose une r\u00e9trospective sur la Coupe du monde de basket","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"R\u00e9trospective sur la Coupe du monde de basket-ball","datePublished":"2019-08-15T11:07:22+00:00","dateModified":"2019-08-30T11:49:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/"},"wordCount":241,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png","keywords":["basket","Coupe du monde de basket"],"articleSection":["Basket-ball","Histoire"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/","url":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/","name":"R\u00e9trospective sur la Coupe du monde de basket-ball","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png","datePublished":"2019-08-15T11:07:22+00:00","dateModified":"2019-08-30T11:49:29+00:00","description":"Avis aux amateurs de basket ! Si vous ma\u00eetrisez l'anglais, vous appr\u00e9cierez ce documentaire qui retrace l'histoire de la Coupe du monde de basket-ball FIBA.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/08\/Histoire-coupe-du-monde-basket.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/retrospective-sur-la-coupe-du-monde-de-basket-ball\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"R\u00e9trospective sur la Coupe du monde de basket-ball"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/45512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=45512"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/45512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/45515"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=45512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=45512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=45512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}