{"id":455421,"date":"2024-01-22T08:00:42","date_gmt":"2024-01-22T07:00:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=455421&#038;preview=true&#038;preview_id=455421"},"modified":"2024-01-22T09:46:11","modified_gmt":"2024-01-22T08:46:11","slug":"playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/","title":{"rendered":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>PLAYOFFS NFL 2024 &#8211; Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs. Si les Lions de Detroit ont fait la loi en 2\u00e8me mi-temps pour sortir 31-23 les Buccaneers de Tampa Bay, le duel au sommet entre Bills et Chiefs a livr\u00e9 un combat de gladiateur. Mahomes et les Chiefs gagnent finalement 27-24 chez les Bills d&rsquo;Allen.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-ravens-et-les-49ers-font-la-loi-a-domicile\/\">Apr\u00e8s 2 victoires \u00e0 domicile samedi<\/a>, les deux duels de dimanche s&rsquo;annon\u00e7aient \u00e9piques, serr\u00e9s et tendus. Et le contrat a \u00e9t\u00e9 rempli sur les deux pelouses. D&rsquo;abord, les <strong>Lions de D\u00e9troit<\/strong>, enfin victorieux en <em>playoffs<\/em> pour la premi\u00e8re fois depuis 1991, retrouvaient leur stade pour une 2\u00e8me fois de suite face aux <strong>Buccaneers<\/strong>, d\u00e9sireux de continuer l&rsquo;aventure. L&rsquo;autre match du jour \u00e9tait extr\u00eamement attendu avec le choc entre <strong>Josh Allen<\/strong>, \u00e0 domicile avec les <strong>Bills de Buffalo<\/strong>, et <strong>Patrick Mahomes<\/strong>, le champion en titre avec les <strong>Chiefs de Kansas City<\/strong>. <em><br \/>\n<\/em><\/p>\n<h2 style=\"text-align: justify;\">Une 2\u00e8me mi-temps de feu \u00e0 D\u00e9troit<\/h2>\n<p style=\"text-align: justify;\">La 1\u00e8re mi-temps entre les <strong>Lions<\/strong> et les <strong>Buccaneers<\/strong> ne restera pas dans les annales en termes de jeu. En effet, les d\u00e9fenses prennent le pas sur les attaques. Ces derni\u00e8res peinent \u00e0 trouver la<em> end zone<\/em>. Les 2 \u00e9quipes rentrent aux vestiaires sur le score de <strong>10-10<\/strong>. Si les <strong>Lions<\/strong> m\u00e8nent dans le jeu, les <strong>Buccaneers<\/strong> ont rat\u00e9 un <em>field goal<\/em> par <strong>Chase McLaughlin <\/strong>avant de revenir au score. Le ballon rebondit sur le poteau et la barre, au grand dam des visiteurs.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\udfa5 DOINK ! Tampa Bay tape le poteau sur ce Field Goal, et Detroit m\u00e8ne toujours de 7 points<a href=\"https:\/\/twitter.com\/Lions?ref_src=twsrc%5Etfw\">@Lions<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/AllGrit?src=hash&amp;ref_src=twsrc%5Etfw\">#AllGrit<\/a><\/p>\n<p>\ud83d\udcfa <a href=\"https:\/\/twitter.com\/beinsports_FR?ref_src=twsrc%5Etfw\">@beinsports_FR<\/a> MAX 6 <a href=\"https:\/\/twitter.com\/hashtag\/NFLextra?src=hash&amp;ref_src=twsrc%5Etfw\">#NFLextra<\/a><br \/>\n\ud83d\udcf1 <a href=\"https:\/\/twitter.com\/NFLonDAZN?ref_src=twsrc%5Etfw\">@NFLonDAZN<\/a> <a href=\"https:\/\/t.co\/ftJUyy4R0L\">pic.twitter.com\/ftJUyy4R0L<\/a><\/p>\n<p>\u2014 NFL France (@NFLFrance) <a href=\"https:\/\/twitter.com\/NFLFrance\/status\/1749176686006915369?ref_src=twsrc%5Etfw\">January 21, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Si les (t\u00e9l\u00e9)spectateurs sont rest\u00e9s sur leur faim dans cette p\u00e9riode, les attaques ont enfin enflamm\u00e9 le <strong>Ford Field<\/strong> plein comme un \u0153uf. <strong>Jared Goff<\/strong> permet aux Lions de mener dans ce duel. Proche de la zone, il transmet le ballon \u00e0 <strong>Craig Reynolds<\/strong> qui s&rsquo;enfonce dans la d\u00e9fense \u00e0 quelques <em>yards<\/em> de la ligne. L&rsquo;ambiance monte d&rsquo;un cran. Et le meilleur est \u00e0 venir.<strong> Rachaad White<\/strong> \u00e9galise sur une passe de <strong>Baker<\/strong> <strong>Mayfield<\/strong> mais cela sera insuffisant. La mobylette<strong> Jahmyr Gibbs<\/strong> remonte 30 yards au milieu d&rsquo;une d\u00e9fense semblable \u00e0 du beurre et marque en coin. Et la d\u00e9fense des <strong>Lions<\/strong> ne l\u00e2chera rien, emp\u00eachant les <strong>Buccaneers<\/strong> de s&rsquo;approcher de la terre promise.<\/p>\n<p style=\"text-align: justify;\">Et ce qui devait arriver arriva avec les h\u00f4tes qui se d\u00e9tachent enfin. <strong>Goff<\/strong> trouve parfaitement<strong> Amon-Ra St. Brown<\/strong> dans la<em> end zone<\/em>. L&rsquo;\u00e9cart est fait et les <strong>Lions<\/strong> commencent \u00e0 entrevoir le match \u00e0 <strong>San Francisco<\/strong>. Les Floridiens tentent de revenir avec un ultime <em>touchdown<\/em> mais ratent la conversion \u00e0 2 points. La d\u00e9fense locale fait le travail, notamment une interception de <strong>Derrick Barnes<\/strong> \u00e0 40 secondes du terme qui plie le match. Gr\u00e2ce \u00e0 ce succ\u00e8s <strong>31-23<\/strong>, les Lions vont en finale de conf\u00e9rence pour la 1\u00e8re fois depuis 1991 ! Ce n&rsquo;est pas ce soir que le lion est mort. Le match de dimanche prochain sera chez les <strong>49ers de San Francisco<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">FINAL: The <a href=\"https:\/\/twitter.com\/Lions?ref_src=twsrc%5Etfw\">@Lions<\/a> are headed to the NFC Championship! <a href=\"https:\/\/twitter.com\/hashtag\/NFLPlayoffs?src=hash&amp;ref_src=twsrc%5Etfw\">#NFLPlayoffs<\/a> <a href=\"https:\/\/t.co\/qqWlyXCbvy\">pic.twitter.com\/qqWlyXCbvy<\/a><\/p>\n<p>\u2014 NFL (@NFL) <a href=\"https:\/\/twitter.com\/NFL\/status\/1749208476675698997?ref_src=twsrc%5Etfw\">January 21, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Le show sur la pelouse<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;\u00e9tait attendu et le duel a tenu ses promesses. Courses, passes, d\u00e9fenses, envol\u00e9es, positions improbables, l&rsquo;ensemble de la panoplie du football \u00e9tait pr\u00e9sente. Entre <strong>Josh Allen<\/strong>, soutenu par toute la <em>Bills Mafia<\/em> \u00e0 domicile, et <strong>Patrick Mahomes<\/strong>, il a fallu des nerfs d&rsquo;acier pour acc\u00e9der \u00e0 la finale et affronter les <strong>Ravens \u00e0 Baltimore<\/strong>. Dans un 1er quart-temps musel\u00e9 par les d\u00e9fenses, les 2 \u00e9quipes sont \u00e0 \u00e9galit\u00e9 <strong>3-3<\/strong>. Et le show des 2 <em>quarterbacks<\/em> commen\u00e7a, se r\u00e9pondant coups pour coups. D&rsquo;abord, <strong>Josh Allen<\/strong> prend les choses en main et trouve la cl\u00e9 dans la d\u00e9fense adverse. Il va inscrire le 1er <em>touchdown<\/em> de la partie. Mais les <strong>Chiefs<\/strong> ne se laissent pas faire et repassent devant. Le chass\u00e9-crois\u00e9 commence. La connexion entre <strong>Mahomes<\/strong> et <strong>Travis Kelce<\/strong> se met alors en place. Le fantasque <em>quarterback<\/em> trouve parfaitement son <em>tight end<\/em> pour prendre la t\u00eate. De quoi piquer <strong>Josh Allen<\/strong>. Il prend les choses en main et ses responsabilit\u00e9s en allant marquer son 2\u00e8me <em>touchdown<\/em> de la soir\u00e9e juste avant la pause. Ainsi, les <strong>Bills<\/strong> m\u00e8nent <strong>17-13<\/strong> \u00e0 la mi-temps.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83c\udfa5 LE DOUBL\u00c9 POUR JOSH ALLEN ! 2e Touchdown au sol juste avant la mi-temps <a href=\"https:\/\/twitter.com\/hashtag\/BillsMafia?src=hash&amp;ref_src=twsrc%5Etfw\">#BillsMafia<\/a> <a href=\"https:\/\/twitter.com\/JoshAllenQB?ref_src=twsrc%5Etfw\">@JoshAllenQB<\/a> | <a href=\"https:\/\/twitter.com\/BuffaloBills?ref_src=twsrc%5Etfw\">@BuffaloBills<\/a><\/p>\n<p>\ud83d\udcfa <a href=\"https:\/\/twitter.com\/beinsports_FR?ref_src=twsrc%5Etfw\">@beinsports_FR<\/a> 1 <a href=\"https:\/\/twitter.com\/hashtag\/NFLextra?src=hash&amp;ref_src=twsrc%5Etfw\">#NFLextra<\/a><br \/>\n\ud83d\udcf1 <a href=\"https:\/\/twitter.com\/NFLonDAZN?ref_src=twsrc%5Etfw\">@NFLonDAZN<\/a> <a href=\"https:\/\/t.co\/RyIhrnx2lS\">pic.twitter.com\/RyIhrnx2lS<\/a><\/p>\n<p>\u2014 NFL France (@NFLFrance) <a href=\"https:\/\/twitter.com\/NFLFrance\/status\/1749235983483043985?ref_src=twsrc%5Etfw\">January 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Et le scenario se r\u00e9p\u00e8te encore avec de nouveau un chass\u00e9-crois\u00e9 entre les 2 \u00e9quipes qui offrent tout un spectacle aux fans pr\u00e9sent au <strong>Highmark<\/strong> <strong>Stadium<\/strong>. Et les <strong>Chiefs<\/strong> reprennent les devants avec encore une fois le duo <strong>Mahomes-Kelce<\/strong> \u00e0 la baguette. Ce dernier arrive \u00e0 contourner la d\u00e9fense des <strong>Bills<\/strong>. Avec ce nouveau <em>touchdown<\/em>, les deux comparses deviennent la paire le plus prolifique en <em>playoffs,<\/em> d\u00e9passant ainsi le c\u00e9l\u00e8bre duo <strong>Brady-Gronkowski<\/strong> en termes de\u00a0<em>touchdowns<\/em>. Et le match est loin d&rsquo;\u00eatre termin\u00e9. Puisque encore une fois, <strong>Josh Allen<\/strong> trouve dans un endroit improbable, <strong>Khalil Shakir<\/strong> pour terminer le 3\u00e8me quart-temps sur le score de <strong>24-20<\/strong> pour les <strong>Bills<\/strong>. En tout d\u00e9but de dernier quart-temps, <strong>Mahomes<\/strong> change ses plans et donne le ballon \u00e0 son <em>running back<\/em> <strong>Isiah Pacheco<\/strong> qui fait les derniers m\u00e8tres manquants pour attaquer les 15 derni\u00e8res minutes en position de leader.<\/p>\n<h2 style=\"text-align: justify;\">Encore Mahomes<\/h2>\n<p style=\"text-align: justify;\">La d\u00e9fense des <strong>Chiefs<\/strong> commence \u00e0 faire un travail de sape et emp\u00eache les Bills de remonter via des <em>field goals<\/em>. Plus le temps passe, plus la tension est \u00e0 son comble entre les 2 \u00e9quipes. Et dans les deux derni\u00e8res minutes, <strong>Tyler Bass<\/strong> rate compl\u00e8tement son <em>field goal<\/em> pour \u00e9galiser.<strong> Kansas City<\/strong> a donc la possession et 3 points d&rsquo;avance. Ils vont forc\u00e9ment manger le chrono au maximum. Charge \u00e0 la d\u00e9fense de Buffalo de reprendre le ballon. Mais en d\u00e9poss\u00e9der <strong>Patrick Mahomes<\/strong> n&rsquo;est pas chose ais\u00e9e. Et le score ne bouge plus, la messe est dite. La d\u00e9tresse dans les yeux de <strong>Bass<\/strong> est aussi immense que la joie de <strong>Taylor Swift<\/strong> de voir les <strong>Chiefs<\/strong>, franchise de son <em>boyfriend<\/em> <strong>Travis Kelce<\/strong>, acc\u00e9der \u00e0 une nouvelle finale de conf\u00e9rence.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">FINAL: The <a href=\"https:\/\/twitter.com\/Chiefs?ref_src=twsrc%5Etfw\">@Chiefs<\/a> are back in the AFC Championship! <a href=\"https:\/\/twitter.com\/hashtag\/NFLPlayoffs?src=hash&amp;ref_src=twsrc%5Etfw\">#NFLPlayoffs<\/a> <a href=\"https:\/\/t.co\/CXDHLZ3SRh\">pic.twitter.com\/CXDHLZ3SRh<\/a><\/p>\n<p>\u2014 NFL (@NFL) <a href=\"https:\/\/twitter.com\/NFL\/status\/1749261607413444747?ref_src=twsrc%5Etfw\">January 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\"><strong>Patrick Mahomes<\/strong> a encore \u00e9t\u00e9 pr\u00e9cieux et sorti un gros match. Pour son 1er match \u00e0 l&rsquo;ext\u00e9rieur en <em>playoffs<\/em> en carri\u00e8re, il s&rsquo;en est bien sorti et ira d\u00e9fier les <strong>Ravens \u00e0 Baltimore<\/strong> dimanche prochain. Les <strong>Bills<\/strong> peuvent nourrir des regrets tout de m\u00eame et auraient aussi m\u00e9rit\u00e9 de passer. Les Chiefs ont un peu mieux g\u00e9r\u00e9 les quelques moments cl\u00e9s de ce match. Le\u00a0 duel attendu a tenu ses promesses et il y a fort \u00e0 parier qu&rsquo;il sera de retour l&rsquo;an prochain, pour le plaisir de tous. Les finales de conf\u00e9rences auront lieu dimanche prochain, avec le Superbowl en ligne de mire.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">For a spot in Super Bowl LVIII. <a href=\"https:\/\/twitter.com\/hashtag\/NFLPlayoffs?src=hash&amp;ref_src=twsrc%5Etfw\">#NFLPlayoffs<\/a> <a href=\"https:\/\/t.co\/DZ4QM6QASk\">pic.twitter.com\/DZ4QM6QASk<\/a><\/p>\n<p>\u2014 NFL (@NFL) <a href=\"https:\/\/twitter.com\/NFL\/status\/1749261866134892565?ref_src=twsrc%5Etfw\">January 22, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PLAYOFFS NFL 2024 &#8211; Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs. Si les Lions de Detroit ont fait la loi en 2\u00e8me mi-temps pour sortir 31-23 les Buccaneers de Tampa Bay, le duel au sommet entre Bills et Chiefs a livr\u00e9 un combat de gladiateur. Mahomes et les Chiefs gagnent finalement 27-24 chez les Bills d&rsquo;Allen.<\/p>\n","protected":false},"author":10,"featured_media":455439,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10739],"tags":[16878,29102,1453,9823],"class_list":["post-455421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football-americain","tag-breve","tag-josh-allen","tag-nfl","tag-patrick-mahomes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux<\/title>\n<meta name=\"description\" content=\"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\" \/>\n<meta property=\"og:description\" content=\"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-22T07:00:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-22T08:46:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Meunier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/x.com\/DamienMeunier69\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\"},\"author\":{\"name\":\"Damien Meunier\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735\"},\"headline\":\"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\",\"datePublished\":\"2024-01-22T07:00:42+00:00\",\"dateModified\":\"2024-01-22T08:46:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\"},\"wordCount\":1222,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png\",\"keywords\":[\"br\u00e8ve\",\"josh allen\",\"NFL\",\"Patrick Mahomes\"],\"articleSection\":[\"Football am\u00e9ricain\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\",\"name\":\"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png\",\"datePublished\":\"2024-01-22T07:00:42+00:00\",\"dateModified\":\"2024-01-22T08:46:11+00:00\",\"description\":\"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png\",\"width\":1200,\"height\":674,\"caption\":\"Playoffs NFL Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735\",\"name\":\"Damien Meunier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Damien Meunier\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis d\u00e9cembre 2016 - Amateur professionnel de sport, d\u2019abord le football, j\u2019aurais pu en faire mon m\u00e9tier. Mais bon, vous savez les \u2026 non, pas les crois\u00e9s, ils vont bien eux. Juste un manque de talent, de technique et de niveau surtout. Mais cette passion est ancr\u00e9e en moi telle la pomme dans la tarte tatin. Le c\u00f4t\u00e9 suiveur\/supporter est \u00e9videmment important au quotidien, que ce soit un soir de juillet 1998 en banlieue lyonnaise ou de juillet 2018 \u00e0 Montr\u00e9al. Car oui, depuis ma France natale, j\u2019ai migr\u00e9 outre-Atlantique, au pays des caribous. L\u00e0, le football se joue \u00e0 la main et non au pied. Et surtout, la religion sportive est plut\u00f4t froide et se joue avec une crosse. Non, ce n\u2019est pas le curling ni le Lacrosse, encore que, mais le hockey sur glace. Une autre vision, une autre culture. On troque les crudit\u00e9s devant la t\u00e9l\u00e9 pour une poutine et on s\u2019installe avec notre chandail pour suivre cela. Et en moins de temps qu\u2019il ne faut pour le dire, ou la vitesse d\u2019un slap shot de McDavid ou un arr\u00eat de la mitaine de Price, j\u2019\u00e9cris sur de l\u2019actualit\u00e9 par ici mais aussi le sport f\u00e9minin, pas assez mis en avant.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/x.com\/DamienMeunier69\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/damien-m\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux","description":"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/","og_locale":"fr_FR","og_type":"article","og_title":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux","og_description":"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.","og_url":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-01-22T07:00:42+00:00","article_modified_time":"2024-01-22T08:46:11+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png","type":"image\/png"}],"author":"Damien Meunier","twitter_card":"summary_large_image","twitter_title":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux","twitter_creator":"@https:\/\/x.com\/DamienMeunier69","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/"},"author":{"name":"Damien Meunier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735"},"headline":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux","datePublished":"2024-01-22T07:00:42+00:00","dateModified":"2024-01-22T08:46:11+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/"},"wordCount":1222,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png","keywords":["br\u00e8ve","josh allen","NFL","Patrick Mahomes"],"articleSection":["Football am\u00e9ricain"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/","url":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/","name":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png","datePublished":"2024-01-22T07:00:42+00:00","dateModified":"2024-01-22T08:46:11+00:00","description":"PLAYOFFS NFL 2024 - Apr\u00e8s les 2 premiers affrontements samedi, le Divisional Round continuait dimanche soir avec 2 gros matchs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Playoffs-NFL-Les-Lions-et-les-Chiefs-en-finale-de-conference-Mahomes-toujours-precieux.png","width":1200,"height":674,"caption":"Playoffs NFL Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/playoffs-nfl-les-lions-et-les-chiefs-en-finale-de-conference-mahomes-toujours-precieux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Playoffs NFL : Les Lions et les Chiefs en finale de conf\u00e9rence, Mahomes toujours pr\u00e9cieux"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/7ce262eb34bbc1847cff5f60345d4735","name":"Damien Meunier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dfe0549a73ac21bb20dfdf302b222ba2?s=96&d=wp_user_avatar&r=g","caption":"Damien Meunier"},"description":"Journaliste\/r\u00e9dacteur depuis d\u00e9cembre 2016 - Amateur professionnel de sport, d\u2019abord le football, j\u2019aurais pu en faire mon m\u00e9tier. Mais bon, vous savez les \u2026 non, pas les crois\u00e9s, ils vont bien eux. Juste un manque de talent, de technique et de niveau surtout. Mais cette passion est ancr\u00e9e en moi telle la pomme dans la tarte tatin. Le c\u00f4t\u00e9 suiveur\/supporter est \u00e9videmment important au quotidien, que ce soit un soir de juillet 1998 en banlieue lyonnaise ou de juillet 2018 \u00e0 Montr\u00e9al. Car oui, depuis ma France natale, j\u2019ai migr\u00e9 outre-Atlantique, au pays des caribous. L\u00e0, le football se joue \u00e0 la main et non au pied. Et surtout, la religion sportive est plut\u00f4t froide et se joue avec une crosse. Non, ce n\u2019est pas le curling ni le Lacrosse, encore que, mais le hockey sur glace. Une autre vision, une autre culture. On troque les crudit\u00e9s devant la t\u00e9l\u00e9 pour une poutine et on s\u2019installe avec notre chandail pour suivre cela. Et en moins de temps qu\u2019il ne faut pour le dire, ou la vitesse d\u2019un slap shot de McDavid ou un arr\u00eat de la mitaine de Price, j\u2019\u00e9cris sur de l\u2019actualit\u00e9 par ici mais aussi le sport f\u00e9minin, pas assez mis en avant.","sameAs":["https:\/\/x.com\/https:\/\/x.com\/DamienMeunier69"],"url":"https:\/\/dicodusport.fr\/blog\/author\/damien-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/455421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=455421"}],"version-history":[{"count":7,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/455421\/revisions"}],"predecessor-version":[{"id":455461,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/455421\/revisions\/455461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/455439"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=455421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=455421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=455421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}