{"id":456201,"date":"2024-01-24T21:47:54","date_gmt":"2024-01-24T20:47:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=456201&#038;preview=true&#038;preview_id=456201"},"modified":"2024-01-25T09:00:23","modified_gmt":"2024-01-25T08:00:23","slug":"slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/","title":{"rendered":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), c\u2019est \u00e0 nouveau Linus Strasser qui s\u2019est impos\u00e9 sur cette night session. Il devance le Norv\u00e9gien Timon Haugan pour 28 centi\u00e8mes. Cl\u00e9ment No\u00ebl compl\u00e8te le podium.<\/em><\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/classement-slalom-hommes-schladming-2024\/\">Classement de slalom de Schladming<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Avec ce trac\u00e9 illumin\u00e9 par les projecteurs et l\u00e9g\u00e8rement verglac\u00e9 cr\u00e9ant un ph\u00e9nom\u00e8ne miroir, les images et le spectacle \u00e9taient au rendez-vous. Les techniciens qui ont pr\u00e9par\u00e9 la piste ont fait le choix de saler la neige, et dans ces conditions-l\u00e0, Il vaut mieux partir avec un petit dossard en 1<sup>\u00e8re<\/sup> manche.<\/p>\n<h2 style=\"text-align: justify;\">Strasser, l\u2019homme en forme du moment<\/h2>\n<p style=\"text-align: justify;\"><strong>Ramon Zenhaeusern<\/strong> n\u2019a pas su tirer b\u00e9n\u00e9fice de son dossard 1 en enfourchant dans la double. En revanche, les deux concurrents apr\u00e8s lui ont r\u00e9alis\u00e9 les 3<sup>\u00e8me<\/sup> et 1<sup>er<\/sup> temps de cette manche en lieu et place de <strong>Cl\u00e9ment No\u00ebl<\/strong> et de <strong>Linus Strasser<\/strong>. L\u2019Allemand est dans une confiance absolue apr\u00e8s sa victoire \u00e0 Kitzb\u00fchel a su profiter de ce petit dossard pour signer le meilleur temps, avec un bas de trac\u00e9 pr\u00e9cis et le meilleur chrono du secteur 3. <strong>Cl\u00e9ment No\u00ebl<\/strong>, tenant du titre ici et sur le trac\u00e9 des coachs fran\u00e7ais, a su assurer le coup apr\u00e8s sa sortie en deuxi\u00e8me manche \u00e0 Kitzb\u00fchel, pour finir \u00e0 36 centi\u00e8mes de <strong>Strasser<\/strong>. <em>\u00ab\u00a0Je n&rsquo;ai pas tout mis dans cette manche, je n&rsquo;ai pas pris tous les risques. Je suis content. Je suis au contact de Strasser malgr\u00e9 la faute que je fais en bas o\u00f9 je perds deux ou trois dixi\u00e8mes\u00a0\u00bb<\/em> confiait notamment le fran\u00e7ais \u00e0 nos conf\u00e8res de L\u2019\u00c9quipe.<\/p>\n<p style=\"text-align: justify;\">Entre ces deux protagonistes est venu s\u2019intercaler <strong>Timon Haugan<\/strong> (+0.10). \u00c0 l\u2019image de l\u2019ensemble de ses compatriotes, le Norv\u00e9gien appr\u00e9cie particuli\u00e8rement ce type de neige. <strong>Manuel Feller<\/strong>, leader de la sp\u00e9cialit\u00e9 et \u00e0 domicile, finit \u00e0 plus d\u2019une seconde (+1.04) de <strong>Strasser<\/strong>.<\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet \u2013\u00a0<a title=\"Coupe du monde de ski alpin \u2013 Classement g\u00e9n\u00e9ral hommes\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-ski-alpin-classement-general-hommes\/\" rel=\"\">Coupe du monde de ski alpin \u2013 Classement g\u00e9n\u00e9ral hommes<\/a><\/strong><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Malheureusement, au fil des dossards, la piste commen\u00e7ait \u00e0 \u00ab casser \u00bb, surement \u00e0 cause du sel jet\u00e9 en amont sur la piste et de la pluie tombante. \u00a0<strong>L\u00e9o Anguemot<\/strong> en a notamment fait les frais, finissant 38<sup>\u00e8me<\/sup> sans r\u00e9ellement faire de fautes et ne pouvant se qualifier pour la 2<sup>\u00e8me<\/sup> manche, tout comme <strong>Hugo Desgrippes<\/strong>. <strong>Victor Muffat-Jeandet<\/strong>, <strong>Auguste Aulnette<\/strong> et <strong>Paco Rassat<\/strong> sont, quant \u00e0 eux, sortis de la piste. Seul <strong>Steven Amiez<\/strong> vient confirmer sa forme du moment (6<sup>\u00e8me<\/sup> \u00e0 Kitzb\u00fchel) en prenant la 17<sup>\u00e8me<\/sup> place de cette premi\u00e8re manche \u00e0 2.18 de <strong>Strasser<\/strong>.<\/p>\n<h2 style=\"text-align: justify;\">Une seconde manche \u00e0 rebondissements, Strasser s\u2019offre un doubl\u00e9<\/h2>\n<p style=\"text-align: justify;\">En deuxi\u00e8me manche, avec une pluie pas du tout pr\u00e9sente au d\u00e9but de la 2<sup>\u00e8me<\/sup> manche et une piste qui a commenc\u00e9 \u00e0 marquer sur le haut du trac\u00e9, certains ont su tirer leurs \u00e9pingles du jeu, \u00e0 l\u2019image de deux skieurs \u00e0 domicile, <strong>Fabio Gstrein <\/strong>et <strong>Johannes Strolz<\/strong> qui ont gagn\u00e9 respectivement 14 et 9 places. Avec cette piste d\u00e9grad\u00e9e, beaucoup de coureurs sont sortis \u00e0 l\u2019image de <strong>Vinatzer<\/strong> et <strong>McGrath<\/strong>. <strong>Steven Amiez<\/strong> qui a r\u00e9ussi \u00e0 finir le trac\u00e9 sans faire une manche spectaculaire, continue \u00e0 marquer de pr\u00e9cieux points au classement WCSL de la FIS, pour rester dans le fameux top 30.<\/p>\n<p style=\"text-align: justify;\">Mais ces conditions n&rsquo;ont pas emp\u00each\u00e9 l&rsquo;Allemand <strong>Strasser<\/strong> de signer sa deuxi\u00e8me victoire cons\u00e9cutive apr\u00e8s celle sur le slalom de Kitzb\u00fchel. Il a su r\u00e9sister notamment \u00e0 <strong>Timon Haugan<\/strong> (+0.28) qui signe l\u00e0 son premier podium. On a longtemps cru que <strong>Cl\u00e9ment No\u00ebl<\/strong> allait perdre le podium acquit \u00e0 la premi\u00e8re manche, mais c&rsquo;\u00e9tait sans compter un gros dernier secteur qui a permis au Fran\u00e7ais de finir devant <strong>Marc Rochat<\/strong>. No\u00ebl termine \u00e0 plus d&rsquo;une seconde de <strong>Strasser<\/strong> qui semble en pleine confiance en ce moment et relance la course au globe de la sp\u00e9cialit\u00e9 face \u00e0 <strong>Manuel Feller<\/strong> qui termine 5\u00e8me de cette course.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">No\u00ebl d\u00e9termin\u00e9 \ud83d\udca2 \ud835\udde3\ud835\udde2\ud835\uddd7\ud835\udddc\ud835\udde8\ud835\udde0 retrouv\u00e9 !\ud83d\udca5<br \/>\n3e place pour <a href=\"https:\/\/twitter.com\/clement__noel?ref_src=twsrc%5Etfw\">@clement__noel<\/a> sur le slalom nocturne de Schladming \ud83c\udde6\ud83c\uddf9<\/p>\n<p>Steven Amiez marque des points en 2e manche avec une 18e place\ud83d\udcaa<\/p>\n<p>\ud83d\udcf7 Agence Zoom <a href=\"https:\/\/t.co\/E6EXmvqnns\">pic.twitter.com\/E6EXmvqnns<\/a><\/p>\n<p>\u2014 FFS &#8211; F\u00e9d\u00e9ration Fran\u00e7aise de Ski (@FedFranceSki) <a href=\"https:\/\/twitter.com\/FedFranceSki\/status\/1750258382391447809?ref_src=twsrc%5Etfw\">January 24, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), c\u2019est \u00e0 nouveau Linus Strasser qui s\u2019est impos\u00e9 sur cette night session. Il devance le Norv\u00e9gien Timon Haugan pour 28 centi\u00e8mes. Cl\u00e9ment No\u00ebl compl\u00e8te le podium.<\/p>\n","protected":false},"author":95,"featured_media":456313,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[47084],"tags":[16878,13905,2233,3007,24,1513],"class_list":["post-456201","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-ski-alpin","tag-breve","tag-schladming","tag-ski-alpin","tag-slalom","tag-sport","tag-sports-dhiver"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-24T20:47:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-25T08:00:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Florian Vernet\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\"},\"author\":{\"name\":\"Florian Vernet\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8d5318ade56dccc8d6ba87254c479570\"},\"headline\":\"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\",\"datePublished\":\"2024-01-24T20:47:54+00:00\",\"dateModified\":\"2024-01-25T08:00:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\"},\"wordCount\":743,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png\",\"keywords\":[\"br\u00e8ve\",\"Schladming\",\"Ski alpin\",\"slalom\",\"sport\",\"sports d'hiver\"],\"articleSection\":[\"Coupe du monde de ski alpin\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\",\"name\":\"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png\",\"datePublished\":\"2024-01-24T20:47:54+00:00\",\"dateModified\":\"2024-01-25T08:00:23+00:00\",\"description\":\"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png\",\"width\":1200,\"height\":674,\"caption\":\"Slalom de Schladming Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8d5318ade56dccc8d6ba87254c479570\",\"name\":\"Florian Vernet\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Capture-Copie-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Capture-Copie-150x150.jpg\",\"caption\":\"Florian Vernet\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/florian-vernet\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene","description":"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/","og_locale":"fr_FR","og_type":"article","og_title":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene","og_description":"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.","og_url":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-01-24T20:47:54+00:00","article_modified_time":"2024-01-25T08:00:23+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png","type":"image\/png"}],"author":"Florian Vernet","twitter_card":"summary_large_image","twitter_title":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/"},"author":{"name":"Florian Vernet","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8d5318ade56dccc8d6ba87254c479570"},"headline":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene","datePublished":"2024-01-24T20:47:54+00:00","dateModified":"2024-01-25T08:00:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/"},"wordCount":743,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png","keywords":["br\u00e8ve","Schladming","Ski alpin","slalom","sport","sports d'hiver"],"articleSection":["Coupe du monde de ski alpin"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/","url":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/","name":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png","datePublished":"2024-01-24T20:47:54+00:00","dateModified":"2024-01-25T08:00:23+00:00","description":"COUPE DU MONDE SKI ALPIN SAISON 2023-2024- Sur la piste du Planai dans le temple du slalom \u00e0 Schladming (Autriche), Cl\u00e9ment No\u00ebl est 3\u00e8me.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Slalom-de-Schladming-Clement-Noel-sur-le-podium-Linus-Strasser-enchaine-1.png","width":1200,"height":674,"caption":"Slalom de Schladming Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/slalom-de-schladming-clement-noel-sur-le-podium-linus-strasser-enchaine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Slalom de Schladming : Cl\u00e9ment No\u00ebl sur le podium, Linus Strasser encha\u00eene"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/8d5318ade56dccc8d6ba87254c479570","name":"Florian Vernet","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Capture-Copie-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/10\/Capture-Copie-150x150.jpg","caption":"Florian Vernet"},"url":"https:\/\/dicodusport.fr\/blog\/author\/florian-vernet\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456201","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/95"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=456201"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456201\/revisions"}],"predecessor-version":[{"id":456247,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456201\/revisions\/456247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/456313"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=456201"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=456201"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=456201"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}