{"id":456498,"date":"2024-01-26T07:45:05","date_gmt":"2024-01-26T06:45:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=456498&#038;preview=true&#038;preview_id=456498"},"modified":"2024-01-25T22:27:00","modified_gmt":"2024-01-25T21:27:00","slug":"transferts-leo-banos-devrait-terminer-la-saison-en-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/","title":{"rendered":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2023-2024 &#8211; Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Le <strong>Stade<\/strong> <strong>Toulousain<\/strong> a perdu pas moins de trois joueurs lors du succ\u00e8s face \u00e0 <strong>Bath<\/strong> le week-end dernier. <strong>Emmanuel<\/strong> <strong>Meafou<\/strong> devrait manquer un mois de comp\u00e9tition alors que <a href=\"https:\/\/dicodusport.fr\/blog\/stade-toulousain-dimitri-delibes-absent-plusieurs-mois\/\"><strong>Dimitri<\/strong> <strong>Delibes<\/strong><\/a> va \u00eatre \u00e9loign\u00e9 des terrains au moins trois mois, \u00e0 cause d&rsquo;une blessure \u00e0 l&rsquo;\u00e9paule. Mais le plus gravement touch\u00e9, c&rsquo;est <a href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-6-nations-un-toulousain-pour-remplacer-anthony-jelonch\/\"><strong>Anthony<\/strong> <strong>Jelonch<\/strong><\/a>, qui va encore \u00eatre \u00e0 l&rsquo;infirmerie pour au moins six mois.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-garbisi-tolofua-priso-ahki-cowan-dickie-les-infos-du-jeudi-25-janvier\/\" target=\"_blank\" rel=\"noopener\">Transferts Rugby : Garbisi, Tolofua, Priso, Ahki, Cowan-Dickie, les infos du jeudi 25 janvier<\/a><\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">L\u00e9o Banos joker m\u00e9dical d&rsquo;Anthony Jelonch ?<\/h2>\n<p style=\"text-align: justify;\"><strong>Ugo Mola<\/strong> s&rsquo;est donc mis en qu\u00eate d&rsquo;un joker m\u00e9dical pour remplacer son flankeur international. Et la solution pourrait bien \u00eatre d\u00e9j\u00e0 trouv\u00e9e, avec une future recrue du club, <strong>L\u00e9o Banos<\/strong>. Le troisi\u00e8me ligne de <strong>Mont-de-Marsan<\/strong> \u00e9volue encore en Pro D2 cette saison, mais a d\u00e9j\u00e0 deux piges pr\u00e9vues avec son futur club \u00e0 des dates bien pr\u00e9cises.<\/p>\n<p style=\"text-align: justify;\"><strong>L\u00e9o<\/strong> <strong>Banos<\/strong> a \u00e9t\u00e9 joker Coupe du monde et vient de revenir \u00e0 <strong>Toulouse<\/strong> le temps du <strong>Tournoi des 6 Nations<\/strong>. Mais avec la blessure d&rsquo;<strong>Anthony Jelonch<\/strong>, il devrait bien terminer la saison avec son futur club. Le <strong>Stade<\/strong> <strong>Montois<\/strong> ne s&rsquo;opposera pas \u00e0 cette option selon nos confr\u00e8res, et le club de Pro D2 ne compte m\u00eame pas lui trouver un rempla\u00e7ant, estimant avoir assez d&rsquo;options dans son effectif.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Stade Montois : L\u00e9o Banos repart \u00e0 Toulouse\u2026 d\u00e9finitivement ?<br \/>\n\u27a1\ufe0f <a href=\"https:\/\/t.co\/jVcH2FwBcT\">https:\/\/t.co\/jVcH2FwBcT<\/a><a href=\"https:\/\/t.co\/jVcH2FwBcT\">https:\/\/t.co\/jVcH2FwBcT<\/a><\/p>\n<p>\u2014 SudOuest Sport (@SudOuest_Sport) <a href=\"https:\/\/twitter.com\/SudOuest_Sport\/status\/1750447603148280293?ref_src=twsrc%5Etfw\">January 25, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":456516,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[9129,47050],"tags":[16878,4008],"class_list":["post-456498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-stade-toulousain"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts : L\u00e9o Banos devrait terminer la saison en Top 14<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-26T06:45:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14\",\"datePublished\":\"2024-01-26T06:45:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\"},\"wordCount\":287,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png\",\"keywords\":[\"br\u00e8ve\",\"Stade Toulousain\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\",\"name\":\"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png\",\"datePublished\":\"2024-01-26T06:45:05+00:00\",\"description\":\"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14","description":"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14","og_description":"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-01-26T06:45:05+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14","datePublished":"2024-01-26T06:45:05+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/"},"wordCount":287,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png","keywords":["br\u00e8ve","Stade Toulousain"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/","name":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png","datePublished":"2024-01-26T06:45:05+00:00","description":"TOP 14 2023-2024 - Selon Sud-Ouest, L\u00e9o Banos devrait terminer la saison avec le Stade Toulousain comme joker m\u00e9dical.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-Leo-Banos-devrait-terminer-la-saison-en-Top-14.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-leo-banos-devrait-terminer-la-saison-en-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : L\u00e9o Banos devrait terminer la saison en Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=456498"}],"version-history":[{"count":3,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456498\/revisions"}],"predecessor-version":[{"id":456528,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/456498\/revisions\/456528"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/456516"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=456498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=456498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=456498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}