{"id":457944,"date":"2024-01-30T08:31:59","date_gmt":"2024-01-30T07:31:59","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=457944&#038;preview=true&#038;preview_id=457944"},"modified":"2024-01-30T08:48:31","modified_gmt":"2024-01-30T07:48:31","slug":"transferts-3-clubs-de-pro-d2-veulent-clement-doumenc","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/","title":{"rendered":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Cl\u00e9ment Doumenc (Montpellier) est courtis\u00e9 par 3 clubs de Pro D2 pour la saison prochaine.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En fin de contrat avec le <strong>MHR<\/strong>, <strong>Cl\u00e9ment<\/strong> <strong>Doumenc<\/strong> fait partie des joueurs qui ne sont plus dans les plans de la nouvelle direction sportive. <strong>Bernard Laporte<\/strong> veut faire le tri dans l&rsquo;effectif du <strong>Montpellier<\/strong> <strong>HR<\/strong> pour insuffler une nouvelle dynamique apr\u00e8s la saison en cours qui est tr\u00e8s compliqu\u00e9e. Les champions de France 2022 vont devoir se battre pour leur maintien.<\/p>\n<ul style=\"text-align: justify;\">\n<li style=\"text-align: justify;\"><strong>\u00c0 ce sujet &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-rugby-tanga-lawes-habel-kuffner-les-infos-du-lundi-29-janvier\/\" target=\"_blank\" rel=\"noopener\">Transferts Rugby : Tanga, Lawes, Habel-Kuffner les infos du lundi 29 janvier<\/a><br \/>\n<\/strong><\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\">Grenoble en pole position pour Cl\u00e9ment Doumenc<\/h2>\n<p style=\"text-align: justify;\">L&rsquo;<strong>Aviron Bayonnais<\/strong> \u00e9tait venu aux renseignements pour <strong>Cl\u00e9ment<\/strong> <strong>Doumenc<\/strong> et voulait en faire le rempla\u00e7ant de <strong>Pierre<\/strong> <strong>Huguet<\/strong>. Mais le club basque se tourne vers d&rsquo;autres pistes, et notamment celle qui m\u00e8ne \u00e0 <strong>Giovanni Habel-K\u00fcffner<\/strong>. Le troisi\u00e8me ligne du Montpellier HR pourrait rebondir en Pro D2 o\u00f9 plusieurs clubs sont int\u00e9ress\u00e9s.<\/p>\n<p style=\"text-align: justify;\"><strong>Vannes<\/strong> et <strong>Soyaux-Angoul\u00eame<\/strong> sont int\u00e9ress\u00e9s par le profil de <strong>Cl\u00e9ment<\/strong> <strong>Doumenc<\/strong>, mais le <strong>FC Grenoble<\/strong> serait l&rsquo;\u00e9quipe la mieux plac\u00e9e pour l&rsquo;accueillir la saison prochaine. Form\u00e9 \u00e0 Carcassonne, le joueur de 26 ans a pour le moment connu que deux clubs chez les professionnels. Cette saison, il a disput\u00e9 neuf matchs dont six comme titulaire.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">[TRANSFERTS] Tanga, Lawes, Doumenc&#8230; Le march\u00e9 des troisi\u00e8mes lignes s&rsquo;agite !<\/p>\n<p>Toutes les infos ici &gt; <a href=\"https:\/\/t.co\/5or0rBpU5e\">https:\/\/t.co\/5or0rBpU5e<\/a> <a href=\"https:\/\/t.co\/CSXn1uGa9o\">pic.twitter.com\/CSXn1uGa9o<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1751707965864784088?ref_src=twsrc%5Etfw\">January 28, 2024<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu&rsquo;il a re\u00e7u en France.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":457945,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[16878,1839],"class_list":["post-457944","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-pro-d2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu&#039;il a re\u00e7u en France.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu&#039;il a re\u00e7u en France.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-01-30T07:31:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-30T07:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc\",\"datePublished\":\"2024-01-30T07:31:59+00:00\",\"dateModified\":\"2024-01-30T07:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/\"},\"wordCount\":269,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/\",\"name\":\"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png\",\"datePublished\":\"2024-01-30T07:31:59+00:00\",\"dateModified\":\"2024-01-30T07:48:31+00:00\",\"description\":\"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu'il a re\u00e7u en France.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2024\\\/01\\\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png\",\"width\":1200,\"height\":674},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu'il a re\u00e7u en France.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc","og_description":"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu'il a re\u00e7u en France.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-01-30T07:31:59+00:00","article_modified_time":"2024-01-30T07:48:31+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc","datePublished":"2024-01-30T07:31:59+00:00","dateModified":"2024-01-30T07:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/"},"wordCount":269,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png","keywords":["br\u00e8ve","Pro D2"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/","name":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png","datePublished":"2024-01-30T07:31:59+00:00","dateModified":"2024-01-30T07:48:31+00:00","description":"TOP 14 2023-2024 - Selon le Midi Olympique, Courtney Lawes aurait choisi de rejoindre Brive parmi les propositions qu'il a re\u00e7u en France.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/01\/Transferts-3-clubs-de-Pro-D2-veulent-Clement-Doumenc.png","width":1200,"height":674},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-3-clubs-de-pro-d2-veulent-clement-doumenc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : 3 clubs de Pro D2 veulent Cl\u00e9ment Doumenc"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/457944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=457944"}],"version-history":[{"count":2,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/457944\/revisions"}],"predecessor-version":[{"id":457966,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/457944\/revisions\/457966"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/457945"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=457944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=457944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=457944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}