{"id":459276,"date":"2024-02-03T10:25:34","date_gmt":"2024-02-03T09:25:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=459276&#038;preview=true&#038;preview_id=459276"},"modified":"2024-02-03T16:31:52","modified_gmt":"2024-02-03T15:31:52","slug":"coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/","title":{"rendered":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#8217;emporte \u00e0 Gudauri !"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><a href=\"https:\/\/dicodusport.fr\/blog\/?s=coupe+du+monde+snowboardcross\">COUPE DU MONDE DE SNOWBOARDCROSS<\/a> &#8211; Chlo\u00e9 Trespeuch a remport\u00e9 l&rsquo;\u00e9preuve de Coupe du monde \u00e0 Gudauri (G\u00e9orgie), ce samedi. En difficult\u00e9 sur les d\u00e9parts, la Tricolore a r\u00e9alis\u00e9 des remont\u00e9es spectaculaires pour surpasser la concurrence, et conforter sa place de leader du classement g\u00e9n\u00e9ral.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Chlo\u00e9 Trespeuch imp\u00e9riale, L\u00e9a Casta 5e<\/h2>\n<p style=\"text-align: justify;\">En t\u00eate du classement g\u00e9n\u00e9ral avant cette \u00e9tape en G\u00e9orgie, <b>Chlo\u00e9 Trespeuch<\/b> avait pour mission de conserver cette position face \u00e0 l\u2019Italienne <b>Michela Moioli<\/b>. Mais rien ne va lui \u00eatre donn\u00e9. En quarts de finale, la Tricolore ne va pas avoir besoin de lutter puisqu\u2019elle est la seule \u00e0 ne pas chuter pour acc\u00e9der aux demies sans encombre. Dans la m\u00eame s\u00e9rie,<b> L\u00e9a Casta<\/b> et <b>Julia Pereira Da Sousa Mabileau <\/b>ont \u00e9t\u00e9 fauch\u00e9es par la Suissesse Aline Albrecht, mais Casta valide tout de m\u00eame sa place dans le Top 8 du jour.<\/p>\n<p style=\"text-align: justify;\">Une fois en demies, le d\u00e9part va \u00eatre catastrophique pour les Bleues. <strong>L\u00e9a Casta<\/strong> perd tout espoir d\u00e8s la premi\u00e8re bosse, mais se rattrape en remportant la petite finale pour d\u00e9crocher une superbe 5e place. Trespeuch poss\u00e8de elle une seconde de retard sur le duo de t\u00eate au bout du premier virage. Largu\u00e9e, elle va donner une le\u00e7on \u00e0 ses rivales en r\u00e9alisant une run magistral pour d\u00e9passer ses concurrentes et terminer en t\u00eate devant Moioli. Grande favorite de la finale, <strong>Chlo\u00e9 Trespeuch<\/strong> va r\u00e9aliser la m\u00eame course qu&rsquo;en demies. Le d\u00e9part est rat\u00e9, mais elle va progressivement remonter Moioli, puis Adamczykova pour couper la ligne en t\u00eate, et remporter une exceptionnelle victoire en terres g\u00e9orgiennes !<\/p>\n<p style=\"text-align: justify;\">Au g\u00e9n\u00e9ral, la Tricolore conforte donc la t\u00eate devant sa rivale italienne, qui termine 4e, tandis que derri\u00e8re, les Australiennes<b> <\/b><b>Josie Baff <\/b>et surtout<b> Belle Bro<\/b><b>ckhoff<\/b> ont perdu des gros points en \u00e9tant sorties pr\u00e9matur\u00e9ment.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\ud83d\udd25 Magnifique course de Chlo\u00e9 Trespeuch !<\/p>\n<p>Pourtant malade, la Fran\u00e7aise est pass\u00e9e en t\u00eate dans le dernier virage pour d\u00e9crocher sa deuxi\u00e8me victoire de la saison, \u00e0 Gudauri ! <a href=\"https:\/\/twitter.com\/hashtag\/lequipeSNOWBOARD?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeSNOWBOARD<\/a> <a href=\"https:\/\/t.co\/Q6v76z7P5B\">pic.twitter.com\/Q6v76z7P5B<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1753711234849935374?ref_src=twsrc%5Etfw\">February 3, 2024<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Julien Tomas, la bonne surprise du jour c\u00f4t\u00e9 masculin<\/h2>\n<p align=\"justify\"><b>Julien Tomas<\/b> a lui r\u00e9alis\u00e9 la plus belle \u00e9preuve de sa jeune carri\u00e8re. Du haut de ses 19 ans, il a tout d\u2019abord assur\u00e9 sa place en quarts en sortant d\u2019un huiti\u00e8me o\u00f9 <strong>Melvin Surget<\/strong> n\u2019est pas pass\u00e9. En quarts, il va r\u00e9aliser un run exceptionnel afin d\u2019aller chercher sa premi\u00e8re demi-finale. Malgr\u00e9 un d\u00e9part d\u00e9licat, il n\u2019a jamais l\u00e2ch\u00e9 avant de placer une attaque tranchante dans les derniers virages afin d\u2019arracher le deuxi\u00e8me spot. En demies, il va de nouveau montrer tout son talent en luttant jusqu\u2019au bout avec Visintin avant d\u2019\u00e9chouer d\u2019un souffle en 3e place. Finalement, il ne fera pas mieux que la 8e place suite \u00e0 une chute en petite finale.<\/p>\n<p align=\"justify\">De leur c\u00f4t\u00e9, <b>Loan Bozzolo<\/b>, <b>L\u00e9o le Bl\u00e9 Jaques <\/b>et <b>Aidan Chollet <\/b>n\u2019ont eux pas d\u00e9pass\u00e9 le stade des quarts de finale d&rsquo;une manche finalement remport\u00e9e par l&rsquo;in\u00e9vitable <strong>\u00c9liot Grondin<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE SNOWBOARDCROSS &#8211; Chlo\u00e9 Trespeuch a remport\u00e9 l&rsquo;\u00e9preuve de Coupe du monde \u00e0 Gudauri (G\u00e9orgie), ce samedi. En difficult\u00e9 sur les d\u00e9parts, la Tricolore a r\u00e9alis\u00e9 des remont\u00e9es spectaculaires pour surpasser la concurrence, et conforter sa place de leader du classement g\u00e9n\u00e9ral.<\/p>\n","protected":false},"author":55,"featured_media":459493,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"1","footnotes":""},"categories":[10126],"tags":[16878,3021,36280,30709,3022,24],"class_list":["post-459276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-snowboard","tag-breve","tag-chloe-trespeuch","tag-coupe-du-monde-snowboardcross","tag-lea-casta","tag-snowboardcross","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#039;emporte \u00e0 Gudauri !<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#039;emporte \u00e0 Gudauri !\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-03T09:25:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-03T15:31:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"674\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#039;emporte \u00e0 Gudauri !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#8217;emporte \u00e0 Gudauri !\",\"datePublished\":\"2024-02-03T09:25:34+00:00\",\"dateModified\":\"2024-02-03T15:31:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\"},\"wordCount\":569,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png\",\"keywords\":[\"br\u00e8ve\",\"Chlo\u00e9 Trespeuch\",\"Coupe du monde snowboardcross\",\"L\u00e9a Casta\",\"snowboardcross\",\"sport\"],\"articleSection\":[\"Snowboard\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#respond\"]}],\"copyrightYear\":\"2024\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\",\"name\":\"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png\",\"datePublished\":\"2024-02-03T09:25:34+00:00\",\"dateModified\":\"2024-02-03T15:31:52+00:00\",\"description\":\"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png\",\"width\":1200,\"height\":674,\"caption\":\"Coupe du monde Snowboardcross Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#8217;emporte \u00e0 Gudauri !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !","description":"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !","og_description":"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2024-02-03T09:25:34+00:00","article_modified_time":"2024-02-03T15:31:52+00:00","og_image":[{"width":1200,"height":674,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#8217;emporte \u00e0 Gudauri !","datePublished":"2024-02-03T09:25:34+00:00","dateModified":"2024-02-03T15:31:52+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/"},"wordCount":569,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png","keywords":["br\u00e8ve","Chlo\u00e9 Trespeuch","Coupe du monde snowboardcross","L\u00e9a Casta","snowboardcross","sport"],"articleSection":["Snowboard"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#respond"]}],"copyrightYear":"2024","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/","name":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png","datePublished":"2024-02-03T09:25:34+00:00","dateModified":"2024-02-03T15:31:52+00:00","description":"COUPE DU MONDE DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch a remport\u00e9 une magnifique victoire en G\u00e9orgie, \u00e0 Gudauri.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2024\/02\/Coupe-du-monde-Snowboardcross-Chloe-Trespeuch-lemporte-a-Gudauri-.png","width":1200,"height":674,"caption":"Coupe du monde Snowboardcross Chlo\u00e9 Trespeuch l'emporte \u00e0 Gudauri !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-snowboardcross-chloe-trespeuch-lemporte-a-gudauri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde Snowboardcross : Chlo\u00e9 Trespeuch l&#8217;emporte \u00e0 Gudauri !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/459276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=459276"}],"version-history":[{"count":5,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/459276\/revisions"}],"predecessor-version":[{"id":459345,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/459276\/revisions\/459345"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/459493"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=459276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=459276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=459276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}